{"id":5675,"date":"2023-09-26T08:05:36","date_gmt":"2023-09-26T08:05:36","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=5675"},"modified":"2024-05-27T17:14:11","modified_gmt":"2024-05-27T17:14:11","slug":"injection-molding-process-steps","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/","title":{"rendered":"4 etapas do processo de moldagem por inje\u00e7\u00e3o de pl\u00e1stico, com anima\u00e7\u00e3o explicada"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5675\" class=\"elementor elementor-5675\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bb1942 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bb1942\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a36659\" data-id=\"8a36659\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-588822c elementor-widget elementor-widget-heading\" data-id=\"588822c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar o \u00edndice\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/#Introduction_to_the_Injection_Molding_Process_Steps\" >Introdu\u00e7\u00e3o \u00e0s etapas do processo de moldagem por inje\u00e7\u00e3o<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/#1_The_Mold_Clamping\" >1. A fixa\u00e7\u00e3o do molde<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/#2_Injection_and_Pressure_Packing\" >2. Embalagem por inje\u00e7\u00e3o e press\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/#3_Cooling_and_Solidification\" >3. Arrefecimento e solidifica\u00e7\u00e3o<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/#Tip_Cooling_Phase_Is_the_Longiest_of_the_Four_Steps\" >Dica: A fase de arrefecimento \u00e9 a mais longa das quatro etapas<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/#4_Mold_Opening_and_Part_Ejection\" >4. Abertura do molde e eje\u00e7\u00e3o da pe\u00e7a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/#Conclusion\" >Conclus\u00e3o<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Introduction_to_the_Injection_Molding_Process_Steps\"><\/span>Introdu\u00e7\u00e3o \u00e0s etapas do processo de moldagem por inje\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1a994f elementor-widget elementor-widget-text-editor\" data-id=\"a1a994f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A moldagem por inje\u00e7\u00e3o, muitas vezes referida simplesmente como \u201cmoldagem\u201d, \u00e9 um processo de fabrico fundamental utilizado para criar produtos de pl\u00e1stico. Neste m\u00e9todo, as part\u00edculas de pl\u00e1stico s\u00e3o <strong>aquecidas at\u00e9 se tornarem l\u00edquidas<\/strong> e depois injectadas na cavidade de um molde atrav\u00e9s do bocal de uma m\u00e1quina de moldagem por inje\u00e7\u00e3o. Uma vez dentro do molde, o pl\u00e1stico fundido <strong>arrefece e solidifica<\/strong>, assumindo a forma da cavidade do molde.<\/p><p class=\"translation-block\">Este processo vers\u00e1til permite a cria\u00e7\u00e3o de formas intrincadas e complexas que seriam demoradas ou mesmo imposs\u00edveis de obter com outros m\u00e9todos de fabrico.<\/p><p class=\"translation-block\">Neste artigo, vamos decompor o processo de moldagem por inje\u00e7\u00e3o em quatro passos simples, para que seja facilmente compreens\u00edvel para os principiantes. Vamos mergulhar no assunto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1966856 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1966856\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86b6df3\" data-id=\"86b6df3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74723b6 elementor-widget elementor-widget-image\" data-id=\"74723b6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-installed-on-machine.jpg\" class=\"attachment-large size-large wp-image-5756\" alt=\"molde de inje\u00e7\u00e3o instalado na m\u00e1quina\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-installed-on-machine.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-installed-on-machine-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">(O molde de inje\u00e7\u00e3o e a m\u00e1quina de moldagem por inje\u00e7\u00e3o)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1382666\" data-id=\"1382666\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f289716 elementor-widget elementor-widget-image\" data-id=\"f289716\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-installed-cross-section.jpg\" class=\"attachment-large size-large wp-image-5757\" alt=\"sec\u00e7\u00e3o transversal do molde de inje\u00e7\u00e3o instalado na m\u00e1quina\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-installed-cross-section.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-installed-cross-section-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">(A sec\u00e7\u00e3o transversal)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1ef4fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1ef4fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc291b3\" data-id=\"fc291b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12b3b1d elementor-widget elementor-widget-heading\" data-id=\"12b3b1d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"1_The_Mold_Clamping\"><\/span>1. A fixa\u00e7\u00e3o do molde<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53185cb elementor-widget elementor-widget-text-editor\" data-id=\"53185cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">O primeiro passo no processo de moldagem por inje\u00e7\u00e3o \u00e9 a fixa\u00e7\u00e3o do molde. Durante esta fase, o molde inferior, que \u00e9 inicialmente posicionado na m\u00e1quina de moldagem por inje\u00e7\u00e3o, avan\u00e7a e fecha-se firmemente com o molde superior. Quando os dois moldes se juntam, o n\u00facleo e a cavidade dentro deles criam um espa\u00e7o oco que dar\u00e1 forma ao produto final.<\/p><p class=\"translation-block\">\u00c9 crucial notar que, nesta altura, a m\u00e1quina de moldagem por inje\u00e7\u00e3o exerce uma for\u00e7a de aperto do molde significativa. Esta for\u00e7a garante que os moldes superior e inferior permane\u00e7am hermeticamente fechados, impedindo o aparecimento das mais pequenas fendas, especialmente sob a intensa press\u00e3o de inje\u00e7\u00e3o que surge mais tarde no processo. Este fecho seguro \u00e9 essencial para o sucesso do processo de moldagem por inje\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f66a70d elementor-widget elementor-widget-image\" data-id=\"f66a70d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-clamping.gif\" class=\"attachment-large size-large wp-image-5697\" alt=\"A anima\u00e7\u00e3o da fixa\u00e7\u00e3o do molde de inje\u00e7\u00e3o\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b49ea4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b49ea4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d74da7a\" data-id=\"d74da7a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7296c13 elementor-widget elementor-widget-heading\" data-id=\"7296c13\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"2_Injection_and_Pressure_Packing\"><\/span>2. Embalagem por inje\u00e7\u00e3o e press\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e8d52 elementor-widget elementor-widget-text-editor\" data-id=\"35e8d52\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">No processo de moldagem por inje\u00e7\u00e3o, o pl\u00e1stico fundido \u00e9 injetado \u00e0 for\u00e7a na cavidade do molde pela m\u00e1quina de moldagem por inje\u00e7\u00e3o, preenchendo todo o espa\u00e7o sob uma press\u00e3o substancial. Uma vez preenchido, a m\u00e1quina de moldagem por inje\u00e7\u00e3o mant\u00e9m uma press\u00e3o de inje\u00e7\u00e3o espec\u00edfica para compensar a perda de volume causada pelo encolhimento natural do pl\u00e1stico em arrefecimento e solidifica\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-351ae50 elementor-widget elementor-widget-image\" data-id=\"351ae50\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/plastic-injection-in-mold.gif\" class=\"attachment-large size-large wp-image-5704\" alt=\"a inje\u00e7\u00e3o de pl\u00e1stico fundido no molde de inje\u00e7\u00e3o\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8b07a elementor-widget elementor-widget-text-editor\" data-id=\"1e8b07a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Normalmente, o <a href=\"https:\/\/www.tuotuo.com.cn\/article-4788.html\" target=\"_blank\" rel=\"noopener\">intervalo ideal para a press\u00e3o de moldagem por inje\u00e7\u00e3o<\/a> com v\u00e1rios pl\u00e1sticos \u00e9 inferior a 80-100 MPa. As coisas come\u00e7am a tornar-se mais dif\u00edceis na gama de 100-120 MPa e, quando ultrapassam os 120-150 MPa, tornam-se significativamente mais exigentes.<\/p><p class=\"translation-block\">A press\u00e3o de inje\u00e7\u00e3o serve como um indicador do esfor\u00e7o necess\u00e1rio para preencher toda a cavidade. Est\u00e1 intimamente ligada a factores como o tamanho total da pe\u00e7a, <a href=\"http:\/\/boyanmfg.com\/injection-molding-wall-thickness\/\">espessura da parede<\/a>, e altura.<\/p><p class=\"translation-block\">Al\u00e9m disso, o controlo da velocidade de inje\u00e7\u00e3o em diferentes fases \u00e9 uma arte, crucial para a obten\u00e7\u00e3o de pe\u00e7as finais de elevada qualidade.<\/p><p class=\"translation-block\">No entanto, \u00e9 importante notar que quando o canal de entrada, o canal de sa\u00edda e a porta principal come\u00e7am a solidificar, torna-se imposs\u00edvel introduzir mais material no molde. Consequentemente, mesmo com o enchimento por press\u00e3o, \u00e9 inevit\u00e1vel algum grau de contra\u00e7\u00e3o no produto acabado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74c0056 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74c0056\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ab02db\" data-id=\"5ab02db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b370f1 elementor-widget elementor-widget-menu-anchor\" data-id=\"9b370f1\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"cooling\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c619e6 elementor-widget elementor-widget-heading\" data-id=\"1c619e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"3_Cooling_and_Solidification\"><\/span>3. Arrefecimento e solidifica\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35d018e elementor-widget elementor-widget-text-editor\" data-id=\"35d018e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Com o molde bem fechado, o pl\u00e1stico derretido no interior da cavidade do molde come\u00e7a a arrefecer e a solidificar. Durante esta fase crucial, o pl\u00e1stico sofre uma transforma\u00e7\u00e3o, passando de um estado l\u00edquido para um estado s\u00f3lido, encolhendo naturalmente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efeb809 elementor-widget elementor-widget-image\" data-id=\"efeb809\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/part-cooling-injection-mold.gif\" class=\"attachment-large size-large wp-image-5705\" alt=\"Arrefecimento da pe\u00e7a no interior do molde de inje\u00e7\u00e3o\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd3ea5c elementor-widget elementor-widget-text-editor\" data-id=\"bd3ea5c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A temperatura do pr\u00f3prio molde desempenha um papel fundamental na determina\u00e7\u00e3o da qualidade do produto final. Normalmente, os aquecedores de moldes geram \u00f3leo aquecido para aumentar a temperatura do molde, enquanto a \u00e1gua fria \u00e9 utilizada para a baixar. Em alguns casos raros, ambos os m\u00e9todos de aquecimento e arrefecimento s\u00e3o utilizados alternativamente num ciclo de produ\u00e7\u00e3o para obter um controlo preciso da temperatura e uma qualidade \u00f3ptima do produto.<\/p><p class=\"translation-block\">A dura\u00e7\u00e3o do processo de arrefecimento e solidifica\u00e7\u00e3o \u00e9 um par\u00e2metro cr\u00edtico que afecta diretamente a qualidade do produto acabado. Determina se o produto est\u00e1 totalmente formado e assegura que as diferen\u00e7as subtis de tamanho s\u00e3o minimizadas.<\/p><p class=\"translation-block\">Quando as pe\u00e7as de pl\u00e1stico tiverem arrefecido e solidificado adequadamente no molde, \u00e9 altura de avan\u00e7ar para o passo seguinte: abrir o molde e remover os componentes rec\u00e9m-formados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cfb535 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cfb535\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee47983\" data-id=\"ee47983\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cce6b2c elementor-widget elementor-widget-heading\" data-id=\"cce6b2c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Tip_Cooling_Phase_Is_the_Longiest_of_the_Four_Steps\"><\/span>Dica: A fase de arrefecimento \u00e9 a mais longa das quatro etapas<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe6223 elementor-widget elementor-widget-text-editor\" data-id=\"efe6223\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">No ciclo de produ\u00e7\u00e3o da moldagem por inje\u00e7\u00e3o, que inclui estas quatro etapas, o processo de arrefecimento destaca-se como o mais demorado, tornando-se um fator essencial para a efici\u00eancia global. A espessura das paredes da pe\u00e7a de pl\u00e1stico desempenha um papel crucial na determina\u00e7\u00e3o da dura\u00e7\u00e3o da fase de arrefecimento.<\/p><p class=\"translation-block\">Em muitos casos, \u00e9 o jito, frequentemente a regi\u00e3o mais espessa, que se torna o principal fator que contribui para tempos de arrefecimento prolongados. Nesses cen\u00e1rios, a implementa\u00e7\u00e3o de um <a href=\"http:\/\/boyanmfg.com\/injection-mold-gate-types\/#hot_runner\"> sistema de canais quentes<\/a> pode revelar-se altamente ben\u00e9fica, uma vez que elimina eficazmente a necessidade de arrefecer o canal de entrada, optimizando o calend\u00e1rio de produ\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce4ebfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce4ebfe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0557315\" data-id=\"0557315\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dc3a16 elementor-widget elementor-widget-heading\" data-id=\"7dc3a16\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"4_Mold_Opening_and_Part_Ejection\"><\/span>4. Abertura do molde e eje\u00e7\u00e3o da pe\u00e7a<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f69246 elementor-widget elementor-widget-text-editor\" data-id=\"4f69246\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Na fase seguinte do processo de moldagem por inje\u00e7\u00e3o, temos a abertura do molde e a eje\u00e7\u00e3o da pe\u00e7a.<\/p><p class=\"translation-block\">Em contraste com a fase de fixa\u00e7\u00e3o do molde, o molde inferior move-se agora para tr\u00e1s, separando-se do molde superior. Simultaneamente, um componente essencial conhecido como pino ejetor entra em a\u00e7\u00e3o, empurrando o produto rec\u00e9m-formado para fora do molde inferior.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-790d78c elementor-widget elementor-widget-image\" data-id=\"790d78c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/injection-mold-opening.gif\" class=\"attachment-large size-large wp-image-5710\" alt=\"abertura do molde de inje\u00e7\u00e3o\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d4648b elementor-widget elementor-widget-text-editor\" data-id=\"6d4648b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">O pino ejetor desempenha um papel fundamental para garantir a remo\u00e7\u00e3o bem sucedida do produto, especialmente quando se trata de artigos com pequenos \u00e2ngulos de inclina\u00e7\u00e3o e paredes altas. Sem o pino ejetor, alguns produtos podem ficar presos no molde, tornando a remo\u00e7\u00e3o praticamente imposs\u00edvel sem os danificar.<\/p><p class=\"translation-block\">Al\u00e9m disso, \u00e9 crucial garantir que o produto n\u00e3o adira ao molde superior porque, normalmente, o molde superior n\u00e3o possui um mecanismo de eje\u00e7\u00e3o. A eje\u00e7\u00e3o adequada garante um processo de produ\u00e7\u00e3o suave e eficiente, permitindo a cria\u00e7\u00e3o de componentes de pl\u00e1stico de alta qualidade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05f0ddd elementor-widget elementor-widget-image\" data-id=\"05f0ddd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/09\/part-ejection-injection-mold.gif\" class=\"attachment-large size-large wp-image-5709\" alt=\"A eje\u00e7\u00e3o da pe\u00e7a de pl\u00e1stico do molde de inje\u00e7\u00e3o\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e00f6ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e00f6ba\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4321ab\" data-id=\"f4321ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e27c7ce elementor-widget elementor-widget-heading\" data-id=\"e27c7ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclus\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-845b579 elementor-widget elementor-widget-text-editor\" data-id=\"845b579\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Em resumo, a teoria do processo de moldagem por inje\u00e7\u00e3o \u00e9 simples de compreender. No entanto, para produzir consistentemente grandes quantidades de produtos de alta qualidade, \u00e9 essencial um controlo preciso de v\u00e1rios par\u00e2metros no processo de moldagem por inje\u00e7\u00e3o. Os principais factores que exigem uma aten\u00e7\u00e3o cuidada incluem a temperatura de inje\u00e7\u00e3o, a press\u00e3o, o tempo de espera, entre outros.<\/p><p class=\"translation-block\">A obten\u00e7\u00e3o deste n\u00edvel de precis\u00e3o n\u00e3o depende apenas de equipamento sofisticado, mas tamb\u00e9m da compet\u00eancia e colabora\u00e7\u00e3o de engenheiros e operadores qualificados com uma vasta experi\u00eancia neste dom\u00ednio. O seu conhecimento e dedica\u00e7\u00e3o s\u00e3o indispens\u00e1veis para garantir a execu\u00e7\u00e3o bem sucedida do processo de moldagem por inje\u00e7\u00e3o e a produ\u00e7\u00e3o de componentes de pl\u00e1stico de primeira qualidade.<\/p><p class=\"translation-block\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Introdu\u00e7\u00e3o \u00e0s Etapas do Processo de Moldagem por Inje\u00e7\u00e3o A moldagem por inje\u00e7\u00e3o, frequentemente referida simplesmente como \u201cmoldagem\u201d, \u00e9 um processo de fabrica\u00e7\u00e3o fundamental utilizado para criar produtos pl\u00e1sticos. Neste m\u00e9todo, part\u00edculas de pl\u00e1stico s\u00e3o aquecidas at\u00e9 se tornarem l\u00edquidas, depois injetadas na cavidade de um molde atrav\u00e9s do bico de uma m\u00e1quina de moldagem por inje\u00e7\u00e3o. Uma vez dentro do molde, o material fundido...&nbsp;<a href=\"https:\/\/boyanmfg.com\/pt\/injection-molding-process-steps\/\" rel=\"bookmark\">Ler mais \u00bb<span class=\"screen-reader-text\">4 etapas do processo de moldagem por inje\u00e7\u00e3o de pl\u00e1stico, com anima\u00e7\u00e3o explicada<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":5741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":90,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72],"tags":[],"class_list":["post-5675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/posts\/5675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/comments?post=5675"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/posts\/5675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/media\/5741"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/media?parent=5675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/categories?post=5675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/tags?post=5675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}