{"id":3682,"date":"2023-02-24T15:00:52","date_gmt":"2023-02-24T15:00:52","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=3682"},"modified":"2024-05-27T17:16:28","modified_gmt":"2024-05-27T17:16:28","slug":"design-for-manufacturing-plastic-injection-molding","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/","title":{"rendered":"Um guia f\u00e1cil para o DFM (Design for Manufacturing) na Moldagem por Inje\u00e7\u00e3o de Pl\u00e1stico"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3682\" class=\"elementor elementor-3682\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b47bbe3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b47bbe3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2acb0c7\" data-id=\"2acb0c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2c5dcb elementor-widget elementor-widget-shortcode\" data-id=\"b2c5dcb\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle translation-block\" style=\"cursor:pointer\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar o \u00edndice\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"><\/path><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default\"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#What_is_an_Injection_Molding_DFM_Design_for_Manufacturing_Report\">O que \u00e9 um relat\u00f3rio DFM (Design for Manufacturing) de moldagem por inje\u00e7\u00e3o?<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#The_Role_of_an_Injection_Molding_DFM_Report\">O papel de um relat\u00f3rio DFM de moldagem por inje\u00e7\u00e3o<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Typical_Contents_of_a_DFM_Report\">Conte\u00fado t\u00edpico de um relat\u00f3rio DFM<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Gate_type_and_locations\">Tipo e localiza\u00e7\u00e3o dos port\u00f5es<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Ejector_pins_type_and_locations\">Tipo e localiza\u00e7\u00e3o dos pinos ejectores<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Parting_Line_Placement\">Coloca\u00e7\u00e3o da linha de separa\u00e7\u00e3o<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Placement_of_Lifters_and_Sliders\">Coloca\u00e7\u00e3o de elevadores e corredi\u00e7as<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Contact_us_today_to_start_your_custom_molding_project\">Contacte-nos hoje para iniciar o seu projeto de moldagem personalizada.<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Wall_and_rib_thicknesses_analysis\">An\u00e1lise da espessura das paredes e das nervuras<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Draft_angles_analysis\">An\u00e1lise dos \u00e2ngulos do projeto<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Possible_optimization_for_the_part_design\">Otimiza\u00e7\u00e3o poss\u00edvel para o desenho da pe\u00e7a<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Mold_Flow_Analysis_MFA\">An\u00e1lise do fluxo do molde (MFA)<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Want_reliable_quality_at_a_low_price\">Quer uma qualidade fi\u00e1vel a um pre\u00e7o baixo?<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Air_Traps\">Purgadores de ar<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Weld_lines\">Linhas de soldadura<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Sink_index\">\u00cdndice do sumidouro<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Deflection\">Deflex\u00e3o<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Mold_drawing\">Desenho do molde<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#Conclusion\">Conclus\u00e3o<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/#We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\">Somos especialistas em moldagem por inje\u00e7\u00e3o de pl\u00e1stico. Contacte-nos agora e obtenha um or\u00e7amento r\u00e1pido!<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb731d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb731d9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79e3ae9\" data-id=\"79e3ae9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ed366c elementor-widget elementor-widget-heading\" data-id=\"3ed366c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_is_an_Injection_Molding_DFM_Design_for_Manufacturing_Report\"><\/span>O que \u00e9 um relat\u00f3rio DFM (Design for Manufacturing) de moldagem por inje\u00e7\u00e3o?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0417714 elementor-widget elementor-widget-text-editor\" data-id=\"0417714\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">O relat\u00f3rio <strong>DFM (Design for Manufacturing)<\/strong> para produtos moldados por inje\u00e7\u00e3o \u00e9 uma ferramenta de avalia\u00e7\u00e3o meticulosamente concebida, especificamente para avaliar o design de produtos moldados por inje\u00e7\u00e3o. O principal objetivo deste relat\u00f3rio \u00e9 garantir que o design do produto n\u00e3o s\u00f3 \u00e9 adequado para o processo de moldagem por inje\u00e7\u00e3o, como tamb\u00e9m \u00e9 optimizado para reduzir os custos e as complexidades de fabrico.<\/p><p class=\"translation-block\">Servindo como <strong>ponte entre os clientes do projeto e os fabricantes de moldes<\/strong>, facilita eficazmente a comunica\u00e7\u00e3o ao <strong>visualizar os conceitos do design em imagens,<\/strong> melhorando assim a qualidade do produto e a efici\u00eancia da produ\u00e7\u00e3o. Em suma, um relat\u00f3rio DFM \u00e9 uma ferramenta anal\u00edtica destinada a garantir a efici\u00eancia e a viabilidade dos projectos de produtos moldados por inje\u00e7\u00e3o.<\/p><p class=\"translation-block\">Adicionalmente, para aplica\u00e7\u00f5es com requisitos mais elevados, a an\u00e1lise do fluxo do molde representa outro passo cr\u00edtico. Embora seja frequentemente considerada uma parte da an\u00e1lise DFM, nem sempre \u00e9 necess\u00e1ria. A an\u00e1lise do fluxo do molde ajuda os projectistas a compreender o comportamento dos materiais dentro do molde, optimizando tanto o design como o processo de produ\u00e7\u00e3o.<\/p><p class=\"translation-block\">Neste artigo, apresentaremos o conceito e a import\u00e2ncia do relat\u00f3rio DFM de uma forma clara e concisa, complementado com exemplos espec\u00edficos. O nosso objetivo \u00e9 demonstrar como um relat\u00f3rio DFM pode ajudar a alcan\u00e7ar a melhor correspond\u00eancia entre o design e a produ\u00e7\u00e3o, levando a uma maior efici\u00eancia, redu\u00e7\u00e3o de custos e melhor desempenho do produto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cc7b21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cc7b21\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43cdbfb\" data-id=\"43cdbfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a74bfb4 elementor-widget elementor-widget-heading\" data-id=\"a74bfb4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"The_Role_of_an_Injection_Molding_DFM_Report\"><\/span>O papel de um relat\u00f3rio DFM de moldagem por inje\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8f0439 elementor-widget elementor-widget-text-editor\" data-id=\"a8f0439\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">O relat\u00f3rio DFM (Design for Manufacturing) para produtos moldados por inje\u00e7\u00e3o desempenha um papel crucial no desenvolvimento do produto e no processo de fabrico. As suas principais fun\u00e7\u00f5es podem ser resumidas da seguinte forma:<\/p><ol><li><p class=\"translation-block\"><strong>Confirmar e otimizar o design do produto<\/strong>: O relat\u00f3rio DFM analisa a viabilidade de um design no processo de fabrico, assegurando que os designs dos produtos cumprem os requisitos de fabrico. Tamb\u00e9m explora potenciais \u00e1reas de otimiza\u00e7\u00e3o no design do produto, melhorando significativamente a qualidade e consist\u00eancia do produto final.<\/p><\/li><li><p class=\"translation-block\"><strong>Otimiza\u00e7\u00e3o dos Planos de Projeto de Moldes<\/strong>: A an\u00e1lise DFM examina diferentes op\u00e7\u00f5es de design de moldes para garantir que a melhor escolha seja feita em termos de qualidade e efici\u00eancia de custos.<\/p><\/li><li><p class=\"translation-block\"><strong>Reduzir o ciclo de desenvolvimento do produto<\/strong>: A an\u00e1lise DFM ajuda a identificar problemas de design antes da produ\u00e7\u00e3o, evitando redesenhos e retrabalhos demorados durante a fase de produ\u00e7\u00e3o, acelerando assim o tempo de coloca\u00e7\u00e3o do produto no mercado.<\/p><\/li><li><p class=\"translation-block\"><strong>Melhorar a colabora\u00e7\u00e3o entre o design e a produ\u00e7\u00e3o<\/strong>: O relat\u00f3rio DFM promove a comunica\u00e7\u00e3o e a colabora\u00e7\u00e3o entre os designers e as equipas de produ\u00e7\u00e3o, ajudando ambas as partes a compreender melhor as necessidades e os constrangimentos de cada um para obter a melhor solu\u00e7\u00e3o de design.<\/p><\/li><li><p class=\"translation-block\"><strong>Avaliando a Compet\u00eancia dos Fabricantes de Moldes<\/strong>: Nem todos os fabricantes de moldes est\u00e3o familiarizados com os potenciais problemas e riscos na fabrica\u00e7\u00e3o de produtos e moldes, e alguns podem n\u00e3o ser adeptos da cria\u00e7\u00e3o de relat\u00f3rios DFM. A qualidade dos seus relat\u00f3rios DFM pode representar diferentes n\u00edveis de especializa\u00e7\u00e3o e compet\u00eancia. Assim, serve como um bom m\u00e9todo para avaliar as capacidades dos fabricantes de moldes.<\/p><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d9de65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d9de65\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49d5075\" data-id=\"49d5075\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00e4054 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"00e4054\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a42f5d elementor-widget elementor-widget-menu-anchor\" data-id=\"6a42f5d\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"DFM\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-feec542 elementor-widget elementor-widget-heading\" data-id=\"feec542\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Typical_Contents_of_a_DFM_Report\"><\/span>Conte\u00fado t\u00edpico de um relat\u00f3rio DFM<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94f9141 elementor-widget elementor-widget-text-editor\" data-id=\"94f9141\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Um relat\u00f3rio DFM (Design for Manufacturability) padr\u00e3o para produtos moldados por inje\u00e7\u00e3o inclui normalmente os seguintes elementos:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fba5883 elementor-widget elementor-widget-text-editor\" data-id=\"fba5883\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\"><a href=\"#gate_design\">Tipo de porta e localiza\u00e7\u00f5es<\/a><br><a href=\"#ejector_design\">Tipo de pinos ejectores e localiza\u00e7\u00f5es<\/a><br><a href=\"#parting_design\">Localiza\u00e7\u00e3o da linha de parti\u00e7\u00e3o<\/a><br><a href=\"#slider_design\">Localiza\u00e7\u00e3o dos elevadores e dos cursores<\/a><br><a href=\"#thickness_analysis\">An\u00e1lise das espessuras das paredes e das nervuras<\/a><br><a href=\"#draft_analysis\">An\u00e1lise dos \u00e2ngulos de escoamento<\/a><br>Poss\u00edvel otimiza\u00e7\u00e3o da conce\u00e7\u00e3o da pe\u00e7a<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7714f52 elementor-widget elementor-widget-text-editor\" data-id=\"7714f52\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nas sec\u00e7\u00f5es seguintes, iremos desenvolver cada um destes elementos, complementados com exemplos pr\u00e1ticos para ilustrar a sua aplica\u00e7\u00e3o e import\u00e2ncia na conce\u00e7\u00e3o de produtos moldados por inje\u00e7\u00e3o. Esta abordagem proporcionar\u00e1 aos leitores uma compreens\u00e3o mais profunda do valor de um relat\u00f3rio DFM e da forma como estas an\u00e1lises podem ser utilizadas para aumentar a efici\u00eancia da conce\u00e7\u00e3o do produto e do processo de fabrico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dc1012 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dc1012\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca71551\" data-id=\"ca71551\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9b244f elementor-widget elementor-widget-menu-anchor\" data-id=\"c9b244f\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"gate_design\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a9cfae e-transform elementor-widget elementor-widget-heading\" data-id=\"4a9cfae\" data-element_type=\"widget\" data-settings='{\"_transform_skewX_effect\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"_transform_skewX_effect_tablet\":{\"unit\":\"deg\",\"size\":\"\",\"sizes\":[]},\"_transform_skewX_effect_mobile\":{\"unit\":\"deg\",\"size\":\"\",\"sizes\":[]},\"_transform_skewY_effect\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"_transform_skewY_effect_tablet\":{\"unit\":\"deg\",\"size\":\"\",\"sizes\":[]},\"_transform_skewY_effect_mobile\":{\"unit\":\"deg\",\"size\":\"\",\"sizes\":[]}}' data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Gate_type_and_locations\"><\/span>Tipo e localiza\u00e7\u00e3o dos port\u00f5es<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff57416 elementor-widget elementor-widget-text-editor\" data-id=\"ff57416\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Esta sec\u00e7\u00e3o esclarece os <a href=\"http:\/\/boyanmfg.com\/injection-mold-gate-types\/\">caminhos e locais atrav\u00e9s dos quais o material entra no molde<\/a>, desempenhando um papel fundamental na qualidade global e no efeito de moldagem dos produtos moldados por inje\u00e7\u00e3o.<\/p><p class=\"translation-block\">O design adequado do port\u00e3o \u00e9 crucial para <strong>evitar defeitos comuns <\/strong>como <strong>incha\u00e7o, linhas de solda e cicatrizes de port\u00e3o.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f9db037 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9db037\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-adca470\" data-id=\"adca470\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14837f4 elementor-widget elementor-widget-image\" data-id=\"14837f4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-gate-location.jpg\" class=\"attachment-large size-large wp-image-3734\" alt=\"conce\u00e7\u00e3o para a localiza\u00e7\u00e3o do port\u00e3o de fabrico\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-gate-location.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-gate-location-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-408118e\" data-id=\"408118e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec69847 elementor-widget elementor-widget-text-editor\" data-id=\"ec69847\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><ul><li>Neste caso, posicion\u00e1mos a porta na lateral do molde, perto de um canto, em vez de no meio. Esta coloca\u00e7\u00e3o reduz significativamente o empeno da pe\u00e7a, uma vez que as portas no centro tendem a causar empeno em ambos os lados, afectando a planicidade.<\/li><li>Al\u00e9m disso, utiliz\u00e1mos uma porta tipo banana, colocando a cicatriz da porta na superf\u00edcie inferior, tornando-a oculta durante a montagem e reduzindo a necessidade de corte manual. Esta abordagem de design tem em conta tanto o aspeto est\u00e9tico do produto como a efici\u00eancia de fabrico.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f75e7bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f75e7bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-175e8d4\" data-id=\"175e8d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0550134 elementor-widget elementor-widget-text-editor\" data-id=\"0550134\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Raz\u00f5es para a escolha do port\u00e3o de bananas<\/strong><\/p><p class=\"translation-block\">Para explicar melhor por que raz\u00e3o foi escolhida a op\u00e7\u00e3o \"banana gate\", vamos examinar uma compara\u00e7\u00e3o de tr\u00eas op\u00e7\u00f5es de conce\u00e7\u00e3o de moldagem por inje\u00e7\u00e3o ilustradas na figura seguinte:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1376a8 elementor-widget elementor-widget-image\" data-id=\"a1376a8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/injection-gate-design-options.jpg\" class=\"attachment-large size-large wp-image-3751\" alt=\"conce\u00e7\u00e3o para fabrico, op\u00e7\u00f5es de conce\u00e7\u00e3o de porta de inje\u00e7\u00e3o\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/injection-gate-design-options.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/injection-gate-design-options-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/injection-gate-design-options-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/injection-gate-design-options-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39efab1 elementor-widget elementor-widget-text-editor\" data-id=\"39efab1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><ol><li><p class=\"translation-block\"><strong>Op\u00e7\u00e3o 1 - Op\u00e7\u00e3o de Porta Direta\/Porta de Espuma<\/strong>: Este tipo de design b\u00e1sico tem uma desvantagem significativa: deixa uma grande cicatriz de porta no centro do produto, que pode at\u00e9 ser vis\u00edvel do outro lado, comumente chamada de \u201c<a href=\"http:\/\/boyanmfg.com\/common-injection-molding-defects\/#gate_blush\">blush de porta<\/a>\u201c. Devido a este problema est\u00e9tico, esta op\u00e7\u00e3o geralmente n\u00e3o \u00e9 recomendada, a menos que o produto n\u00e3o tenha requisitos de apar\u00eancia.<\/p><\/li><li><p class=\"translation-block\"><strong>Op\u00e7\u00e3o 2 - Op\u00e7\u00e3o de port\u00e3o lateral\/port\u00e3o de borda<\/strong>: Este projeto \u00e9 mais vi\u00e1vel, mas ainda tem desvantagens. Embora as cicatrizes das portas sejam mais pequenas do que as deixadas pelas portas diretas, ficam pequenas cicatrizes nas extremidades do produto. Estas podem ser vis\u00edveis ap\u00f3s a montagem, tornando esta conce\u00e7\u00e3o menos do que ideal.<\/p><\/li><li><p class=\"translation-block\"><strong>Op\u00e7\u00e3o 3 - Op\u00e7\u00e3o Banana Gate<\/strong>: Este design esconde eficazmente as cicatrizes da comporta ap\u00f3s a montagem, sendo assim a abordagem geralmente recomendada. No entanto, \u00e9 importante notar que quebrar a porta e ejetar a pe\u00e7a pode ser um pouco desafiador com uma porta banana, e tamb\u00e9m apresenta maior resist\u00eancia ao fluxo.<\/p><\/li><\/ol><p class=\"translation-block\">Dado que o jito est\u00e1 localizado no centro do molde, a <strong>op\u00e7\u00e3o 2 e a op\u00e7\u00e3o 3<\/strong> s\u00e3o geralmente<strong> mais adequadas para uma configura\u00e7\u00e3o de duas cavidades<\/strong> para evitar canais excessivamente longos. No entanto, para produtos maiores, onde uma configura\u00e7\u00e3o de cavidade \u00fanica \u00e9 preferida para economizar custos, um sistema de canal quente pode ser necess\u00e1rio para resolver o problema de canais longos devido ao port\u00e3o estar em um lado do produto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc2b87c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc2b87c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9300208\" data-id=\"9300208\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49b2556 elementor-widget elementor-widget-menu-anchor\" data-id=\"49b2556\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ejector_design\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58bb851 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58bb851\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-80fb475\" data-id=\"80fb475\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec7c26 elementor-widget elementor-widget-heading\" data-id=\"eec7c26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Ejector_pins_type_and_locations\"><\/span>Tipo e localiza\u00e7\u00e3o dos pinos ejectores<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-889fd4a elementor-widget elementor-widget-text-editor\" data-id=\"889fd4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Os pinos ejectores desempenham um papel crucial na liberta\u00e7\u00e3o suave do produto moldado do molde. A sele\u00e7\u00e3o dos seus tipos e localiza\u00e7\u00f5es precisas tem um impacto significativo na integridade e na qualidade da superf\u00edcie do produto.<\/p><ul><li style=\"list-style-type: none;\"><ol><li>Uma considera\u00e7\u00e3o fundamental durante a fase de conce\u00e7\u00e3o \u00e9 <strong>se as marcas do pino ejetor s\u00e3o aceit\u00e1veis na superf\u00edcie do produto.<\/strong><\/li><li>\u00c9 essencial garantir que o produto possa ser ejectado sem problemas do molde <strong>sem causar qualquer branqueamento esteticamente desagrad\u00e1vel das marcas dos pinos ejectores ou outras formas de danos.<\/strong><\/li><\/ol><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10e65f6 elementor-widget elementor-widget-text-editor\" data-id=\"10e65f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A configura\u00e7\u00e3o adequada dos pinos ejectores \u00e9 vital para manter a integridade e o aspeto do produto durante o processo de desmoldagem.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc6feb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc6feb0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc59aa6\" data-id=\"dc59aa6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73c0e50 elementor-widget elementor-widget-image\" data-id=\"73c0e50\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-ejector-pin-design.jpg\" class=\"attachment-large size-large wp-image-3736\" alt=\"conce\u00e7\u00e3o para fabrico conce\u00e7\u00e3o de cavilha ejectora\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-ejector-pin-design.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-ejector-pin-design-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b484d6\" data-id=\"1b484d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eeaf40 elementor-widget elementor-widget-image\" data-id=\"1eeaf40\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Ejector-pins-in-a-mold.jpg\" class=\"attachment-large size-large wp-image-3737\" alt=\"Pinos ejectores num molde\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Ejector-pins-in-a-mold.jpg 450w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Ejector-pins-in-a-mold-225x300.jpg 225w\" sizes=\"(max-width: 450px) 100vw, 450px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-789ee11 elementor-widget elementor-widget-text-editor\" data-id=\"789ee11\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><ul><li>Uma vez que as nervuras e as sali\u00eancias (qualquer carater\u00edstica com paredes verticais) criar\u00e3o resist\u00eancia \u00e0 eje\u00e7\u00e3o, os pinos de eje\u00e7\u00e3o ser\u00e3o concebidos perto destas carater\u00edsticas para equilibrar a resist\u00eancia. Isto evitar\u00e1 a distor\u00e7\u00e3o da superf\u00edcie (mantendo-os planos).<\/li><li>Quanto mais nervuras a pe\u00e7a tiver, mais pinos ejectores ter\u00e3o de ser atribu\u00eddos para equilibrar a for\u00e7a de resist\u00eancia das nervuras.<\/li><li>Os tubos ejectores (semelhantes aos pinos ejectores, mas ocos no interior) ser\u00e3o colocados nas sali\u00eancias com orif\u00edcios.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b6e433 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b6e433\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d603e34\" data-id=\"d603e34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40eb444 elementor-widget elementor-widget-menu-anchor\" data-id=\"40eb444\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"parting_design\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8913a55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8913a55\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2ed74ed\" data-id=\"2ed74ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53e1ac5 elementor-widget elementor-widget-heading\" data-id=\"53e1ac5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Parting_Line_Placement\"><\/span>Coloca\u00e7\u00e3o da linha de separa\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f85a50c elementor-widget elementor-widget-text-editor\" data-id=\"f85a50c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-wkwzg-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-wkwzg-1n7m0yu\"><div class=\"flex flex-col pb-9 text-sm\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-53\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] } group final-completion\"><div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"2e5f50d2-8182-4409-9537-33bfa288e935\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p class=\"translation-block\">A linha de separa\u00e7\u00e3o, como ponto crucial onde as metades do molde de inje\u00e7\u00e3o se encontram, afecta principalmente a apar\u00eancia do produto, particularmente atrav\u00e9s da potencial forma\u00e7\u00e3o de marcas de linha. Com o uso prolongado e o desgaste do molde, estas marcas de linha podem tornar-se mais pronunciadas. Portanto, \u00e9 aconselh\u00e1vel <strong>posicionar a linha de separa\u00e7\u00e3o <\/strong>em \u00e1reas onde ela tenha <strong>m\u00ednimo impacto na apar\u00eancia do produto.<\/strong><\/p><p class=\"translation-block\">Al\u00e9m disso, uma vez que a linha de parti\u00e7\u00e3o \u00e9 onde o molde fecha, tamb\u00e9m pode afetar a precis\u00e3o das dimens\u00f5es do produto. Os impactos espec\u00edficos na precis\u00e3o dimensional podem ser encontrados na sec\u00e7\u00e3o <a href=\"http:\/\/boyanmfg.com\/injection-molding-tolerances\/#type_A_dimensions\">dimens\u00f5es do tipo A nas diretrizes de toler\u00e2ncias de moldagem por inje\u00e7\u00e3o.<\/a><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc18af9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc18af9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63c11fa\" data-id=\"63c11fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b2ea93 elementor-widget elementor-widget-text-editor\" data-id=\"3b2ea93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Exemplo 1<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b27c45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b27c45\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea57486\" data-id=\"ea57486\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd47808 elementor-widget elementor-widget-image\" data-id=\"dd47808\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/flat-parting-line-for-plastic-part.jpg\" class=\"attachment-large size-large wp-image-3701\" alt=\"linha de corte plano para pe\u00e7as de pl\u00e1stico\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/flat-parting-line-for-plastic-part.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/flat-parting-line-for-plastic-part-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/flat-parting-line-for-plastic-part-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/flat-parting-line-for-plastic-part-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-741ae04\" data-id=\"741ae04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e7d3be elementor-widget elementor-widget-text-editor\" data-id=\"3e7d3be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">Para pe\u00e7as como este painel, a escolha da localiza\u00e7\u00e3o da linha de separa\u00e7\u00e3o \u00e9 relativamente simples e direta. Optar por uma posi\u00e7\u00e3o numa superf\u00edcie plana escalonada ajuda a evitar a cria\u00e7\u00e3o de marcas de linha e \u00e9 tamb\u00e9m menos suscet\u00edvel ao desgaste do molde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d76fc4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d76fc4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d74c9b\" data-id=\"5d74c9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b22016 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b22016\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3516a9c\" data-id=\"3516a9c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-720d230 elementor-widget elementor-widget-text-editor\" data-id=\"720d230\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Exemplo 2<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-250bc2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"250bc2e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31f5dce\" data-id=\"31f5dce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9740f83 elementor-widget elementor-widget-image\" data-id=\"9740f83\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/parting-line-for-plastic-tube.jpg\" class=\"attachment-large size-large wp-image-3700\" alt=\"linha de corte para tubo de pl\u00e1stico\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/parting-line-for-plastic-tube.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/parting-line-for-plastic-tube-600x450.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/parting-line-for-plastic-tube-300x225.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/parting-line-for-plastic-tube-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8035e21\" data-id=\"8035e21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6d9ae7 elementor-widget elementor-widget-text-editor\" data-id=\"b6d9ae7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">Para este componente, o desenho da linha de separa\u00e7\u00e3o \u00e9 algo complexo. Normalmente, para pe\u00e7as de pl\u00e1stico em forma de tubo, a abordagem padr\u00e3o (Op\u00e7\u00e3o 1) coloca a linha de separa\u00e7\u00e3o numa superf\u00edcie da extremidade. No entanto, dado o comprimento desta pe\u00e7a (que requer um molde muito alto) e a necessidade de manter um \u00e2ngulo de inclina\u00e7\u00e3o m\u00ednimo ou nulo no di\u00e2metro exterior (uma vez que um \u00e2ngulo de inclina\u00e7\u00e3o alteraria visivelmente o tamanho de uma extremidade), posicion\u00e1-la horizontalmente no molde torna-se uma op\u00e7\u00e3o mais adequada, favorecendo assim a Op\u00e7\u00e3o 2.<\/p><p class=\"translation-block\">Para evitar que o tubo se torne oval ou se dobre, foi projetado um <a href=\"http:\/\/boyanmfg.com\/injection-mold-gate-types\/#Spoke_Gate\">spoke gate<\/a> na superf\u00edcie da extremidade. Uma desvantagem da Op\u00e7\u00e3o 2 \u00e9 o corredor estendido, que leva ao desperd\u00edcio de material e ao potencial de projec\u00e7\u00f5es a frio. Para mitigar este problema, a ado\u00e7\u00e3o de um design de canal quente pode ser uma solu\u00e7\u00e3o ben\u00e9fica, contrabalan\u00e7ando os problemas associados ao canal mais longo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2bb1fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2bb1fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba74cc5\" data-id=\"ba74cc5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27734c8 elementor-widget elementor-widget-menu-anchor\" data-id=\"27734c8\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"slider_design\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7822ef3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7822ef3\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-129142a\" data-id=\"129142a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e48514 elementor-widget elementor-widget-heading\" data-id=\"7e48514\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Placement_of_Lifters_and_Sliders\"><\/span>Coloca\u00e7\u00e3o de elevadores e corredi\u00e7as<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d3894a elementor-widget elementor-widget-text-editor\" data-id=\"8d3894a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-wkwzg-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-wkwzg-1n7m0yu\"><div class=\"flex flex-col pb-9 text-sm\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-63\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] } group final-completion\"><div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"d372af2e-5e90-4178-97a3-5f622d38ac3a\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p class=\"translation-block\">No caso de pe\u00e7as pl\u00e1sticas com rebaixos, a utiliza\u00e7\u00e3o de mecanismos de deslizamento lateral, tais como elevadores e deslizadores, \u00e9 essencial. O seu posicionamento deve ser especificamente destacado no relat\u00f3rio DFM.<\/p><p class=\"translation-block\">Tal como a linha de separa\u00e7\u00e3o, os elevadores e os cursores, enquanto componentes m\u00f3veis, podem criar marcas de linhas no produto. \u00c9 crucial garantir que a sua coloca\u00e7\u00e3o \u00e9 aceit\u00e1vel em termos de apar\u00eancia e funcionalidade do produto.<\/p><p class=\"translation-block\">Al\u00e9m disso, estes componentes podem tamb\u00e9m afetar a precis\u00e3o dimensional das pe\u00e7as, um impacto semelhante ao da linha de corte.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-157ee35 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"157ee35\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78879e0\" data-id=\"78879e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1304202 elementor-widget elementor-widget-image\" data-id=\"1304202\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-location-of-sliders.jpg\" class=\"attachment-large size-large wp-image-3718\" alt=\"Localiza\u00e7\u00e3o DFM dos cursores do molde de inje\u00e7\u00e3o\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-location-of-sliders.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-location-of-sliders-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-location-of-sliders-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-location-of-sliders-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f0ce4f\" data-id=\"4f0ce4f\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-059b8dc elementor-widget elementor-widget-image\" data-id=\"059b8dc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"380\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/plastic-mold-helical-gear.png\" class=\"attachment-full size-full wp-image-1959\" alt=\"molde de pl\u00e1stico para uma engrenagem helicoidal\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/plastic-mold-helical-gear.png 380w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/plastic-mold-helical-gear-300x300.png 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/plastic-mold-helical-gear-100x100.png 100w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/plastic-mold-helical-gear-150x150.png 150w\" sizes=\"(max-width: 380px) 100vw, 380px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89cc96a elementor-widget elementor-widget-heading\" data-id=\"89cc96a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Contact_us_today_to_start_your_custom_molding_project\"><\/span>Contacte-nos hoje para iniciar o seu projeto de moldagem personalizada.<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-756d6c9 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"756d6c9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pedir um or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a04baa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a04baa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-555e8c7\" data-id=\"555e8c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c8c7e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c8c7e6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-05b3fc9\" data-id=\"05b3fc9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f5db0f elementor-widget elementor-widget-text-editor\" data-id=\"5f5db0f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">A partir do exemplo da imagem acima, \u00e9 evidente onde aparecer\u00e3o as marcas de linha criadas pelo controlo deslizante. No entanto, estas marcas de linha podem ser muito subtis e quase impercept\u00edveis.<\/p><p class=\"translation-block\">No entanto, se o produto for produzido em grandes quantidades, o desgaste do molde ir\u00e1 gradualmente tornar estas marcas mais pronunciadas. Por conseguinte, esta quest\u00e3o deve ser tida em considera\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e2abe9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e2abe9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4777b7f\" data-id=\"4777b7f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39c8b1b elementor-widget elementor-widget-menu-anchor\" data-id=\"39c8b1b\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"thickness_analysis\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e3eda9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e3eda9\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ffc285b\" data-id=\"ffc285b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c51440 elementor-widget elementor-widget-heading\" data-id=\"7c51440\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Wall_and_rib_thicknesses_analysis\"><\/span>An\u00e1lise da espessura das paredes e das nervuras<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d151d55 elementor-widget elementor-widget-text-editor\" data-id=\"d151d55\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">As espessuras das paredes e das nervuras t\u00eam um impacto significativo nos produtos moldados por inje\u00e7\u00e3o:<\/p><ul><li>Espessuras de parede desiguais ou inadequadas podem levar a problemas como deforma\u00e7\u00e3o, contra\u00e7\u00e3o desigual ou concentra\u00e7\u00e3o de tens\u00f5es durante o processo de fabrico.<\/li><li>Uma espessura de parede adequada \u00e9 crucial para assegurar a resist\u00eancia estrutural do produto, garantindo simultaneamente um fluxo de material uniforme e o arrefecimento dentro do molde, evitando assim defeitos.<\/li><li>A conce\u00e7\u00e3o da espessura das nervuras deve estar em harmonia com a espessura da parede prim\u00e1ria para manter a resist\u00eancia e a estabilidade globais do produto, bem como para otimizar a utiliza\u00e7\u00e3o do material e a efici\u00eancia da produ\u00e7\u00e3o.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ef1104c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef1104c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a686ef\" data-id=\"7a686ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff0d79f elementor-widget elementor-widget-image\" data-id=\"ff0d79f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-wall-thickness-analysis.jpg\" class=\"attachment-large size-large wp-image-3715\" alt=\"An\u00e1lise da espessura da parede DFM\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-wall-thickness-analysis.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-wall-thickness-analysis-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-wall-thickness-analysis-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-wall-thickness-analysis-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-912a969\" data-id=\"912a969\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abc655a elementor-widget elementor-widget-text-editor\" data-id=\"abc655a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">Como mostrado neste exemplo, uma vez que as nervuras est\u00e3o localizadas numa superf\u00edcie inclinada, resulta inevitavelmente em algumas \u00e1reas com paredes mais espessas do que outras. Esta espessura desigual tende a levar \u00e0 forma\u00e7\u00e3o de marcas de afundamento nestas \u00e1reas.<\/p><p class=\"translation-block\">Embora seja poss\u00edvel compensar este facto durante a produ\u00e7\u00e3o, aumentando a press\u00e3o de inje\u00e7\u00e3o e o tempo de reten\u00e7\u00e3o, mant\u00e9m-se um certo grau de marcas de afundamento, tal como foi confirmado em s\u00e9ries de produ\u00e7\u00e3o subsequentes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d88add elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d88add\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c591fe4\" data-id=\"c591fe4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2042782 elementor-widget elementor-widget-menu-anchor\" data-id=\"2042782\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"draft_analysis\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-459da27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"459da27\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1270668\" data-id=\"1270668\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-925e25f elementor-widget elementor-widget-heading\" data-id=\"925e25f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Draft_angles_analysis\"><\/span>An\u00e1lise dos \u00e2ngulos do projeto<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eafbc36 elementor-widget elementor-widget-text-editor\" data-id=\"eafbc36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">O \u00e2ngulo de inclina\u00e7\u00e3o \u00e9 um aspeto cr\u00edtico da conce\u00e7\u00e3o de produtos moldados por inje\u00e7\u00e3o, afectando principalmente o processo de desmoldagem. Um \u00e2ngulo de inclina\u00e7\u00e3o adequado assegura que o produto pode ser suave e completamente libertado do molde ap\u00f3s a produ\u00e7\u00e3o, minimizando os danos ou a deforma\u00e7\u00e3o da superf\u00edcie.<\/p><p class=\"translation-block\">Se o \u00e2ngulo de inclina\u00e7\u00e3o n\u00e3o for definido corretamente, o produto pode ficar colado ao molde durante a eje\u00e7\u00e3o, aumentando as dificuldades de produ\u00e7\u00e3o e o risco de danos. Por conseguinte, a conce\u00e7\u00e3o do \u00e2ngulo de inclina\u00e7\u00e3o correto \u00e9 vital para garantir a qualidade do produto e aumentar a efici\u00eancia da produ\u00e7\u00e3o.<\/p><p class=\"translation-block\">A maioria dos softwares de projeto modernos inclui funcionalidades de an\u00e1lise do \u00e2ngulo de inclina\u00e7\u00e3o, que podem apresentar os \u00e2ngulos de inclina\u00e7\u00e3o de v\u00e1rias \u00e1reas utilizando cores e n\u00fameros para facilitar a visualiza\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1afdf2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1afdf2d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-583eb3f\" data-id=\"583eb3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e9d645 elementor-widget elementor-widget-image\" data-id=\"7e9d645\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-draft-angle-analysis.jpg\" class=\"attachment-large size-large wp-image-3725\" alt=\"conce\u00e7\u00e3o para fabrico an\u00e1lise do \u00e2ngulo de inclina\u00e7\u00e3o\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-draft-angle-analysis.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/DFM-draft-angle-analysis-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a8b656\" data-id=\"7a8b656\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e14430d elementor-widget elementor-widget-text-editor\" data-id=\"e14430d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">A partir do exemplo apresentado na imagem, \u00e9 evidente que se a sec\u00e7\u00e3o verde (a parte sem um \u00e2ngulo de inclina\u00e7\u00e3o) tiver uma determinada altura, \u00e9 essencial adicionar-lhe um \u00e2ngulo de inclina\u00e7\u00e3o. No entanto, se a altura da sec\u00e7\u00e3o verde for muito baixa, pode ser ignorada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9354be9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9354be9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0214ae\" data-id=\"d0214ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-170129e elementor-widget elementor-widget-heading\" data-id=\"170129e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Possible_optimization_for_the_part_design\"><\/span>Otimiza\u00e7\u00e3o poss\u00edvel para o desenho da pe\u00e7a<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cf0d2c elementor-widget elementor-widget-text-editor\" data-id=\"8cf0d2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Na conclus\u00e3o do relat\u00f3rio DFM, com base na an\u00e1lise anterior, s\u00e3o apresentadas sugest\u00f5es de melhoria espec\u00edficas para o design do produto, particularmente no que diz respeito a ajustes na espessura da parede e nos \u00e2ngulos de inclina\u00e7\u00e3o.<\/p><p class=\"translation-block\">Al\u00e9m disso, os utilizadores do produto devem avaliar a viabilidade do design da porta, a disposi\u00e7\u00e3o dos pinos ejectores e as defini\u00e7\u00f5es da linha de separa\u00e7\u00e3o com base nas propostas de design do molde mencionadas no relat\u00f3rio. Este processo tem como objetivo garantir que o design global cumpre os requisitos de produ\u00e7\u00e3o e as normas de qualidade, facilitando um fluxo de trabalho de produ\u00e7\u00e3o eficaz e eficiente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d60c08 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1d60c08\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b3f0ce elementor-widget elementor-widget-menu-anchor\" data-id=\"8b3f0ce\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"MFA\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-094e51d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"094e51d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fa4f55\" data-id=\"5fa4f55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16964ab elementor-widget elementor-widget-heading\" data-id=\"16964ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Mold_Flow_Analysis_MFA\"><\/span>An\u00e1lise do fluxo do molde (MFA)<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a17781 elementor-widget elementor-widget-text-editor\" data-id=\"8a17781\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A an\u00e1lise do fluxo do molde \u00e9 uma ferramenta essencial para simular e otimizar o processo de moldagem por inje\u00e7\u00e3o de pl\u00e1stico. Ao modelar o fluxo, o arrefecimento e a solidifica\u00e7\u00e3o do pl\u00e1stico dentro do molde, ajuda a identificar potenciais problemas de produ\u00e7\u00e3o, tais como armadilhas de g\u00e1s, deforma\u00e7\u00f5es, concentra\u00e7\u00e3o de tens\u00f5es ou enchimento insuficiente.<\/p><p class=\"translation-block\">Esta an\u00e1lise permite a otimiza\u00e7\u00e3o da conce\u00e7\u00e3o do molde e dos par\u00e2metros de inje\u00e7\u00e3o antes da produ\u00e7\u00e3o real, garantindo a qualidade do produto e aumentando a efici\u00eancia da produ\u00e7\u00e3o. A an\u00e1lise do fluxo do molde \u00e9 importante para reduzir o n\u00famero de ensaios, encurtar os ciclos de desenvolvimento do produto e diminuir os custos de produ\u00e7\u00e3o.<\/p><p class=\"translation-block\">No entanto, a an\u00e1lise do fluxo do molde tamb\u00e9m envolve custos adicionais. Ela n\u00e3o \u00e9 necess\u00e1ria para todos os produtos, especialmente aqueles com estruturas mais simples. A decis\u00e3o de realizar a an\u00e1lise do fluxo do molde deve ser baseada em circunst\u00e2ncias espec\u00edficas, considerando a complexidade do produto, a escala de produ\u00e7\u00e3o e a rela\u00e7\u00e3o custo-efic\u00e1cia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7bfa791 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bfa791\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b60e2ba\" data-id=\"b60e2ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-966ec26 elementor-widget elementor-widget-image\" data-id=\"966ec26\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Mold-filling-simulation-animation.gif\" class=\"attachment-large size-large wp-image-3846\" alt=\"Anima\u00e7\u00e3o de simula\u00e7\u00e3o de enchimento de moldes\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-292f4a1 elementor-widget elementor-widget-menu-anchor\" data-id=\"292f4a1\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"MFA_subjects\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffa4ff0 elementor-widget elementor-widget-text-editor\" data-id=\"ffa4ff0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-mvgrc-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-mvgrc-1n7m0yu\"><div class=\"flex flex-col pb-9 text-sm\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-81\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] } group final-completion\"><div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"e48836c3-22fb-4975-9b52-44263a8161f8\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p class=\"translation-block\">Geralmente, um relat\u00f3rio de an\u00e1lise de fluxo de molde inclui os seguintes conte\u00fados\uff1a<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-092320d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"092320d\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\",\"shape_divider_top\":\"curve\"}'>\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n    <path class=\"elementor-shape-fill\" d=\"M1000,4.3V0H0v4.3C0.9,23.1,126.7,99.2,500,100S1000,22.7,1000,4.3z\"><\/path>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a3c8ce\" data-id=\"6a3c8ce\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ff3983 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ff3983\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8f86d3d\" data-id=\"8f86d3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a54853 elementor-widget elementor-widget-image\" data-id=\"5a54853\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-animation-corner-connector.gif\" class=\"attachment-large size-large wp-image-4000\" alt=\"anima\u00e7\u00e3o do fluxo do molde conetor de canto\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a599811\" data-id=\"a599811\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46e3128 elementor-widget elementor-widget-image-carousel\" data-id=\"46e3128\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"1\",\"navigation\":\"none\",\"effect\":\"fade\",\"speed\":1000,\"_animation\":\"none\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\"}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-1.png\" alt=\"conetor de canto de pl\u00e1stico 1\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-2.png\" alt=\"conetor de canto de pl\u00e1stico 2\"><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-33980dc\" data-id=\"33980dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a507625 elementor-widget elementor-widget-heading\" data-id=\"a507625\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Want_reliable_quality_at_a_low_price\"><\/span> Quer uma qualidade fi\u00e1vel a um pre\u00e7o baixo?<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f41277e elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"f41277e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pedir um or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e8e9d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e8e9d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-240144c\" data-id=\"240144c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec4f3a3 elementor-widget elementor-widget-spacer\" data-id=\"ec4f3a3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b729cb elementor-widget elementor-widget-text-editor\" data-id=\"7b729cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Em seguida, explicaremos o conte\u00fado do relat\u00f3rio relacionado com os potenciais defeitos de moldagem por inje\u00e7\u00e3o que podem ocorrer nas pe\u00e7as.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f2e315d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2e315d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-01b0b76\" data-id=\"01b0b76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f04628 elementor-widget elementor-widget-text-editor\" data-id=\"6f04628\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\">Informa\u00e7\u00f5es gerais sobre a pe\u00e7a (o peso e o tamanho da pe\u00e7a, o material a ser usado com um grau espec\u00edfico).<br>Processamento recomendado (par\u00e2metros de moldagem, como press\u00e3o, temperatura, etc.)<br>Tempo de enchimento (isso incluir\u00e1 uma anima\u00e7\u00e3o do processo de enchimento).<br>Contorno de enchimento (parece um mapa de contorno geogr\u00e1fico).<br>Press\u00e3o na comuta\u00e7\u00e3o V\/P (ou seja, mudar do controlo de volume para o controlo de press\u00e3o).<br>Press\u00e3o no final do enchimento.<br>Temperatura da frente de fluxo.<br>Temperatura do volume no final do enchimento.<br>For\u00e7a de aperto (isto ir\u00e1 sugerir a tonelagem da m\u00e1quina de inje\u00e7\u00e3o a ser utilizada).<br><a href=\"#air_trap\"><strong>Air Traps<\/strong> (Tend\u00eancia de bolhas de ar)<\/a>.<br><strong><a href=\"#weld_lines\">Weld Lines<\/a>.<\/strong><br>Retra\u00e7\u00e3o volum\u00e9trica na eje\u00e7\u00e3o.<br><a href=\"#Sink_index\"><strong>Sink index<\/strong> (a tend\u00eancia de marcas de afundamento)<\/a>.<br>Temperatura da pe\u00e7a no final do resfriamento.<br><a href=\"#deflection\"><strong>Deflection<\/strong> (a tend\u00eancia de empenamento, dobra e distor\u00e7\u00e3o)<\/a>.<br>Conclus\u00f5es e sugest\u00f5es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-414be18 elementor-widget elementor-widget-menu-anchor\" data-id=\"414be18\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"air_trap\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72ce615 elementor-widget elementor-widget-heading\" data-id=\"72ce615\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Air_Traps\"><\/span>Purgadores de ar<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d7b76c elementor-widget elementor-widget-text-editor\" data-id=\"0d7b76c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A armadilha de ar refere-se a \u00e1reas dentro do molde onde o ar fica preso durante o processo de moldagem por inje\u00e7\u00e3o. Este aprisionamento pode levar a defeitos no produto final, tais como vazios ou enchimento incompleto, uma vez que o ar aprisionado impede que o material pl\u00e1stico ocupe efetivamente toda a cavidade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3abe9cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3abe9cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0edb0fc\" data-id=\"0edb0fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b63cd5 elementor-widget elementor-widget-text-editor\" data-id=\"1b63cd5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">Neste exemplo, podemos ver que esta pe\u00e7a tem uma baixa tend\u00eancia para a forma\u00e7\u00e3o de bolhas de ar, o que significa que deve ser boa para a produ\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9b39212\" data-id=\"9b39212\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-333b576 elementor-widget elementor-widget-image\" data-id=\"333b576\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-air-traps.jpg\" class=\"attachment-large size-large wp-image-3792\" alt=\"an\u00e1lise do fluxo do molde, purgadores de ar\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-air-traps.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-air-traps-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-air-traps-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-air-traps-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f84b840 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f84b840\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2efa4f\" data-id=\"f2efa4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba64a5d elementor-widget elementor-widget-menu-anchor\" data-id=\"ba64a5d\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"weld_lines\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-28133a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28133a0\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7bf9a28\" data-id=\"7bf9a28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf46901 elementor-widget elementor-widget-heading\" data-id=\"cf46901\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Weld_lines\"><\/span>Linhas de soldadura<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6788e7d elementor-widget elementor-widget-text-editor\" data-id=\"6788e7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A Linha de Solda indica os locais potenciais na pe\u00e7a moldada onde duas ou mais frentes de fluxo de pl\u00e1stico fundido podem convergir. <a href=\"https:\/\/www.youtube.com\/watch?v=3dmfwZUKAgg\" target=\"_blank\" rel=\"noopener\">Esta converg\u00eancia pode criar uma linha ou costura<\/a>, conhecida como linha de soldadura, que pode ser mais fraca e menos agrad\u00e1vel esteticamente do que o material circundante, afectando potencialmente a integridade estrutural e o aspeto da pe\u00e7a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4824a90 elementor-widget elementor-widget-image\" data-id=\"4824a90\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-weld-lines.jpg\" class=\"attachment-large size-large wp-image-3791\" alt=\"an\u00e1lise do fluxo do molde, linhas de soldadura\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-weld-lines.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-weld-lines-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-weld-lines-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-weld-lines-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-144ab51 elementor-widget elementor-widget-text-editor\" data-id=\"144ab51\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">Esta pe\u00e7a tem uma tend\u00eancia moderada para formar linhas de soldadura. Se a cor e o brilho do material n\u00e3o forem escolhidos corretamente, aparecer\u00e3o linhas de fus\u00e3o vis\u00edveis na superf\u00edcie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f10ad9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f10ad9d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-209bf1d\" data-id=\"209bf1d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-214f45e elementor-widget elementor-widget-menu-anchor\" data-id=\"214f45e\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Sink_index\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e10f47e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e10f47e\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0c13135\" data-id=\"0c13135\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83d2d45 elementor-widget elementor-widget-heading\" data-id=\"83d2d45\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Sink_index\"><\/span>\u00cdndice do sumidouro<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99d2d4c elementor-widget elementor-widget-text-editor\" data-id=\"99d2d4c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">O \u00cdndice de Afundamento no relat\u00f3rio quantifica a probabilidade de forma\u00e7\u00e3o de marcas de afundamento numa pe\u00e7a moldada. Estas marcas ocorrem tipicamente em \u00e1reas mais espessas onde o material encolhe \u00e0 medida que arrefece, conduzindo a depress\u00f5es ou reentr\u00e2ncias na superf\u00edcie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cb1c139 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb1c139\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b77464f\" data-id=\"b77464f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c68fe2f elementor-widget elementor-widget-image\" data-id=\"c68fe2f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-sink-marks.jpg\" class=\"attachment-large size-large wp-image-3793\" alt=\"an\u00e1lise do fluxo do molde, marcas de afundamento\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-sink-marks.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-sink-marks-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-sink-marks-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-flow-analysis-sink-marks-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6263045\" data-id=\"6263045\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8f9647 elementor-widget elementor-widget-text-editor\" data-id=\"f8f9647\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\"><span style=\"color: #374151;font-family: S\u00f6hne, ui-sans-serif, system-ui, -apple-system, 'Segoe UI', Roboto, Ubuntu, Cantarell, 'Noto Sans', sans-serif, 'Helvetica Neue', Arial, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji'\">Com base no exemplo representado na imagem, a quantidade de afundamento prevista \u00e9 \u22640.0218mm. Isto indica que as espessuras da parede e das nervuras est\u00e3o bem concebidas e que as marcas de afundamento est\u00e3o dentro de um intervalo aceit\u00e1vel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7605c3 elementor-widget elementor-widget-text-editor\" data-id=\"b7605c3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Al\u00e9m disso, para um aspeto visualmente apelativo, eis as quantidades de lava-loi\u00e7a aconselhadas para v\u00e1rios tipos de acabamentos de superf\u00edcie:<\/p><ul><li>Para uma superf\u00edcie texturada: \u22640,10 mm<\/li><li>Para uma superf\u00edcie pintada: \u22640,05 mm<\/li><li>Para uma superf\u00edcie revestida: \u22640,03 mm<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b2bda2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b2bda2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7e5aef\" data-id=\"b7e5aef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eff6ddc elementor-widget elementor-widget-menu-anchor\" data-id=\"eff6ddc\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"deflection\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0a0b721 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a0b721\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-62dc273\" data-id=\"62dc273\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdf52f6 elementor-widget elementor-widget-heading\" data-id=\"bdf52f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Deflection\"><\/span>Deflex\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0075c99 elementor-widget elementor-widget-text-editor\" data-id=\"0075c99\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A Deflex\u00e3o refere-se \u00e0 probabilidade de uma pe\u00e7a moldada se deformar ou dobrar. Prev\u00ea o grau em que uma pe\u00e7a se pode deformar, normalmente devido a um arrefecimento desigual, \u00e0 contra\u00e7\u00e3o do material ou a tens\u00f5es internas durante o processo de moldagem<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f4bddb elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"5f4bddb\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"1\",\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"effect\":\"slide\",\"speed\":500}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Mold-flow-analysis-overall-deflections.jpg\" alt=\"deflex\u00f5es globais, an\u00e1lise do fluxo de moldes\"><figcaption class=\"elementor-image-carousel-caption\">Deforma\u00e7\u00e3o global<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Mold-flow-analysis-deflection-in-Y-direction.jpg\" alt=\"deflex\u00e3o na dire\u00e7\u00e3o Y, an\u00e1lise do fluxo do molde\"><figcaption class=\"elementor-image-carousel-caption\">Deflex\u00e3o ao longo da dire\u00e7\u00e3o X<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Mold-flow-analysis-deflection-in-X-direction.jpg\" alt=\"deflex\u00e3o na dire\u00e7\u00e3o X, an\u00e1lise do fluxo do molde\"><figcaption class=\"elementor-image-carousel-caption\">Deflex\u00e3o ao longo da dire\u00e7\u00e3o Y<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/Mold-flow-analysis-deflection-in-Z-direction.jpg\" alt=\"deflex\u00e3o na dire\u00e7\u00e3o Z, an\u00e1lise do fluxo do molde\"><figcaption class=\"elementor-image-carousel-caption\">Deflex\u00e3o ao longo da dire\u00e7\u00e3o Z<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a1c066 elementor-widget elementor-widget-text-editor\" data-id=\"8a1c066\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nota:<\/p><p class=\"translation-block\">Neste exemplo, o foco deve ser a deflex\u00e3o na dire\u00e7\u00e3o Z, que se refere \u00e0 deforma\u00e7\u00e3o por empeno da pe\u00e7a. No entanto, com base na experi\u00eancia, este empeno do painel pode ser minimizado aumentando a press\u00e3o e o tempo de embalamento, um facto que foi confirmado em execu\u00e7\u00f5es de produ\u00e7\u00e3o subsequentes.<\/p><p class=\"translation-block\">\u00c9 importante notar que muitas ferramentas de software de an\u00e1lise do fluxo do molde nem sempre s\u00e3o exactas na previs\u00e3o da extens\u00e3o da deforma\u00e7\u00e3o da pe\u00e7a. Confiar na experi\u00eancia continua a ser crucial para uma an\u00e1lise eficaz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a0d658 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0a0d658\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c33b9f4 elementor-widget elementor-widget-menu-anchor\" data-id=\"c33b9f4\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"mold_drawing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45a95ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45a95ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f52f05b\" data-id=\"f52f05b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3793084 elementor-widget elementor-widget-heading\" data-id=\"3793084\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Mold_drawing\"><\/span>Desenho do molde<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cb7c566 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb7c566\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1bff8ab\" data-id=\"1bff8ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5be9b3d elementor-widget elementor-widget-text-editor\" data-id=\"5be9b3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-mvgrc-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-mvgrc-1n7m0yu\"><div class=\"flex flex-col pb-9 text-sm\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-105\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] } group final-completion\"><div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"08e3d6e4-f090-4f26-aecb-978065dc2818\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p class=\"translation-block\">Note-se que o objetivo do DFM n\u00e3o \u00e9 aprofundar os pormenores intrincados do molde, mas apresentar sucintamente as informa\u00e7\u00f5es mais importantes. Esta abordagem ajuda-o a concentrar-se nos aspectos principais, poupando tempo na prepara\u00e7\u00e3o do relat\u00f3rio.<\/p><p class=\"translation-block\">Para uma vis\u00e3o global do molde, \u00e9 aconselh\u00e1vel solicitar o desenho do molde.<\/p><p class=\"translation-block\">O desenho do molde \u00e9 especialmente valioso para quaisquer necessidades futuras de repara\u00e7\u00e3o. Cont\u00e9m todos os dados dimensionais necess\u00e1rios para a maquina\u00e7\u00e3o CNC dos componentes do molde.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0a2f944\" data-id=\"0a2f944\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d93ff5 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"7d93ff5\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"1\",\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"effect\":\"slide\",\"speed\":500}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-drawing-example-1.jpg\" alt=\"exemplo de desenho de molde 1\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-drawing-example-2.jpg\" alt=\"exemplo de desenho de molde 2\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-drawing-example-3.jpg\" alt=\"exemplo de desenho de molde 3\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/mold-drawing-example-4.jpg\" alt=\"exemplo de desenho de molde 4\"><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db19efb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db19efb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd33499\" data-id=\"dd33499\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e77f271 elementor-widget elementor-widget-heading\" data-id=\"e77f271\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclus\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-190f742 elementor-widget elementor-widget-text-editor\" data-id=\"190f742\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Em conclus\u00e3o, atrav\u00e9s das etapas de an\u00e1lise acima descritas, os riscos potenciais podem ser amplamente antecipados, permitindo a identifica\u00e7\u00e3o e a melhoria dos problemas existentes. Este processo tamb\u00e9m permite o estabelecimento de um plano de conce\u00e7\u00e3o b\u00e1sico antes da produ\u00e7\u00e3o, tornando o trabalho subsequente mais organizado e sistem\u00e1tico.<\/p><p class=\"translation-block\">No entanto, \u00e9 importante notar que a an\u00e1lise do software de desenho 3D n\u00e3o \u00e9 totalmente exacta, mas oferece um valor de refer\u00eancia significativo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e938478 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e938478\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b95edb\" data-id=\"2b95edb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0b753a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0b753a\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c79b95c\" data-id=\"c79b95c\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f8460d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f8460d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f58b825\" data-id=\"f58b825\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23160d9 elementor-widget elementor-widget-image\" data-id=\"23160d9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png\" class=\"attachment-large size-large wp-image-6453\" alt=\"Caixa triangular sobremoldada em TPU\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1ae3479\" data-id=\"1ae3479\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a363a8 elementor-widget elementor-widget-heading\" data-id=\"7a363a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Somos especialistas em moldagem por inje\u00e7\u00e3o de pl\u00e1stico. Contacte-nos agora e obtenha um or\u00e7amento r\u00e1pido!<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a4549f8\" data-id=\"a4549f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-baa662c elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"baa662c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pedir um or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 um Relat\u00f3rio DFM (Design for Manufacturing) para Moldagem por Inje\u00e7\u00e3o? O relat\u00f3rio DFM (Design for Manufacturing) para produtos moldados por inje\u00e7\u00e3o \u00e9 uma ferramenta de avalia\u00e7\u00e3o meticulosamente concebida, especificamente para avaliar o design de produtos moldados por inje\u00e7\u00e3o. O objetivo principal deste relat\u00f3rio \u00e9 garantir que o design do produto n\u00e3o seja apenas adequado para a inje\u00e7\u00e3o\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/pt\/design-for-manufacturing-plastic-injection-molding\/\" rel=\"bookmark\">Ler mais \u00bb<span class=\"screen-reader-text\">Um guia f\u00e1cil para o DFM (Design for Manufacturing) na Moldagem por Inje\u00e7\u00e3o de Pl\u00e1stico<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":3834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72],"tags":[],"class_list":["post-3682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/posts\/3682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/comments?post=3682"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/posts\/3682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/media\/3834"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/media?parent=3682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/categories?post=3682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/pt\/wp-json\/wp\/v2\/tags?post=3682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}