{"id":7039,"date":"2023-12-18T09:13:44","date_gmt":"2023-12-18T09:13:44","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=7039"},"modified":"2024-05-27T17:11:11","modified_gmt":"2024-05-27T17:11:11","slug":"family-molds-in-injection-molding","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/","title":{"rendered":"Il vantaggio degli stampi familiari nello stampaggio a iniezione: Un caso di studio sulla cavit\u00e0 4\u00d74"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"7039\" class=\"elementor elementor-7039\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e19ed79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e19ed79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d138e18\" data-id=\"d138e18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53551e9 elementor-widget elementor-widget-shortcode\" data-id=\"53551e9\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle translation-block\" style=\"cursor:pointer\">Indice dei contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Allinea la tabella dei contenuti\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"><\/path><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default\"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#Understanding_Family_Molds_in_Injection_Molding\">Comprensione degli stampi familiari nello stampaggio a iniezione<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#Advantages_of_Using_Family_Molds_in_Injection_Molding\">Vantaggi dell'utilizzo di stampi familiari nello stampaggio a iniezione<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#Limitations_and_Conditions_for_Using_Family_Molds\">Limitazioni e condizioni di utilizzo delle muffe familiari<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#The_Need_for_Similarity_in_Products_within_Family_Molds\">Necessit\u00e0 di somiglianza dei prodotti all'interno degli stampi familiari<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#Additional_Limitations_in_Using_Family_Molds\">Ulteriori limitazioni nell'uso delle muffe familiari<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#Easing_Family_Mold_Constraints_During_Prototyping\">Ridurre i vincoli dello stampo famigliare durante la prototipazione<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#An_Example_of_a_4%C3%974_Family_Mold\">Un esempio di stampo familiare 4\u00d74<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#Conclusion\">Conclusione<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/#We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\">Siamo esperti nello stampaggio a iniezione di materie plastiche. Contattateci subito per ottenere un rapido preventivo!<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec30b8d elementor-widget elementor-widget-heading\" data-id=\"ec30b8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Understanding_Family_Molds_in_Injection_Molding\"><\/span>Comprensione degli stampi familiari nello stampaggio a iniezione<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d327eee elementor-widget elementor-widget-text-editor\" data-id=\"d327eee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Gli <strong>stampi famiglia<\/strong> nello stampaggio a iniezione sono un tipo di stampo unico che consente di posizionare e stampare parti diverse all'interno dello stesso stampo. In sostanza, le cavit\u00e0 per le varie parti vengono create all'interno di un unico stampo, <strong>per consentire la produzione simultanea di pi\u00f9 componenti in un unico ciclo di stampaggio a iniezione<\/strong>. Questo metodo viene utilizzato principalmente per ridurre il numero di stampi necessari, abbassando cos\u00ec i costi complessivi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-563c499 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"563c499\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8f0413\" data-id=\"b8f0413\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ac82b4 elementor-widget elementor-widget-heading\" data-id=\"4ac82b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Advantages_of_Using_Family_Molds_in_Injection_Molding\"><\/span>Vantaggi dell'utilizzo di stampi familiari nello stampaggio a iniezione<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0f7c84 elementor-widget elementor-widget-text-editor\" data-id=\"d0f7c84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Gli stampi famiglia nello stampaggio a iniezione possono essere uno strumento efficiente <strong>se usati correttamente<\/strong>. Essi integrano la produzione di pi\u00f9 parti diverse all'interno di un unico stampo, offrendo numerosi vantaggi. Ecco i principali vantaggi dell'utilizzo degli stampi familiari:<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\"><strong>1. Risparmio sui costi<a href=\"http:\/\/boyanmfg.com\/injection-mold-cost-in-china\/\">delle spese per gli stampi<\/a><\/strong>: L'inserimento di parti diverse nello stesso stampo riduce significativamente il numero di stampi necessari. Ogni stampo indipendente ha bisogno di una base e di accessori propri, ma l'uso di uno stampo familiare pu\u00f2 far risparmiare circa 20-60% di questi costi.<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\">Ci\u00f2 \u00e8 particolarmente vero per i pezzi che richiedono porte laterali, dove uno stampo a cavit\u00e0 singola potrebbe richiedere un canale pi\u00f9 lungo, aumentando i costi. Uno stampo familiare a 1+1 cavit\u00e0 pu\u00f2 accorciare la pista, riducendo di fatto i costi.<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\">Inoltre, quando diversi pezzi hanno forme e dimensioni simili, come i pulsanti di una chiave d'auto, la produzione di questi pezzi con uno stampo familiare pu\u00f2 portare a sostanziali risparmi sui costi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc972b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc972b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d065221\" data-id=\"d065221\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7264e68 elementor-widget elementor-widget-image\" data-id=\"7264e68\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-4-buttons-front.jpg\" class=\"attachment-large size-large wp-image-7076\" alt=\"bottoni realizzati con uno stampo familiare 4x2, lato anteriore\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-4-buttons-front.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-4-buttons-front-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d71253\" data-id=\"1d71253\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4abc3af elementor-widget elementor-widget-image\" data-id=\"4abc3af\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-4-buttons-back.jpg\" class=\"attachment-large size-large wp-image-7075\" alt=\"bottoni realizzati con uno stampo familiare 4x2, lato posteriore\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-4-buttons-back.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-4-buttons-back-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-acd4488 elementor-widget elementor-widget-text-editor\" data-id=\"acd4488\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\"><strong>2. Ideale per <a href=\"http:\/\/boyanmfg.com\/low-volume-plastic-injection-molding\/\">la produzione di piccoli lotti<\/a><\/strong>: Per la produzione su piccola scala, gli stampi familiari riducono la necessit\u00e0 di frequenti modifiche e aggiustamenti dello stampo, risparmiando tempo e costi. Questo li rende una scelta ideale per la produzione su piccola scala o di prototipi.<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\"><strong>3. Riduzione dei <a href=\"https:\/\/www.tuotuo.com.cn\/article-4805.html\" target=\"_blank\" rel=\"noopener\">costi dei bracci robotici<\/a><\/strong>: nelle linee di produzione in cui i bracci robotici sono utilizzati per la rimozione dei pezzi, l'impiego di uno stampo familiare significa che \u00e8 necessario un solo set di bracci robotici. Questo non solo riduce i costi di progettazione e produzione, ma semplifica anche il processo di produzione.<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\">Anche se alcuni prodotti richiedono due o pi\u00f9 stampi familiari, l'uso di due set di bracci robotici, invece di progettare un set per ogni singolo stampo, consente di risparmiare sui costi di progettazione e manutenzione.<\/p><p class=\"translation-block\">In sintesi, gli stampi familiari offrono una soluzione produttiva economica e adattabile, particolarmente indicata per progetti che richiedono la produzione di pezzi diversi. Riducendo il numero di stampi, semplificando il processo produttivo e riducendo i costi del braccio robotico, ottimizzano efficacemente l'efficienza produttiva e il controllo dei costi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc13527 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc13527\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0271f5\" data-id=\"a0271f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8acb94 elementor-widget elementor-widget-heading\" data-id=\"f8acb94\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Limitations_and_Conditions_for_Using_Family_Molds\"><\/span>Limitazioni e condizioni di utilizzo delle muffe familiari<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53eb341 elementor-widget elementor-widget-text-editor\" data-id=\"53eb341\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Sebbene gli stampi familiari nello stampaggio a iniezione offrano alcuni vantaggi, il loro utilizzo \u00e8 soggetto a condizioni e limitazioni specifiche. Non si tratta di posizionare arbitrariamente parti diverse all'interno di uno stampo, come si potrebbe scegliere liberamente i piatti in un ristorante.<\/p><p class=\"translation-block\">In realt\u00e0, l'utilizzo di stampi familiari deve rispettare una serie di condizioni rigorose. Queste condizioni sono essenziali per assicurare un processo produttivo regolare e garantire la qualit\u00e0 dei prodotti finali. Comprendere e rispettare queste limitazioni \u00e8 fondamentale per utilizzare efficacemente gli stampi familiari nella produzione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9ae7c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9ae7c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9496247\" data-id=\"9496247\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b894ed0 elementor-widget elementor-widget-heading\" data-id=\"b894ed0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"The_Need_for_Similarity_in_Products_within_Family_Molds\"><\/span>Necessit\u00e0 di somiglianza dei prodotti all'interno degli stampi familiari<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aae32f0 elementor-widget elementor-widget-text-editor\" data-id=\"aae32f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Quando si producono pezzi utilizzando stampi familiari nello stampaggio a iniezione, \u00e8 necessario prestare particolare attenzione alla somiglianza di <strong>forma, dimensioni, <\/strong>e<strong> spessore delle pareti<\/strong> dei pezzi.\u00a0<\/p><h4><strong>Impatto sulla qualit\u00e0 del prodotto<\/strong>:<\/h4><p class=\"translation-block\">Durante il processo di stampaggio a iniezione, la velocit\u00e0, la pressione e la temperatura possono influenzare le dimensioni e la qualit\u00e0 superficiale dei prodotti. Ogni prodotto ha una finestra di condizioni ottimali per lo stampaggio a iniezione, che comprende un intervallo ideale e uno accettabile. Tuttavia, per prodotti con dimensioni e spessori di parete diversi, queste finestre di condizione possono differire in modo significativo, a volte senza alcuna sovrapposizione. Ci\u00f2 significa che potrebbero non essere adatti alla produzione nello stesso stampo famiglia. Gli stampi famiglia potrebbero non essere applicabili in situazioni in cui:<\/p><ul><li>a. \u00c8 richiesta una precisione estremamente elevata nelle dimensioni del prodotto.<\/li><li>b. <a href=\"http:\/\/boyanmfg.com\/common-injection-molding-defects\/\">Difetti di stampaggio a iniezione<\/a> come nel caso di parti trasparenti o di prodotti che presentano difetti superficiali.<\/li><\/ul><h4><strong>Impatto sugli stampi a iniezione<\/strong>:<\/h4><p class=\"translation-block\">Gli stampi nel processo di stampaggio a iniezione devono sopportare una pressione significativa. Se c'\u00e8 una notevole differenza di dimensioni tra i prodotti in uno stampo familiare, lo stampo pu\u00f2 essere soggetto a forze eccentriche non uniformi. Se queste forze sbilanciate agiscono ripetutamente, potrebbero ridurre la durata dello stampo.<\/p><p class=\"translation-block\">In conclusione, sebbene gli stampi familiari nello stampaggio a iniezione offrano vantaggi in termini di efficienza e risparmio di costi nel processo di produzione, \u00e8 necessario considerare la coerenza delle dimensioni, della forma e dello spessore delle pareti dei prodotti. Se questi fattori variano troppo, potrebbero influire sulla qualit\u00e0 dei prodotti e sulla durata dello stampo. Pertanto, quando si opta per gli stampi familiari, questi fattori devono essere valutati attentamente per garantire un processo di produzione regolare e la qualit\u00e0 dei prodotti finali.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4a6eb0 elementor-widget elementor-widget-image\" data-id=\"e4a6eb0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-1112.jpg\" class=\"attachment-large size-large wp-image-7082\" alt=\"uno stampo familiare con disposizione delle cavit\u00e0 1+1+1+2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-1112.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/family-mold-1112-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"> Questo stampo familiare presenta una disposizione di 1+1+1+2 cavit\u00e0, in cui la parte pi\u00f9 piccola \u00e8 sensibilmente pi\u00f9 piccola delle altre tre.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55a4613 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55a4613\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f08ab30\" data-id=\"f08ab30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60bce43 elementor-widget elementor-widget-heading\" data-id=\"60bce43\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Additional_Limitations_in_Using_Family_Molds\"><\/span>Ulteriori limitazioni nell'uso delle muffe familiari<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254d499 elementor-widget elementor-widget-text-editor\" data-id=\"254d499\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Oltre a considerare la consistenza delle dimensioni e della forma dei prodotti, esistono altre limitazioni nell'utilizzo di stampi familiari nello stampaggio a iniezione:<\/p><ol><li><p class=\"translation-block\"><strong>Consistenza di materiali e colori<\/strong>: Tutti i pezzi prodotti nello stesso stampo familiare devono utilizzare materiali e colori identici. Questo requisito deriva dal fatto che tutti i pezzi vengono prodotti contemporaneamente in un unico ciclo di stampaggio a iniezione, rendendo impossibile l'utilizzo di materiali o colori diversi per ciascun pezzo.<\/p><\/li><li><p class=\"translation-block\"><strong>Corrispondenza tra numero di cavit\u00e0 e requisiti dei pezzi<\/strong>: il numero di cavit\u00e0 per ciascun pezzo nello stampo (cio\u00e8 il numero di pezzi prodotti per ciclo di iniezione) deve corrispondere alla quantit\u00e0 necessaria per l'assemblaggio del prodotto finale. Ad esempio, se un gruppo di prodotti richiede 2 parti A, 1 parte B e 3 parti C, il rapporto delle cavit\u00e0 per le parti A, B e C nello stampo di famiglia deve essere 2:1:3.<\/p><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d3aae1 elementor-widget elementor-widget-heading\" data-id=\"7d3aae1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Easing_Family_Mold_Constraints_During_Prototyping\"><\/span>Ridurre i vincoli dello stampo famigliare durante la prototipazione<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12b81a0 elementor-widget elementor-widget-text-editor\" data-id=\"12b81a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Durante la fase di prototipazione, queste due condizioni possono essere attenuate:<\/p><ul><li>Nella fase di prototipazione, pu\u00f2 essere accettabile scartare alcuni pezzi in eccesso. Sebbene ci\u00f2 comporti un certo spreco di materiale, \u00e8 pi\u00f9 tollerabile rispetto al risparmio sui costi dello stampo.<\/li><li>Un altro approccio consiste nel bloccare alcuni dei canali, impedendo la produzione di pezzi in questi punti bloccati durante il processo di iniezione. In genere, si utilizza una brasatura di rame, che pu\u00f2 essere rimossa in un secondo momento, se necessario. Questo metodo riduce efficacemente lo spreco di materiale (evitando di produrre pezzi inutili) e viene generalmente utilizzato in scenari in cui viene prodotta una quantit\u00e0 leggermente superiore di pezzi.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ac4d91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ac4d91\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bc1e06\" data-id=\"9bc1e06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c64584 elementor-widget elementor-widget-heading\" data-id=\"7c64584\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un esempio di stampo familiare 4x4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3626904 elementor-widget elementor-widget-text-editor\" data-id=\"3626904\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Si tratta di un'applicazione di successo di uno stampo familiare 4\u00d74. Il prodotto \u00e8 composto da quattro parti diverse, ognuna delle quali presenta quattro cavit\u00e0. Ci\u00f2 significa che ogni ciclo di stampaggio a iniezione pu\u00f2 produrre 4\u00d74=16 parti in plastica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee973b2 elementor-widget elementor-widget-image\" data-id=\"ee973b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/4-parts-family-mold.jpg\" class=\"attachment-large size-large wp-image-7087\" alt=\"4 parti in ABS realizzate con uno stampo familiare\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/4-parts-family-mold.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/4-parts-family-mold-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Questi 4 pezzi, realizzati in ABS, sono stati prodotti con uno stampo familiare.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc85ed3 elementor-widget elementor-widget-text-editor\" data-id=\"bc85ed3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Il materiale utilizzato per questi prodotti \u00e8 l'ABS di colore chiaro, noto per la sua tolleranza ai difetti estetici, che offre una finestra pi\u00f9 ampia per le condizioni di stampaggio a iniezione, il che \u00e8 molto vantaggioso per l'utilizzo di stampi familiari.<\/p><p class=\"translation-block\">Nonostante le differenze nelle dimensioni di questi quattro prodotti, in particolare i pulsanti sono molto pi\u00f9 piccoli rispetto agli altri componenti, i loro spessori delle pareti sono abbastanza simili. In particolare, questo stampo \u00e8 stato utilizzato per oltre 150.000 colpi senza praticamente alcun problema.<\/p><p class=\"translation-block\">Come si vede nel video, questi prodotti vengono estratti da ventose su bracci robotici e poi lasciati cadere nei rispettivi contenitori. Questa configurazione consente una produzione continua senza la necessit\u00e0 di cambiare gli stampi, con un notevole risparmio sui costi di manodopera. Sono sufficienti controlli regolari sulla qualit\u00e0 del prodotto e sul funzionamento della macchina. Questo esempio dimostra chiaramente l'efficienza e i vantaggi in termini di risparmio dei costi dell'utilizzo di stampi familiari.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22706d3 elementor-widget elementor-widget-video\" data-id=\"22706d3\" data-element_type=\"widget\" data-settings='{\"youtube_url\":\"https:\\\/\\\/youtu.be\\\/CNJumLK8v4k\",\"video_type\":\"youtube\",\"controls\":\"yes\"}' data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2013744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2013744\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f79f3e8\" data-id=\"f79f3e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-341804e elementor-widget elementor-widget-heading\" data-id=\"341804e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusione<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d16fb7d elementor-widget elementor-widget-text-editor\" data-id=\"d16fb7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In sintesi, gli stampi familiari offrono molte comodit\u00e0 nella produzione, ma hanno anche dei limiti specifici. Comprendere queste limitazioni \u00e8 fondamentale per pianificare meglio il processo produttivo, garantire l'efficienza e mantenere la qualit\u00e0. Durante la fase di prototipazione, queste limitazioni possono essere opportunamente attenuate per risparmiare costi e tempo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1e9329 elementor-widget elementor-widget-spacer\" data-id=\"f1e9329\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c74869 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c74869\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cffd31f\" data-id=\"cffd31f\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d5ad75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d5ad75\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f2c466a\" data-id=\"f2c466a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-676a61f elementor-widget elementor-widget-image\" data-id=\"676a61f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png\" class=\"attachment-large size-large wp-image-6453\" alt=\"Scatola triangolare sovrastampata in TPU\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e5dba8e\" data-id=\"e5dba8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62dc1bc elementor-widget elementor-widget-heading\" data-id=\"62dc1bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Siamo esperti nello stampaggio a iniezione di materie plastiche. Contattateci subito per ottenere un rapido preventivo!<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6eea6bd\" data-id=\"6eea6bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a49cb75 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"a49cb75\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Comprensione degli stampi familiari nello stampaggio a iniezione Gli stampi familiari nello stampaggio a iniezione sono un tipo unico di stampo che consente di posizionare e stampare parti diverse all'interno dello stesso utensile. In sostanza, le cavit\u00e0 per varie parti vengono create all'interno di un unico stampo, consentendo la produzione simultanea di pi\u00f9 componenti in un unico ciclo di stampaggio a iniezione. Questo\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/it\/family-molds-in-injection-molding\/\" rel=\"bookmark\">Continua a leggere \u00bb<span class=\"screen-reader-text\">Il vantaggio degli stampi familiari nello stampaggio a iniezione: Un caso di studio sulla cavit\u00e0 4\u00d74<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":7073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":91,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72],"tags":[],"class_list":["post-7039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts\/7039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/comments?post=7039"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts\/7039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/media\/7073"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/media?parent=7039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/categories?post=7039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/tags?post=7039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}