{"id":6985,"date":"2023-12-16T15:41:13","date_gmt":"2023-12-16T15:41:13","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=6985"},"modified":"2024-05-27T17:11:11","modified_gmt":"2024-05-27T17:11:11","slug":"explore-flame-retardant-plastics","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/","title":{"rendered":"Scegliere la giusta plastica ignifuga: Una guida completa"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6985\" class=\"elementor elementor-6985\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b43618c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b43618c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6f9a81\" data-id=\"e6f9a81\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1dae8b elementor-widget elementor-widget-heading\" data-id=\"f1dae8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Indice dei contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Allinea la tabella dei contenuti\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#The_Importance_of_Understanding_the_Flame_Retardant_Plastics\" >L'importanza di comprendere le materie plastiche ritardanti di fiamma<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#Classification_of_Plastic_Flame_Retardants\" >Classificazione dei ritardanti di fiamma per plastica<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#Understanding_Halogen_Elements\" >Conoscere gli elementi alogeni<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#What_are_Halogenated_Flame_Retardants\" >Cosa sono i ritardanti di fiamma alogenati?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#What_are_Non-Halogenated_Flame_Retardants\" >Cosa sono i ritardanti di fiamma non alogenati?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#Comparing_their_Advantages_and_Disadvantages\" >Confronto tra vantaggi e svantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#Guide_to_Choosing_the_Right_Flame_Retardant_Nylon\" >Guida alla scelta del giusto nylon ignifugo<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/#We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\" >Siamo esperti nello stampaggio a iniezione di materie plastiche. Contattateci subito per ottenere un rapido preventivo!<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"The_Importance_of_Understanding_the_Flame_Retardant_Plastics\"><\/span>L'importanza di comprendere le materie plastiche ritardanti di fiamma<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7eba4a elementor-widget elementor-widget-text-editor\" data-id=\"b7eba4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nella scelta delle materie plastiche ritardanti di fiamma, \u00e8 fondamentale acquisire una certa conoscenza dell'argomento.<\/p><p class=\"translation-block\">Inizialmente, la scelta del <a href=\"https:\/\/www.sohu.com\/a\/249064162_300419\" target=\"_blank\" rel=\"noopener\"><strong>classificato di infiammabilit\u00e0<\/strong><\/a> \u00e8 fondamentale e spesso \u00e8 una scelta semplice. Tuttavia, il <strong>tipo di ritardante di fiamma per plastica<\/strong>, un aspetto spesso trascurato, \u00e8 altrettanto importante.<\/p><p class=\"translation-block\">I ritardanti di fiamma svolgono un ruolo decisivo nel migliorare la resistenza al fuoco delle materie plastiche, impedendo o rallentando efficacemente la propagazione delle fiamme. La scelta del ritardante di fiamma giusto non \u00e8 solo una questione di <strong>sicurezza<\/strong>, ma anche di <strong>protezione dell'ambiente<\/strong> e <strong>efficacia dei costi<\/strong>. I diversi tipi di ritardanti di fiamma agiscono attraverso vari meccanismi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53fb6f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53fb6f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b56f3c\" data-id=\"6b56f3c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f3d255 elementor-widget elementor-widget-heading\" data-id=\"1f3d255\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Classification_of_Plastic_Flame_Retardants\"><\/span>Classificazione dei ritardanti di fiamma per plastica<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e066eb6 elementor-widget elementor-widget-text-editor\" data-id=\"e066eb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In generale, i ritardanti di fiamma sono classificati in due tipi: <strong>alogenati <\/strong>e <strong>non alogenati&gt;.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78998bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78998bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa80205\" data-id=\"fa80205\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a97a0ab elementor-widget elementor-widget-heading\" data-id=\"a97a0ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Understanding_Halogen_Elements\"><\/span>Conoscere gli elementi alogeni<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b74ebb elementor-widget elementor-widget-text-editor\" data-id=\"4b74ebb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Per prima cosa, approfondiamo <a href=\"https:\/\/www.angelo.edu\/faculty\/kboudrea\/periodic\/periodic_main7.htm\" target=\"_blank\" rel=\"noopener\">cosa sono gli elementi alogeni.<\/a> Gli alogeni sono gli elementi del settimo gruppo principale della tavola periodica, tra cui il fluoro (F), il cloro (Cl), il bromo (Br), lo iodio (I) e l'astatina (At).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-289d4f8 elementor-widget elementor-widget-image\" data-id=\"289d4f8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"311\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Halogens-in-the-periodic-table.jpg\" class=\"attachment-large size-large wp-image-7006\" alt=\"Gli elementi alogeni nella tavola periodica\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Halogens-in-the-periodic-table.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Halogens-in-the-periodic-table-300x156.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0900fc9 elementor-widget elementor-widget-text-editor\" data-id=\"0900fc9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Questi elementi hanno una caratteristica comune: <strong>sette elettroni nel loro guscio elettronico pi\u00f9 esterno<\/strong>, che li rende altamente reattivi e facilmente in grado di formare composti con altri elementi.<\/p><p class=\"translation-block\">Gli alogeni esistono tipicamente come ioni negativi, come lo ione cloro (Cl) nel cloruro di sodio (NaCl). Presentano una forte elettrofilia e propriet\u00e0 ossidanti nelle reazioni chimiche. Ampiamente presenti in natura in varie forme, dall'acqua salata ai minerali, gli alogeni sono utilizzati in una serie di applicazioni, tra cui la disinfezione, la produzione farmaceutica e la lavorazione della plastica. A causa della loro reattivit\u00e0, gli alogeni hanno sollevato problemi ambientali e sanitari.<\/p><p class=\"translation-block\">\u00c8 importante notare che nei ritardanti di fiamma gli elementi alogeni prevalentemente utilizzati sono il bromo (Br) e il cloro (Cl), con il bromo pi\u00f9 comune.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b23637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b23637\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a7c8ab1\" data-id=\"a7c8ab1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8d0a7e elementor-widget elementor-widget-heading\" data-id=\"b8d0a7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_are_Halogenated_Flame_Retardants\"><\/span>Cosa sono i ritardanti di fiamma alogenati?<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-307c265 elementor-widget elementor-widget-text-editor\" data-id=\"307c265\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">I ritardanti di fiamma alogenati sono sostanze chimiche che contengono elementi alogeni (come bromo [Br] e cloro [Cl]) e sono utilizzati per migliorare la resistenza al fuoco dei materiali. Durante la combustione, questi ritardanti interrompono la catena di reazioni chimiche delle fiamme rilasciando radicali liberi alogeni. I ritardanti di fiamma alogenati comprendono principalmente le seguenti categorie:<\/p><ul><li><p class=\"translation-block\"><strong>Ritardanti di fiamma bromurati<\/strong>:<\/p><ul><li>I ritardanti di fiamma alogenati pi\u00f9 comuni e diffusi.<\/li><li>Includono sostanze come il tetrabromobisfenolo A (TBBPA), il decabromodifenil etere (Deca-BDE) e l'esabromociclododecano (HBCD).<\/li><li>Applicabile a diverse materie plastiche, dispositivi elettronici, tessuti e altro ancora.<\/li><\/ul><\/li><li><p class=\"translation-block\"><strong>Ritardanti di fiamma clorurati<\/strong>:<\/p><ul><li>Includono paraffine clorurate, polietilene clorurato e altri.<\/li><li>Questi ritardanti sono comunemente utilizzati nel PVC e in altri polimeri clorurati.<\/li><\/ul><\/li><li><p class=\"translation-block\"><strong>Ritardanti di fiamma a base di bromo e cloro<\/strong>:<\/p><ul><li>Composti che combinano gli elementi bromo e cloro.<\/li><li>Esempi sono gli alcani clorurati bromurati, i benzeni clorurati bromurati, ecc.<\/li><li>Questi ritardanti compositi utilizzano gli effetti sinergici del bromo e del cloro per aumentare la capacit\u00e0 di ritardare la fiamma.<\/li><\/ul><\/li><li><p class=\"translation-block\"><strong>Combinazione di composti bromurati con altri additivi<\/strong>:<\/p><ul><li>Per aumentare l'efficienza e ridurre i costi, i ritardanti di fiamma bromurati sono spesso utilizzati insieme a sinergizzanti come il triossido di antimonio (Sb2O3).<\/li><li>Questa combinazione migliora la resistenza alla fiamma complessiva del materiale.<\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4f17dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4f17dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e698d4d\" data-id=\"e698d4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e2b3e9 elementor-widget elementor-widget-heading\" data-id=\"0e2b3e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_are_Non-Halogenated_Flame_Retardants\"><\/span>Cosa sono i ritardanti di fiamma non alogenati?<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb59d2a elementor-widget elementor-widget-text-editor\" data-id=\"bb59d2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">I ritardanti di fiamma non alogenati sono una classe di composti che non contengono elementi alogeni (come il cloro [Cl] e il bromo [Br]) nella loro composizione chimica. Questi ritardanti sono generalmente considerati pi\u00f9 ecologici perch\u00e9 non rilasciano composti alogeni durante la combustione, che potrebbero essere dannosi sia per l'ambiente che per la salute umana. I principali tipi di ritardanti di fiamma non alogenati includono:<\/p><ul><li><p class=\"translation-block\"><strong>Ritardanti di fiamma a base di fosforo<\/strong>:<\/p><ul><li>Questi ritardanti agiscono formando uno strato di carbone durante la combustione, isolando il materiale dall'ossigeno e inibendo cos\u00ec la propagazione della fiamma.<\/li><li>I ritardanti comuni a base di fosforo includono il fosforo rosso, il fosfato di ammonio e i fosfati.<\/li><li>Adatto a varie materie plastiche, fibre, rivestimenti e gomme.<\/li><\/ul><\/li><li><p class=\"translation-block\"><strong>Ritardanti di fiamma a base di azoto<\/strong>:<\/p><ul><li>Questi ritardanti funzionano in genere rilasciando gas non combustibili o promuovendo la formazione di uno strato carbonioso stabile attraverso reazioni chimiche.<\/li><li>I comuni ritardanti a base di azoto includono melamina, resine urea-formaldeide, ecc.<\/li><li>Utilizzato di frequente nelle plastiche espanse, nelle fibre e nei rivestimenti.<\/li><\/ul><\/li><li><p class=\"translation-block\"><strong>Ritardanti di fiamma inorganici<\/strong>:<\/p><ul><li>Tra cui l'idrossido di alluminio, l'idrossido di magnesio e cos\u00ec via, queste sostanze assorbono una quantit\u00e0 significativa di calore e rilasciano vapore acqueo quando vengono riscaldate, riducendo cos\u00ec la temperatura del materiale e rallentando la propagazione della fiamma.<\/li><li>Ampiamente applicato nelle materie plastiche, nelle gomme e nei rivestimenti.<\/li><\/ul><\/li><li><p class=\"translation-block\"><strong>Ritardanti di fiamma organici non alogenati<\/strong>:<\/p><ul><li>Questa categoria comprende vari composti organici, come la grafite espandibile e i composti a base epossidica.<\/li><li>Durante la combustione, reagiscono chimicamente formando uno strato di carbone espanso, che garantisce il ritardo di fiamma.<\/li><\/ul><\/li><li><p class=\"translation-block\"><strong>Ritardanti di fiamma basati sulle nanotecnologie<\/strong>:<\/p><ul><li>Utilizzando la nanotecnologia, questi ritardanti prevedono l'aggiunta di minuscole nanoparticelle ai materiali per aumentarne la resistenza alla fiamma.<\/li><li>Queste nanoparticelle possono essere inorganiche, come i nano-ossidi, o materiali ibridi organici-inorganici.<\/li><\/ul><\/li><\/ul><p class=\"translation-block\">La scelta dei ritardanti di fiamma non alogenati dipende dal tipo di materiale da ritardare, dalle condizioni di lavorazione, dai requisiti di applicazione del prodotto finale e da considerazioni sull'impatto ambientale e sulla salute. A fronte di normative ambientali sempre pi\u00f9 severe e di una maggiore richiesta di sicurezza da parte del mercato, la tecnologia dei ritardanti di fiamma non alogenati \u00e8 in rapida evoluzione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8771cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8771cf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25ffcca\" data-id=\"25ffcca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e4f2f2 elementor-widget elementor-widget-heading\" data-id=\"5e4f2f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Comparing_their_Advantages_and_Disadvantages\"><\/span>Confronto tra vantaggi e svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d379155 elementor-widget elementor-widget-text-editor\" data-id=\"d379155\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-bowfw-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-bowfw-1n7m0yu\"><div class=\"flex flex-col pb-9 text-sm\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-39\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\"><div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"afad2d0d-f433-427d-8156-30f7f1ddc240\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p class=\"translation-block\">I ritardanti di fiamma alogenati e non alogenati hanno ciascuno i propri punti di forza e di debolezza in termini di resistenza alla fiamma, impatto ambientale e campo di applicazione.<\/p><h4><strong>Ritardanti di fiamma alogenati<\/strong><\/h4><ul><li><strong>Vantaggi<\/strong><ul><li>In genere, offrono un'elevata efficienza ignifuga, interrompendo rapidamente la propagazione della fiamma, soprattutto nei prodotti elettronici ed elettrici.<\/li><li>Sono economici, stabili, richiedono bassi livelli di aggiunta, sono compatibili con le resine sintetiche e mantengono le propriet\u00e0 fisiche e chimiche originali dei prodotti.<\/li><\/ul><\/li><li><strong>Svantaggi<\/strong><ul><li>Le principali preoccupazioni sono di natura ambientale e sanitaria. Questi ritardanti possono rilasciare gas alogenati tossici e altre sostanze nocive durante la combustione, causando l'inquinamento ambientale e potenzialmente influenzando la salute umana nel tempo. Per questo motivo, il loro uso \u00e8 limitato o vietato in molti Paesi e regioni.<\/li><\/ul><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-98f293d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98f293d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c3d8031\" data-id=\"c3d8031\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8a510e elementor-widget elementor-widget-image\" data-id=\"c8a510e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/halogenated-flame-retardant-burning-mark.jpg\" class=\"attachment-large size-large wp-image-7026\" alt=\"marchio di combustione su nylon alogenato ritardante di fiamma\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/halogenated-flame-retardant-burning-mark.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/halogenated-flame-retardant-burning-mark-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Segni di bruciatura su nylon alogenato ritardante di fiamma<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-75c4813\" data-id=\"75c4813\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e8cac8 elementor-widget elementor-widget-image\" data-id=\"5e8cac8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/non-halogenated-flame-retardant-burning-mark.jpg\" class=\"attachment-large size-large wp-image-7025\" alt=\"marchio di combustione su nylon ritardante di fiamma non alogenato\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/non-halogenated-flame-retardant-burning-mark.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/non-halogenated-flame-retardant-burning-mark-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Segno di bruciatura su nylon ritardante di fiamma non alogenato<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-055e529 elementor-widget elementor-widget-text-editor\" data-id=\"055e529\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ritardanti di fiamma non alogenati<\/strong><\/h4><ul><li><strong>Vantaggi<\/strong><ul><li>Rispettosi dell'ambiente. Non producono gas alogenati tossici quando vengono bruciati, il che li rende una scelta pi\u00f9 sicura e sostenibile. I ritardanti non alogenati, come quelli a base di fosforo e azoto, sono spesso utilizzati in applicazioni con requisiti ambientali pi\u00f9 elevati.<\/li><\/ul><\/li><li><strong>Svantaggi<\/strong><ul><li>La loro efficacia di ritardare la fiamma potrebbe non essere cos\u00ec elevata come quella dei ritardanti alogenati e possono essere pi\u00f9 costosi.<\/li><\/ul><\/li><\/ul><p class=\"translation-block\">Pertanto, quando si sceglie un ritardante di fiamma, \u00e8 necessario considerare in modo completo fattori quali l'efficacia del ritardo di fiamma, l'impatto ambientale e il costo per trovare la soluzione pi\u00f9 adatta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-183b34d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"183b34d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0653076 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0653076\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ba5d6d\" data-id=\"8ba5d6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b9305d elementor-widget elementor-widget-heading\" data-id=\"2b9305d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Guide_to_Choosing_the_Right_Flame_Retardant_Nylon\"><\/span>Guida alla scelta del giusto nylon ignifugo<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12aecaf elementor-widget elementor-widget-text-editor\" data-id=\"12aecaf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Recentemente, al momento di acquistare il nylon ritardante di fiamma, abbiamo scoperto che i fornitori offrono generalmente <strong>tre opzioni principali<\/strong>: nylon ritardante di fiamma alogenato (solitamente bromato), nylon ritardante di fiamma non alogenato e nylon ritardante di fiamma al fosforo rosso. Tra questi, i nylon ritardanti di fiamma alogenati e non alogenati sono pi\u00f9 comunemente utilizzati, mentre il nylon ritardante di fiamma al fosforo rosso \u00e8 relativamente meno comune.<\/p><h4>Diversi colori di questi materiali<\/h4><p class=\"translation-block\">In primo luogo, questi diversi tipi di nylon ritardante di fiamma si distinguono per i loro colori. Il nylon ritardante di fiamma alogenato appare di colore giallo chiaro, mentre il nylon ritardante di fiamma non alogenato tende pi\u00f9 al bianco, assomigliando al nylon con l'aggiunta di pigmenti bianchi. Inoltre, entrambi questi tipi possono essere trasformati in nero o in altri colori scuri. Il nylon ritardante di fiamma al fosforo rosso, invece, \u00e8 disponibile principalmente nei colori nero e marrone.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d8d9e elementor-widget elementor-widget-image\" data-id=\"44d8d9e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"343\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Halogenated-non-halogenated-nylons.jpg\" class=\"attachment-large size-large wp-image-7017\" alt=\"Niloni alogenati e non alogenati ritardanti di fiamma\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Halogenated-non-halogenated-nylons.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Halogenated-non-halogenated-nylons-300x172.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Niloni ritardanti di fiamma alogenati e non alogenati<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1b09db elementor-widget elementor-widget-text-editor\" data-id=\"a1b09db\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Caratteristiche della combustione<\/h4><p class=\"translation-block\">Un altro metodo per identificare questi materiali consiste nel bruciarli leggermente con un accendino. Il nylon ritardante di fiamma alogenato produce fumo nero e un forte odore irritante al momento della combustione, mentre il nylon ritardante di fiamma non alogenato emette meno fumo bianco e ha un odore meno intenso.<\/p><h4>Ulteriori dettagli richiedono uno sforzo supplementare e non sempre sono essenziali.<\/h4><p class=\"translation-block\">Una comprensione pi\u00f9 approfondita dei componenti specifici dei ritardanti di fiamma potrebbe richiedere uno sforzo supplementare. La maggior parte dei produttori non \u00e8 in grado di fornire informazioni dettagliate, poich\u00e9 in realt\u00e0 esistono solo pochi tipi di ritardanti di fiamma sul mercato, ma sono stati semplificati in queste tre categorie per facilitare la memorizzazione e la selezione. Questi ritardanti di fiamma sono solitamente prodotti in forma granulare, simili a normali pellet di plastica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e065fd elementor-widget elementor-widget-image\" data-id=\"5e065fd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/flame-retardants-granular-form.jpg\" class=\"attachment-large size-large wp-image-7015\" alt=\"I ritardanti di fiamma sono solitamente prodotti in forma granulare.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/flame-retardants-granular-form.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/flame-retardants-granular-form-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad3cf15 elementor-widget elementor-widget-text-editor\" data-id=\"ad3cf15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In sintesi, nella scelta del nylon ritardante di fiamma \u00e8 fondamentale considerare il colore, le caratteristiche di combustione e gli scenari di applicazione. Ci\u00f2 non riguarda solo le prestazioni del prodotto, ma anche la sicurezza nella lavorazione e nell'uso successivi. Pertanto, \u00e8 essenziale chiarire le esigenze e comunicare accuratamente con i fornitori per selezionare il tipo di nylon ritardante di fiamma pi\u00f9 adatto al proprio progetto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bef0cb elementor-widget elementor-widget-spacer\" data-id=\"1bef0cb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5a49fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5a49fc\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8684fa7\" data-id=\"8684fa7\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e469e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e469e9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-96fe965\" data-id=\"96fe965\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55cb8df elementor-widget elementor-widget-image\" data-id=\"55cb8df\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png\" class=\"attachment-large size-large wp-image-6453\" alt=\"Scatola triangolare sovrastampata in TPU\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ea3dfe5\" data-id=\"ea3dfe5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcdd9cc elementor-widget elementor-widget-heading\" data-id=\"dcdd9cc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\"><\/span><span>Siamo esperti nello stampaggio a iniezione di materie plastiche. Contattateci subito per ottenere un rapido preventivo!<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-10a34a4\" data-id=\"10a34a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c2e36a elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"9c2e36a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>L'importanza di comprendere le materie plastiche ritardanti di fiamma. Quando si selezionano materie plastiche ritardanti di fiamma, acquisire alcune conoscenze sull'argomento \u00e8 cruciale. Inizialmente, decidere la classificazione di infiammabilit\u00e0 \u00e8 fondamentale, e questa scelta \u00e8 spesso semplice. Tuttavia, il tipo di ritardante di fiamma per plastica, un aspetto spesso trascurato, \u00e8 altrettanto importante. I ritardanti di fiamma svolgono un ruolo decisivo in\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/it\/explore-flame-retardant-plastics\/\" rel=\"bookmark\">Continua a leggere \u00bb<span class=\"screen-reader-text\">Scegliere la giusta plastica ignifuga: Una guida completa<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":7031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":92,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72],"tags":[],"class_list":["post-6985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts\/6985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/comments?post=6985"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts\/6985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/media\/7031"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/media?parent=6985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/categories?post=6985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/tags?post=6985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}