{"id":6650,"date":"2023-11-30T02:19:12","date_gmt":"2023-11-30T02:19:12","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=6650"},"modified":"2026-03-16T05:50:26","modified_gmt":"2026-03-16T05:50:26","slug":"injection-molding-tolerances","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/","title":{"rendered":"Tolleranze per lo stampaggio a iniezione: DIN 16901, ISO 20457 e le nostre linee guida pratiche"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6650\" class=\"elementor elementor-6650\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d39f3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d39f3a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4449719\" data-id=\"4449719\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c77127e elementor-widget elementor-widget-shortcode\" data-id=\"c77127e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle translation-block\" style=\"cursor:pointer\">Indice dei contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Allinea la tabella dei contenuti\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"><\/path><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default\"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Why_are_Injection_Molding_Tolerances_Important\">Perch\u00e9 le tolleranze dello stampaggio a iniezione sono importanti?<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Sources_of_Dimensional_Deviations_in_Injection_Molded_Parts\">Fonti di deviazioni dimensionali nelle parti stampate ad iniezione<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Molding_Process_Factors\">Fattori del processo di stampaggio<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Mold_Factors\">Fattori di muffa<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Understanding_the_DIN_16901_Standard\">Comprendere la norma DIN 16901<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Why_We_Need_to_Understand_DIN_16901\">Perch\u00e9 Dobbiamo Comprendere la DIN 16901<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Dimension_Classification\">Classificazione delle Dimensioni<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Tolerance_groups\">Gruppi di tolleranza<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Access_to_DIN_16901\">Accesso a DIN 16901<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#ISO_20457_The_Modern_Global_Standard_for_Plastic_Part_Tolerances\">ISO 20457: Lo standard globale moderno per le tolleranze dei componenti plastici<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#What_ISO_20457_Improves_Compared_to_DIN_16901\">Cosa migliora la ISO 20457 rispetto alla DIN 16901<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#3_DIN%E2%80%AF16901_ignores_the_fact_that_%E2%80%9Cthe_farther_from_the_datum_the_larger_the_error%E2%80%9D\">3. La DIN\u202f16901 ignora il fatto che \u201cpi\u00f9 ci si allontana dal riferimento, maggiore \u00e8 l'errore\u201d<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Boyans_Simplified_Injection_Molding_Tolerance_Chart\">Diagramma di Tolleranza Semplificato per lo Stampaggio a Iniezione di Boyan<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Understanding_Injection_Molding_Tolerance_Components\">Comprendere i Componenti della Tolleranza nello Stampaggio a Iniezione<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Norminal_dimension_Upper_and_Lower_Tolerances\">Dimensione nominale, Tolleranze Superiore e Inferiore<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Choosing_Dimension_Range\">Scelta dell'intervallo di dimensioni<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Determining_Nominal_Dimensions\">Determinazione delle dimensioni nominali<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Considering_Practical_Application\">Considerare l'applicazione pratica<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Coordination_and_Verification\">Coordinamento e verifica<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Let_Boyan_Help_You_Select_the_Right_Injection_Molding_Tolerances\">Lascia che Boyan ti Aiuti a Selezionare le Tolleranze Corrette per lo Stampaggio a Iniezione<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Focusing_on_Key_Dimensions\">Concentrarsi sulle dimensioni chiave<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Handling_Less_Important_Dimensions\">Gestione delle dimensioni meno importanti<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Information_and_Materials_Required_for_Effective_Tolerance_Determination\">Informazioni e materiali necessari per un'efficace determinazione della tolleranza<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#FAQ\">FAQ<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#Appendix_Common_Standards_for_Injection_Molded_Parts\">Appendice: Standard Comuni per i Componenti Stampati a Iniezione<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/#We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\">Siamo esperti nello stampaggio a iniezione di materie plastiche. Contattateci subito per ottenere un rapido preventivo!<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8182a8b elementor-widget elementor-widget-heading\" data-id=\"8182a8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Why_are_Injection_Molding_Tolerances_Important\"><\/span>Perch\u00e9 le tolleranze dello stampaggio a iniezione sono importanti?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f049352 elementor-widget elementor-widget-text-editor\" data-id=\"f049352\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nel processo di produzione dei pezzi stampati a iniezione, le variazioni dimensionali sono inevitabili a causa delle influenze dello stampo, della macchina di stampaggio a iniezione, dei materiali e dei fattori ambientali. Pertanto, \u00e8 fondamentale stabilire tolleranze ragionevoli per le dimensioni dei prodotti e assicurarsi che siano rispettate. Tolleranze adeguate possono:<\/p><ul><li>Garantire il corretto funzionamento delle parti, soprattutto quando pi\u00f9 componenti devono combaciare tra loro;<\/li><li>Garantire la coerenza e l'affidabilit\u00e0 del prodotto;<\/li><li>Riflettere le capacit\u00e0 produttive e gestionali della fabbrica;<\/li><li>Migliorare l'immagine aziendale e la soddisfazione dei clienti.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc0b20d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc0b20d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a896a92\" data-id=\"a896a92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d862877 elementor-widget elementor-widget-image\" data-id=\"d862877\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/product-category\/plastic-injection-molding\/precision-injection-molding\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/top-and-bottom-plastic-pin-connector-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1395\" alt=\"connettore a pin in plastica superiore e inferiore\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/top-and-bottom-plastic-pin-connector-300x300.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/top-and-bottom-plastic-pin-connector-100x100.jpg 100w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/top-and-bottom-plastic-pin-connector-600x600.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/top-and-bottom-plastic-pin-connector-150x150.jpg 150w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/top-and-bottom-plastic-pin-connector.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3be6c11\" data-id=\"3be6c11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80114e1 elementor-widget elementor-widget-image\" data-id=\"80114e1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/plastic-lens-retainer-for-smartphone-cameras\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/12\/plastic-retainer-for-phone-lens-300x300.jpg\" class=\"attachment-medium size-medium wp-image-3408\" alt=\"fermo in plastica per l&#039;obiettivo del telefono\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/12\/plastic-retainer-for-phone-lens-300x300.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/12\/plastic-retainer-for-phone-lens-100x100.jpg 100w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/12\/plastic-retainer-for-phone-lens-600x600.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/12\/plastic-retainer-for-phone-lens-150x150.jpg 150w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/12\/plastic-retainer-for-phone-lens.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-17a1375 elementor-widget elementor-widget-text-editor\" data-id=\"17a1375\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Stabilire valori di tolleranza appropriati \u00e8 essenziale. Tolleranze troppo grandi o troppo piccole possono causare problemi nell'uso del prodotto e sono indice di una scarsa conoscenza dello stampaggio a iniezione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94da94f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"94da94f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2998e86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2998e86\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0671a7c\" data-id=\"0671a7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-676813c elementor-widget elementor-widget-heading\" data-id=\"676813c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Sources_of_Dimensional_Deviations_in_Injection_Molded_Parts\"><\/span>Fonti di deviazioni dimensionali nelle parti stampate ad iniezione<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2c19b0 elementor-widget elementor-widget-text-editor\" data-id=\"b2c19b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Le deviazioni dimensionali nei pezzi stampati a iniezione derivano principalmente da due categorie: <strong>fattori del processo di stampaggio<\/strong> e<strong> fattori dello stampo.<\/strong> Ecco una spiegazione dettagliata e un'espansione di questi fattori:<\/p><h3><span class=\"ez-toc-section\" id=\"Molding_Process_Factors\"><\/span>Fattori del processo di stampaggio<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li><strong>Inconsistenza dei materiali plastici<\/strong>: Le diverse materie plastiche presentano caratteristiche di flusso, raffreddamento e ritiro diverse durante lo stampaggio. Una scarsa uniformit\u00e0 dei materiali pu\u00f2 portare a incongruenze dimensionali all'interno dello stesso lotto o tra lotti diversi.<\/li><li><strong>Precisione di controllo delle macchine per lo stampaggio a iniezione<\/strong>: La precisione del controllo della temperatura e della pressione durante il processo di stampaggio a iniezione influisce direttamente sulla stabilit\u00e0 dimensionale dei prodotti. Le fluttuazioni di temperatura e pressione possono portare a dimensioni finali incoerenti.<\/li><li><strong>Temperatura dello stampo<\/strong>: Il controllo della temperatura dello stampo \u00e8 fondamentale per la qualit\u00e0 dello stampaggio. Una temperatura non uniforme o un controllo impreciso possono provocare un raffreddamento non uniforme dei pezzi, compromettendo la precisione dimensionale.<\/li><li><strong>Deformazione elastica dello stampo<\/strong>: Sotto la pressione dell'iniezione, lo stampo pu\u00f2 subire una leggera deformazione elastica, che influisce indirettamente sulle dimensioni e sulla forma dei pezzi.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31cd257 elementor-widget elementor-widget-image\" data-id=\"31cd257\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/all-electric-molding-machine-r8r87a9uev9yqllcgtmfun0dtsckrutavnvbpyzytk.jpg\" title=\"macchina di stampaggio tutta elettrica\" alt=\"macchina di stampaggio tutta elettrica\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5450b60 elementor-widget elementor-widget-text-editor\" data-id=\"5450b60\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Mold_Factors\"><\/span>Fattori di muffa<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li><strong>Precisione di produzione delle dimensioni dello stampo<\/strong>: La precisione con cui viene fabbricato lo stampo \u00e8 un fattore chiave nel determinare l'accuratezza dimensionale del prodotto finale. Lievi deviazioni nello stampo possono essere amplificate durante il processo di stampaggio.<\/li><li><strong>Precisione posizionale dei componenti mobili dello stampo<\/strong>: Per gli stampi con componenti mobili come cursori e perni di espulsione, l'accuratezza del posizionamento ripetitivo di queste parti influisce inevitabilmente sulla coerenza delle dimensioni del prodotto. Maggiori dettagli su questo aspetto saranno spiegati in seguito.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60f1dc7 elementor-widget elementor-widget-image\" data-id=\"60f1dc7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/injection-mold-lego-part-300x169.jpg\" class=\"attachment-medium size-medium wp-image-4104\" alt=\"stampo ad iniezione lego vista generale\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/injection-mold-lego-part-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/injection-mold-lego-part-600x338.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/injection-mold-lego-part-768x432.jpg 768w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/injection-mold-lego-part.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d527646 elementor-widget elementor-widget-text-editor\" data-id=\"d527646\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In conclusione, il problema delle deviazioni dimensionali nei pezzi stampati a iniezione \u00e8 complesso e influenzato da vari fattori, tra cui le propriet\u00e0 dei materiali, le prestazioni delle attrezzature e la qualit\u00e0 dello stampo. Nella produzione reale, il controllo preciso dei parametri del processo di stampaggio, l'utilizzo di stampi ad alta precisione e l'ottimizzazione della qualit\u00e0 dei materiali possono ridurre efficacemente le deviazioni dimensionali, garantendo cos\u00ec la qualit\u00e0 e le prestazioni del prodotto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b0c32d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6b0c32d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf5fdf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf5fdf8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a71b979\" data-id=\"a71b979\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e79a2af elementor-widget elementor-widget-heading\" data-id=\"e79a2af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Understanding_the_DIN_16901_Standard\"><\/span>Comprendere la norma DIN 16901<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a38166d elementor-widget elementor-widget-heading\" data-id=\"a38166d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Why_We_Need_to_Understand_DIN_16901\"><\/span>Perch\u00e9 Dobbiamo Comprendere la DIN 16901<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed8051 elementor-widget elementor-widget-text-editor\" data-id=\"1ed8051\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Prima di discutere la DIN 16901, \u00e8 importante chiarire perch\u00e9 questa norma merita un'attenzione speciale. Le tolleranze per i pezzi stampati a iniezione hanno caratteristiche molto diverse da quelle per i pezzi lavorati a CNC, perch\u00e9 la formatura della plastica \u00e8 fortemente influenzata da fattori come il <strong>ritiro del materiale<\/strong>, la <strong>struttura dello stampo<\/strong> e le <strong>variazioni del processo<\/strong>.<\/p><p class=\"translation-block\">Tra i <a href=\"#standards\">vari standard (si prega di fare riferimento alla fine di questa pagina)<\/a> utilizzati per le tolleranze delle parti stampate a iniezione, DIN 16901 \u00e8 uno dei pi\u00f9 rappresentativi e ampiamente citati. Pertanto, acquisire una solida comprensione di DIN 16901 fornisce una base utile per comprendere i principi generali e la logica pratica dietro le tolleranze dello stampaggio a iniezione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e8ddff elementor-widget elementor-widget-heading\" data-id=\"4e8ddff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Dimension_Classification\"><\/span> Classificazione delle Dimensioni<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2747830 elementor-widget elementor-widget-text-editor\" data-id=\"2747830\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nella norma DIN 16901, le tolleranze sono suddivise in due tipi: <strong>Tipo A<\/strong> e <strong>Tipo B<\/strong>, specificatamente studiate per le caratteristiche dei pezzi stampati a iniezione. Per comprendere meglio questo concetto, analizziamo il processo di chiusura di uno stampo a iniezione, illustrato di seguito:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caec31d elementor-widget elementor-widget-image\" data-id=\"caec31d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/mold-closing-part-forming.gif\" class=\"attachment-large size-large wp-image-8160\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25bcd80 elementor-widget elementor-widget-text-editor\" data-id=\"25bcd80\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Osserviamo che alcune dimensioni delle parti in plastica (<strong>tipo B<\/strong>) sono <strong>determinate esclusivamente dalle caratteristiche della parte superiore e inferiore dello stampo<\/strong>. Queste dimensioni tendono a cambiare molto poco durante il processo di stampaggio a iniezione.<\/p><p class=\"translation-block\">Al contrario, altre dimensioni (<strong>Tipo A<\/strong>), come lo spessore dei fianchi e del fondo, vengono determinate dopo la chiusura degli stampi superiore e inferiore. Poich\u00e9 ogni volta che gli stampi si chiudono pu\u00f2 verificarsi un disallineamento, ci\u00f2 pu\u00f2 comportare alcune deviazioni. Pertanto, per queste dimensioni \u00e8 consentita una tolleranza maggiore.<\/p><p class=\"translation-block\">Le dimensioni di tipo A comprendono anche le dimensioni formate con la partecipazione di parti mobili come cursori e sollevatori.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dee6709 elementor-widget elementor-widget-image\" data-id=\"dee6709\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/misalignment-upper-lower-mold.gif\" class=\"attachment-large size-large wp-image-8161\" alt=\"disallineamento dello stampo superiore inferiore per comprendere la tolleranza di stampaggio\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d40f63 elementor-widget elementor-widget-image\" data-id=\"7d40f63\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TYPE-A-B-diemsnions-tolerance.jpg\" class=\"attachment-large size-large wp-image-8162\" alt=\"Dimensioni di tipo A e di tipo B per tolleranze di stampaggio a iniezione\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TYPE-A-B-diemsnions-tolerance.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TYPE-A-B-diemsnions-tolerance-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a08444 elementor-widget elementor-widget-text-editor\" data-id=\"0a08444\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In altre parole, le dimensioni di <strong>tipo B<\/strong> non sono influenzate dai componenti mobili all'interno dello stampo. Secondo la <strong>Figura 1<\/strong> che segue, le dimensioni di tipo B sono note anche come<strong> dimensioni legate allo stampo<\/strong> nella norma DIN 16901, che indica essenzialmente la stessa idea.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03025d7 elementor-widget elementor-widget-image\" data-id=\"03025d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/molding-tolerance-mold-related-dimensions.jpg\" class=\"attachment-large size-large wp-image-6663\" alt=\"tolleranza di stampaggio dimensioni relative allo stampo\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/molding-tolerance-mold-related-dimensions.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/molding-tolerance-mold-related-dimensions-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Dimensioni del tipo B<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f678e5f elementor-widget elementor-widget-menu-anchor\" data-id=\"f678e5f\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"type_A_dimensions\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44f0591 elementor-widget elementor-widget-text-editor\" data-id=\"44f0591\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Le dimensioni di <strong>tipo A<\/strong>, tuttavia, come mostrato nella <strong>figura 2<\/strong> seguente, sono influenzate da queste parti mobili, comprese le posizioni relative dello stampo superiore, dello stampo inferiore, dei cursori e dei sollevatori, che possono determinare piccole deviazioni dimensionali. Analogamente, le dimensioni di tipo A sono definite <strong>dimensioni non legate allo stampo<\/strong> nella norma DIN 16901.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5a7071 elementor-widget elementor-widget-image\" data-id=\"f5a7071\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"487\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/molding-tolerance-non-mold-related-dimensions.jpg\" class=\"attachment-large size-large wp-image-6664\" alt=\"Tolleranza nello stampaggio a iniezione, dimensioni non legate allo stampo, tipo A\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/molding-tolerance-non-mold-related-dimensions.jpg 650w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/molding-tolerance-non-mold-related-dimensions-600x450.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/molding-tolerance-non-mold-related-dimensions-300x225.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Dimensioni del tipo A<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-376cc03 elementor-widget elementor-widget-text-editor\" data-id=\"376cc03\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Come gi\u00e0 accennato, le tolleranze per le dimensioni del <strong>Tipo A<\/strong> sono generalmente<strong> pi\u00f9 ampie di quelle del <strong>Tipo B<\/strong>, il che riflette la realt\u00e0 dello stampaggio a iniezione. I professionisti esperti nello stampaggio a iniezione o nella progettazione di stampi in genere riescono a distinguere facilmente tra le dimensioni di tipo A e quelle di tipo B.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8a2008 elementor-widget elementor-widget-image\" data-id=\"a8a2008\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"352\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/DIN-16901-tolerances-type-A-and-B.jpg\" class=\"attachment-large size-large wp-image-6674\" alt=\"Tolleranze DIN 16901 per le dimensioni di tipo A e B\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/DIN-16901-tolerances-type-A-and-B.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/DIN-16901-tolerances-type-A-and-B-300x176.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tolleranza per il tipo A &gt; tipo B<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83638e0 elementor-widget elementor-widget-heading\" data-id=\"83638e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Tolerance_groups\"><\/span>Gruppi di tolleranza<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5980c6e elementor-widget elementor-widget-text-editor\" data-id=\"5980c6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"82\" data-end=\"427\" class=\"translation-block\">Nella DIN 16901 ci sono <strong data-start=\"299\" data-end=\"323\">sei gruppi di tolleranza<\/strong>: 110, 120, 130, 140, 150 e 160, con il <strong data-start=\"364\" data-end=\"391\">110 che \u00e8 il pi\u00f9 rigoroso<\/strong> e il <strong data-start=\"396\" data-end=\"426\">160 che \u00e8 il pi\u00f9 permissivo<\/strong>.<\/p><p data-start=\"461\" data-end=\"563\" class=\"translation-block\">Per ogni materiale, ci sono tre possibili livelli di tolleranza. Questi livelli sono classificati come segue:<\/p><ul><li data-start=\"567\" data-end=\"676\"><strong data-start=\"567\" data-end=\"589\">Tolleranza Generale:<\/strong> Questa \u00e8 la tolleranza predefinita per le dimensioni in cui non \u00e8 indicata una tolleranza specifica.<\/li><li data-start=\"679\" data-end=\"885\"><strong data-start=\"679\" data-end=\"712\">Tolleranze di Tipo 1 e Tipo 2:<\/strong> Queste tolleranze si applicano quando sono specificate deviazioni per una particolare dimensione. \u00c8 possibile scegliere tra i corrispondenti livelli di tolleranza in base al materiale e alle dimensioni della parte.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09ed799 elementor-widget elementor-widget-image\" data-id=\"09ed799\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/DIN-16901-material-to-tolerance.jpg\" class=\"attachment-large size-large wp-image-6680\" alt=\"DIN 16901 correlazione tra materiale e gruppo di tolleranza\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/DIN-16901-material-to-tolerance.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/DIN-16901-material-to-tolerance-300x144.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-754ea6c elementor-widget elementor-widget-text-editor\" data-id=\"754ea6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 data-start=\"887\" data-end=\"942\">Esempio di gruppi di tolleranza per materiali diversi<\/h4><ul><li data-start=\"0\" data-end=\"63\">Per <strong data-start=\"4\" data-end=\"12\">PMMA<\/strong>, i gruppi di tolleranza sono <strong data-start=\"39\" data-end=\"60\">130, 120 e 110<\/strong>.<\/li><li data-start=\"65\" data-end=\"193\">Per <strong data-start=\"69\" data-end=\"93\">POM (senza carica)<\/strong>, quando il <strong data-start=\"104\" data-end=\"142\">la lunghezza dello stampaggio \u00e8 inferiore a 150 mm<\/strong>, i gruppi di tolleranza sono <strong data-start=\"169\" data-end=\"190\">130, 120 e 110<\/strong>.<\/li><li data-start=\"195\" data-end=\"324\">Per <strong data-start=\"199\" data-end=\"223\">POM (senza carica)<\/strong>, quando il <strong data-start=\"234\" data-end=\"273\">la lunghezza dello stampaggio \u00e8 di 150 mm o superiore<\/strong>, i gruppi di tolleranza sono <strong data-start=\"300\" data-end=\"321\">150, 140 e 130<\/strong>.<\/li><li data-start=\"326\" data-end=\"400\">Per <strong data-start=\"330\" data-end=\"351\">POM (con carica)<\/strong>, i gruppi di tolleranza sono <strong data-start=\"378\" data-end=\"399\">140, 130 e 120<\/strong>.<\/li><\/ul><p class=\"translation-block\">Da questi esempi, possiamo vedere diversi punti importanti:<\/p><ul><li data-start=\"1450\" data-end=\"1569\"><strong data-start=\"1450\" data-end=\"1509\">Le diverse materie plastiche hanno una diversa stabilit\u00e0 dimensionale<\/strong>: Alcune materie plastiche sono pi\u00f9 difficili da controllare con precisione rispetto ad altre.<\/li><li data-start=\"1572\" data-end=\"1706\"><strong data-start=\"1572\" data-end=\"1633\">La presenza di riempitivi <\/strong>(come fibra di vetro, Talco, Carbonato di calcio)<strong data-start=\"1572\" data-end=\"1633\"> pu\u00f2 migliorare la stabilit\u00e0 dimensionale<\/strong>: I materiali con cariche sono generalmente pi\u00f9 stabili e pi\u00f9 facili da controllare.<\/li><li data-start=\"1707\" data-end=\"1879\"><p data-start=\"1709\" data-end=\"1879\" class=\"translation-block\"><strong data-start=\"1709\" data-end=\"1751\">I pezzi pi\u00f9 grandi richiedono tolleranze pi\u00f9 ampie<\/strong>: man mano che le dimensioni di base del pezzo aumentano, l'intervallo di tolleranza tipicamente diventa pi\u00f9 grande, rendendo pi\u00f9 difficile il controllo preciso.<\/p><\/li><\/ul><p data-start=\"1881\" data-end=\"2040\" data-is-last-node=\"\" data-is-only-node=\"\" class=\"translation-block\">Comprendendo i gruppi di tolleranza, i produttori possono selezionare i livelli di tolleranza appropriati in base al materiale, alle dimensioni della parte e al livello di precisione richiesto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62897fa elementor-widget elementor-widget-text-editor\" data-id=\"62897fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In sintesi, la norma DIN 16901 fornisce una guida fondamentale sulle tolleranze dimensionali per l'industria dello stampaggio a iniezione. Definisce diversi livelli di tolleranza in base al grado di impatto delle dimensioni e al tipo di materiale utilizzato, ma per le tolleranze di forma e di posizione \u00e8 necessario consultare altre norme.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dde3a1 elementor-widget elementor-widget-text-editor\" data-id=\"5dde3a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Access_to_DIN_16901\"><\/span>Accesso a DIN 16901<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">Il contenuto dettagliato della norma DIN 16901 non \u00e8 disponibile pubblicamente. Come la maggior parte degli standard ingegneristici, deve essere acquistato, quindi non troverete il documento completo online gratuitamente. Invece, forniamo i nostri valori di tolleranza sviluppati internamente dall'azienda, che sono descritti nella sezione sottostante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce0e86c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ce0e86c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50739bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50739bd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2ab0b8\" data-id=\"f2ab0b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d3cb53 elementor-widget elementor-widget-heading\" data-id=\"4d3cb53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"ISO_20457_The_Modern_Global_Standard_for_Plastic_Part_Tolerances\"><\/span>ISO 20457: Lo standard globale moderno per le tolleranze dei componenti plastici<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a23db78 elementor-widget elementor-widget-text-editor\" data-id=\"a23db78\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">La DIN\u202f16901 risale ai primi anni '80 e, sebbene sia ancora ampiamente citata, non \u00e8 mai stata aggiornata perch\u00e9 standard pi\u00f9 recenti e completi ne hanno infine sostituito il ruolo. L'ISO\u202f20457:2018 \u00e8 ora considerato il <strong>successore moderno e internazionale<\/strong> della DIN\u202f16901. Fornisce un sistema di tolleranze pi\u00f9 chiaro, pi\u00f9 prevedibile e pi\u00f9 coerente a livello globale per i componenti plastici stampati.<\/p><p class=\"translation-block\">L'ISO\u202f20457 introduce <strong>nove gradi di tolleranza (TG1\u2013TG9)<\/strong>, rispetto ai sei gruppi di tolleranza (110\u2013160) della DIN\u202f16901.<\/p><ul><li><strong>TG1<\/strong> \u00e8 il grado pi\u00f9 stretto.<\/li><li><strong>TG9<\/strong> \u00e8 la pi\u00f9 ampia. Nella produzione reale, solo un sottoinsieme di queste classi \u00e8 comunemente utilizzato.<\/li><\/ul><p class=\"translation-block\">La norma formalizza inoltre la distinzione tra due tipi di dimensioni:<\/p><ul><li><strong>W (dimensioni specifiche per utensile)<\/strong> \u2014 generalmente equivalente alle dimensioni di Tipo B nella DIN\u202f16901.<\/li><li><strong>NW (dimensioni non specifiche per utensile)<\/strong> \u2014 generalmente equivalente alle dimensioni di Tipo A nella DIN\u202f16901.<\/li><\/ul><p class=\"translation-block\">Ci\u00f2 rende il sistema pi\u00f9 facile da comprendere per chiunque abbia familiarit\u00e0 con la vecchia norma DIN.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07a277d elementor-widget elementor-widget-heading\" data-id=\"07a277d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_ISO_20457_Improves_Compared_to_DIN_16901\"><\/span>Cosa migliora la ISO 20457 rispetto alla DIN 16901<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71cd5c7 elementor-widget elementor-widget-text-editor\" data-id=\"71cd5c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>1. La DIN\u202f16901 definiva solo tolleranze dimensionali, non tolleranze geometriche<\/h4><p class=\"translation-block\">ISO\u202f20457 colma questa lacuna aggiungendo:<\/p><ul><li>tolleranze di posizione (Tabella 9)<\/li><li>tolleranze del profilo superficiale (Tabella 10)<\/li><li>uso obbligatorio di ISO 1101, ISO 5458, ISO 5459<\/li><li>tolleranze di profilo per superfici a forma libera<\/li><\/ul><p class=\"translation-block\">Ci\u00f2 porta la tolleranza geometrica dei componenti plastici allo stesso livello di completezza degli standard per i componenti metallici.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98cab72 elementor-widget elementor-widget-text-editor\" data-id=\"98cab72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>2. Il sistema di tolleranze della DIN\u202f16901 \u00e8 troppo semplificato<\/h4><p class=\"translation-block\">La DIN\u202f16901 assegna i gruppi di tolleranza basandosi solo sul <strong>tipo di materiale<\/strong> e sulla <strong>fascia dimensionale<\/strong>, trascurando fattori chiave che influenzano la precisione dello stampaggio a iniezione. Questo spesso comporta:<\/p><ul><li>tolleranze troppo lasche<\/li><li>tolleranze non realizzabili<\/li><li>disaccordi tra clienti e fornitori<\/li><\/ul><p class=\"translation-block\">L'ISO\u202f20457 risolve questo problema introducendo un <strong>sistema di punteggio a cinque fattori (P1\u2013P5)<\/strong>:<\/p><ol><li>processo di stampaggio (Tabella 4)<\/li><li>rigidezza del materiale (Tabella 5)<\/li><li>tasso di restringimento (Tabella 6)<\/li><li>anisotropia di ritiro (Tabella 7)<\/li><li>sforzo di produzione (Serie 1\u20134, Tabella 8)<\/li><\/ol><p class=\"translation-block\">Il punteggio totale determina il <strong>grado di tolleranza TG<\/strong>. Le tolleranze diventano quantificabili, prevedibili e pi\u00f9 facili da negoziare.<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5705e72 elementor-widget elementor-widget-text-editor\" data-id=\"5705e72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"3_DIN%E2%80%AF16901_ignores_the_fact_that_%E2%80%9Cthe_farther_from_the_datum_the_larger_the_error%E2%80%9D\"><\/span>3. La DIN\u202f16901 ignora il fatto che \u201cpi\u00f9 ci si allontana dal riferimento, maggiore \u00e8 l'errore\u201d<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">I componenti plastici accumulano errori dovuti a ritiro, deformazione e raffreddamento non uniforme. Questi effetti aumentano con la distanza dal riferimento, ma la DIN\u202f16901 non ne tiene conto.<\/p><p class=\"translation-block\"><strong>Come l'ISO\u202f20457 risolve questo problema:<\/strong> Introduce <strong>Dp<\/strong>, la distanza da una caratteristica all'origine del dato:<\/p><ul><li>le tolleranze di posizione dipendono da Dp (Tabella 9)<\/li><li>le tolleranze di profilo dipendono da Dp (Tabella 10)<\/li><\/ul><p class=\"translation-block\">Ci\u00f2 allinea i valori di tolleranza al comportamento fisico reale<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c046d32 elementor-widget elementor-widget-text-editor\" data-id=\"c046d32\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>4. La DIN\u202f16901 fornisce tolleranze ma nessuna regola di accettazione<\/h4><p class=\"translation-block\">La DIN\u202f16901 fornisce tabelle di tolleranza ma non definisce metodi di ispezione o criteri di accettazione.<\/p><p class=\"translation-block\">L'ISO\u202f20457 aggiunge <strong>ABF \u2014 Condizioni di accettazione per la produzione di parti stampate (Capitolo 8)<\/strong>, che chiarisce:<\/p><ul><li>cosa deve essere ispezionato<\/li><li>come gestire le deviazioni<\/li><li>come trattare le caratteristiche funzionali rispetto a quelle non funzionali<\/li><li>come gestire la variazione di ritiro<\/li><li>come documentare gli accordi<\/li><\/ul><p class=\"translation-block\">La ISO\u202f20457 \u00e8 la prima norma che combina regole di tolleranza e regole di accettazione in un sistema completo per componenti plastici stampati.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a14f1f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0a14f1f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d077de4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d077de4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3338b5a\" data-id=\"3338b5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99deb4b elementor-widget elementor-widget-heading\" data-id=\"99deb4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Boyans_Simplified_Injection_Molding_Tolerance_Chart\"><\/span>Diagramma di Tolleranza Semplificato per lo Stampaggio a Iniezione di Boyan<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed7f26 elementor-widget elementor-widget-text-editor\" data-id=\"4ed7f26\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Se non sei uno specialista dello stampaggio a iniezione e hai solo bisogno di parti stampate per il tuo prodotto, non \u00e8 necessario dedicare molto tempo allo studio di questi standard. Per semplificare le cose, <strong>Boyan ha creato una tabella delle tolleranze semplificata<\/strong> che funge da riferimento pratico per la maggior parte dei progetti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9707af3 elementor-widget elementor-widget-text-editor\" data-id=\"9707af3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; font-family: Arial, sans-serif; table-layout: fixed;\"><colgroup> <col style=\"width: 28%;\"> <col style=\"width: 12%;\"> <col style=\"width: 12%;\"> <col style=\"width: 12%;\"> <col style=\"width: 12%;\"> <col style=\"width: 12%;\"> <col style=\"width: 12%;\"> <\/colgroup><thead><tr><th style=\"border: 1px solid #000000; padding: 8px; text-align: left;\">Dimensione Nominale (mm)<\/th><th style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0-20<\/th><th style=\"border: 1px solid #000; padding: 8px; text-align: center;\">20-50<\/th><th style=\"border: 1px solid #000; padding: 8px; text-align: center;\">50-120<\/th><th style=\"border: 1px solid #000; padding: 8px; text-align: center;\">120-230<\/th><th style=\"border: 1px solid #000; padding: 8px; text-align: center;\">230-400<\/th><th style=\"border: 1px solid #000; padding: 8px; text-align: center;\">400-1000<\/th><\/tr><\/thead><tbody><tr><td style=\"border: 1px solid #000; padding: 8px;\">Molto stretto (\u00b1mm)<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.02<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.03<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.04<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.05<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.10<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.20<\/td><\/tr><tr><td style=\"border: 1px solid #000; padding: 8px;\">Stretto (\u00b1mm)<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.10<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.15<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.20<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.30<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.40<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.90<\/td><\/tr><tr><td style=\"border: 1px solid #000; padding: 8px;\">Normale (\u00b1mm)<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.20<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.25<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.35<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.55<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.80<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">1.80<\/td><\/tr><tr><td style=\"border: 1px solid #000; padding: 8px;\">Largo (\u00b1mm)<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.35<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.40<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.60<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">0.95<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">1.40<\/td><td style=\"border: 1px solid #000; padding: 8px; text-align: center;\">3.00<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30c37b6 elementor-widget elementor-widget-text-editor\" data-id=\"30c37b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Per componenti plastici di precisione generale, gli standard sopra menzionati funzionano bene. Quando un progetto richiede tolleranze ancora pi\u00f9 strette\u2014simili a <strong><a href=\"https:\/\/boyanmfg.com\/shop\/injection-mold-for-lego-brick-like-parts\/\">Componenti LEGO<\/a><\/strong>\u2014anche questi intervalli pi\u00f9 severi sono raggiungibili, ma solo sotto <strong>condizioni di produzione di precisione<\/strong>, che naturalmente comportano costi pi\u00f9 elevati. Nel nostro grafico, questo livello appare come la <strong>\u201cmolto stretto\u201d<\/strong> classe di tolleranza. Raggiungere tale accuratezza potrebbe richiedere la costruzione di un <strong>stampo di prova<\/strong> prima di impegnarsi nello stampo di produzione finale.<\/li><li>Poich\u00e9 questo grafico semplificato non distingue tra materiali diversi o tra tipi diversi di caratteristiche (come dimensione A rispetto a dimensione B), i valori dovrebbero essere considerati come <strong>linee guida approssimative piuttosto che limiti rigidi<\/strong>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28d9261 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"28d9261\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb7663f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb7663f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8ee725\" data-id=\"e8ee725\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be9d9b9 elementor-widget elementor-widget-heading\" data-id=\"be9d9b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Understanding_Injection_Molding_Tolerance_Components\"><\/span>Comprendere i Componenti della Tolleranza nello Stampaggio a Iniezione<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f98b4fd elementor-widget elementor-widget-text-editor\" data-id=\"f98b4fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">La scelta del giusto intervallo di tolleranza \u00e8 un passo fondamentale per garantire un montaggio e una funzionalit\u00e0 accurati dei pezzi. Le tolleranze sono costituite principalmente dalla dimensione nominale e dalle tolleranze superiori e inferiori. Ecco una guida concisa su come selezionare le tolleranze adeguate per le dimensioni corrispondenti:<\/p><h3><span class=\"ez-toc-section\" id=\"Norminal_dimension_Upper_and_Lower_Tolerances\"><\/span>Dimensione nominale, Tolleranze Superiore e Inferiore<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li>La tolleranza \u00e8 costituita dalla<strong> dimensione nominale<\/strong> e il <strong>tolleranze superiori e inferiori<\/strong>. La dimensione nominale \u00e8 la dimensione di base specificata, mentre le tolleranze superiori e inferiori definiscono l'intervallo di dimensioni accettabili intorno alla dimensione nominale.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-776d222 elementor-widget elementor-widget-image\" data-id=\"776d222\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"208\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/tolerance-band-for-molding.jpg\" class=\"attachment-large size-large wp-image-6681\" alt=\"banda di tolleranza per lo stampaggio a iniezione\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/tolerance-band-for-molding.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/tolerance-band-for-molding-300x178.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fee2d9 elementor-widget elementor-widget-text-editor\" data-id=\"7fee2d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Nello stampaggio a iniezione, la zona di tolleranza \u00e8 spesso <strong>simmetrica, come \u00b10,08 mm o \u00b10,15 mm<\/strong>. Questo fornisce ai produttori una dimensione target chiara da perseguire, perch\u00e9 la deviazione positiva e negativa dal target sono generalmente considerate ugualmente probabili.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8c9cc elementor-widget elementor-widget-text-editor\" data-id=\"1e8c9cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Choosing_Dimension_Range\"><\/span>Scelta dell'intervallo di dimensioni<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li>Facendo riferimento a norme di tolleranza come la DIN 16901, \u00e8 possibile determinare un intervallo di dimensioni adeguato per materiali specifici. Queste norme forniscono le tolleranze raccomandate per diversi tipi di dimensioni, come le dimensioni di tipo A e di tipo B.<\/li><\/ul><h3><span class=\"ez-toc-section\" id=\"Determining_Nominal_Dimensions\"><\/span>Determinazione delle dimensioni nominali<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li>Selezionare la dimensione nominale \u00e8 un passo critico, sebbene spesso non sia direttamente definita dagli standard di tolleranza. La dimensione nominale dovrebbe essere determinata in base all'intento di progettazione, ai requisiti funzionali e alla compatibilit\u00e0 di assemblaggio. Ad esempio, se un componente deve adattarsi strettamente con parti accoppiate, potrebbe essere necessaria una dimensione nominale pi\u00f9 piccola o pi\u00f9 precisa.<\/li><\/ul><h3><span class=\"ez-toc-section\" id=\"Considering_Practical_Application\"><\/span>Considerare l'applicazione pratica<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li>Quando si scelgono le tolleranze, si deve considerare anche l'ambiente di applicazione pratica del pezzo. Ad esempio, se il pezzo verr\u00e0 utilizzato in ambienti con notevoli variazioni di temperatura, potrebbe essere necessario un intervallo di tolleranza pi\u00f9 ampio per tenere conto dell'espansione o della contrazione termica.<\/li><\/ul><h3><span class=\"ez-toc-section\" id=\"Coordination_and_Verification\"><\/span>Coordinamento e verifica<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li>Una volta stabilite le tolleranze, dovrebbero essere riviste con il team di progettazione, il reparto di produzione e il personale di controllo qualit\u00e0 per garantire che siano sia producibili che in grado di soddisfare i requisiti prestazionali. Se necessario, dovrebbero essere effettuati test e validazioni per confermare che le tolleranze selezionate siano appropriate.<\/li><\/ul><p class=\"translation-block\">In sintesi, la scelta della tolleranza appropriata comporta una considerazione completa dei requisiti di progettazione, delle propriet\u00e0 dei materiali, dei metodi di lavorazione e degli ambienti di applicazione reali, per garantire la qualit\u00e0 e le prestazioni del prodotto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67366e2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"67366e2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06aa5bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06aa5bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9e580e\" data-id=\"b9e580e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62fee5b elementor-widget elementor-widget-heading\" data-id=\"62fee5b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Let_Boyan_Help_You_Select_the_Right_Injection_Molding_Tolerances\"><\/span>Lascia che Boyan ti Aiuti a Selezionare le Tolleranze Corrette per lo Stampaggio a Iniezione<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eec8bc elementor-widget elementor-widget-text-editor\" data-id=\"4eec8bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">La scelta di tolleranze adeguate \u00e8 fondamentale per garantire la qualit\u00e0 e la funzionalit\u00e0 dei pezzi in plastica. Data la morbidezza e l'elasticit\u00e0 delle materie plastiche, misurare con precisione le loro dimensioni pu\u00f2 essere una sfida. Offriamo la nostra esperienza per aiutarvi a determinare l'intervallo di tolleranza dimensionale adatto. Ecco il nostro approccio e la nostra metodologia:<\/p><h3><span class=\"ez-toc-section\" id=\"Focusing_on_Key_Dimensions\"><\/span>Concentrarsi sulle dimensioni chiave<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li>Per le dimensioni chiave che sono critiche per la funzionalit\u00e0 e la qualit\u00e0 complessiva del prodotto, stabiliamo intervalli di tolleranza rigorosi. Creiamo strumenti di misura specializzati, come i calibri go\/no-go, per garantire una misurazione precisa delle dimensioni.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aca52f1 elementor-widget elementor-widget-image\" data-id=\"aca52f1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/CNC-machined-3d-inspection-gauge-r8r89ue10ms2cdvjixfvmzrk1jqjq6yzwbswr37eee.jpg\" title=\"Misuratore di ispezione 3d lavorato a CNC\" alt=\"Calibro di ispezione 3d lavorato a CNC per il controllo della parte in plastica\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Uno strumento di ispezione lavorato a CNC in acciaio<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3459378 elementor-widget elementor-widget-image\" data-id=\"3459378\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/injection-mold-for-lego-brick-like-parts\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/cnc-machined-inspection-gauge-for-plastic-bricks-r8r87a9uev9yqllcgtmfun0dtsckrutavnvbpyzydg.jpg\" title=\"calibro di ispezione lavorato a macchina per mattoni di plastica\" alt=\"calibro di ispezione lavorato a macchina per mattoni di plastica\" loading=\"lazy\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Un altro misuratore di ispezione prodotto da CNC<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5414c4 elementor-widget elementor-widget-image\" data-id=\"b5414c4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"464\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/inspection-result-for-the-plastic-bricks.jpg\" class=\"attachment-large size-large wp-image-1044\" alt=\"risultato dell&#039;ispezione dei mattoni di plastica\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/inspection-result-for-the-plastic-bricks.jpg 700w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/inspection-result-for-the-plastic-bricks-600x398.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/inspection-result-for-the-plastic-bricks-300x199.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3414b29 elementor-widget elementor-widget-text-editor\" data-id=\"3414b29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Handling_Less_Important_Dimensions\"><\/span>Gestione delle dimensioni meno importanti<span class=\"ez-toc-section-end\"><\/span><\/h3><ul><li>Per le dimensioni secondarie meno critiche, in genere utilizziamo strumenti di misura standard come i calibri. Valutiamo anche l'adattamento di queste dimensioni utilizzando i pezzi corrispondenti per garantire la compatibilit\u00e0.<\/li><li>Oltre all'utilizzo di pezzi di montaggio per la misurazione, possiamo anche utilizzare strumenti di ispezione stampati in 3D per misurare la precisione dimensionale. Sebbene i prodotti stampati in 3D abbiano una precisione inferiore, tipicamente entro +\/- 0,1-0,2 mm, sono economici e hanno cicli di produzione brevi, il che li rende adatti ad applicazioni con requisiti di precisione leggermente inferiori.<\/li><li>A volte garantiamo solo l'adattamento senza fornire valori di tolleranza specifici. Come gi\u00e0 detto, \u00e8 difficile misurare con precisione le dimensioni della plastica, soprattutto per i materiali pi\u00f9 morbidi come TPE, TPU e silicone.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d913cfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d913cfc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-711222d\" data-id=\"711222d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76d7203 elementor-widget elementor-widget-image\" data-id=\"76d7203\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/3D-printed-samples-detecting-3D-contours-2-r8r8bgo0sczuc7iw2mmqxl24vfrazfecsc90i8szom.jpg\" title=\"Campioni stampati in 3D che rilevano contorni 3D 2\" alt=\"Campioni stampati in 3D per il rilevamento di contorni 3D, immagine 2\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0c19a23\" data-id=\"0c19a23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c6f057 elementor-widget elementor-widget-image\" data-id=\"1c6f057\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/3d-printed-inspection-gauge.jpg\" class=\"attachment-large size-large wp-image-6688\" alt=\"Misuratore di ispezione stampato in 3d\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/3d-printed-inspection-gauge.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/3d-printed-inspection-gauge-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a5b5f3 elementor-widget elementor-widget-text-editor\" data-id=\"7a5b5f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Information_and_Materials_Required_for_Effective_Tolerance_Determination\"><\/span>Informazioni e materiali necessari per un'efficace determinazione della tolleranza<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">Per svolgere questi compiti in modo pi\u00f9 efficace, abbiamo bisogno delle seguenti informazioni e materiali da parte vostra:<\/p><ul><li><strong>Scenari d'uso specifici del componente<\/strong>: La comprensione dell'ambiente e delle condizioni di utilizzo del pezzo ci aiuta a determinare con maggiore precisione l'intervallo di tolleranza.<\/li><li><strong>Esempi di parti abbinate<\/strong>: Se possibile, fornire campioni di altri pezzi che verranno utilizzati insieme al pezzo in questione pu\u00f2 aiutarci a valutare e testare meglio l'adattabilit\u00e0 delle tolleranze.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1391a0 elementor-widget elementor-widget-text-editor\" data-id=\"e1391a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Il nostro obiettivo \u00e8 aiutarvi a determinare le giuste tolleranze in modo economico ed efficiente. Questo approccio \u00e8 particolarmente vantaggioso per le piccole e medie imprese, in quanto consente di risparmiare tempo e costi, garantendo al contempo la qualit\u00e0 del prodotto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3a8235 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c3a8235\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-408f4c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"408f4c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b38303f\" data-id=\"b38303f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8696101 elementor-widget elementor-widget-heading\" data-id=\"8696101\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"FAQ\"><\/span>FAQ<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fcbcc2 elementor-widget elementor-widget-toggle\" data-id=\"4fcbcc2\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8361\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8361\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come si confronta la precisione delle parti stampate a iniezione con quella delle parti metalliche?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8361\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8361\"><p class=\"translation-block\">Un errore comune per chi non ha familiarit\u00e0 con le materie plastiche \u00e8 applicare direttamente le tolleranze delle parti metalliche ai pezzi stampati a iniezione.<\/p>\n<p class=\"translation-block\">Le materie plastiche si comportano in modo molto diverso: hanno una rigidit\u00e0 inferiore, una deformazione maggiore e le loro dimensioni finali sono influenzate da molti parametri di stampaggio. Una certa quantit\u00e0 di deformazione \u00e8 anche inevitabile. Per questi motivi, le parti in plastica generalmente non possono mantenere le stesse tolleranze strette delle parti metalliche lavorate.<\/p>\n<p class=\"translation-block\">Tuttavia, possiamo controllare strettamente <strong>le dimensioni critiche<\/strong> e ottenere alta precisione dove necessario (fino a <strong>\u00b10,02 mm<\/strong>). Per le dimensioni influenzate dalla deformazione naturale, ci concentriamo sui requisiti funzionali ed estetici piuttosto che forzare tolleranze irrealistiche.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8362\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8362\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gli utenti generali devono studiare standard come DIN 16901 o ISO 20457?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8362\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8362\"><p class=\"translation-block\">La maggior parte degli utenti non ha bisogno di studiare in dettaglio le norme DIN 16901 o ISO 20457. Questi standard sono utilizzati principalmente da ingegneri e team di qualit\u00e0. Per la maggior parte dei progetti, \u00e8 sufficiente capire cosa significa tolleranza, come influisce sulla funzione del pezzo e quali intervalli di tolleranza sono tipicamente raggiungibili. Ecco perch\u00e9 forniamo un grafico semplificato delle tolleranze basato sull'esperienza reale di produzione.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8363\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8363\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qual \u00e8 la differenza tra tolleranza dimensionale e tolleranza geometrica?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8363\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8363\"><p class=\"translation-block\">La tolleranza dimensionale controlla la dimensione di una caratteristica, mentre la tolleranza geometrica controlla la forma, la planarit\u00e0, il parallelismo, la rotondit\u00e0 e altre caratteristiche legate alla forma. La norma ISO 20457 pone maggiore enfasi sulle tolleranze geometriche rispetto a standard pi\u00f9 vecchi come la DIN 16901.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8364\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8364\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Il design della parte influisce sulle tolleranze raggiungibili?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8364\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8364\"><p class=\"translation-block\">S\u00ec. Caratteristiche come pareti lunghe e sottili, grandi superfici piane, nervature, perni e geometrie asimmetriche possono aumentare l'imbarcamento e rendere pi\u00f9 difficile il raggiungimento di tolleranze strette. Buone pratiche di progettazione\u2014spessore uniforme delle pareti, flusso bilanciato e angolo di sformo appropriato\u2014aiutano a migliorare la stabilit\u00e0 dimensionale.<\/p>\n<p class=\"translation-block\">\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8365\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-8365\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Diverse aree della stessa parte possono avere livelli di tolleranza differenti?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8365\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-8365\"><p class=\"translation-block\">S\u00ec. \u00c8 comune applicare tolleranze strette solo alle caratteristiche critiche (agganci a scatto, punti di allineamento, superfici di tenuta) e utilizzare tolleranze standard per le aree non critiche. Questo approccio riduce i costi garantendo al contempo le prestazioni funzionali.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8366\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-8366\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Se una dimensione non ha una tolleranza specificata, deve rispettare la tolleranza generale?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8366\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-8366\"><p class=\"translation-block\">Non proprio.<\/p>\n<p class=\"translation-block\">Secondo la norma ISO 20457:2018, un componente \u00e8 accettabile purch\u00e9 soddisfi i suoi <strong>requisiti funzionali e d'uso<\/strong>, anche se alcune dimensioni escono dalla tolleranza generale\u2014a meno che non sia diversamente concordato.<\/p>\n<p class=\"translation-block\">L'unica eccezione \u00e8 quando una deviazione influisce sull'aspetto o sulla percezione dell'utente, anche se il pezzo funziona ancora correttamente.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8367\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-8367\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00c8 possibile ottenere tolleranze molto strette per parti simili ai mattoncini LEGO?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8367\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-8367\"><p class=\"translation-block\">S\u00ec, ma raggiungere tale precisione spesso richiede:<\/p>\n<ul>\n<li>Utensileria ad alta precisione<\/li>\n<li>Condizioni di stampaggio stabili e ripetibili<\/li>\n<li>Materiali con basso ritiro<\/li>\n<li>In alcuni casi, una <strong>stampo di prova<\/strong> prima di costruire lo stampo di produzione finale<\/li>\n<\/ul>\n<p class=\"translation-block\">Questi passaggi aiutano a confermare se la precisione richiesta \u00e8 realistica e ripetibile.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8368\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-8368\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come scelgo la tolleranza giusta per il mio pezzo?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8368\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-8368\"><p class=\"translation-block\">Inizia considerando:<\/p>\n<ul>\n<li>Requisiti funzionali del componente<\/li>\n<li>Se le caratteristiche devono incastrarsi, agganciarsi o scorrere insieme<\/li>\n<li>Caratteristiche di ritiro del materiale<\/li>\n<li>Compromessi tra costo e precisione<\/li>\n<\/ul>\n<p class=\"translation-block\">Se non sei sicuro, il nostro team di ingegneria pu\u00f2 rivedere il tuo design e raccomandare tolleranze appropriate.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8369\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-8369\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Tolleranze pi\u00f9 strette significano sempre costi pi\u00f9 alti?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8369\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-8369\"><p class=\"translation-block\">Generalmente s\u00ec. Tolleranze pi\u00f9 strette richiedono:<\/p>\n<ul>\n<li>Utensileria pi\u00f9 precisa<\/li>\n<li>Controllo di processo pi\u00f9 rigoroso<\/li>\n<li>Tempi di ciclo pi\u00f9 lunghi<\/li>\n<li>Ulteriori ispezioni e controlli qualit\u00e0<\/li>\n<\/ul>\n<p class=\"translation-block\">Per la maggior parte dei pezzi, un intervallo di tolleranza standard \u00e8 sufficiente e pi\u00f9 conveniente.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83610\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-83610\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Boyan pu\u00f2 aiutare a verificare se i miei requisiti di tolleranza sono raggiungibili?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83610\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-83610\"><p class=\"translation-block\">S\u00ec. Se condividi il tuo modello CAD e i requisiti di tolleranza, possiamo valutare la fattibilit\u00e0 e suggerire eventuali modifiche. Per tolleranze estremamente strette, potremmo raccomandare di costruire prima uno stampo di prova per convalidare il design.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8a939 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1e8a939\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d68acf4 elementor-widget elementor-widget-spacer\" data-id=\"d68acf4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f135ba1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f135ba1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f988217\" data-id=\"f988217\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b52235 elementor-widget elementor-widget-menu-anchor\" data-id=\"0b52235\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"standards\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2758be elementor-widget elementor-widget-heading\" data-id=\"f2758be\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Appendix_Common_Standards_for_Injection_Molded_Parts\"><\/span>Appendice: Standard Comuni per i Componenti Stampati a Iniezione<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81c7091 elementor-widget elementor-widget-text-editor\" data-id=\"81c7091\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nel processo di produzione e progettazione dei pezzi stampati a iniezione, si fa comunemente riferimento a diversi standard per garantire la qualit\u00e0 e la coerenza del prodotto. Di seguito sono elencati per un rapido riferimento:<\/p><ul><li><strong>DIN 16901: 1982-11<\/strong>\u00a0 \u2014 Questa norma tedesca affronta specificamente le tolleranze dimensionali e le deviazioni per i componenti stampati in plastica, applicabili a una variet\u00e0 di materiali plastici utilizzati nello stampaggio a iniezione.<\/li><li><strong>ISO 20457: 2018 <\/strong>\u2014 Questa norma internazionale offre una guida completa alle tolleranze dimensionali per i pezzi stampati in plastica, applicabile a vari metodi di lavorazione della plastica.<\/li><li><strong>DIN 16742 \u2014 <\/strong>\u00c8 uno standard per le tolleranze generali e le condizioni di accettazione dei pezzi stampati in plastica. Si applica non solo allo stampaggio a iniezione, ma anche allo stampaggio a compressione e all'estrusione.<\/li><li><strong>GB\/T 14486-2008 \u2014 <\/strong>Questa \u00e8 una norma nazionale cinese, che copre le specifiche di tolleranza dimensionale per i pezzi stampati in plastica, adatta a vari metodi di lavorazione della plastica.<\/li><li><strong>Norma dell'Industria Automobilistica QC-T-29017-1991 \u2014 <\/strong>Questa specifica norma per l'industria automobilistica cinese dettaglia le tolleranze dimensionali per i componenti stampati in plastica all'interno del settore automobilistico.<\/li><li><strong>SAIC Standard MGR ES.22.PL.103 \u2014 <\/strong>Questa \u00e8 una norma aziendale della SAIC Motor Corporation Limited in Cina, che guida specificamente le tolleranze dimensionali nella progettazione e produzione di parti in plastica all'interno dell'azienda.<\/li><li><a href=\"https:\/\/www.dau-components.co.uk\/doc\/General_Tolerances_-DIN_-ISO_-2768.pdf\" target=\"_blank\" rel=\"noopener\"><strong>ISO 2768<\/strong><\/a> \u2014 Questa norma internazionale \u00e8 applicabile ai pezzi lavorati, inclusi i componenti in plastica, dove tolleranze specifiche non sono esplicitamente indicate.<\/li><li><strong>JIS B 0401 \u2014 <\/strong>Questa norma industriale giapponese, simile alla ISO 2768, fornisce linee guida per le dimensioni non specificamente indicate con tolleranze nei disegni di ingegneria meccanica.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd53cd1 elementor-widget elementor-widget-text-editor\" data-id=\"fd53cd1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Tra queste norme, la ISO 2768 \u00e8 forse la pi\u00f9 nota. Tuttavia, si tratta di uno standard generale per tolleranze non specificate e non \u00e8 stato progettato specificamente per i pezzi stampati a iniezione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49980bc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"49980bc\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-975c154 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"975c154\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3381143\" data-id=\"3381143\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98775a3 elementor-widget elementor-widget-spacer\" data-id=\"98775a3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6797600 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6797600\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddd92d6\" data-id=\"ddd92d6\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ce9beee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce9beee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-eceb6ff\" data-id=\"eceb6ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd49a3f elementor-widget elementor-widget-image\" data-id=\"dd49a3f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png\" class=\"attachment-large size-large wp-image-6453\" alt=\"Scatola triangolare sovrastampata in TPU\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-99fd0f5\" data-id=\"99fd0f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a855b3d elementor-widget elementor-widget-heading\" data-id=\"a855b3d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Siamo esperti nello stampaggio a iniezione di materie plastiche. Contattateci subito per ottenere un rapido preventivo!<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8eb2297\" data-id=\"8eb2297\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b835413 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"b835413\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Perch\u00e9 le tolleranze dello stampaggio a iniezione sono importanti? Nel processo di produzione dei componenti stampati a iniezione, le variazioni dimensionali sono inevitabili a causa delle influenze dello stampo, della macchina per lo stampaggio a iniezione, dei materiali e dei fattori ambientali. Pertanto, stabilire tolleranze ragionevoli per le dimensioni del prodotto e garantire che le rispettino \u00e8 fondamentale. Tolleranze appropriate possono: Assicurare che i componenti funzionino correttamente,\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/it\/injection-molding-tolerances\/\" rel=\"bookmark\">Continua a leggere \u00bb<span class=\"screen-reader-text\">Tolleranze per lo stampaggio a iniezione: DIN 16901, ISO 20457 e le nostre linee guida pratiche<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":6709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":91,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72,57],"tags":[],"class_list":["post-6650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding","category-working-with-boyan"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts\/6650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/comments?post=6650"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/posts\/6650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/media\/6709"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/media?parent=6650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/categories?post=6650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/it\/wp-json\/wp\/v2\/tags?post=6650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}