{"id":7519,"date":"2024-01-12T07:00:10","date_gmt":"2024-01-12T07:00:10","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=7519"},"modified":"2025-09-23T15:25:07","modified_gmt":"2025-09-23T15:25:07","slug":"printing-on-plastic-methods-guide","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/","title":{"rendered":"Les 3 principales m\u00e9thodes d'impression sur plastique : s\u00e9rigraphie, tampographie et gravure au laser"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"7519\" class=\"elementor elementor-7519\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69a2ea9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69a2ea9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-903c248\" data-id=\"903c248\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-888cbb1 elementor-widget elementor-widget-heading\" data-id=\"888cbb1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table des mati\u00e8res\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Types_of_Printing_on_Plastic_Parts\" >Types d'impression sur des pi\u00e8ces en plastique<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Screen_Printing\" >S\u00e9rigraphie<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#How_Screen_Printing_works\" >Comment fonctionne la s\u00e9rigraphie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Advantages_of_Screen_Printing\" >Avantages de la s\u00e9rigraphie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Disadvantages_of_Screen_Printing\" >Inconv\u00e9nients de la s\u00e9rigraphie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Ink_Curing_Processes\" >Proc\u00e9d\u00e9s de s\u00e9chage de l'encre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Rotary_Screen_Printing_%E2%80%94_Video_Walkthrough\" >S\u00e9rigraphie rotative - Pr\u00e9sentation vid\u00e9o<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Pad_Printing\" >Tampographie<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#How_Pad_Printing_Workds\" >Comment fonctionne la tampographie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Advantages_of_Pad_Printing\" >Avantages de la tampographie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Disadvantages_of_Pad_Printing\" >Inconv\u00e9nients de la tampographie<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Ink_Requirements_for_Screen_Pad_Printing\" >Exigences en mati\u00e8re d'encre pour la s\u00e9rigraphie et la tampographie<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Ink_Adhesion_to_Substrate\" >Adh\u00e9sion de l'encre au support<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Alcohol_Resistance\" >R\u00e9sistance \u00e0 l'alcool<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#UV_Resistance_Sunlight_Exposure\" >R\u00e9sistance aux UV (exposition au soleil)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Laser_Etching\" >Gravure au laser<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#How_Laser_Etching_Works\" >Comment fonctionne la gravure au laser ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Advantages_of_Laser_Marking\" >Avantages du marquage au laser<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Disadvantages_of_Laser_Marking\" >Inconv\u00e9nients du marquage au laser<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#Conclusion\" >Conclusion<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/#We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\" >Nous sommes experts en moulage par injection de plastique. Contactez-nous d\u00e8s maintenant pour obtenir un devis rapide !<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Types_of_Printing_on_Plastic_Parts\"><\/span>Types d'impression sur des pi\u00e8ces en plastique<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2327e8 elementor-widget elementor-widget-text-editor\" data-id=\"e2327e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Lors de la production d'articles en plastique, il est courant d'imprimer une s\u00e9rie de <strong>dessins<\/strong> ou<strong>de textes<\/strong> sur leurs surfaces afin d'en am\u00e9liorer l'attrait visuel. Il s'agit souvent d'ajouter des \u00e9l\u00e9ments tels que des <strong>logos d'entreprise, des num\u00e9ros de mod\u00e8le de produit et divers autres motifs ou \u0153uvres d'art<\/strong>.<\/p><p class=\"translation-block\">Actuellement, il existe une vari\u00e9t\u00e9 de techniques pour appliquer ces impressions sur des pi\u00e8ces en plastique. Parmi elles, la <strong>s\u00e9rigraphie, la tampographie<\/strong> et la <strong>gravure au laser<\/strong> sont les m\u00e9thodes les plus utilis\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc274a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc274a3\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aee8ba6\" data-id=\"aee8ba6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20dcaac elementor-widget elementor-widget-menu-anchor\" data-id=\"20dcaac\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"screen_printing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f29c2d elementor-widget elementor-widget-heading\" data-id=\"7f29c2d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Screen_Printing\"><\/span>S\u00e9rigraphie<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f575aa elementor-widget elementor-widget-heading\" data-id=\"3f575aa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"How_Screen_Printing_works\"><\/span>Comment fonctionne la s\u00e9rigraphie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6796ea elementor-widget elementor-widget-text-editor\" data-id=\"a6796ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><a href=\"https:\/\/simple.wikipedia.org\/wiki\/Screen_printing\" target=\"_blank\" rel=\"noopener\">La s\u00e9rigraphie<\/a> fonctionne selon les principes de base du \u201cblocage\u201d et de la \u201cperm\u00e9abilit\u00e9 \u00e0 l'encre\u201d. Ce processus peut \u00eatre d\u00e9compos\u00e9 en plusieurs \u00e9tapes cl\u00e9s :<\/p><p class=\"translation-block\"><strong>1. Cr\u00e9ation du cadre de l'\u00e9cran<\/strong> : Au d\u00e9part, un <strong>cadre<\/strong> est n\u00e9cessaire, g\u00e9n\u00e9ralement en bois ou en m\u00e9tal. Un <strong>maillot de moustiquaire<\/strong>, g\u00e9n\u00e9ralement une fine maille de nylon ou de polyester, est <strong>tendu \u00e9troitement sur ce cadre.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-847aae2 elementor-widget elementor-widget-image\" data-id=\"847aae2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-frame-front.jpg\" class=\"attachment-large size-large wp-image-7537\" alt=\"cadre de s\u00e9rigraphie face avant\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-frame-front.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-frame-front-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5341d25 elementor-widget elementor-widget-text-editor\" data-id=\"5341d25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">&lt;Application de l&#039;\u00e9mulsion photo<\/strong> : Une couche d'<strong>\u00e9mulsion photosensible<\/strong> est appliqu\u00e9e uniform\u00e9ment sur l'\u00e9cran. Une fois expos\u00e9e \u00e0 la lumi\u00e8re, cette \u00e9mulsion durcit, tandis que les zones non expos\u00e9es restent souples et peuvent \u00eatre lav\u00e9es \u00e0 l'eau.<\/p><p class=\"translation-block\">&lt;Exposition<\/strong> : le motif pr\u00e9par\u00e9 (g\u00e9n\u00e9ralement un motif noir sur un film transparent) est plac\u00e9 sur l'\u00e9cran recouvert de l'\u00e9mulsion photo, puis il est expos\u00e9 \u00e0 la lumi\u00e8re. Apr\u00e8s l'exposition, les zones de l'\u00e9mulsion situ\u00e9es sous le motif restent souples.<\/p><p class=\"translation-block\"><strong>4. d\u00e9veloppement<\/strong> : Apr\u00e8s l'exposition, l'\u00e9cran est lav\u00e9 \u00e0 l'eau. L'\u00e9mulsion <strong>non expos\u00e9e<\/strong> est lav\u00e9e, r\u00e9v\u00e9lant les d\u00e9tails du motif. De cette fa\u00e7on, l'encre ne peut passer qu'\u00e0 travers ces parties non obstru\u00e9es de la maille.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b086d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b086d1\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03e3ba0\" data-id=\"03e3ba0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7dbbc33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dbbc33\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-93e0758\" data-id=\"93e0758\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7e129a elementor-widget elementor-widget-image\" data-id=\"b7e129a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-frame.jpg\" class=\"attachment-large size-large wp-image-7529\" alt=\"Le cadre pour la s\u00e9rigraphie 2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-frame.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-frame-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-afee8a7\" data-id=\"afee8a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68a2bd7 elementor-widget elementor-widget-image\" data-id=\"68a2bd7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-mesh.jpg\" class=\"attachment-large size-large wp-image-7530\" alt=\"gros plan de la maille de l&#039;\u00e9cran d&#039;impression\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-mesh.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-mesh-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e5db24 elementor-widget elementor-widget-text-editor\" data-id=\"2e5db24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">L'image montre l'aspect g\u00e9n\u00e9ral de l'ensemble du cadre de s\u00e9rigraphie, ainsi qu'un gros plan de la structure des mailles du cadre.<\/p><p class=\"translation-block\">L'image montre que les mailles correspondant au dessin sont ouvertes et laissent passer l'encre, tandis que les autres mailles sont recouvertes d'une \u00e9mulsion photosensible qui bloque l'encre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e09b47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e09b47\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e8e7f6\" data-id=\"4e8e7f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-baa68da elementor-widget elementor-widget-text-editor\" data-id=\"baa68da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>5. Impression<\/strong> : L'\u00e9cran est plac\u00e9 au-dessus du mat\u00e9riau \u00e0 imprimer. L'encre est vers\u00e9e dessus et une raclette est utilis\u00e9e pour presser uniform\u00e9ment l'encre sur le mat\u00e9riau \u00e0 travers les zones non obstru\u00e9es du tissu.<\/p><p class=\"translation-block\">&lt;Nettoyage et r\u00e9utilisation<\/strong> : Apr\u00e8s l'impression, l'\u00e9cran est soigneusement nettoy\u00e9 pour \u00e9liminer toute l'encre et l'\u00e9mulsion, ce qui le rend pr\u00eat pour une utilisation ult\u00e9rieure.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eeae66f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eeae66f\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9c8cce\" data-id=\"f9c8cce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e3ecef elementor-widget elementor-widget-text-editor\" data-id=\"5e3ecef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" class=\"translation-block\"><strong>Exemples de s\u00e9rigraphie<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f5ed8d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5ed8d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b48ec7d\" data-id=\"b48ec7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f99829 elementor-widget elementor-widget-image\" data-id=\"3f99829\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-1.jpg\" class=\"attachment-large size-large wp-image-7550\" alt=\"exemple de s\u00e9rigraphie 1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-1-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-40b896b\" data-id=\"40b896b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7277130 elementor-widget elementor-widget-image\" data-id=\"7277130\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-2.jpg\" class=\"attachment-large size-large wp-image-7551\" alt=\"exemple de s\u00e9rigraphie 2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-2-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8ac08fb\" data-id=\"8ac08fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43cc5eb elementor-widget elementor-widget-image\" data-id=\"43cc5eb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-3.jpg\" class=\"attachment-large size-large wp-image-7552\" alt=\"exemple de s\u00e9rigraphie 3\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-3.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/screen-printing-example-3-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-913c19a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"913c19a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebe37c4\" data-id=\"ebe37c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ab1290 elementor-widget elementor-widget-text-editor\" data-id=\"5ab1290\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Advantages_of_Screen_Printing\"><\/span>Avantages de la s\u00e9rigraphie<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">&lt;Polyvalence<\/strong> : la s\u00e9rigraphie peut \u00eatre appliqu\u00e9e \u00e0 un large \u00e9ventail de mat\u00e9riaux, tels que le papier, le plastique, le m\u00e9tal, le verre, le bois et m\u00eame le tissu.<\/p><p class=\"translation-block\"><strong>Couches d'encre durables et \u00e9paisses<\/strong> : la couche d'encre de la s\u00e9rigraphie est plus \u00e9paisse que celle des autres m\u00e9thodes d'impression, ce qui permet d'obtenir des couleurs plus vives et une bonne r\u00e9sistance \u00e0 la lumi\u00e8re et \u00e0 l'usure.<\/p><p class=\"translation-block\"><strong>Couleurs \u00e9clatantes<\/strong> : Gr\u00e2ce au transfert direct de l'encre de l'\u00e9cran au mat\u00e9riau, la saturation des couleurs est \u00e9lev\u00e9e, ce qui permet d'obtenir des effets saisissants.<\/p><p class=\"translation-block\"><strong>Efficacit\u00e9 pour la production de masse<\/strong> : la s\u00e9rigraphie est tr\u00e8s rentable pour la production \u00e0 grande \u00e9chelle. Une fois le mod\u00e8le \u00e9tabli, elle permet une reproduction rapide et \u00e9conomique.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c4d6b7 elementor-widget elementor-widget-text-editor\" data-id=\"7c4d6b7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Disadvantages_of_Screen_Printing\"><\/span>Inconv\u00e9nients de la s\u00e9rigraphie<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\"><strong>Limites de la surface d'impression<\/strong> : La surface d'impression doit \u00eatre aussi plate que possible. Les surfaces irr\u00e9guli\u00e8res peuvent entra\u00eener une r\u00e9partition in\u00e9gale de l'encre. Des creux excessifs peuvent emp\u00eacher l'\u00e9cran d'entrer en contact avec la surface, ce qui g\u00eane l'impression.<\/p><p class=\"translation-block\"><strong>D\u00e9fis pos\u00e9s par les surfaces cylindriques<\/strong> : La s\u00e9rigraphie sur des surfaces cylindriques est possible, mais elle exige que l'\u00e9cran se d\u00e9place en synchronisation avec la rotation du produit, ce qui augmente la complexit\u00e9 et le co\u00fbt. Cette m\u00e9thode est moins adapt\u00e9e \u00e0 la production \u00e0 petite \u00e9chelle.<\/p><p class=\"translation-block\"><strong>Volume requis<\/strong> : la s\u00e9rigraphie est g\u00e9n\u00e9ralement plus adapt\u00e9e \u00e0 la production \u00e0 grande \u00e9chelle en raison de la n\u00e9cessit\u00e9 d'utiliser des gabarits et des fixations pour positionner les produits pendant l'impression. Il existe des montages simples et des montages complets pour les petits et les grands volumes, respectivement. Le positionnement manuel avec des montages simples peut avoir un taux d'erreur plus \u00e9lev\u00e9.<\/p><p class=\"translation-block\"><strong>Limitations des couleurs<\/strong> : chaque couleur n\u00e9cessite un \u00e9cran s\u00e9par\u00e9. G\u00e9n\u00e9ralement utilis\u00e9 pour les couleurs simples, doubles ou triples, l'augmentation du nombre de couleurs peut accro\u00eetre les difficult\u00e9s et les co\u00fbts de production, avec un risque suppl\u00e9mentaire de d\u00e9salignement entre les diff\u00e9rentes couleurs.<\/p><p class=\"translation-block\"><strong>Limitations de la r\u00e9solution<\/strong> : Compar\u00e9e \u00e0 d'autres technologies d'impression comme l'impression num\u00e9rique, la s\u00e9rigraphie offre un niveau de d\u00e9tail et de r\u00e9solution inf\u00e9rieur.<\/p><p class=\"translation-block\"><strong>Nettoyage et entretien<\/strong> : Un nettoyage et un entretien r\u00e9guliers de l'\u00e9cran sont n\u00e9cessaires, en particulier dans les environnements de production \u00e0 haute intensit\u00e9.<\/p><p class=\"translation-block\"><strong>Inqui\u00e9tudes environnementales<\/strong> : Certains solvants et encres utilis\u00e9s en s\u00e9rigraphie peuvent \u00eatre nocifs pour l'environnement. Il est important de s'assurer que les encres sont conformes aux normes environnementales telles que RoHS et REACH.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3af5e84 elementor-widget elementor-widget-text-editor\" data-id=\"3af5e84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Ink_Curing_Processes\"><\/span>Proc\u00e9d\u00e9s de s\u00e9chage de l'encre<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\"><strong>Assurer la durabilit\u00e9 par le durcissement<\/strong> Pour que les encres atteignent une adh\u00e9rence et une durabilit\u00e9 optimales, un processus de durcissement est essentiel. Il existe deux principaux types de m\u00e9thodes de durcissement :<\/p><p class=\"translation-block\"><strong>Coloration thermique<\/strong> : dans cette m\u00e9thode, les articles imprim\u00e9s sont plac\u00e9s dans une chambre \u00e0 temp\u00e9rature constante. Ils sont expos\u00e9s \u00e0 un rayonnement infrarouge lointain ou chauff\u00e9s \u00e0 l'air chaud, ce qui d\u00e9clenche une r\u00e9action thermique qui durcit l'encre. La temp\u00e9rature est g\u00e9n\u00e9ralement comprise entre 60\u00b0C et 100\u00b0C, et peut parfois atteindre 150\u00b0C.<\/p><p class=\"translation-block\">En g\u00e9n\u00e9ral, des temp\u00e9ratures de durcissement plus \u00e9lev\u00e9es permettent d'obtenir de meilleurs r\u00e9sultats d'impression. Toutefois, le traitement \u00e0 haute temp\u00e9rature peut entra\u00eener un r\u00e9tr\u00e9cissement et une d\u00e9formation, et tout d\u00e9pend donc de la mati\u00e8re plastique sur laquelle l'impression est r\u00e9alis\u00e9e.<\/p><p class=\"translation-block\"><strong>S\u00e9chage UV<\/strong> : cette m\u00e9thode consiste \u00e0 exposer les articles imprim\u00e9s \u00e0 des longueurs d'onde sp\u00e9cifiques de la lumi\u00e8re ultraviolette (UV). Le processus photor\u00e9actif sous la lumi\u00e8re UV provoque le durcissement de l'encre. Le s\u00e9chage UV est une m\u00e9thode efficace pour solidifier rapidement l'encre et est particuli\u00e8rement utile pour certains types de formulations d'encre et d'applications d'impression.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00dce11 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00dce11\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53e547d\" data-id=\"53e547d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bffbd6f elementor-widget elementor-widget-heading\" data-id=\"bffbd6f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Rotary_Screen_Printing_%E2%80%94_Video_Walkthrough\"><\/span>S\u00e9rigraphie rotative - Pr\u00e9sentation vid\u00e9o<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54357c2 elementor-widget elementor-widget-text-editor\" data-id=\"54357c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong data-start=\"53\" data-end=\"73\">Ce que vous allez voir.<\/strong> Cette vid\u00e9o montre rapidement comment fonctionne la s\u00e9rigraphie : l'encre est pouss\u00e9e par une raclette \u00e0 travers les zones ouvertes d'un pochoir (\u00e9cran) sur un substrat en plastique, puis elle s\u00e8che et durcit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ffc943e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffc943e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f9867c\" data-id=\"4f9867c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e13b695 elementor-widget elementor-widget-image\" data-id=\"e13b695\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/boyanmfg.com\/shop\/plastic-adjustment-knob-rotary-screen-printing\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Plastic-control-Knob-1.jpg\" class=\"attachment-large size-large wp-image-9790\" alt=\"Vue de face d&#039;un bouton de r\u00e9glage en plastique avec des rep\u00e8res d&#039;\u00e9chelle imprim\u00e9s sur la surface, avec un design textur\u00e9 pour une meilleure prise en main.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Plastic-control-Knob-1.jpg 750w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Plastic-control-Knob-1-300x225.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Plastic-control-Knob-1-600x450.jpg 600w\" sizes=\"(max-width: 750px) 100vw, 750px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a2cab1\" data-id=\"5a2cab1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2417aa5 elementor-widget elementor-widget-video\" data-id=\"2417aa5\" data-element_type=\"widget\" data-settings='{\"youtube_url\":\"https:\\\/\\\/www.youtube.com\\\/watch?v=k2e-dGuE-VI\",\"video_type\":\"youtube\",\"controls\":\"yes\"}' data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e23c7 elementor-widget elementor-widget-text-editor\" data-id=\"26e23c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"260\" data-end=\"428\" class=\"translation-block\"><strong data-start=\"260\" data-end=\"289\">Du plat au cylindrique.<\/strong> La s\u00e9rigraphie est g\u00e9n\u00e9ralement utilis\u00e9e sur des pi\u00e8ces plates sans protub\u00e9rance. Avec la s\u00e9rigraphie rotative, la m\u00e9thode s'\u00e9tend aux pi\u00e8ces cylindriques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9348ad elementor-widget elementor-widget-text-editor\" data-id=\"a9348ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"430\" data-end=\"720\" class=\"translation-block\"><strong data-start=\"430\" data-end=\"469\">Mouvement synchronis\u00e9 (comment \u00e7a tourne).<\/strong> La pi\u00e8ce tourne en synchronisation avec l'\u00e9cran. Dans cet exemple, un entra\u00eenement \u00e0 cr\u00e9maill\u00e8re couple le mouvement avec pr\u00e9cision. Certains syst\u00e8mes s'appuient sur la friction entre l'\u00e9cran et la pi\u00e8ce pour la faire tourner, mais nous pr\u00e9f\u00e9rons les engrenages positifs pour \u00e9viter le glissement et le flou qu'il provoque.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aa1b22 elementor-widget elementor-widget-image\" data-id=\"4aa1b22\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"406\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Alignment-for-Accurate-Printing.jpg\" class=\"attachment-large size-large wp-image-9793\" alt=\"Vue rapproch\u00e9e montrant les filets int\u00e9rieurs du bouton de r\u00e9glage en plastique align\u00e9s sur les bossages en relief de l&#039;arbre de positionnement.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Alignment-for-Accurate-Printing.jpg 900w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Alignment-for-Accurate-Printing-300x135.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Alignment-for-Accurate-Printing-768x346.jpg 768w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/09\/Alignment-for-Accurate-Printing-600x271.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Vue rapproch\u00e9e des filets int\u00e9rieurs du bouton de r\u00e9glage en plastique, qui s'alignent sur les bossages en relief de l'arbre de positionnement pour un alignement pr\u00e9cis de l'impression.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84c68d2 elementor-widget elementor-widget-text-editor\" data-id=\"84c68d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"722\" data-end=\"894\" class=\"translation-block\"><strong data-start=\"722\" data-end=\"742\">Fixation et ajustement.<\/strong> La pi\u00e8ce s'engage dans un bouton de positionnement\/localisateur. L'ajustement doit \u00eatre pr\u00e9cis : un ajustement trop l\u00e2che entra\u00eene un maculage de l'impression ; un ajustement trop serr\u00e9 rend l'insertion difficile et risque de l'endommager.<\/p><p data-start=\"896\" data-end=\"1131\" class=\"translation-block\"><strong data-start=\"896\" data-end=\"923\">Enregistrement et qualit\u00e9.<\/strong> Les num\u00e9ros imprim\u00e9s et la rainure interne s'alignent sur des positions de r\u00e9f\u00e9rence fixes - rien n'est al\u00e9atoire. La s\u00e9rigraphie rotative exige une attention particuli\u00e8re aux d\u00e9tails afin d'obtenir une clart\u00e9, une pr\u00e9cision et une forte adh\u00e9rence.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-453a949 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"453a949\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68e4321 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68e4321\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-216fa21\" data-id=\"216fa21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d91ae0c elementor-widget elementor-widget-menu-anchor\" data-id=\"d91ae0c\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"pad_printing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c050342 elementor-widget elementor-widget-heading\" data-id=\"c050342\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Pad_Printing\"><\/span>Tampographie<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eae81a elementor-widget elementor-widget-heading\" data-id=\"9eae81a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"How_Pad_Printing_Workds\"><\/span>Comment fonctionne la tampographie<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c49e20a elementor-widget elementor-widget-text-editor\" data-id=\"c49e20a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">&lt;La tampographie est une technique d&#039;impression indirecte, principalement utilis\u00e9e pour imprimer sur des surfaces irr\u00e9guli\u00e8res ou des mat\u00e9riaux difficiles \u00e0 imprimer. Les \u00e9tapes de base de la tampographie peuvent \u00eatre r\u00e9sum\u00e9es comme suit :<\/p><p class=\"translation-block\"><strong>1. Fabrication de la plaque et gravure<\/strong> : Au d\u00e9part, on cr\u00e9e une plaque d'impression avec le motif souhait\u00e9, g\u00e9n\u00e9ralement fabriqu\u00e9e \u00e0 partir de m\u00e9taux tels que l'acier ou le cuivre. La zone du motif est grav\u00e9e avec de minuscules \u00e9videments.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91d1b3b elementor-widget elementor-widget-image\" data-id=\"91d1b3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/plate-and-pad-for-printing.jpg\" class=\"attachment-large size-large wp-image-7541\" alt=\"plaque et tampon pour la tampographie\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/plate-and-pad-for-printing.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/plate-and-pad-for-printing-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">L'assiette et le tampon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7767f98 elementor-widget elementor-widget-text-editor\" data-id=\"7767f98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">&lt;2) Remplissage d&#039;encre<\/strong> : l'encre est ensuite ins\u00e9r\u00e9e dans les zones grav\u00e9es de la plaque d'impression.<\/p><p class=\"translation-block\"><strong>3. \u00e9limination de l'exc\u00e8s d'encre<\/strong> : Une racle (ou une raclette) est utilis\u00e9e pour essuyer l'exc\u00e8s d'encre de la surface de la plaque, en ne laissant de l'encre que dans les zones grav\u00e9es.<\/p><p class=\"translation-block\">&lt;Utilisation du tampon<\/strong> : Un tampon en silicone souple et \u00e9lastique (le tampon dans la tampographie) entre en contact avec la plaque, transf\u00e9rant l'encre des zones grav\u00e9es sur le tampon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-800c1ac elementor-widget elementor-widget-image\" data-id=\"800c1ac\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"139\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/different-pads-for-pad-printing.jpg\" class=\"attachment-large size-large wp-image-7542\" alt=\"diff\u00e9rents tampons pour la tampographie\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/different-pads-for-pad-printing.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/different-pads-for-pad-printing-300x70.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Les coussinets en silicone peuvent prendre diff\u00e9rentes formes.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58a41e8 elementor-widget elementor-widget-text-editor\" data-id=\"58a41e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>5. Transfert sur le produit<\/strong> : le tampon se d\u00e9place ensuite vers l'article \u00e0 imprimer, en appuyant doucement pour transf\u00e9rer l'encre du tampon sur la surface de l'article. La souplesse et l'\u00e9lasticit\u00e9 du tampon en silicone lui permettent de s'adapter \u00e0 diverses surfaces irr\u00e9guli\u00e8res.<\/p><p class=\"translation-block\"><strong>6. s\u00e9chage et durcissement<\/strong> : l'encre s\u00e8che et durcit sur la surface de l'article, achevant ainsi le processus d'impression.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a734cc4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a734cc4\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cbc071\" data-id=\"3cbc071\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a19d609 elementor-widget elementor-widget-text-editor\" data-id=\"a19d609\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" class=\"translation-block\"><strong>Exemples d'impression sur tablette<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0eb6592 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0eb6592\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0569fb1\" data-id=\"0569fb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bcdffa elementor-widget elementor-widget-image\" data-id=\"6bcdffa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/light-diffusing-plastic-part\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/pad-printing-example-1.jpg\" class=\"attachment-large size-large wp-image-7555\" alt=\"tampographie exemple 1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/pad-printing-example-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/pad-printing-example-1-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e218332\" data-id=\"e218332\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10a91ca elementor-widget elementor-widget-image\" data-id=\"10a91ca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/pad-printing-example-2.jpg\" class=\"attachment-large size-large wp-image-7556\" alt=\"exemple de tampographie 2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/pad-printing-example-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/pad-printing-example-2-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a22159 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a22159\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b08fde4\" data-id=\"b08fde4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-927930a elementor-widget elementor-widget-text-editor\" data-id=\"927930a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Advantages_of_Pad_Printing\"><\/span>Avantages de la tampographie<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\"><strong>Convient aux surfaces complexes<\/strong> : La tampographie permet d'imprimer sur des surfaces irr\u00e9guli\u00e8res, in\u00e9gales, courbes et m\u00eame rugueuses.<\/p><p class=\"translation-block\"><strong>Repr\u00e9sentation de d\u00e9tails fins<\/strong> : cette m\u00e9thode permet d'imprimer des motifs et des textes complexes, ce qui la rend adapt\u00e9e \u00e0 l'impression graphique de haute pr\u00e9cision.<\/p><p class=\"translation-block\"><strong>Versatilit\u00e9 dans la compatibilit\u00e9 des mat\u00e9riaux<\/strong> : La tampographie peut \u00eatre appliqu\u00e9e \u00e0 une grande vari\u00e9t\u00e9 de mat\u00e9riaux, notamment les plastiques, les m\u00e9taux, le verre, la c\u00e9ramique et le bois.<\/p><p class=\"translation-block\"><strong>Adaptabilit\u00e9 de la couleur<\/strong> : Plusieurs couleurs d'encre peuvent \u00eatre utilis\u00e9es, bien que chaque cycle d'impression ne puisse appliquer qu'une seule couleur. L'impression multicolore est possible gr\u00e2ce \u00e0 plusieurs cycles d'impression.<\/p><p class=\"translation-block\"><strong>Efficacit\u00e9 et flexibilit\u00e9<\/strong> : La tampographie est bien adapt\u00e9e \u00e0 la production rapide et \u00e0 la personnalisation de petits lots, avec un changement de plaque pratique.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cabb9d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cabb9d0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-027342b\" data-id=\"027342b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d64269 elementor-widget elementor-widget-text-editor\" data-id=\"3d64269\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Disadvantages_of_Pad_Printing\"><\/span>Inconv\u00e9nients de la tampographie<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\"><strong>Limitations des couleurs<\/strong> : comme pour la s\u00e9rigraphie, chaque cycle d'impression ne peut utiliser qu'une seule couleur, ce qui rend l'impression multicolore plus longue et plus co\u00fbteuse.<\/p><p class=\"translation-block\"><strong>Limites de la surface d'impression<\/strong> : Bien que la tampographie excelle avec les surfaces in\u00e9gales, elle pr\u00e9sente des limites lorsqu'il s'agit de surfaces extr\u00eamement irr\u00e9guli\u00e8res ou de structures en escalier. Ces formes peuvent entraver l'expansion du tampon de silicone et affecter son contact avec la surface d'impression. Un contact incomplet peut entra\u00eener une distorsion des motifs d'impression, ce qui nuit \u00e0 la qualit\u00e9 de l'impression. Une attention particuli\u00e8re est n\u00e9cessaire pour s'assurer que le tampon entre uniform\u00e9ment en contact avec l'ensemble de la zone d'impression afin d'obtenir une impression claire et pr\u00e9cise.<\/p><p class=\"translation-block\"><strong>Limitations de la taille du motif<\/strong> : En raison des contraintes de taille du tampon en silicone, la zone d'impression est g\u00e9n\u00e9ralement petite et ne convient pas \u00e0 l'impression de grandes surfaces.<\/p><p class=\"translation-block\"><strong>Peu de profondeur d'encre dans les impressions uniques<\/strong> : la couche d'encre appliqu\u00e9e au cours d'un seul cycle d'impression est relativement mince. Ce ph\u00e9nom\u00e8ne peut \u00eatre compens\u00e9 efficacement en effectuant deux ou trois cycles d'impression, ce qui entra\u00eene \u00e9galement un co\u00fbt de production plus \u00e9lev\u00e9.<\/p><p class=\"translation-block\"><strong>Temps de s\u00e9chage de l'encre<\/strong> : certains types d'encre n\u00e9cessitent des temps de s\u00e9chage plus longs, ce qui peut avoir un impact sur l'efficacit\u00e9 de la production.<\/p><p class=\"translation-block\">&lt;Impact environnemental<\/strong> : Certaines encres de tampographie peuvent contenir des compos\u00e9s organiques volatils (COV), ce qui pr\u00e9sente des risques potentiels pour l'environnement et la sant\u00e9 des op\u00e9rateurs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7e3b68 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f7e3b68\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d361a1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d361a1f\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b57eb53\" data-id=\"b57eb53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15f278b elementor-widget elementor-widget-heading\" data-id=\"15f278b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Ink_Requirements_for_Screen_Pad_Printing\"><\/span>Exigences en mati\u00e8re d'encre pour la s\u00e9rigraphie et la tampographie<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2c374f elementor-widget elementor-widget-text-editor\" data-id=\"a2c374f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">La s\u00e9rigraphie et la tampographie requi\u00e8rent des propri\u00e9t\u00e9s d'encre sp\u00e9cifiques pour garantir une performance et une durabilit\u00e9 optimales sur les surfaces plastiques. Voici quelques-unes des principales exigences en mati\u00e8re d'encre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb077f elementor-widget elementor-widget-heading\" data-id=\"9fb077f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Ink_Adhesion_to_Substrate\"><\/span>Adh\u00e9sion de l'encre au support<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a44695e elementor-widget elementor-widget-text-editor\" data-id=\"a44695e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"414\" data-end=\"689\" class=\"translation-block\">L'adh\u00e9rence entre l'encre et le plastique est une exigence fondamentale pour la s\u00e9rigraphie et la tampographie. L'adh\u00e9rence est le plus souvent \u00e9valu\u00e9e \u00e0 l'aide du <strong>test d'adh\u00e9rence par hachures crois\u00e9es<\/strong> - souvent appel\u00e9 <strong>test de la grille<\/strong> - tandis qu'une m\u00e9thode plus rapide et informelle consiste \u00e0 gratter l'impression avec un ongle ou une spatule en plastique pour voir si elle se d\u00e9tache.<\/p><p data-start=\"691\" data-end=\"760\" class=\"translation-block\">Les plastiques peuvent \u00eatre class\u00e9s en deux cat\u00e9gories en fonction de l'adh\u00e9rence de l'encre :<\/p><ol data-start=\"762\" data-end=\"1222\"><li data-start=\"762\" data-end=\"999\"><p data-start=\"765\" data-end=\"999\" class=\"translation-block\"><strong data-start=\"765\" data-end=\"782\">Bonne adh\u00e9rence<\/strong> : Les plastiques ayant une polarit\u00e9 mol\u00e9culaire plus \u00e9lev\u00e9e, tels que <strong>ABS (souvent le choix le plus facile et pr\u00e9f\u00e9r\u00e9 pour l'impression plastique)<\/strong>, PA, PC et PVC, ont une \u00e9nergie de surface relativement \u00e9lev\u00e9e, de sorte que les encres adh\u00e8rent bien sans pr\u00e9traitement. Pour ces mat\u00e9riaux, le choix d'une encre compatible est g\u00e9n\u00e9ralement suffisant.<\/p><\/li><li data-start=\"1004\" data-end=\"1222\"><p data-start=\"1007\" data-end=\"1222\" class=\"translation-block\"><strong data-start=\"1007\" data-end=\"1024\">Mauvaise adh\u00e9rence<\/strong> : Les plastiques \u00e0 faible polarit\u00e9 tels que le PE, le PP, le PET et le POM (les plus difficiles \u00e0 imprimer) n\u00e9cessitent g\u00e9n\u00e9ralement un pr\u00e9traitement pour obtenir une bonne adh\u00e9rence de l'encre. Les m\u00e9thodes courantes comprennent le traitement plasma ou corona, le traitement \u00e0 la flamme ou l'application d'un appr\u00eat ou d'un promoteur d'adh\u00e9rence.<\/p><\/li><\/ol><p data-start=\"1224\" data-end=\"1488\" class=\"translation-block\">Dans certains cas, les mat\u00e9riaux plastiques contenant des plastifiants ou d'autres additifs peuvent affaiblir l'adh\u00e9rence de l'encre au fil du temps, car ces produits chimiques migrent vers la surface. Pour \u00e9viter cela, il est recommand\u00e9 d'utiliser des mat\u00e9riaux vierges et d'\u00e9viter les plastiques contenant des additifs inconnus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dfe0d8 elementor-widget elementor-widget-heading\" data-id=\"5dfe0d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Alcohol_Resistance\"><\/span>R\u00e9sistance \u00e0 l'alcool<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84db7f1 elementor-widget elementor-widget-text-editor\" data-id=\"84db7f1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1524\" data-end=\"1742\" class=\"translation-block\">Certains produits en plastique, en particulier dans les appareils m\u00e9dicaux, l'\u00e9lectronique et les int\u00e9rieurs automobiles, peuvent entrer en contact avec de l'alcool pendant leur utilisation. Dans ces cas, il est important de choisir des encres r\u00e9sistantes \u00e0 l'alcool.<\/p><p data-start=\"1744\" data-end=\"2099\" class=\"translation-block\">Pour tester la r\u00e9sistance \u00e0 l'alcool, une boule de coton imbib\u00e9e d'alcool est frott\u00e9e sur la surface imprim\u00e9e 50 \u00e0 100 fois. Si l'encre commence \u00e0 se d\u00e9coller, l'encre n'est pas r\u00e9sistante \u00e0 l'alcool. Dans les environnements exigeant une r\u00e9sistance \u00e0 l'alcool, veillez \u00e0 s\u00e9lectionner des encres con\u00e7ues pour r\u00e9sister \u00e0 l'exposition \u00e0 l'alcool. Cela d\u00e9pend de la formulation de l'encre, des additifs et du processus de s\u00e9chage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-001577a elementor-widget elementor-widget-heading\" data-id=\"001577a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"UV_Resistance_Sunlight_Exposure\"><\/span>R\u00e9sistance aux UV (exposition au soleil)<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d9f177 elementor-widget elementor-widget-text-editor\" data-id=\"6d9f177\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2150\" data-end=\"2338\" class=\"translation-block\">Alors que les encres standard conviennent \u00e0 un usage int\u00e9rieur, les produits destin\u00e9s \u00e0 un usage ext\u00e9rieur doivent \u00eatre dot\u00e9s d'encres capables de r\u00e9sister aux rayons ultraviolets (UV) afin d'\u00e9viter toute d\u00e9gradation due \u00e0 une exposition prolong\u00e9e au soleil.<\/p><p data-start=\"2340\" data-end=\"2752\" class=\"translation-block\">Sous l'effet des UV, les encres peuvent s'estomper, se d\u00e9colorer et finir par se poudrer ou se d\u00e9coller.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a204a0 elementor-widget elementor-widget-text-editor\" data-id=\"4a204a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2340\" data-end=\"2752\" class=\"translation-block\">C'est pourquoi les encres r\u00e9sistantes aux UV sont n\u00e9cessaires pour les produits d'ext\u00e9rieur. Par exemple, un produit imprim\u00e9 avec une encre standard a vu sa couleur passer du vert au bleu apr\u00e8s seulement six mois d'exposition \u00e0 la lumi\u00e8re du soleil.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ff5095 elementor-widget elementor-widget-image\" data-id=\"9ff5095\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/ink-color-fading-plastic.jpg\" class=\"attachment-large size-large wp-image-9806\" alt=\"Comparaison d&#039;une \u00e9tiquette imprim\u00e9e pr\u00e9sentant une d\u00e9coloration : en haut, une nouvelle impression d&#039;un jaune-vert brillant ; en bas, la m\u00eame \u00e9tiquette apr\u00e8s 6 mois d&#039;exposition au soleil, d\u00e9color\u00e9e en un vert terne.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/ink-color-fading-plastic.jpg 750w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/ink-color-fading-plastic-300x225.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/ink-color-fading-plastic-600x450.jpg 600w\" sizes=\"(max-width: 750px) 100vw, 750px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Marquage nouvellement imprim\u00e9 compar\u00e9 au m\u00eame marquage apr\u00e8s six mois d'exposition au soleil. La couleur est pass\u00e9e du vert vif au cyan et devrait continuer \u00e0 s'estomper vers le blanc si l'exposition se poursuit.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e606bad elementor-widget elementor-widget-text-editor\" data-id=\"e606bad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2340\" data-end=\"2752\" class=\"translation-block\">En revanche, avec une encre r\u00e9sistante aux UV, la couleur est rest\u00e9e stable m\u00eame apr\u00e8s 12 mois, avec seulement une usure mineure \u00e0 certains endroits.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e310bf elementor-widget elementor-widget-image\" data-id=\"1e310bf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/UV-Resistant-Ink.jpg\" class=\"attachment-large size-large wp-image-9814\" alt=\"Encre r\u00e9sistante aux UV montrant un changement de couleur minimal apr\u00e8s 12 mois d&#039;exposition au soleil.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/UV-Resistant-Ink.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/UV-Resistant-Ink-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/UV-Resistant-Ink-768x432.jpg 768w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/UV-Resistant-Ink-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Encre r\u00e9sistante aux UV, montr\u00e9e apr\u00e8s 12 mois d'exposition \u00e0 la lumi\u00e8re directe du soleil, montrant un changement minime de couleur, d\u00e9montrant ses propri\u00e9t\u00e9s durables.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c22a65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c22a65\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b19c0f\" data-id=\"4b19c0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6432a42 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6432a42\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da87145 elementor-widget elementor-widget-heading\" data-id=\"da87145\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Laser_Etching\"><\/span>Gravure au laser<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7195541 elementor-widget elementor-widget-text-editor\" data-id=\"7195541\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">&lt;La gravure laser<\/strong> est \u00e9galement connue sous le nom de<strong> gravure laser<\/strong> ou<strong> marquage laser.<\/strong> Elle consiste \u00e0 utiliser des faisceaux laser \u00e0 haute \u00e9nergie pour graver des marques sur la surface. Cette m\u00e9thode permet de cr\u00e9er des marques durables et pr\u00e9cises, telles que du texte, des motifs et des codes-barres, sur diff\u00e9rents types de surfaces en plastique. Le processus de marquage au laser comprend g\u00e9n\u00e9ralement les \u00e9tapes suivantes :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8e67a elementor-widget elementor-widget-text-editor\" data-id=\"7b8e67a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"How_Laser_Etching_Works\"><\/span>Comment fonctionne la gravure au laser ?<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\"><strong>Conception de l'\u0153uvre<\/strong> : la premi\u00e8re \u00e9tape consiste \u00e0 concevoir le contenu \u00e0 marquer, qui peut comprendre du texte, des graphiques, des codes-barres, etc. Ces dessins sont g\u00e9n\u00e9ralement cr\u00e9\u00e9s \u00e0 l'aide d'un logiciel sp\u00e9cialis\u00e9 sur un ordinateur.<\/p><p class=\"translation-block\"><strong>R\u00e9glage des param\u00e8tres du laser<\/strong> : En fonction de l'effet de marquage souhait\u00e9 et du type de plastique, les param\u00e8tres du laser, tels que la puissance, la vitesse, la mise au point et la fr\u00e9quence, sont r\u00e9gl\u00e9s en cons\u00e9quence.<\/p><p class=\"translation-block\"><strong>Ex\u00e9cution du marquage au laser<\/strong> : Le produit en plastique est plac\u00e9 sur la table de travail de la machine de marquage au laser. Le laser \u00e9met un faisceau \u00e0 haute \u00e9nergie qui se d\u00e9place le long d'une trajectoire pr\u00e9d\u00e9termin\u00e9e, en se concentrant sur la surface du plastique.<\/p><p class=\"translation-block\"><strong>R\u00e9action du mat\u00e9riau<\/strong> : Lorsque le laser entre en contact avec la surface du plastique, plusieurs r\u00e9actions physiques ou chimiques diff\u00e9rentes peuvent se produire, en fonction de la nature du plastique et des r\u00e9glages du laser :<\/p><ul><li><strong>Enl\u00e8vement de mat\u00e9riaux<\/strong>: Le laser ablate une couche de la surface, cr\u00e9ant ainsi une marque en creux.<\/li><li><strong>Changement de couleur<\/strong>: La chaleur du laser provoque un changement de couleur dans le plastique, formant un contraste distinct dans le marquage.<\/li><li><strong>Changement chimique<\/strong>: Le laser induit une r\u00e9action chimique qui modifie la couleur ou la texture de la surface du mat\u00e9riau.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5260791 elementor-widget elementor-widget-text-editor\" data-id=\"5260791\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Refroidissement et traitement<\/strong> : Une fois le processus de marquage termin\u00e9, un refroidissement et un traitement suppl\u00e9mentaire peuvent parfois s'av\u00e9rer n\u00e9cessaires pour garantir la qualit\u00e9 du marquage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f95ae7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f95ae7a\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33c1348\" data-id=\"33c1348\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-392c57e elementor-widget elementor-widget-text-editor\" data-id=\"392c57e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" class=\"translation-block\"><strong>Exemples d'impression laser<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a93b434 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a93b434\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-adbb107\" data-id=\"adbb107\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a604f1 elementor-widget elementor-widget-image\" data-id=\"8a604f1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/light-diffusing-plastic-part\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/laser-printing-example-1.jpg\" class=\"attachment-large size-large wp-image-7564\" alt=\"impression laser sur une surface cylindrique\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/laser-printing-example-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/laser-printing-example-1-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee0cfd9\" data-id=\"ee0cfd9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3139d0a elementor-widget elementor-widget-image\" data-id=\"3139d0a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/laser-printing-example-2.jpg\" class=\"attachment-large size-large wp-image-7563\" alt=\"impression laser exemple 2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/laser-printing-example-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/01\/laser-printing-example-2-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9da5f78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9da5f78\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ccefdd\" data-id=\"2ccefdd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57889e1 elementor-widget elementor-widget-text-editor\" data-id=\"57889e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Advantages_of_Laser_Marking\"><\/span>Avantages du marquage au laser<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\"><strong>Pr\u00e9cision et d\u00e9tails<\/strong> : Le marquage laser permet de cr\u00e9er des motifs extr\u00eamement fins et complexes.<\/p><p class=\"translation-block\"><strong>Processus sans contact<\/strong> : le processus de marquage n'implique aucun contact physique, ce qui r\u00e9duit l'usure ou la d\u00e9formation du produit.<\/p><p class=\"translation-block\"><strong>Vitesse et automatisation<\/strong> : Le marquage est rapide et peut \u00eatre facilement int\u00e9gr\u00e9 dans des lignes de production automatis\u00e9es.<\/p><p class=\"translation-block\">&lt;Durabilit\u00e9<\/strong> : les marquages sont durables et r\u00e9sistants \u00e0 la d\u00e9coloration et \u00e0 l'usure.<\/p><p class=\"translation-block\">Toutefois, l'efficacit\u00e9 du marquage laser peut varier en fonction du type de plastique et de sa couleur. Les mat\u00e9riaux r\u00e9agissent diff\u00e9remment au laser, ce qui n\u00e9cessite d'adapter les param\u00e8tres du laser \u00e0 des mat\u00e9riaux sp\u00e9cifiques.<\/p><h3><span class=\"ez-toc-section\" id=\"Disadvantages_of_Laser_Marking\"><\/span>Inconv\u00e9nients du marquage au laser<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\"><strong>Limites de couleur<\/strong> : les couleurs obtenues avec le marquage laser d\u00e9pendent largement du mat\u00e9riau et de sa r\u00e9action au laser. En g\u00e9n\u00e9ral, les marquages sont de couleur gris clair pour contraster avec l'arri\u00e8re-plan. En raison de limitations techniques, les autres choix de couleurs sont restreints.<\/p><p class=\"translation-block\"><strong>Limitations sur les surfaces irr\u00e9guli\u00e8res<\/strong> : En raison des contraintes li\u00e9es \u00e0 la distance focale, le marquage laser peut avoir du mal \u00e0 obtenir des impressions uniformes et claires sur des surfaces irr\u00e9guli\u00e8res ou textur\u00e9es.<\/p><p class=\"translation-block\">&lt;Probl\u00e8mes de durabilit\u00e9<\/strong> : Bien qu'ils soient g\u00e9n\u00e9ralement consid\u00e9r\u00e9s comme permanents, les marquages au laser peuvent s'estomper ou s'user dans certaines conditions, telles qu'une exposition prolong\u00e9e \u00e0 une lumi\u00e8re intense ou \u00e0 des produits chimiques agressifs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d1a644 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d1a644\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6eb1e8\" data-id=\"d6eb1e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f81e6ac elementor-widget elementor-widget-heading\" data-id=\"f81e6ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusion<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7830abe elementor-widget elementor-widget-text-editor\" data-id=\"7830abe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">L'impression sur les produits en plastique ne se limite pas \u00e0 la s\u00e9rigraphie, \u00e0 la tampographie et \u00e0 la gravure laser ; il existe \u00e9galement d'autres m\u00e9thodes telles que l'impression par transfert d'eau, la d\u00e9coration dans le moule, l'estampage \u00e0 chaud et l'impression \u00e0 jet d'encre.<\/p><p class=\"translation-block\">Lors de la s\u00e9lection de la technologie d'impression appropri\u00e9e, divers facteurs tels que le type de mat\u00e9riau, les caract\u00e9ristiques de la surface, les exigences de conception et l'\u00e9chelle de production doivent \u00eatre pris en compte pour r\u00e9pondre aux besoins esth\u00e9tiques et pratiques du produit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59657a2 elementor-widget elementor-widget-spacer\" data-id=\"59657a2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-613dd3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"613dd3d\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce3269c\" data-id=\"ce3269c\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c78404d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c78404d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-186f6e2\" data-id=\"186f6e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccba062 elementor-widget elementor-widget-image\" data-id=\"ccba062\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png\" class=\"attachment-large size-large wp-image-6453\" alt=\"Bo\u00eete triangulaire surmoul\u00e9e en TPU\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7293d14\" data-id=\"7293d14\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9fc3ae elementor-widget elementor-widget-heading\" data-id=\"c9fc3ae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\"><\/span><span>Nous sommes experts en moulage par injection de plastique. Contactez-nous d\u00e8s maintenant pour obtenir un devis rapide !<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1864994\" data-id=\"1864994\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a949d5 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"7a949d5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demande de devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3599b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3599b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-873c93b\" data-id=\"873c93b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d6b900 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d6b900\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3043d96\" data-id=\"3043d96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ac6393b\" data-id=\"ac6393b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Types d'impression sur pi\u00e8ces plastiques. Pendant la production d'articles en plastique, il est courant d'imprimer une gamme de motifs ou de textes sur leurs surfaces pour am\u00e9liorer leur attrait visuel. Cela implique souvent l'ajout d'\u00e9l\u00e9ments tels que des logos d'entreprise, des num\u00e9ros de mod\u00e8les de produits, et divers autres motifs ou \u0153uvres artistiques. Actuellement, diverses techniques existent pour appliquer...&nbsp;<a href=\"https:\/\/boyanmfg.com\/fr\/printing-on-plastic-methods-guide\/\" rel=\"bookmark\">Lire plus \u00bb<span class=\"screen-reader-text\">Les 3 principales m\u00e9thodes d'impression sur plastique : s\u00e9rigraphie, tampographie et gravure au laser<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":7569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":90,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72],"tags":[],"class_list":["post-7519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/posts\/7519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/comments?post=7519"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/posts\/7519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/media\/7569"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/media?parent=7519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/categories?post=7519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/tags?post=7519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}