{"id":7103,"date":"2023-12-20T15:40:13","date_gmt":"2023-12-20T15:40:13","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=7103"},"modified":"2025-02-05T15:13:12","modified_gmt":"2025-02-05T15:13:12","slug":"pa6-and-pa66-nylon-injection-molding","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/","title":{"rendered":"Ma\u00eetriser le moulage par injection du nylon : Aper\u00e7u des PA6 et PA66"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"7103\" class=\"elementor elementor-7103\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf1f5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf1f5e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb4be5c\" data-id=\"eb4be5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57d1e08 elementor-widget elementor-widget-shortcode\" data-id=\"57d1e08\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle translation-block\" style=\"cursor:pointer\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table des mati\u00e8res\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"><\/path><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default\"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Understanding_the_Fundamentals_of_Nylon_Injection_Molding\">Comprendre les principes fondamentaux du moulage par injection du nylon<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Versality_of_Nylon_Injection_Molded_Products\">Polyvalence des produits moul\u00e9s par injection en nylon<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#What_is_Nylon\">Qu'est-ce que le nylon ?<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Types_of_Nylon\">Types de nylon<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Advantages_and_Disadvantages_of_Nylon\">Avantages et inconv\u00e9nients du nylon<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Nylon_6_and_Nylon_66_for_Injection_Molding\">Nylon 6 et Nylon 66 pour le moulage par injection<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Types_of_Modified_Nylon\">Types de nylon modifi\u00e9<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Key_Considerations_for_Nylon_Injection_Molding\">Consid\u00e9rations cl\u00e9s pour le moulage par injection du nylon<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Why_Many_Small_and_Medium_Enterprises_Engage_in_Nylon_Modification\">Pourquoi de nombreuses petites et moyennes entreprises s'engagent-elles dans la modification du nylon ?<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#On-Site_Visits_to_Small_and_Medium_Material_Manufacturers\">Visites sur place des petits et moyens fabricants de mat\u00e9riaux<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#Material_Performance_Testing_Experiments\">Essais de performance des mat\u00e9riaux Exp\u00e9riences<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/#We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\">Nous sommes experts en moulage par injection de plastique. Contactez-nous d\u00e8s maintenant pour obtenir un devis rapide !<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bad65d4 elementor-widget elementor-widget-heading\" data-id=\"bad65d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Understanding_the_Fundamentals_of_Nylon_Injection_Molding\"><\/span>Comprendre les principes fondamentaux du moulage par injection du nylon<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f66aa5c elementor-widget elementor-widget-text-editor\" data-id=\"f66aa5c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Dans le domaine de la fabrication des mati\u00e8res plastiques, le moulage par injection du nylon est une technique essentielle, connue pour sa <strong>versatilit\u00e9<\/strong> et sa <strong>r\u00e9sistance<\/strong>. Cette m\u00e9thode permet de transformer le nylon en divers produits, des pi\u00e8ces automobiles aux articles de tous les jours, en mettant en \u00e9vidence sa durabilit\u00e9 et son adaptabilit\u00e9.<\/p><p class=\"translation-block\">Cet article se penche sur les nuances du moulage par injection du nylon, en se concentrant sur ses formes les plus populaires, le PA6 et le PA66, et sur les aspects essentiels du processus de moulage. Notre exploration offre un aper\u00e7u de ce processus de fabrication cl\u00e9, en soulignant comment les modifications am\u00e9liorent les propri\u00e9t\u00e9s du nylon et ses applications dans diverses industries. Rejoignez-nous pour d\u00e9couvrir le monde complexe du moulage par injection du nylon, pierre angulaire de la fabrication moderne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2e8ae0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2e8ae0\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a2b4ab\" data-id=\"9a2b4ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dda2507 elementor-widget elementor-widget-heading\" data-id=\"dda2507\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Versality_of_Nylon_Injection_Molded_Products\"><\/span>Polyvalence des produits moul\u00e9s par injection en nylon<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-252792a elementor-widget elementor-widget-text-editor\" data-id=\"252792a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\"><em>Le nylon est tellement utilis\u00e9 que les produits moul\u00e9s par injection en nylon sont presque omnipr\u00e9sents dans notre vie quotidienne. Vous trouverez ci-dessous quelques exemples de produits en nylon, qui vous donneront un aper\u00e7u rapide de leurs nombreuses applications.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5185eb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5185eb4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38031ef\" data-id=\"38031ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4743ae0 elementor-widget elementor-widget-image\" data-id=\"4743ae0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/injection-mold-power-tool-housing\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing.jpg\" class=\"attachment-large size-large wp-image-4437\" alt=\"bo\u00eetier de l&#039;outil \u00e9lectrique\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing-600x450.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing-300x225.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Bo\u00eetier en nylon pour outils \u00e9lectriques<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-55b5c8b\" data-id=\"55b5c8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e1c358 elementor-widget elementor-widget-image\" data-id=\"9e1c358\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/finding-custom-plastic-gear-manufacturer\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2019\/04\/2-level-plastic-gear.jpg\" class=\"attachment-large size-large wp-image-4245\" alt=\"Engrenage en plastique \u00e0 2 niveaux\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2019\/04\/2-level-plastic-gear.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2019\/04\/2-level-plastic-gear-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Engrenages en plastique nylon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d07c9e3\" data-id=\"d07c9e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d814f32 elementor-widget elementor-widget-image\" data-id=\"d814f32\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/plastic-lens-retainer-for-smartphone-cameras\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/plastic-retainer-for-phone-lens-r8r87wtxr1eoplvzqh85itt4l2ukcdzvgwx571p4fs.jpg\" title=\"support en plastique pour la lentille du t\u00e9l\u00e9phone\" alt=\"support en plastique pour la lentille du t\u00e9l\u00e9phone\" loading=\"lazy\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Support de lentilles pour t\u00e9l\u00e9phones intelligents<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e6dab9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e6dab9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d487828\" data-id=\"d487828\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5460797 elementor-widget elementor-widget-image\" data-id=\"5460797\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg\" class=\"attachment-large size-large wp-image-7720\" alt=\"moulage d&#039;insert de bo\u00eetier en nylon\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Moulage par insertion d'un bo\u00eetier en nylon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38c5257\" data-id=\"38c5257\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9d9214 elementor-widget elementor-widget-image\" data-id=\"c9d9214\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Hair-Dryer-Casing.jpg\" class=\"attachment-large size-large wp-image-7129\" alt=\"Bo\u00eetier de s\u00e8che-cheveux en nylon haute r\u00e9sistance\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Hair-Dryer-Casing.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Hair-Dryer-Casing-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Bo\u00eetier de s\u00e8che-cheveux en nylon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-80c8ace\" data-id=\"80c8ace\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e3ba78 elementor-widget elementor-widget-image\" data-id=\"8e3ba78\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/Automotive-Air-Filtration-Enclosure-r8r86x42jc1sgfbvj1sbw2tm0fqm7w22o04oyj6308.jpg\" title=\"Enceinte de filtration d&#039;air automobile\" alt=\"Enceinte de filtration d&#039;air automobile\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Enceinte de filtration d'air automobile<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eac1e90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eac1e90\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-aac89bb\" data-id=\"aac89bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-157914a elementor-widget elementor-widget-image\" data-id=\"157914a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Auto-Cable-Fasteners-and-Clasps.jpg\" class=\"attachment-large size-large wp-image-7132\" alt=\"Attaches et fermetures de c\u00e2bles automobiles en nylon\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Auto-Cable-Fasteners-and-Clasps.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Auto-Cable-Fasteners-and-Clasps-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Attaches et fermetures de c\u00e2bles automobiles en nylon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ae1f7c2\" data-id=\"ae1f7c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb9740 elementor-widget elementor-widget-image\" data-id=\"bbb9740\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Vehicle-Radiator-Fan-Blades.jpg\" class=\"attachment-large size-large wp-image-7130\" alt=\"Ventilateurs de radiateur pour v\u00e9hicules\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Vehicle-Radiator-Fan-Blades.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Vehicle-Radiator-Fan-Blades-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Ventilateurs de radiateur pour v\u00e9hicules<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2418b66\" data-id=\"2418b66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9203401 elementor-widget elementor-widget-image\" data-id=\"9203401\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/custom-nylon-gear-top-view-r8r8c9szgddkkhjz9v2ul873sfcv1ub1qhv8c98dko.jpg\" title=\"engrenage en nylon sur mesure vue de dessus\" alt=\"engrenage en nylon sur mesure vue de dessus\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Engrenage en nylon \u00e0 parois \u00e9paisses<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbcfc33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbcfc33\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf91560\" data-id=\"bf91560\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b8e394 elementor-widget elementor-widget-spacer\" data-id=\"9b8e394\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e359c15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e359c15\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4197fe9\" data-id=\"4197fe9\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-436e19c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"436e19c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-33e93c6\" data-id=\"33e93c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43883c1 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"43883c1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demande de devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f40b05a\" data-id=\"f40b05a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4023e84 elementor-widget elementor-widget-text-editor\" data-id=\"4023e84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Vous avez besoin d'une expertise en moulage par injection de nylon ? Contactez-nous pour un service exceptionnel!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-207abb7\" data-id=\"207abb7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1475acc elementor-widget elementor-widget-image\" data-id=\"1475acc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-1.png\" class=\"attachment-large size-large wp-image-3998\" alt=\"connecteur d&#039;angle en plastique 1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-1.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-1-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e38009d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e38009d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8979946\" data-id=\"8979946\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffc7ab2 elementor-widget elementor-widget-heading\" data-id=\"ffc7ab2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_is_Nylon\"><\/span>Qu'est-ce que le nylon ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-929605c elementor-widget elementor-widget-text-editor\" data-id=\"929605c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><a href=\"https:\/\/en.wikipedia.org\/wiki\/Nylon\" target=\"_blank\" rel=\"noopener\">Le nylon est un <strong>polyamide<\/strong><\/a> synth\u00e9tique (abr\u00e9g\u00e9 en <strong>PA<\/strong>), un type de polym\u00e8re form\u00e9 par des liaisons<strong> amide<\/strong> (-NH-CO-). Il appartient \u00e0 la famille des <strong>polym\u00e8res thermoplastiques semi-cristallins<\/strong>. Connu pour sa<strong> solidit\u00e9, sa robustesse,<\/strong> sa r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es, sa r\u00e9sistance \u00e0 l'usure et sa faible friction, le nylon est largement utilis\u00e9 dans la fabrication de textiles et dans les processus de moulage par injection. <a href=\"https:\/\/en.wikipedia.org\/wiki\/Nylon\" target=\"_blank\" rel=\"noopener\">Ce mat\u00e9riau a \u00e9t\u00e9 invent\u00e9 et nomm\u00e9 par la soci\u00e9t\u00e9 am\u00e9ricaine DuPont \u00e0 la fin des ann\u00e9es 1930.<\/a> Le nylon a d'abord \u00e9t\u00e9 utilis\u00e9 pour les poils des brosses \u00e0 dents, avant d'\u00eatre \u00e9tendu \u00e0 la production de bas, de parachutes et d'autres articles.<\/p><p class=\"translation-block\">Le nom \u201cnylon\u201d est tout \u00e0 fait m\u00e9morable, bien qu'il n'y ait pas d'explication claire quant \u00e0 sa signification sp\u00e9cifique. Il s'agit n\u00e9anmoins d'un exemple r\u00e9ussi de marque commerciale.<\/p><p class=\"translation-block\">Il est important de noter que si le nylon est un type de polyamide, <strong>tous les polyamides ne sont pas appel\u00e9s nylon<\/strong>. Par exemple, les mati\u00e8res naturelles comme la soie et la laine sont des polyamides compos\u00e9s d'acides amin\u00e9s, et certains polyamides aromatiques n'entrent pas non plus dans la cat\u00e9gorie du nylon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5afe1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5afe1e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c01de3\" data-id=\"3c01de3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5719f6a elementor-widget elementor-widget-heading\" data-id=\"5719f6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Types_of_Nylon\"><\/span>Types de nylon<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-332a459 elementor-widget elementor-widget-text-editor\" data-id=\"332a459\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Les principaux types de nylon sont le<strong>Nylon 6<\/strong> et le <strong>Nylon 66<\/strong>, qui dominent le march\u00e9. Le nylon 6 est connu sous le nom de polycaprolactame, tandis que le nylon 66 est un polyhexam\u00e9thyl\u00e8ne adipamide. Le nylon 66 est environ 12% plus dur que le nylon 6. Viennent ensuite le nylon 11, le nylon 12, le nylon 610 et le nylon 612.<\/p><p class=\"translation-block\">Il existe \u00e9galement des types de nylon tels que le Nylon 1010, le Nylon 46, le Nylon 7, le Nylon 9, le Nylon 13, ainsi que des vari\u00e9t\u00e9s plus r\u00e9centes telles que le Nylon 6I, le Nylon 9T et la sp\u00e9cialit\u00e9 Nylon MXD6, qui est connue pour ses propri\u00e9t\u00e9s de barri\u00e8re. Ces divers types de nylon offrent une gamme de propri\u00e9t\u00e9s qui r\u00e9pondent \u00e0 diff\u00e9rents besoins et applications industriels.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86f48e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86f48e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b75688c\" data-id=\"b75688c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5edb48d elementor-widget elementor-widget-heading\" data-id=\"5edb48d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Advantages_and_Disadvantages_of_Nylon\"><\/span>Avantages et inconv\u00e9nients du nylon<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4cc921 elementor-widget elementor-widget-text-editor\" data-id=\"e4cc921\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Le nylon, mati\u00e8re synth\u00e9tique largement utilis\u00e9e, pr\u00e9sente les avantages et les inconv\u00e9nients suivants :<\/p><h4><strong>Avantages :<\/strong><\/h4><ol><li><strong>R\u00e9sistance m\u00e9canique \u00e9lev\u00e9e<\/strong>: Le nylon est connu pour son excellente r\u00e9sistance et sa t\u00e9nacit\u00e9, ce qui en fait un mat\u00e9riau id\u00e9al pour les applications n\u00e9cessitant une r\u00e9sistance m\u00e9canique \u00e9lev\u00e9e. Sa t\u00e9nacit\u00e9 augmente encore lorsqu'il absorbe de l'eau.<\/li><li><strong>R\u00e9sistance aux hautes temp\u00e9ratures<\/strong>: Le nylon standard peut supporter des temp\u00e9ratures sup\u00e9rieures \u00e0 100 \u2103, et certains types modifi\u00e9s peuvent m\u00eame supporter jusqu'\u00e0 200 \u2103.<\/li><li><strong>Surface lisse et r\u00e9sistante \u00e0 l'usure<\/strong>: La surface du nylon est lisse et pr\u00e9sente un faible coefficient de frottement, ce qui lui conf\u00e8re une grande r\u00e9sistance \u00e0 l'usure. Il pr\u00e9sente des propri\u00e9t\u00e9s autolubrifiantes lorsqu'il est utilis\u00e9 dans des machines en mouvement, ce qui r\u00e9duit le bruit et \u00e9limine le besoin de lubrifiants dans les applications \u00e0 faible frottement.<\/li><li><strong>R\u00e9sistance \u00e0 la corrosion<\/strong>: Le nylon r\u00e9siste bien aux alcalis et \u00e0 la plupart des solutions salines. Il r\u00e9siste \u00e9galement aux acides faibles, aux huiles de moteur, \u00e0 l'essence, aux compos\u00e9s d'hydrocarbures aromatiques et aux solvants g\u00e9n\u00e9raux. Le nylon est inerte aux compos\u00e9s aromatiques et offre une excellente r\u00e9sistance \u00e0 l'essence, aux huiles, aux graisses, \u00e0 l'alcool et aux alcalis faibles, ainsi que d'impressionnantes propri\u00e9t\u00e9s antivieillissement.<\/li><li><strong>Bonne isolation \u00e9lectrique<\/strong>: Le nylon conserve un certain niveau de r\u00e9sistance \u00e9lectrique, m\u00eame dans les environnements humides.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8520911 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8520911\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee545b5\" data-id=\"ee545b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-792460c elementor-widget elementor-widget-text-editor\" data-id=\"792460c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" class=\"translation-block\">Le nylon est id\u00e9al pour le moulage d'inserts m\u00e9talliques en raison de sa r\u00e9sistance<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b4a724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b4a724\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-42753ab\" data-id=\"42753ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5f46a0 elementor-widget elementor-widget-image\" data-id=\"b5f46a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg\" class=\"attachment-large size-large wp-image-7720\" alt=\"moulage d&#039;insert de bo\u00eetier en nylon\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67472e3\" data-id=\"67472e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3057627 elementor-widget elementor-widget-image\" data-id=\"3057627\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/inserted-nut-nylon-part.jpg\" class=\"attachment-large size-large wp-image-7724\" alt=\"\u00e9crou ins\u00e9r\u00e9 pi\u00e8ce en nylon\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/inserted-nut-nylon-part.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/inserted-nut-nylon-part-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2824fdf elementor-widget elementor-widget-text-editor\" data-id=\"2824fdf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">La r\u00e9sistance et la robustesse du nylon en font un mat\u00e9riau id\u00e9al pour le moulage d'inserts m\u00e9talliques. La mallette comporte 34 \u00e9crous m\u00e9talliques encastr\u00e9s. Comme leur installation manuelle prend plus de 2 minutes, le pr\u00e9chauffage des inserts est inefficace. Cependant, le risque de fissuration du plastique est faible, m\u00eame avec des inserts froids.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-426a7a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"426a7a0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce068fc\" data-id=\"ce068fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a274c08 elementor-widget elementor-widget-text-editor\" data-id=\"a274c08\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Inconv\u00e9nients :<\/strong><\/h4><ol><li><strong>Absorption d'eau et gonflement<\/strong>: Le nylon a tendance \u00e0 absorber l'eau, avec un taux d'absorption sup\u00e9rieur \u00e0 3%, ce qui entra\u00eene une mauvaise qualit\u00e9 de l'eau. <a href=\"http:\/\/boyanmfg.com\/injection-molding-tolerances\/\">stabilit\u00e9 dimensionnelle<\/a>.<\/li><li><strong>Faible r\u00e9sistance aux UV<\/strong>: Une exposition prolong\u00e9e \u00e0 l'ext\u00e9rieur peut entra\u00eener le vieillissement et la d\u00e9gradation du nylon.<\/li><li><strong>R\u00e9sistance limit\u00e9e \u00e0 la temp\u00e9rature<\/strong>: Le nylon devient cassant et perd de sa r\u00e9sistance dans les environnements \u00e0 basse temp\u00e9rature, tandis qu'il est sujet au vieillissement et \u00e0 la d\u00e9gradation \u00e0 haute temp\u00e9rature.<\/li><\/ol><p class=\"translation-block\">Par cons\u00e9quent, lorsque l'on choisit le nylon comme mat\u00e9riau, il est essentiel de tenir compte de ces forces et faiblesses afin de s'assurer de son ad\u00e9quation et de sa durabilit\u00e9 pour des applications sp\u00e9cifiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc9bf7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc9bf7e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecef1f6\" data-id=\"ecef1f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cbabe5 elementor-widget elementor-widget-heading\" data-id=\"2cbabe5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Nylon_6_and_Nylon_66_for_Injection_Molding\"><\/span>Nylon 6 et Nylon 66 pour le moulage par injection<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d7f6b elementor-widget elementor-widget-text-editor\" data-id=\"c4d7f6b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Ces deux types de nylon \u00e9tant les plus couramment utilis\u00e9s dans le moulage par injection, comparons-les pour comprendre leurs caract\u00e9ristiques. Tous deux appartiennent \u00e0 la famille des polym\u00e8res polyamides et pr\u00e9sentent des similitudes au niveau de leur structure mol\u00e9culaire.<\/p><p class=\"translation-block\"><strong>Similitudes et diff\u00e9rences:<\/strong>.<\/p><ol><li><p class=\"translation-block\"><strong>Nature semi-cristalline<\/strong> : les deux sont des plastiques semi-cristallins, mais le Nylon 66 a un degr\u00e9 de cristallinit\u00e9 plus \u00e9lev\u00e9 que le Nylon 6, ce qui entra\u00eene certaines diff\u00e9rences dans les propri\u00e9t\u00e9s physiques.<\/p><\/li><li><p class=\"translation-block\"><strong>Densit\u00e9<\/strong> : la densit\u00e9 du nylon 6 et du nylon 66 est d'environ 1,10 \u00e0 1,15 g\/cm3. Toutefois, l'incorporation de fibres de verre ou d'autres charges peut augmenter la densit\u00e9, qui reste g\u00e9n\u00e9ralement inf\u00e9rieure \u00e0 1,5 g\/cm3.<\/p><\/li><li><p class=\"translation-block\"><a href=\"http:\/\/boyanmfg.com\/melting-point-of-plastics-guide\/\"><strong>Point de fusion<\/strong><\/a> : le point de fusion du Nylon 66 est d'environ 260 \u2103, soit 20 \u00e0 40 degr\u00e9s de plus que le Nylon 6. Cela conf\u00e8re au nylon 66 une r\u00e9sistance sup\u00e9rieure \u00e0 la chaleur, mais il n'est pas aussi \u00e9lastique, robuste et r\u00e9sistant \u00e0 la fatigue que le nylon 6.<\/p><\/li><li><p class=\"translation-block\"><strong>R\u00e9sistance<\/strong> : Le nylon 6 offre une meilleure r\u00e9sistance.<\/p><\/li><li><p class=\"translation-block\"><strong>Duret\u00e9<\/strong> : Le Nylon 66 est plus dur que le Nylon 6.<\/p><\/li><li><p class=\"translation-block\"><strong>Viscosit\u00e9 et moulage<\/strong> : le nylon 6 a une viscosit\u00e9 plus faible, ce qui le rend plus facile \u00e0 mouler et permet d'obtenir une meilleure brillance de surface. Cependant, il a un taux d'absorption d'eau plus \u00e9lev\u00e9, avec un taux d'absorption d'eau \u00e0 saturation d'environ 10%. Ce taux d'absorption \u00e9lev\u00e9 peut r\u00e9duire consid\u00e9rablement les performances du mat\u00e9riau, ce qui doit \u00eatre pris en compte lors de la conception.<\/p><\/li><li><p class=\"translation-block\"><strong>R\u00e9sistance \u00e0 la temp\u00e9rature<\/strong> : le Nylon 66 peut r\u00e9sister \u00e0 des temp\u00e9ratures d'environ 180-190 degr\u00e9s Celsius, soit 50-60 degr\u00e9s de plus que le Nylon 6.<\/p><\/li><\/ol><p class=\"translation-block\">En comprenant ces diff\u00e9rences et ces similitudes, les fabricants et les concepteurs peuvent prendre des d\u00e9cisions plus \u00e9clair\u00e9es quant au type de nylon le mieux adapt\u00e9 \u00e0 leurs applications sp\u00e9cifiques, en particulier en ce qui concerne les processus de moulage par injection.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96c7f40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96c7f40\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5911117\" data-id=\"5911117\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aab1139 elementor-widget elementor-widget-heading\" data-id=\"aab1139\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Types_of_Modified_Nylon\"><\/span>Types de nylon modifi\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de28149 elementor-widget elementor-widget-text-editor\" data-id=\"de28149\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Pour pallier les faiblesses du nylon, diverses formes modifi\u00e9es de nylon ont \u00e9t\u00e9 d\u00e9velopp\u00e9es sur le march\u00e9. Les m\u00e9thodes de modification les plus courantes sont le m\u00e9lange, le remplissage et la copolym\u00e9risation. Le m\u00e9lange consiste \u00e0 m\u00e9langer le nylon avec d'autres plastiques ou caoutchoucs pour compl\u00e9ter leurs forces respectives ; la modification par remplissage ajoute g\u00e9n\u00e9ralement des mat\u00e9riaux tels que des fibres de verre, du carbonate de calcium ou du talc pour augmenter la r\u00e9sistance et r\u00e9duire le retrait ; la copolym\u00e9risation modifie la cha\u00eene mol\u00e9culaire, en greffant ou en segmentant d'autres groupes fonctionnels ou polym\u00e8res sur les cha\u00eenes de PA6 pour am\u00e9liorer les performances globales.<\/p><p class=\"translation-block\">Voici quelques nylons modifi\u00e9s couramment utilis\u00e9s :<\/p><ol><li><p class=\"translation-block\"><strong>Nylon renforc\u00e9<\/strong> : La plupart du nylon renforc\u00e9 utilise des fibres de verre, ainsi que des charges telles que le carbonate de calcium et le talc. Ces additifs am\u00e9liorent la stabilit\u00e9 dimensionnelle et la duret\u00e9, mais ils peuvent \u00e9galement augmenter la densit\u00e9 et r\u00e9duire la t\u00e9nacit\u00e9 et la brillance de la surface du mat\u00e9riau.<\/p><\/li><li><p class=\"translation-block\"><strong>Nylon durci<\/strong> : Le but premier du durcissement avec du caoutchouc est d'am\u00e9liorer les performances \u00e0 basse temp\u00e9rature. Le nylon ordinaire devient cassant et perd sa fonctionnalit\u00e9 \u00e0 des temp\u00e9ratures comprises entre -30 et -20 degr\u00e9s Celsius. Les agents de trempe les plus courants sont le caoutchouc EPDM, le caoutchouc EPR, le caoutchouc nitrile, le caoutchouc styr\u00e8ne-butadi\u00e8ne et le caoutchouc polybutadi\u00e8ne, l'EPDM \u00e9tant le plus utilis\u00e9. Cependant, le nylon renforc\u00e9 peut r\u00e9duire la fluidit\u00e9 du mat\u00e9riau, ce qui rend le moulage par injection plus difficile. Il est important de noter que l'utilisation conjointe d'agents durcisseurs et de retardateurs de flamme peut rendre ces derniers inefficaces.<\/p><\/li><li><p class=\"translation-block\"><strong>Nylon r\u00e9sistant \u00e0 l'usure<\/strong> : Le nylon r\u00e9sistant \u00e0 l'usure est obtenu par l'ajout d'additifs tels que des fibres de carbone, du disulfure de molybd\u00e8ne, du graphite, de la poudre de PTFE ou de la poudre de silicone pour r\u00e9duire le frottement ou augmenter la duret\u00e9 de la surface, r\u00e9duisant ainsi l'usure.<\/p><\/li><li><p class=\"translation-block\"><a href=\"http:\/\/boyanmfg.com\/explore-flame-retardant-plastics\/\"><strong>Nylon ignifug\u00e9<\/strong><\/a> : Les retardateurs de flamme disponibles sur le march\u00e9 se r\u00e9partissent g\u00e9n\u00e9ralement en trois cat\u00e9gories : les retardateurs halog\u00e9n\u00e9s, les retardateurs non halog\u00e9n\u00e9s et les retardateurs \u00e0 base de phosphore rouge, bien que ce dernier soit moins courant. Les retardateurs de flamme non halog\u00e9n\u00e9s sont plus respectueux de l'environnement car ils produisent moins de fum\u00e9e et de sous-produits lors de la combustion. Les retardateurs de flamme halog\u00e9n\u00e9s sont plus efficaces mais produisent de la fum\u00e9e noire et des gaz nocifs en br\u00fblant. Il est essentiel de comprendre que les plastiques ignifuges ne sont pas ininflammables, mais qu'ils sont con\u00e7us pour s'\u00e9teindre une fois que la source de la flamme est supprim\u00e9e.<\/p><\/li><li><p class=\"translation-block\"><strong>Nylon transparent<\/strong> : Le nylon transparent peut atteindre un taux de transmission de la lumi\u00e8re sup\u00e9rieur \u00e0 90%, comparable \u00e0 celui du PMMA, et poss\u00e8de \u00e9galement une bonne r\u00e9sistance \u00e0 la traction et aux chocs. La cl\u00e9 de la cr\u00e9ation du nylon transparent r\u00e9side dans la modification de l'arrangement des cha\u00eenes de polym\u00e8re ou dans l'introduction de comonom\u00e8res sp\u00e9cifiques pour r\u00e9duire la cristallinit\u00e9, car les r\u00e9gions cristallines et amorphes sont responsables de l'opacit\u00e9 du mat\u00e9riau.<\/p><\/li><\/ol><p class=\"translation-block\">En outre, il existe d'autres types de nylon, tels que le nylon \u00e9lectrod\u00e9pos\u00e9, le nylon r\u00e9sistant aux UV, etc. Ces techniques de modification ont consid\u00e9rablement \u00e9largi les applications du nylon, r\u00e9pondant ainsi \u00e0 un plus grand nombre de besoins industriels et quotidiens.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c10f42 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0c10f42\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c1ed0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c1ed0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c135d0e\" data-id=\"c135d0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c93e6d elementor-widget elementor-widget-heading\" data-id=\"6c93e6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Key_Considerations_for_Nylon_Injection_Molding\"><\/span>Consid\u00e9rations cl\u00e9s pour le moulage par injection du nylon<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91cf286 elementor-widget elementor-widget-text-editor\" data-id=\"91cf286\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Lorsqu'il s'agit de moulage par injection de nylon, plusieurs m\u00e9thodes et techniques cl\u00e9s doivent \u00eatre ma\u00eetris\u00e9es pour garantir la qualit\u00e9 du produit. Ces m\u00e9thodes et techniques sont les suivantes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61a3261 elementor-widget elementor-widget-image\" data-id=\"61a3261\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/all-electric-molding-machine.jpg\" title=\"machine \u00e0 mouler enti\u00e8rement \u00e9lectrique\" alt=\"machine \u00e0 mouler enti\u00e8rement \u00e9lectrique\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4ddd6e elementor-widget elementor-widget-text-editor\" data-id=\"a4ddd6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>S\u00e9chage du mat\u00e9riau Nylon<\/strong> : Le nylon est susceptible d'absorber l'humidit\u00e9, il est donc crucial de le s\u00e9cher avant le moulage par injection. La temp\u00e9rature de s\u00e9chage recommand\u00e9e est de 120 \u2103 pendant 4 heures. Cette \u00e9tape diff\u00e8re de celle de certains autres plastiques comme le PP, qui ne n\u00e9cessitent pas de s\u00e9chage pr\u00e9alable.<\/p><p class=\"translation-block\"><strong>Temp\u00e9rature de moulage par injection<\/strong> :<\/p><ul><li><p class=\"translation-block\"><strong>PA6<\/strong> : La plage normale de temp\u00e9rature de moulage par injection pour le PA6 est de 220-260 \u2103. Il est g\u00e9n\u00e9ralement recommand\u00e9 de r\u00e9gler les temp\u00e9ratures des deuxi\u00e8me et troisi\u00e8me \u00e9tapes \u00e0 240-250 \u2103, la temp\u00e9rature de la buse \u00e9tant contr\u00f4l\u00e9e \u00e0 210-220 \u2103. La temp\u00e9rature au niveau de la porte doit \u00eatre inf\u00e9rieure de 10 degr\u00e9s \u00e0 la temp\u00e9rature de la buse, car une temp\u00e9rature trop \u00e9lev\u00e9e peut entra\u00eener des difficult\u00e9s dans l'\u00e9vacuation du mat\u00e9riau et le glissement de la vis.<\/p><\/li><li><p class=\"translation-block\">&lt;PA66<\/strong> : Le point de fusion du PA66 est d'environ 255-260 \u2103. La temp\u00e9rature de la buse doit \u00eatre r\u00e9gl\u00e9e entre 265 et 275 \u2103, et les temp\u00e9ratures des deuxi\u00e8me et troisi\u00e8me \u00e9tages entre 280 et 290 \u2103, la temp\u00e9rature de la porte se situant autour de 280 \u2103.<\/p><\/li><li><p class=\"translation-block\"><strong>Nylon renforc\u00e9<\/strong> : Pour le nylon renforc\u00e9 (tant pour le Nylon 6 que pour le Nylon 66), il est conseill\u00e9 d'augmenter la temp\u00e9rature de moulage par injection de 10 \u00e0 20 degr\u00e9s en raison de sa fluidit\u00e9 relativement faible. Pour am\u00e9liorer l'aspect du produit, les temp\u00e9ratures des deuxi\u00e8me et troisi\u00e8me \u00e9tapes peuvent \u00e9galement \u00eatre augment\u00e9es de 10 \u00e0 20 degr\u00e9s.<\/p><\/li><\/ul><p class=\"translation-block\"><strong>Vitesse d'injection<\/strong> : Lors de la fabrication de produits en nylon contenant des fibres de verre, il est n\u00e9cessaire d'augmenter la vitesse d'injection afin d'\u00e9viter l'apparition de fibres flottantes \u00e0 la surface du produit.<\/p><p class=\"translation-block\"><strong>Temp\u00e9rature de moulage<\/strong> : Pour le nylon 6 et le nylon 66, la temp\u00e9rature de moulage recommand\u00e9e est de 80-120 \u2103. La temp\u00e9rature du moule affecte la qualit\u00e9 de la surface et la <strong>cristallinit\u00e9<\/strong> du produit. Les produits \u00e0 parois fines n\u00e9cessitent une temp\u00e9rature de moulage plus \u00e9lev\u00e9e, tandis que ceux \u00e0 parois plus \u00e9paisses peuvent \u00eatre trait\u00e9s \u00e0 une temp\u00e9rature de moulage plus basse, telle que 40-80 degr\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9db9ca5 elementor-widget elementor-widget-text-editor\" data-id=\"9db9ca5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Plus d'explications sur la temp\u00e9rature du moule<\/strong><\/h4><p class=\"translation-block\">La temp\u00e9rature du moule joue un r\u00f4le crucial dans la d\u00e9termination de la qualit\u00e9 de la surface et de la cristallinit\u00e9 des produits. Une temp\u00e9rature de moule plus \u00e9lev\u00e9e se traduit par une meilleure qualit\u00e9 de surface et augmente \u00e9galement la cristallinit\u00e9 du produit. Cela s'explique par le fait qu'une temp\u00e9rature plus \u00e9lev\u00e9e ralentit le processus de refroidissement, ce qui donne au plastique plus de temps pour se cristalliser.<\/p><p class=\"translation-block\">L'augmentation de la cristallinit\u00e9 rend les produits en nylon plus denses, plus r\u00e9sistants \u00e0 l'usure, plus durs et augmente leur module d'\u00e9lasticit\u00e9. Elle r\u00e9duit \u00e9galement l'absorption d'eau, ce qui rend ces produits plus adapt\u00e9s aux applications o\u00f9 la r\u00e9sistance et la rigidit\u00e9 sont essentielles.<\/p><p class=\"translation-block\">En revanche, si vous souhaitez que vos produits en nylon soient plus souples et plus extensibles, vous devez viser une cristallinit\u00e9 plus faible. Vous pouvez y parvenir en r\u00e9duisant la temp\u00e9rature du moule. Des temp\u00e9ratures plus basses acc\u00e9l\u00e8rent le processus de refroidissement, perturbent le processus de cristallisation dans le mat\u00e9riau nylon et, par cons\u00e9quent, r\u00e9duisent sa cristallinit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62ac0c6 elementor-widget elementor-widget-text-editor\" data-id=\"62ac0c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"994105e7-9248-40f9-98a9-2f4ec3386ea1\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><h4><strong>Le tacle <a href=\"http:\/\/boyanmfg.com\/common-injection-molding-defects\/\">Fibre flottante<\/a> sur la surface du nylon<\/strong><\/h4><p class=\"translation-block\">Lors du moulage par injection de nylon renforc\u00e9 de fibres de verre, un probl\u00e8me courant est celui des \u201cfibres flottantes\u201d, qui sont des zones rugueuses et in\u00e9gales \u00e0 la surface, caus\u00e9es par l'accumulation et la remont\u00e9e des fibres de verre.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ccb657 elementor-widget elementor-widget-image\" data-id=\"0ccb657\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/common-injection-molding-defects\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"487\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic.jpg\" class=\"attachment-large size-large wp-image-7376\" alt=\"fibre flottante \u00e0 la surface d&#039;une pi\u00e8ce en plastique nylon\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic.jpg 650w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic-600x450.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic-300x225.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56dfdf4 elementor-widget elementor-widget-text-editor\" data-id=\"56dfdf4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Pour r\u00e9soudre le probl\u00e8me des fibres flottantes, la premi\u00e8re approche consiste \u00e0 am\u00e9liorer la fluidit\u00e9 du mat\u00e9riau nylon, \u00e0 augmenter la temp\u00e9rature du moule et \u00e0 accro\u00eetre la vitesse d'injection et la pression. Une autre m\u00e9thode consiste \u00e0 ajouter un agent de compatibilit\u00e9 entre la fibre de verre et le mat\u00e9riau nylon, bien qu'elle soit g\u00e9n\u00e9ralement plus co\u00fbteuse car elle n\u00e9cessite un soutien suppl\u00e9mentaire de la part des fournisseurs de mat\u00e9riaux et peut r\u00e9duire les performances du nylon \u00e0 d'autres \u00e9gards.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce418f8 elementor-widget elementor-widget-text-editor\" data-id=\"ce418f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Utilisation de nylon pur pour \u00e9viter les fibres flottantes<\/strong><\/h4><p class=\"translation-block\">Parfois, m\u00eame apr\u00e8s avoir pris toutes les mesures mentionn\u00e9es ci-dessus, il est impossible d'emp\u00eacher la pr\u00e9sence de petites fibres flottantes \u00e0 la surface du produit, comme le montrent les photos ci-dessous :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eea6420 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eea6420\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0fb07e4\" data-id=\"0fb07e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79b7ee7 elementor-widget elementor-widget-image\" data-id=\"79b7ee7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-1.jpg\" class=\"attachment-large size-large wp-image-9430\" alt=\"L\u00e9g\u00e8re fibre flottante sur une pi\u00e8ce moul\u00e9e par injection en nylon, vue de loin\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-1-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b336002\" data-id=\"b336002\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39addfd elementor-widget elementor-widget-image\" data-id=\"39addfd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-2.jpg\" class=\"attachment-large size-large wp-image-9429\" alt=\"l\u00e9g\u00e8re fibre flottante sur une pi\u00e8ce moul\u00e9e par injection en nylon, vue rapproch\u00e9e\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-82955ca elementor-widget elementor-widget-text-editor\" data-id=\"82955ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Ces fibres flottantes sont g\u00e9n\u00e9ralement acceptables dans de nombreux cas, mais elles ne le sont pas pour les produits de qualit\u00e9 sup\u00e9rieure. Dans ce cas, vous devrez peut-\u00eatre opter pour du nylon pur. Bien entendu, sans la pr\u00e9sence de fibres de verre, les fibres flottantes ne posent plus de probl\u00e8me.<\/p><p class=\"translation-block\">Cependant, le nylon pur pose d'autres probl\u00e8mes. Il adh\u00e8re plus fortement au moule, ce qui peut entra\u00eener un blanchiment localis\u00e9 et une d\u00e9formation lorsque le produit est \u00e9ject\u00e9 du moule. En outre, son taux de r\u00e9traction est plus \u00e9lev\u00e9 que celui du nylon renforc\u00e9 de fibres de verre, ce qui peut entra\u00eener une r\u00e9duction de la taille du produit. Il s'agit l\u00e0 de probl\u00e8mes suppl\u00e9mentaires qu'il convient de r\u00e9soudre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72be79f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"72be79f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d87516a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d87516a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-843f83a\" data-id=\"843f83a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6471936 elementor-widget elementor-widget-heading\" data-id=\"6471936\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Why_Many_Small_and_Medium_Enterprises_Engage_in_Nylon_Modification\"><\/span>Pourquoi de nombreuses petites et moyennes entreprises s'engagent-elles dans la modification du nylon ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5d765a elementor-widget elementor-widget-text-editor\" data-id=\"e5d765a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">De nombreuses petites et moyennes entreprises choisissent de se lancer dans la modification du nylon, en particulier du PA6 et du PA66, pour plusieurs raisons :<\/p><p class=\"translation-block\"><strong>Grande application<\/strong> : l'excellente solidit\u00e9 du nylon, sa r\u00e9sistance \u00e0 l'usure, sa r\u00e9sistance \u00e0 la corrosion chimique et sa tol\u00e9rance aux temp\u00e9ratures \u00e9lev\u00e9es lui permettent d'\u00eatre utilis\u00e9 dans divers domaines tels que l'automobile, l'\u00e9lectronique, les machines et les biens de consommation courante. Cette diversit\u00e9 offre aux petites et moyennes entreprises un vaste espace de march\u00e9.<\/p><p class=\"translation-block\"><strong>Haut potentiel de modification<\/strong> : le nylon peut \u00eatre am\u00e9lior\u00e9 par l'ajout de diff\u00e9rents mat\u00e9riaux (tels que des fibres de verre ou de carbone), de charges (telles que des charges min\u00e9rales) et d'autres additifs (tels que des retardateurs de flamme et des stabilisateurs d'UV) pour r\u00e9pondre \u00e0 des besoins sp\u00e9cifiques.<\/p><p class=\"translation-block\"><strong>Facilit\u00e9 de traitement<\/strong> : le nylon est facile \u00e0 mouler et le co\u00fbt de l'\u00e9quipement de production et d'essai n'est pas \u00e9lev\u00e9, ce qui r\u00e9duit la barri\u00e8re \u00e0 l'entr\u00e9e. Le principal co\u00fbt est li\u00e9 \u00e0 la n\u00e9cessit\u00e9 de disposer d'un espace de production et de stockage important.<\/p><p class=\"translation-block\"><strong>Cost-Effective<\/strong> : le nylon offre un bon \u00e9quilibre entre co\u00fbt et performance. Les petites et moyennes entreprises peuvent acheter des mati\u00e8res premi\u00e8res \u00e0 moindre co\u00fbt et am\u00e9liorer la comp\u00e9titivit\u00e9 de leurs produits en les modifiant.<\/p><p class=\"translation-block\"><strong>Demande stable<\/strong> : la demande de nylon est relativement stable, offrant aux petites et moyennes entreprises un environnement commercial pr\u00e9visible, ce qui est particuli\u00e8rement important pour celles dont les ressources sont limit\u00e9es.<\/p><p class=\"translation-block\"><strong>Technologie mature<\/strong> : la technologie de modification du nylon est relativement mature, et les m\u00e9thodes et formules de traitement connexes sont facilement accessibles, ce qui r\u00e9duit les difficult\u00e9s techniques et permet aux petites et moyennes entreprises de les ma\u00eetriser plus facilement.<\/p><p class=\"translation-block\">Par cons\u00e9quent, la modification du nylon est un choix id\u00e9al pour les petites et moyennes usines de plastique, car elle est techniquement r\u00e9alisable, \u00e9conomiquement raisonnable et adaptable aux demandes stables du march\u00e9. Cela les aide \u00e0 s'implanter dans un secteur tr\u00e8s concurrentiel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8468aca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8468aca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f30e30d\" data-id=\"f30e30d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ad2a29 elementor-widget elementor-widget-heading\" data-id=\"3ad2a29\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"On-Site_Visits_to_Small_and_Medium_Material_Manufacturers\"><\/span>Visites sur place des petits et moyens fabricants de mat\u00e9riaux<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c49054 elementor-widget elementor-widget-text-editor\" data-id=\"6c49054\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Lors de la s\u00e9lection et de l'\u00e9valuation des fabricants de mat\u00e9riaux de petite et moyenne taille, la visite de leurs usines est une \u00e9tape cruciale. En vous rendant sur place, vous pouvez vous rendre compte directement si leur processus de production et leur gestion du stockage respectent les normes de contr\u00f4le de la qualit\u00e9. Ces visites vous permettent \u00e9galement d'inspecter la qualit\u00e9 des mati\u00e8res premi\u00e8res utilis\u00e9es et de v\u00e9rifier si l'usine est \u00e9quip\u00e9e d'un mat\u00e9riel d'essai ad\u00e9quat pour garantir la qualit\u00e9 du produit.<\/p><p class=\"translation-block\">Une communication directe avec les fabricants est \u00e9galement essentielle. Les conversations vous permettront de d\u00e9terminer s'ils poss\u00e8dent les connaissances professionnelles et la compr\u00e9hension n\u00e9cessaires pour garantir la qualit\u00e9 des produits et le service apr\u00e8s-vente. En outre, les \u00e9changes avec les membres de l'\u00e9quipe peuvent vous donner un aper\u00e7u de leur attitude au travail et de leur sens du service, qui sont des facteurs importants dans le choix du bon fournisseur.<\/p><p class=\"translation-block\">Pour mieux illustrer ce processus, voici une vid\u00e9o pr\u00e9sentant le site de production du nylon modifi\u00e9. Cette vid\u00e9o vous permet d'observer visuellement l'environnement de production et les processus op\u00e9rationnels, ce qui est extr\u00eamement utile pour \u00e9valuer les capacit\u00e9s de production et la qualit\u00e9 des produits.<\/p><p class=\"translation-block\">En r\u00e9sum\u00e9, les visites sur place vous permettent non seulement d'obtenir des informations de premi\u00e8re main sur les fabricants, mais aussi de prendre des d\u00e9cisions plus \u00e9clair\u00e9es et plus pratiques. Ces \u00e9valuations peuvent renforcer votre confiance dans les capacit\u00e9s de contr\u00f4le de la qualit\u00e9 et de production du fournisseur, en vous assurant que le partenaire que vous avez choisi peut r\u00e9pondre aux besoins de votre entreprise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1d48fb elementor-widget elementor-widget-video\" data-id=\"e1d48fb\" data-element_type=\"widget\" data-settings='{\"youtube_url\":\"https:\\\/\\\/youtu.be\\\/kJjP1VA620c\",\"video_type\":\"youtube\",\"controls\":\"yes\"}' data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c312a22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c312a22\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2509e3\" data-id=\"c2509e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6912c94 elementor-widget elementor-widget-heading\" data-id=\"6912c94\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Material_Performance_Testing_Experiments\"><\/span>Essais de performance des mat\u00e9riaux Exp\u00e9riences<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf48ef elementor-widget elementor-widget-text-editor\" data-id=\"4bf48ef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Les usines de fabrication de mat\u00e9riaux sont g\u00e9n\u00e9ralement \u00e9quip\u00e9es de divers \u00e9quipements exp\u00e9rimentaux pour tester les performances des mat\u00e9riaux. Ces tests comprennent principalement<\/p><ol><li><p class=\"translation-block\"><strong>Test de r\u00e9sistance \u00e0 la traction (y compris l'allongement \u00e0 la rupture)<\/strong> : ce test mesure la capacit\u00e9 du mat\u00e9riau \u00e0 r\u00e9sister aux forces de traction. Les r\u00e9sultats sont g\u00e9n\u00e9ralement exprim\u00e9s en m\u00e9gapascals (MPa). Il comprend \u00e9galement l'allongement \u00e0 la rupture, qui est la mesure dans laquelle le mat\u00e9riau peut s'allonger avant de se rompre, g\u00e9n\u00e9ralement exprim\u00e9e en pourcentage (%).<\/p><\/li><li><p class=\"translation-block\"><strong>Test de r\u00e9sistance \u00e0 la flexion<\/strong> : ce test \u00e9value la performance du mat\u00e9riau en flexion. Il consiste \u00e0 appliquer une force pour plier le mat\u00e9riau et \u00e0 mesurer la force requise et le degr\u00e9 de flexion, g\u00e9n\u00e9ralement exprim\u00e9s en m\u00e9gapascals (MPa).<\/p><\/li><li><p class=\"translation-block\"><strong>Test de r\u00e9sistance aux chocs<\/strong> : ce test \u00e9value la r\u00e9sistance du mat\u00e9riau aux chocs soudains. Les r\u00e9sultats sont exprim\u00e9s en kilojoules par m\u00e8tre carr\u00e9 (KJ\/m\u00b2), ce qui indique la t\u00e9nacit\u00e9 du mat\u00e9riau ou sa r\u00e9sistance aux chocs.<\/p><\/li><li><p class=\"translation-block\"><strong>Test de densit\u00e9 du mat\u00e9riau<\/strong> : ce test d\u00e9termine la densit\u00e9 du mat\u00e9riau, c'est-\u00e0-dire la masse par unit\u00e9 de volume. Les r\u00e9sultats sont exprim\u00e9s en grammes par centim\u00e8tre cube (g\/cm\u00b3). Le test consiste \u00e0 peser le mat\u00e9riau dans l'air et dans l'eau pour d\u00e9terminer sa densit\u00e9.<\/p><\/li><li><p class=\"translation-block\"><strong>Test d'\u00e9coulement de la mati\u00e8re fondue<\/strong> : le taux d'\u00e9coulement de la mati\u00e8re fondue (MFR) ou indice de fusion (MI) mesure le nombre de grammes de r\u00e9sine fondue qui s'\u00e9coulent \u00e0 travers un tube capillaire standard dans des conditions de temp\u00e9rature et de pression sp\u00e9cifiques pendant un temps donn\u00e9 (g\u00e9n\u00e9ralement 10 minutes), exprim\u00e9 en grammes par 10 minutes (g\/10min).<\/p><\/li><\/ol><p class=\"translation-block\">Une vid\u00e9o est fournie ici pour montrer comment ces tests sont effectu\u00e9s. Dans la vid\u00e9o, vous pouvez voir le processus et l'\u00e9quipement de test r\u00e9el, ce qui vous aide \u00e0 mieux comprendre les op\u00e9rations sp\u00e9cifiques et la signification de chaque test.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44481f8 elementor-widget elementor-widget-video\" data-id=\"44481f8\" data-element_type=\"widget\" data-settings='{\"youtube_url\":\"https:\\\/\\\/youtu.be\\\/_pyAI0IbShA\",\"video_type\":\"youtube\",\"controls\":\"yes\"}' data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a3a196 elementor-widget elementor-widget-text-editor\" data-id=\"9a3a196\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Ces essais sont essentiels pour garantir que les mat\u00e9riaux r\u00e9pondent aux exigences de performance pour des applications sp\u00e9cifiques. Gr\u00e2ce \u00e0 ces donn\u00e9es exp\u00e9rimentales d\u00e9taill\u00e9es, les fabricants peuvent \u00e9valuer et am\u00e9liorer les mat\u00e9riaux avec pr\u00e9cision et fournir ainsi des produits de meilleure qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c86a7f9 elementor-widget elementor-widget-spacer\" data-id=\"c86a7f9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c8bc7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c8bc7c\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc20e01\" data-id=\"bc20e01\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55b2a5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55b2a5e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-95011af\" data-id=\"95011af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6119e4 elementor-widget elementor-widget-image\" data-id=\"e6119e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png\" class=\"attachment-large size-large wp-image-6453\" alt=\"Bo\u00eete triangulaire surmoul\u00e9e en TPU\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d97de55\" data-id=\"d97de55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a176a73 elementor-widget elementor-widget-heading\" data-id=\"a176a73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Nous sommes experts en moulage par injection de plastique. Contactez-nous d\u00e8s maintenant pour obtenir un devis rapide !<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-72ab601\" data-id=\"72ab601\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24c9e9e elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"24c9e9e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demande de devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Comprendre les fondamentaux du moulage par injection du nylon Dans le domaine de la fabrication plastique, le moulage par injection du nylon est une technique essentielle, reconnue pour sa polyvalence et sa r\u00e9sistance. Cette m\u00e9thode transforme le nylon en produits vari\u00e9s, allant des pi\u00e8ces automobiles aux articles du quotidien, d\u00e9montrant sa durabilit\u00e9 et son adaptabilit\u00e9. Cet article explore les subtilit\u00e9s du moulage par injection du nylon,\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/fr\/pa6-and-pa66-nylon-injection-molding\/\" rel=\"bookmark\">Lire plus \u00bb<span class=\"screen-reader-text\">Ma\u00eetriser le moulage par injection du nylon : Aper\u00e7u des PA6 et PA66<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":7142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":92,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,56],"tags":[],"class_list":["post-7103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-sourcing-skills"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/posts\/7103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/comments?post=7103"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/posts\/7103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/media\/7142"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/media?parent=7103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/categories?post=7103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/fr\/wp-json\/wp\/v2\/tags?post=7103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}