{"id":9248,"date":"2024-10-20T23:03:19","date_gmt":"2024-10-20T23:03:19","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=9248"},"modified":"2024-11-19T03:22:13","modified_gmt":"2024-11-19T03:22:13","slug":"injection-mold-assembly-and-manual-fitting","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/","title":{"rendered":"Montaje de moldes de inyecci\u00f3n y ajuste manual"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9248\" class=\"elementor elementor-9248\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db1d274 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db1d274\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbfd7fd\" data-id=\"cbfd7fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3b91ac elementor-widget elementor-widget-heading\" data-id=\"d3b91ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#The_Importance_of_Injection_Mold_Assembly_and_Manual_Fitting\" >La importancia del montaje de moldes de inyecci\u00f3n y del ajuste manual<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#What_is_Manual_Fitting\" >\u00bfQu\u00e9 es la adaptaci\u00f3n manual?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Key_Areas_to_Inspect_in_Manual_Fitting\" >\u00c1reas clave a inspeccionar en el montaje manual<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Common_Inspection_Methods\" >M\u00e9todos comunes de inspecci\u00f3n<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Red_Dan_Inspection_Method\" >M\u00e9todo de inspecci\u00f3n Red Dan<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Adjustment_Methods\" >M\u00e9todos de ajuste<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Inspection_of_Sliders_and_Lifters\" >Inspecci\u00f3n de correderas y elevadores<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Tactile_Inspection\" >Inspecci\u00f3n t\u00e1ctil<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Mold_Fitting_Timeline\" >Cronolog\u00eda de la adaptaci\u00f3n de moldes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/#Summary\" >Resumen<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"The_Importance_of_Injection_Mold_Assembly_and_Manual_Fitting\"><\/span>La importancia del montaje de moldes de inyecci\u00f3n y del ajuste manual<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a196b8 elementor-widget elementor-widget-text-editor\" data-id=\"7a196b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">En el proceso de fabricaci\u00f3n del moldeo por inyecci\u00f3n, el <strong>montaje del molde<\/strong> y el <strong>ajuste manual<\/strong> son etapas cruciales que requieren un tiempo y un esfuerzo considerables. Estos procesos exigen una atenci\u00f3n meticulosa a los detalles, una gran experiencia y precisi\u00f3n artesanal.<\/p><p class=\"translation-block\"><strong>Un enfoque cuidadoso y deliberado<\/strong> es esencial para lograr una calidad \u00f3ptima del molde. Solo con este nivel de precisi\u00f3n se puede garantizar un molde de alta calidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b09f9c elementor-widget elementor-widget-heading\" data-id=\"5b09f9c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_is_Manual_Fitting\"><\/span>\u00bfQu\u00e9 es la adaptaci\u00f3n manual?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4778f1e elementor-widget elementor-widget-text-editor\" data-id=\"4778f1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El ajuste manual se refiere al proceso de ajustar a mano la precisi\u00f3n dimensional de los componentes individuales del molde despu\u00e9s de haber sido mecanizados. Esto garantiza que todos los <a href=\"http:\/\/boyanmfg.com\/injection-mold-cost-in-china\/#basic_structure\">componentes del molde<\/a> <strong>se ajusten perfectamente, se alineen correctamente y alcancen las holguras necesarias para los componentes m\u00f3viles<\/strong> como correderas, elevadores y pasadores eyectores. El objetivo es ajustar estos componentes para que funcionen y se alineen con precisi\u00f3n durante el proceso de inyecci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-224d773 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"224d773\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e6b37e\" data-id=\"7e6b37e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d4901c elementor-widget elementor-widget-heading\" data-id=\"8d4901c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Key_Areas_to_Inspect_in_Manual_Fitting\"><\/span>\u00c1reas clave a inspeccionar en el montaje manual<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0886827 elementor-widget elementor-widget-text-editor\" data-id=\"0886827\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Al realizar el montaje manual, es necesario inspeccionar varias zonas cr\u00edticas:<\/p><p class=\"translation-block\"><strong>1. Superficie de separaci\u00f3n<\/strong>: La <a href=\"http:\/\/boyanmfg.com\/design-for-manufacturing-plastic-injection-molding\/#parting_design\">superficie de separaci\u00f3n<\/a> del molde debe ser plana y estar bien alineada. Un mal contacto o huecos entre estas superficies pueden provocar rebabas durante el moldeo por inyecci\u00f3n. Conseguir una alineaci\u00f3n perfecta es relativamente sencillo para superficies planas, pero puede ser m\u00e1s complejo para l\u00edneas de separaci\u00f3n tridimensionales.<\/p><p class=\"translation-block\"><strong>2. Superficie de punzonado<\/strong>: Las superficies de punzonado, que crean aberturas en la pieza moldeada, deben encajar con precisi\u00f3n.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-001f6a6 elementor-widget elementor-widget-image\" data-id=\"001f6a6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/plastic-part-with-opening.jpg\" class=\"attachment-large size-large wp-image-9355\" alt=\"un componente de pl\u00e1stico con una abertura que requiere un punzonado a trav\u00e9s de la superficie en molde de inyecci\u00f3n\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/plastic-part-with-opening.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/plastic-part-with-opening-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">un componente de pl\u00e1stico con una abertura <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8145e79 elementor-widget elementor-widget-text-editor\" data-id=\"8145e79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El n\u00facleo del molde y la cavidad deben estar en contacto a la altura correcta para garantizar un contacto uniforme cuando se cierre el molde. Una desalineaci\u00f3n en este punto puede provocar una presi\u00f3n desigual y la formaci\u00f3n de rebabas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0200112 elementor-widget elementor-widget-image\" data-id=\"0200112\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9357\" alt=\"La superficie perforada de un molde de inyecci\u00f3n en una vista 3D\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La superficie perforada en una vista 3D<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84e44c8 elementor-widget elementor-widget-image\" data-id=\"84e44c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-2.jpg\" class=\"attachment-large size-large wp-image-9356\" alt=\"La superficie de punzonado de un molde de inyecci\u00f3n en la secci\u00f3n transversal\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-2-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La superficie del punz\u00f3n en la vista transversal.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5d9a16 elementor-widget elementor-widget-text-editor\" data-id=\"c5d9a16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>3. Correderas y elevadores<\/strong>: Las correderas y los elevadores deben tener la holgura correcta con sus ra\u00edles gu\u00eda, normalmente entre 0,01 y 0,05 mm, dependiendo del tama\u00f1o. Estos componentes tambi\u00e9n deben estar enrasados con el n\u00facleo del molde para evitar l\u00edneas de desajuste o problemas dimensionales en la pieza moldeada.<\/p><p class=\"translation-block\"><strong>4. Bordes afilados y rebabas<\/strong>: Aunque el biselado durante el mecanizado CNC puede ser costoso, es una pr\u00e1ctica com\u00fan eliminar manualmente las rebabas y los bordes afilados utilizando amoladoras para garantizar un funcionamiento suave y evitar da\u00f1os durante el montaje del molde.<\/p><p class=\"translation-block\"><strong>5. Ventilaci\u00f3n del molde<\/strong>: La ventilaci\u00f3n adecuada es esencial para permitir que el aire escape durante el moldeo por inyecci\u00f3n. Los respiraderos deben comprobarse para asegurarse de que son del tama\u00f1o correcto. Los orificios de ventilaci\u00f3n de tama\u00f1o excesivo pueden provocar rebabas, mientras que los orificios de ventilaci\u00f3n de tama\u00f1o insuficiente pueden atrapar el aire y provocar defectos.<\/p><p class=\"translation-block\">Al centrarse en estas \u00e1reas durante el ajuste manual, los fabricantes de moldes pueden garantizar el buen funcionamiento del molde de inyecci\u00f3n y evitar defectos durante la producci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d50f168 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d50f168\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30bf079\" data-id=\"30bf079\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b30a48f elementor-widget elementor-widget-heading\" data-id=\"b30a48f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Common_Inspection_Methods\"><\/span>M\u00e9todos comunes de inspecci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cd6b2f elementor-widget elementor-widget-text-editor\" data-id=\"9cd6b2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El m\u00e9todo m\u00e1s utilizado para comprobar el ajuste y la alineaci\u00f3n de las superficies mecanizadas del molde es el uso de un compuesto de marcado rojo o azul (denominado <strong>\u201cDan rojo\u201d<\/strong> o <strong>\u201cDan azul\u201d<\/strong>). Esta t\u00e9cnica suele complementarse con herramientas de medici\u00f3n precisas, como calibres vernier y micr\u00f3metros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a274af6 elementor-widget elementor-widget-text-editor\" data-id=\"a274af6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Nota:<\/strong><br><strong>Dan rojo<\/strong>: Tiene una textura m\u00e1s dura y es relativamente m\u00e1s \u00e1spero, por lo que es m\u00e1s adecuado para el ajuste de moldes de gran superficie o la alineaci\u00f3n de piezas mec\u00e1nicas pesadas. Puede mostrar puntos de contacto m\u00e1s pronunciados.<br><strong>Blue Dan<\/strong>: Tiene una textura m\u00e1s blanda y es ideal para el ajuste preciso de moldes, mostrando claramente marcas de contacto m\u00e1s ligeras. Es adecuado para comprobaciones de alineaci\u00f3n de moldes de alta precisi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f82dd82 elementor-widget elementor-widget-text-editor\" data-id=\"f82dd82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Con los continuos avances en la tecnolog\u00eda de mecanizado y medici\u00f3n, el uso de<strong> m\u00e1quinas de medici\u00f3n de coordenadas (MMC)<\/strong> se ha hecho cada vez m\u00e1s popular. Las MMC pueden proporcionar un perfil completo de la pieza que se est\u00e1 midiendo y, a menudo, pueden sustituir al m\u00e9todo tradicional Red Dan para realizar inspecciones m\u00e1s precisas y exhaustivas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eb4d7f elementor-widget elementor-widget-text-editor\" data-id=\"4eb4d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Red_Dan_Inspection_Method\"><\/span>M\u00e9todo de inspecci\u00f3n Red Dan<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">El m\u00e9todo Red Dan (o Blue Dan) consiste en aplicar una capa fina y uniforme de compuesto de marcado sobre una mitad de la superficie del molde. Es importante asegurarse de que la aplicaci\u00f3n es uniforme y tiene un grosor consistente.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4e5dd7 elementor-widget elementor-widget-image\" data-id=\"f4e5dd7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/red-Dan-mold.jpg\" class=\"attachment-large size-large wp-image-9283\" alt=\"Aplicaci\u00f3n de Dan Rojo en la superficie del molde\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/red-Dan-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/red-Dan-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6931f1d elementor-widget elementor-widget-text-editor\" data-id=\"6931f1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">A continuaci\u00f3n, se juntan las dos mitades del molde y se presionan firmemente para garantizar un contacto total.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-755c3e6 elementor-widget elementor-widget-image\" data-id=\"755c3e6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/closed-mold-dan-transfer.jpg\" class=\"attachment-large size-large wp-image-9291\" alt=\"\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/closed-mold-dan-transfer.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/closed-mold-dan-transfer-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a2d200 elementor-widget elementor-widget-text-editor\" data-id=\"1a2d200\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Tras separar las mitades del molde, se inspecciona la transferencia de Red Dan a la superficie del molde opuesto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8975041 elementor-widget elementor-widget-image\" data-id=\"8975041\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/dan-transfer-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9293\" alt=\"inspecci\u00f3n de la transferencia de dan en la otra mitad del molde\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/dan-transfer-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/dan-transfer-injection-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af32b25 elementor-widget elementor-widget-text-editor\" data-id=\"af32b25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Buen ajuste<\/strong>: Si las superficies est\u00e1n bien alineadas, el Dan Rojo se transferir\u00e1 uniformemente a la superficie correspondiente de la otra mitad del molde, lo que indica un ajuste uniforme y correcto.<\/li><li><strong>Ajuste demasiado estrecho<\/strong>: Un color intenso indica una holgura m\u00ednima entre las superficies, lo que sugiere un ajuste muy apretado.<\/li><li><strong>Grandes lagunas<\/strong>: Un color m\u00e1s claro o desigual sugiere que hay mayores diferencias entre las superficies. Si no se transfiere ning\u00fan Dan Rojo, esto indica una desalineaci\u00f3n significativa, y las zonas en cuesti\u00f3n requerir\u00e1n un mayor ajuste de las dimensiones o la forma.<\/li><\/ul><p class=\"translation-block\">Una vez unidas las mitades del molde, es importante utilizar una varilla de cobre o aluminio para martillar el molde con fuerza a fin de garantizar un contacto firme de las mitades del molde. De lo contrario, podr\u00edan quedar grandes zonas sin transferencia de Red Dan, lo que dar\u00eda lugar a una inspecci\u00f3n incompleta y a resultados inexactos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe2a75b elementor-widget elementor-widget-image\" data-id=\"fe2a75b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/hammering-mold-dye-transfer.jpg\" class=\"attachment-large size-large wp-image-9302\" alt=\"Martilleo del molde para garantizar la transferencia completa del tinte\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/hammering-mold-dye-transfer.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/hammering-mold-dye-transfer-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Golpear el molde con una varilla de aluminio para transferir el tinte.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c67a4a elementor-widget elementor-widget-text-editor\" data-id=\"2c67a4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Para mejorar la eficacia, es muy recomendable utilizar una <a href=\"https:\/\/www.youtube.com\/watch?v=1nROYXfgDFA\" target=\"_blank\" rel=\"noopener\">prensa para marcar moldes<\/a>. Esta m\u00e1quina puede aplicar una presi\u00f3n uniforme en toda la superficie del molde, logrando una mejor transferencia del compuesto de marcado que el martilleo manual. Adem\u00e1s, reduce el esfuerzo f\u00edsico de los trabajadores y acelera el proceso. Para moldes m\u00e1s grandes, es esencial utilizar una m\u00e1quina de sujeci\u00f3n, ya que su peso hace que la manipulaci\u00f3n manual sea poco pr\u00e1ctica e ineficaz para lograr resultados precisos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d16113 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d16113\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2c48aa\" data-id=\"b2c48aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddddc64 elementor-widget elementor-widget-heading\" data-id=\"ddddc64\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Adjustment_Methods\"><\/span>M\u00e9todos de ajuste<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49253c9 elementor-widget elementor-widget-text-editor\" data-id=\"49253c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Existen varios m\u00e9todos para ajustar las dimensiones de los componentes de los moldes de inyecci\u00f3n y conseguir la precisi\u00f3n necesaria:<\/p><h4 style=\"padding-left: 40px;\"><strong>1. Rectificadora<\/strong><\/h4><p style=\"padding-left: 40px;\" class=\"translation-block\">Uno de los m\u00e9todos m\u00e1s utilizados para ajustar la altura de superficies planas es la rectificadora. Este m\u00e9todo es r\u00e1pido, c\u00f3modo y rentable, por lo que resulta ideal para realizar peque\u00f1os ajustes en las secciones planas de las piezas del molde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8a3a1 elementor-widget elementor-widget-image\" data-id=\"ee8a3a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/grind-Injection-mold-surface.jpg\" class=\"attachment-large size-large wp-image-9312\" alt=\"rectificar la superficie del componente del molde para ajustar la altura\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/grind-Injection-mold-surface.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/grind-Injection-mold-surface-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96e02b3 elementor-widget elementor-widget-text-editor\" data-id=\"96e02b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"padding-left: 40px;\"><strong>2. Ajuste manual<\/strong><\/h4><p style=\"padding-left: 40px;\" class=\"translation-block\">Para superficies curvas, los ajustes manuales suelen limitarse a peque\u00f1as correcciones localizadas. Se utilizan herramientas como <strong>limas, papel de lija<\/strong> y <strong>amoladoras el\u00e9ctricas<\/strong> (como <strong>herramientas rotativas<\/strong> o <strong>amoladora angular<\/strong>) para perfeccionar zonas espec\u00edficas. Este m\u00e9todo suele hacerse gradualmente, utilizando la t\u00e9cnica Red Dan mencionada anteriormente para acercarse a las dimensiones deseadas. Sin embargo, como el ajuste manual requiere mucho tiempo, es m\u00e1s adecuado para peque\u00f1os ajustes que para cambios a gran escala.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43421bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43421bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c5bc0c2\" data-id=\"c5bc0c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c401a8f elementor-widget elementor-widget-image\" data-id=\"c401a8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-1.jpg\" class=\"attachment-large size-large wp-image-9335\" alt=\"Utilice una herramienta rotativa para eliminar el exceso de material y ajustar el tama\u00f1o en el ajuste manual del molde\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-1-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d33a89\" data-id=\"3d33a89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-867fbf4 elementor-widget elementor-widget-image\" data-id=\"867fbf4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-2.jpg\" class=\"attachment-large size-large wp-image-9334\" alt=\"Utilice una herramienta rotativa para eliminar el exceso de material y ajustar el tama\u00f1o en el ajuste manual del molde\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3696472 elementor-widget elementor-widget-text-editor\" data-id=\"3696472\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" class=\"translation-block\">Utilice una herramienta rotativa para eliminar el exceso de material y ajustar el tama\u00f1o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b558b82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b558b82\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9149f6c\" data-id=\"9149f6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bce8832 elementor-widget elementor-widget-image\" data-id=\"bce8832\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/angle-grinder-chamfer.jpg\" class=\"attachment-large size-large wp-image-9336\" alt=\"Utilice una amoladora angular para biselar\uff0cmoldear el accesorio manual.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/angle-grinder-chamfer.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/angle-grinder-chamfer-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Utilice una amoladora angular para biselar los bordes afilados<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-707ff0c\" data-id=\"707ff0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d31e9d elementor-widget elementor-widget-image\" data-id=\"4d31e9d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/file-removing-excessive-material.jpg\" class=\"attachment-large size-large wp-image-9337\" alt=\"Utilice una lima para eliminar el exceso de material y ajustar el tama\u00f1o, ajuste manual del molde\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/file-removing-excessive-material.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/file-removing-excessive-material-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Utilice una lima para limar el material sobrante y ajustar el tama\u00f1o.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-193a786 elementor-widget elementor-widget-text-editor\" data-id=\"193a786\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"padding-left: 40px;\"><strong>3. Fresado CNC y mecanizado por electroerosi\u00f3n<\/strong><\/h4><p style=\"padding-left: 40px;\" class=\"translation-block\">Cuando se requieren ajustes de mayor envergadura, sobre todo para contornos complejos o superficies con desviaciones significativas, se necesitan fresadoras CNC o mecanizado por descarga el\u00e9ctrica (EDM) para repasar la pieza. Las correcciones manuales no son lo suficientemente precisas para modificaciones importantes, especialmente en moldes con elevados requisitos de precisi\u00f3n dimensional. Adem\u00e1s, se desaconseja el limado manual en moldes de alta precisi\u00f3n en los que las marcas visibles de herramientas son inaceptables y pueden comprometer la calidad y funcionalidad del producto final.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b4f849 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b4f849\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8fb6b4a\" data-id=\"8fb6b4a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a2a4fa elementor-widget elementor-widget-image\" data-id=\"2a2a4fa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/cnc-milling-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9320\" alt=\"Fresado CNC para la producci\u00f3n de moldes de inyecci\u00f3n\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/cnc-milling-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/cnc-milling-injection-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Fresado CNC<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1346631\" data-id=\"1346631\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8f4a49 elementor-widget elementor-widget-image\" data-id=\"c8f4a49\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/EDM-machining-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9321\" alt=\"Mecanizado por electroerosi\u00f3n para la producci\u00f3n de moldes de inyecci\u00f3n\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/EDM-machining-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/EDM-machining-injection-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">EDM (Mecanizado por descarga el\u00e9ctrica)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d67549a elementor-widget elementor-widget-text-editor\" data-id=\"d67549a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Estos m\u00e9todos garantizan que las piezas del molde puedan ajustarse de forma eficaz, manteniendo al mismo tiempo los altos niveles de precisi\u00f3n necesarios para un rendimiento \u00f3ptimo del molde. Cada m\u00e9todo tiene su caso de uso espec\u00edfico, siendo los m\u00e9todos manuales adecuados para peque\u00f1os retoques y el mecanizado m\u00e1s avanzado necesario para correcciones importantes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7fd801 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7fd801\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73b5203\" data-id=\"73b5203\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-100d3f7 elementor-widget elementor-widget-heading\" data-id=\"100d3f7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Inspection_of_Sliders_and_Lifters\"><\/span>Inspecci\u00f3n de correderas y elevadores<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-555cda8 elementor-widget elementor-widget-text-editor\" data-id=\"555cda8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Durante el proceso de montaje manual, la inspecci\u00f3n y el ajuste de correderas y elevadores son tareas importantes. Es fundamental garantizar su precisi\u00f3n dimensional y geom\u00e9trica, as\u00ed como mantener la holgura adecuada con sus carriles gu\u00eda.<\/p><p class=\"translation-block\"><strong>Un ajuste inadecuado puede afectar a la precisi\u00f3n de las piezas de pl\u00e1stico que se fabrican y acelerar el desgaste de estos componentes durante el funcionamiento del molde.<\/strong><\/p><h3><span class=\"ez-toc-section\" id=\"Tactile_Inspection\"><\/span>Inspecci\u00f3n t\u00e1ctil<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">Uno de los m\u00e9todos m\u00e1s utilizados para evaluar el ajuste y la holgura de las correderas y los elevadores es la inspecci\u00f3n t\u00e1ctil. Esto implica mover manualmente las correderas (y los elevadores):<\/p><ul><li><strong>Movimiento lateral<\/strong>: Al mover la corredera de un lado a otro, no debe apreciarse holgura ni flojedad.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524eceb elementor-widget elementor-widget-image\" data-id=\"524eceb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Lateral-Movement-Slider.jpg\" class=\"attachment-large size-large wp-image-9342\" alt=\"Comprobaci\u00f3n del movimiento lateral de la corredera en el conjunto del molde\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Lateral-Movement-Slider.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Lateral-Movement-Slider-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e023def elementor-widget elementor-widget-text-editor\" data-id=\"e023def\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Movimiento hacia delante y hacia atr\u00e1s<\/strong>: La corredera debe moverse con la resistencia adecuada, ni demasiado apretada ni demasiado floja.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d31d24a elementor-widget elementor-widget-image\" data-id=\"d31d24a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Forward-Movement-Slider.jpg\" class=\"attachment-large size-large wp-image-9341\" alt=\"Inspecci\u00f3n del movimiento de avance y retroceso de la corredera a lo largo del ra\u00edl gu\u00eda durante el montaje del molde de inyecci\u00f3n.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Forward-Movement-Slider.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Forward-Movement-Slider-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8540fca elementor-widget elementor-widget-text-editor\" data-id=\"8540fca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Si el ajuste es demasiado estrecho o el componente no encaja en absoluto, se puede retirar material para reducir ligeramente las dimensiones. Sin embargo, si el ajuste es demasiado flojo, la \u00fanica soluci\u00f3n es rehacer la corredera o el elevador para conseguir el tama\u00f1o y la tolerancia correctos. Por lo tanto, hay que tener mucho cuidado durante el proceso de ajuste para evitar una retirada excesiva de material.<\/p><p class=\"translation-block\">Dada la precisi\u00f3n que requiere el montaje de correderas y elevadores, este proceso exige t\u00e9cnicos experimentados con grandes habilidades. La precisi\u00f3n y la eficacia del montaje manual de moldes dependen en gran medida de su experiencia para garantizar que todos los componentes est\u00e9n alineados y funcionen seg\u00fan lo previsto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccab789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccab789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bdd5205\" data-id=\"bdd5205\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d80bc elementor-widget elementor-widget-heading\" data-id=\"17d80bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Mold_Fitting_Timeline\"><\/span>Cronolog\u00eda de la adaptaci\u00f3n de moldes<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b5c153 elementor-widget elementor-widget-text-editor\" data-id=\"6b5c153\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El proceso de ajustar manualmente las dimensiones del molde para obtener precisi\u00f3n requiere mucho trabajo y tiempo, por lo que constituye una parte importante del ciclo global de fabricaci\u00f3n del molde.<\/p><ul><li><strong>Productos sencillos<\/strong>: En el caso de los productos que solo requieren superficies de separaci\u00f3n planas, el proceso es relativamente r\u00e1pido y suele durar entre 1 y 2 d\u00edas.<\/li><li><strong>Perforaci\u00f3n de superficies<\/strong>: Si el molde incluye superficies perforadas, el proceso de ajuste se vuelve m\u00e1s complejo y suele tardar entre 2 y 3 d\u00edas en completarse.<\/li><li><strong>Deslizadores y elevadores<\/strong>: Cuando un molde tiene numerosas correderas y elevadores, el tiempo necesario aumenta considerablemente. En funci\u00f3n del n\u00famero y la complejidad de estos componentes, el proceso de ajuste puede durar entre 3 y 10 d\u00edas.<\/li><\/ul><p class=\"translation-block\">En resumen, el plazo de montaje del molde depende en gran medida de la cantidad y la complejidad de las correderas y los elevadores. El tama\u00f1o total del molde y su complejidad estructural tambi\u00e9n influyen en la duraci\u00f3n del proceso de montaje.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0e1cfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0e1cfa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46f16c1\" data-id=\"46f16c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5044e11 elementor-widget elementor-widget-heading\" data-id=\"5044e11\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Summary\"><\/span>Resumen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92793c8 elementor-widget elementor-widget-text-editor\" data-id=\"92793c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">En conclusi\u00f3n, el montaje y el ajuste de moldes son etapas vitales en todo el proceso de fabricaci\u00f3n de moldes de inyecci\u00f3n. Influyen significativamente en la <strong>duraci\u00f3n del ciclo de fabricaci\u00f3n<\/strong> y son cruciales para garantizar la <strong>calidad de los moldes<\/strong>.<\/p><p class=\"translation-block\">Si tiene alguna pregunta, no dude en ponerse en contacto con nosotros o dejar un comentario a continuaci\u00f3n, y haremos todo lo posible por responderle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La importancia del montaje del molde de inyecci\u00f3n y el ajuste manual. En el proceso de fabricaci\u00f3n por moldeo por inyecci\u00f3n, el montaje del molde y el ajuste manual son etapas cruciales que requieren un tiempo y esfuerzo considerables. Estos procesos exigen una atenci\u00f3n meticulosa al detalle, una amplia experiencia y una artesan\u00eda de precisi\u00f3n. Un enfoque cuidadoso y deliberado es esencial para lograr una calidad \u00f3ptima del molde.\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/\" rel=\"bookmark\">Leer M\u00e1s \u00bb<span class=\"screen-reader-text\">Montaje de moldes de inyecci\u00f3n y ajuste manual<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":9367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"default","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":90,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"[\"thumbnail\",\"title\",\"meta\",\"content\",\"tags\",\"comments\",\"post-navigation\",\"sharing-icons\"]","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72],"tags":[],"class_list":["post-9248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/posts\/9248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/comments?post=9248"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/posts\/9248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/media\/9367"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/media?parent=9248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/categories?post=9248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/tags?post=9248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}