{"id":1463,"date":"2019-04-20T16:07:00","date_gmt":"2019-04-20T16:07:00","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=1463"},"modified":"2024-05-27T17:16:30","modified_gmt":"2024-05-27T17:16:30","slug":"gear-terminology-teeth-calculation-formulas-easy-guide","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/","title":{"rendered":"Terminolog\u00eda de los engranajes y f\u00f3rmulas de c\u00e1lculo de los dientes gu\u00eda f\u00e1cil"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1463\" class=\"elementor elementor-1463\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72e0e04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72e0e04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d83670f\" data-id=\"d83670f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b901de2 elementor-widget elementor-widget-heading\" data-id=\"b901de2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#This_is_a_simpler_version_of_gear_terminology_and_teeth_calculation_formulas\" >Esta es una versi\u00f3n m\u00e1s sencilla de la terminolog\u00eda de los engranajes y las f\u00f3rmulas de c\u00e1lculo de los dientes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#Table_of_content\" >Contenido<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#1_Teeth_number_z\" >1.  N\u00famero de dientes (z)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#2_Reference_circle_and_reference_diameter_d\" >2. C\u00edrculo de referencia y di\u00e1metro de referencia (d)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#3_Module_m\" >3. M\u00f3dulo (m)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#4_Center_distance_a\" >4. Distancia entre ejes (a)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#5_Pressure_angle_%CE%B1\" >5. \u00c1ngulo de presi\u00f3n (\u03b1)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#6_Minimum_teeth_number_zmin_without_undercutting_in_gear\" >6. N\u00famero m\u00ednimo de dientes (zmin) sin socavamiento en el engranaje<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#7_Profile_shift_coefficient_x\" >7. Coeficiente de desplazamiento del perfil (x)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#In_summary\" >En resumen:<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#Frequently_Asked_Questions%E2%80%8B\" >Preguntas frecuentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/#If_youre_looking_for_plastic_gear_solutions_we_might_be_able_to_assist_Let_us_know_how_we_can_help\" >Si busca soluciones para engranajes de pl\u00e1stico, quiz\u00e1 podamos ayudarle. H\u00e1ganos saber c\u00f3mo podemos ayudarle.<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"This_is_a_simpler_version_of_gear_terminology_and_teeth_calculation_formulas\"><\/span>Esta es una versi\u00f3n m\u00e1s sencilla de la terminolog\u00eda de los engranajes y las f\u00f3rmulas de c\u00e1lculo de los dientes<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2469168 elementor-widget elementor-widget-text-editor\" data-id=\"2469168\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"fusion-text\"><p class=\"translation-block\">Este post pretende explicar la terminolog\u00eda de los engranajes y las f\u00f3rmulas de c\u00e1lculo de los dientes de una forma m\u00e1s sencilla para los principiantes, y tambi\u00e9n para aquellos que han aprendido engranajes hace tiempo pero quieren retomarlos r\u00e1pidamente.<\/p><p class=\"translation-block\">Los engranajes tienen muchos par\u00e1metros que requerir\u00e1n un poco de matem\u00e1ticas y formaci\u00f3n geom\u00e9trica para entenderlos completamente. Sin embargo, no es necesario profundizar demasiado en los conceptos b\u00e1sicos del conocimiento de engranajes, despu\u00e9s de haber le\u00eddo este post, <strong>usted debe ser capaz de hacer dise\u00f1os preliminares de engranajes o tener una comunicaci\u00f3n efectiva con los dise\u00f1adores de engranajes<\/strong>.<\/p><\/div><div class=\"fusion-text\"><p class=\"translation-block\">Empecemos por la forma de engranaje b\u00e1sica, los engranajes rectos:<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dca945 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0dca945\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b360c1 elementor-widget elementor-widget-menu-anchor\" data-id=\"2b360c1\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"topic\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0549a9 elementor-widget elementor-widget-heading\" data-id=\"b0549a9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Table_of_content\"><\/span>Contenido<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bda9662 elementor-widget elementor-widget-text-editor\" data-id=\"bda9662\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">1. N\u00famero de dientes (z); 2. C\u00edrculo de referencia y di\u00e1metro de referencia (d); 3. 3. <a href=\"#module\">M\u00f3dulo (m)<\/a>; 4. Distancia al centro (a)<\/a>. <a href=\"#z_minimun\">N\u00famero m\u00ednimo de dientes (z<sub>min<\/sub>)<\/a>; 7.<a href=\"#profile_shift\">Coeficiente de desplazamiento del perfil (x)<\/a>; 8. <a href=\"#summary\">Tabla resumen<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-081afe0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"081afe0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08f5726 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08f5726\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f508d7d\" data-id=\"f508d7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8dbe80 elementor-widget elementor-widget-heading\" data-id=\"f8dbe80\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"1_Teeth_number_z\"><\/span>1.  N\u00famero de dientes (z)\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20bdde5 elementor-widget elementor-widget-text-editor\" data-id=\"20bdde5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Esto es bastante sencillo, es el n\u00famero de dientes del engranaje.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b58af6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b58af6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65c9e65\" data-id=\"65c9e65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfa30fa elementor-widget elementor-widget-menu-anchor\" data-id=\"dfa30fa\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"reference_circle\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e221efd elementor-widget elementor-widget-heading\" data-id=\"e221efd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"2_Reference_circle_and_reference_diameter_d\"><\/span>2. C\u00edrculo de referencia y di\u00e1metro de referencia (d)<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f11136e elementor-widget elementor-widget-text-editor\" data-id=\"f11136e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_2 fusion-builder-column-3 fusion-one-half fusion-column-first 1_2\"><div class=\"fusion-column-wrapper\" data-bg-url=\"\"><div class=\"fusion-text\"><p class=\"translation-block\">El di\u00e1metro de la punta (da) y el di\u00e1metro de la ra\u00edz (df) corresponden a la parte superior e inferior de los dientes.<\/p><p class=\"translation-block\">El di\u00e1metro de referencia se utiliza en el dise\u00f1o y c\u00e1lculo de engranajes. Tiene conexiones directas con otros par\u00e1metros importantes del engranaje como el m\u00f3dulo (m), la distancia entre ejes (c) y el \u00e1ngulo de presi\u00f3n (\u03b1).<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a93c4f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a93c4f7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c4b964\" data-id=\"7c4b964\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71ec420 elementor-widget elementor-widget-text-editor\" data-id=\"71ec420\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El di\u00e1metro de la punta (da) y el di\u00e1metro de la ra\u00edz (df) corresponden a la parte superior e inferior de los dientes.<\/p><p class=\"translation-block\">El di\u00e1metro de referencia se utiliza en el dise\u00f1o y c\u00e1lculo de engranajes. Tiene conexiones directas con otros par\u00e1metros importantes del engranaje como el m\u00f3dulo (m), la distancia entre ejes (c) y el \u00e1ngulo de presi\u00f3n (\u03b1).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7ab43b5\" data-id=\"7ab43b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db267fb elementor-widget elementor-widget-image\" data-id=\"db267fb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"398\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-reference-circle.jpg\" class=\"attachment-large size-large wp-image-1466\" alt=\"c\u00edrculo de referencia del engranaje\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-reference-circle.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-reference-circle-300x239.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-8023e1f elementor-widget elementor-widget-text-editor\" data-id=\"8023e1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El giro de 2 ruedas dentadas puede considerarse el giro acoplado de 2 c\u00edrculos de referencia sin deslizamiento. La relaci\u00f3n de transmisi\u00f3n i=d2\/d1. d1 y d2 se refieren a los di\u00e1metros de referencia de 2 ruedas dentadas acopladas (la rueda 1 es la rueda motriz y la rueda 2 es la rueda conducida).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b960a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b960a09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3af2760\" data-id=\"3af2760\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1a7373 elementor-widget elementor-widget-image\" data-id=\"f1a7373\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"355\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/reference-circles-on-2-meshing-gears.jpg\" class=\"attachment-large size-large wp-image-1469\" alt=\"\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/reference-circles-on-2-meshing-gears.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/reference-circles-on-2-meshing-gears-300x213.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52815da\" data-id=\"52815da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51f5042 elementor-widget elementor-widget-image\" data-id=\"51f5042\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"550\" height=\"414\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-reference-circles-in-3D.jpg\" class=\"attachment-large size-large wp-image-1468\" alt=\"c\u00edrculos de referencia de los engranajes en 3D\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-reference-circles-in-3D.jpg 550w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-reference-circles-in-3D-300x226.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c2d421 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c2d421\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-619413c\" data-id=\"619413c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-deb19e6 elementor-widget elementor-widget-text-editor\" data-id=\"deb19e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El c\u00edrculo de referencia se encuentra en alg\u00fan punto entre la punta y la base de los dientes, normalmente es donde el grosor del diente es igual al espaciado, pero no siempre es as\u00ed (hablaremos del desplazamiento del perfil m\u00e1s adelante en este post).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fd0ee2a\" data-id=\"fd0ee2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-170b764 elementor-widget elementor-widget-image\" data-id=\"170b764\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"316\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/location-of-reference-circle.jpg\" class=\"attachment-large size-large wp-image-1470\" alt=\"localizaci\u00f3n del c\u00edrculo de referencia para el engranaje\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/location-of-reference-circle.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/location-of-reference-circle-300x190.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5745c3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5745c3b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c8b853\" data-id=\"3c8b853\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a46b6 elementor-widget elementor-widget-menu-anchor\" data-id=\"51a46b6\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"module\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7578c79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7578c79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-254349a\" data-id=\"254349a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fbb268 elementor-widget elementor-widget-heading\" data-id=\"2fbb268\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"3_Module_m\"><\/span>3. M\u00f3dulo (m)<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a9a96d4\" data-id=\"a9a96d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3a5a8b elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"a3a5a8b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#topic\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al tema \u2191<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3033124 elementor-widget elementor-widget-text-editor\" data-id=\"3033124\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">El m\u00f3dulo es probablemente el par\u00e1metro de engranaje m\u00e1s importante, y aparece casi siempre en las f\u00f3rmulas de c\u00e1lculo de dientes. En realidad, no es tan dif\u00edcil de entender como podr\u00eda imaginarse. Primero entendamos qu\u00e9 es el paso, El paso es la longitud de arco entre los puntos correspondientes de dientes adyacentes, normalmente en el c\u00edrculo de referencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0efbd5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0efbd5e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4eeb674\" data-id=\"4eeb674\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d43484 elementor-widget elementor-widget-image\" data-id=\"3d43484\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"368\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-pitch-and-module.jpg\" class=\"attachment-large size-large wp-image-1473\" alt=\"paso de engranaje y m\u00f3dulo\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-pitch-and-module.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-pitch-and-module-300x221.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f3d2696\" data-id=\"f3d2696\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e28066 elementor-widget elementor-widget-image\" data-id=\"8e28066\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"310\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/machining-of-gear-teeth.jpg\" class=\"attachment-large size-large wp-image-1472\" alt=\"\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/machining-of-gear-teeth.jpg 550w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/machining-of-gear-teeth-300x169.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-28bceec elementor-widget elementor-widget-text-editor\" data-id=\"28bceec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1 fusion-builder-column-13 fusion-one-full fusion-column-first fusion-column-last 1_1\"><div class=\"fusion-column-wrapper\" data-bg-url=\"\"><div class=\"fusion-text\"><p class=\"translation-block\">Entonces tenemos el di\u00e1metro de referencia <strong>d=circunferencia\/\u03c0=pitch*z\/\u03c0<\/strong>, para facilitar el c\u00e1lculo, definimos el <strong>pitch\/\u03c0<\/strong> como el m\u00f3dulo, y ahora tenemos la ecuaci\u00f3n de <strong>d=m*z<\/strong>, esto facilita mucho el c\u00e1lculo, \u00bfverdad? Los m\u00f3dulos se han estandarizado en los siguientes n\u00fameros \uff08<strong>unidad: mm<\/strong>\uff09:<\/p><\/div><div class=\"fusion-text\"><p class=\"translation-block\">Primera serie (recomendada): 0.1, 0.12, 0.15, 0.2, 0.25, 0.3, 0.4, 0.5, 0.6, 0.8, 1, 1.25, 1.5, 2, 2.5, 3, 4, 5, 6, 8, 10, 12, 16, 20, 25, 32, 40, 50<\/p><p class=\"translation-block\">Segunda serie (menos utilizada): 0.35, 0.7, 0.9, 1.75, 2.25, 2.75, 3.25, 3.5, 3.75, 4.5, 5.5, 6.5, 7, 9, 11, 14, 18, 22, 28, 30, 36, 45<\/p><\/div><div class=\"fusion-clearfix\">\u00a0<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1 fusion-builder-column-14 fusion-one-full fusion-column-first fusion-column-last 1_1\"><div class=\"fusion-column-wrapper\" data-bg-url=\"\"><div class=\"fusion-text\"><p class=\"translation-block\">Sin embargo, en el caso de los engranajes de pl\u00e1stico moldeados por inyecci\u00f3n, no es necesario adoptar estos n\u00fameros de m\u00f3dulo est\u00e1ndar, ya que los dientes no se cortan con talladoras de dientes est\u00e1ndar.<\/p><\/div><div class=\"fusion-text\"><p class=\"translation-block\">Ahora tenemos la relaci\u00f3n de transmisi\u00f3n i=d2\/d1=z2\/z1 (la marcha 1 es la marcha motriz y la marcha 2 es la marcha conducida).<\/p><p class=\"translation-block\">El m\u00f3dulo tambi\u00e9n tiene que ver con la altura del diente, para los engranajes est\u00e1ndar, la altura del diente es igual a 2,25*m:<\/p><p class=\"translation-block\">addendum <strong>ha=1*m<\/strong>, dedendum <strong>hf=1,25*m<\/strong>, altura del diente <strong>h=2,25*m<\/strong>.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7508081 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7508081\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fc2554\" data-id=\"5fc2554\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d9f7ef elementor-widget elementor-widget-menu-anchor\" data-id=\"0d9f7ef\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"center_distance\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-014d4ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"014d4ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0ec797b\" data-id=\"0ec797b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63b3d69 elementor-widget elementor-widget-heading\" data-id=\"63b3d69\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"4_Center_distance_a\"><\/span>4. Distancia entre ejes (a)<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e67cbe0\" data-id=\"e67cbe0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c651fc elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"4c651fc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#topic\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al tema \u2191<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b00c071 elementor-widget elementor-widget-text-editor\" data-id=\"b00c071\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">2 engranajes que engranan siempre tienen el mismo m\u00f3dulo de lo contrario no coinciden. Ahora podemos llegar a la conclusi\u00f3n de que<strong> a=(d1+d2)\/2=m(z1+z2)\/2<\/strong>, pero puede ser ligeramente diferente haciendo algunos ajustes en las geometr\u00edas de los engranajes (desplazamiento del perfil de los dientes).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2027b26 elementor-widget elementor-widget-image\" data-id=\"2027b26\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"305\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-module-and-tooth-height.jpg\" class=\"attachment-large size-large wp-image-1474\" alt=\"m\u00f3dulo de engranaje y altura del diente\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-module-and-tooth-height.jpg 700w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-module-and-tooth-height-600x261.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-module-and-tooth-height-300x131.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8c6ae9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8c6ae9\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\",\"animation\":\"none\"}'>\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b46768\" data-id=\"4b46768\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc47c98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc47c98\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-139bf91\" data-id=\"139bf91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d576b74 elementor-widget elementor-widget-heading\" data-id=\"d576b74\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/boyanmfg.com\/finding-custom-plastic-gear-manufacturer\/\">Puesto relacionado: El dise\u00f1o y la fabricaci\u00f3n de engranajes de pl\u00e1stico<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18dc9df\" data-id=\"18dc9df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce956ab elementor-widget elementor-widget-image\" data-id=\"ce956ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/plastic-gear-with-spline-shaft-r8r87xrp508mp2ygwcl220wd3nsjnraecpf05gs3fg.png\" title=\"engranaje de pl\u00e1stico con eje estriado\" alt=\"engranaje de pl\u00e1stico con eje estriado\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69adcd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69adcd8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6b7286\" data-id=\"c6b7286\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01f735e elementor-widget elementor-widget-menu-anchor\" data-id=\"01f735e\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"pressure_angle\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c8fb4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c8fb4f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c2bc577\" data-id=\"c2bc577\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1403877 elementor-widget elementor-widget-heading\" data-id=\"1403877\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"5_Pressure_angle_%CE%B1\"><\/span><a href=\"http:\/\/boyanmfg.com\/insights-gear-common-normal-involute-line\/#%CE%B1\">5. \u00c1ngulo de presi\u00f3n (\u03b1)<\/a><span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-990cb22\" data-id=\"990cb22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f58fe5 elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"7f58fe5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#topic\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al tema \u2191<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e893067 elementor-widget elementor-widget-text-editor\" data-id=\"e893067\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">En pocas palabras, como su nombre indica, es el \u00e1ngulo entre la direcci\u00f3n de la fuerza de contacto <span style=\"text-decoration: underline\">sobre el punto de contacto<\/span> del diente y la direcci\u00f3n de movimiento de ese punto sobre el perfil del diente.<\/p><p class=\"translation-block\">En geometr\u00eda, es el \u00e1ngulo entre la l\u00ednea normal al perfil del diente evolvente y la l\u00ednea normal a su l\u00ednea radial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c5ee2b elementor-widget elementor-widget-image\" data-id=\"8c5ee2b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"476\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/center-distance-of-meshing-gears.jpg\" class=\"attachment-large size-large wp-image-1475\" alt=\"distancia entre ejes de los engranajes\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/center-distance-of-meshing-gears.jpg 550w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/center-distance-of-meshing-gears-300x260.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-026b264 elementor-widget elementor-widget-image\" data-id=\"026b264\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"413\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/pressure-angle-of-gear.jpg\" class=\"attachment-large size-large wp-image-1477\" alt=\"\u00e1ngulo de presi\u00f3n del engranaje\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/pressure-angle-of-gear.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/pressure-angle-of-gear-300x207.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc59d2b elementor-widget elementor-widget-text-editor\" data-id=\"fc59d2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">\u00a0<\/p><p class=\"translation-block\">Si quieres entender completamente el \u00e1ngulo de presi\u00f3n entonces necesitas profundizar para entender la <a href=\"http:\/\/boyanmfg.com\/insights-gear-common-normal-involute-line\/#involute\">l\u00ednea involuta<\/a> del perfil del diente. Esto es s\u00f3lo una forma m\u00e1s f\u00e1cil de explicaci\u00f3n.<\/p><p class=\"translation-block\">Diferentes puntos del perfil del diente tienen diferentes \u00e1ngulos de presi\u00f3n, pero cuando hablamos del \u00e1ngulo de presi\u00f3n de una rueda dentada, normalmente nos referimos al del c\u00edrculo de referencia. La mayor\u00eda de los engranajes utilizan 20\u00b0 como \u00e1ngulo de presi\u00f3n, algunos tienen 14,5\u00b0 o 25\u00b0. 2 engranajes acoplados deben tener el mismo m\u00f3dulo y \u00e1ngulo de presi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3515c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3515c0\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\",\"animation\":\"none\"}'>\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd3451a\" data-id=\"fd3451a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fcc6ad8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcc6ad8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-55825ed\" data-id=\"55825ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc51522 elementor-widget elementor-widget-spacer\" data-id=\"fc51522\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e168084 elementor-widget elementor-widget-heading\" data-id=\"e168084\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/boyanmfg.com\/insights-gear-common-normal-involute-line\/\">Related post: Explicaci\u00f3n de la longitud normal com\u00fan de involuta y engranaje<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-153b2e4\" data-id=\"153b2e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0956342 elementor-widget elementor-widget-image\" data-id=\"0956342\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/insights-gear-common-normal-involute-line\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/03\/common-normal-length-stable.jpg\" class=\"attachment-large size-large wp-image-8050\" alt=\"la longitud normal com\u00fan permanece estable\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/03\/common-normal-length-stable.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/03\/common-normal-length-stable-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8053e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8053e6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0fd790\" data-id=\"d0fd790\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e848f4 elementor-widget elementor-widget-menu-anchor\" data-id=\"5e848f4\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"z_minimum\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19a953f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19a953f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e458587\" data-id=\"e458587\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06ea34f elementor-widget elementor-widget-heading\" data-id=\"06ea34f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"6_Minimum_teeth_number_zmin_without_undercutting_in_gear\"><\/span>6. N\u00famero m\u00ednimo de dientes (<strong>z<sub>min<\/sub><\/strong>) sin socavar la marcha<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0447cee\" data-id=\"0447cee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b49592 elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"4b49592\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#topic\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al tema \u2191<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b140b45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b140b45\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-546ea83\" data-id=\"546ea83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f16027 elementor-widget elementor-widget-text-editor\" data-id=\"8f16027\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">No se puede tener cualquier n\u00famero de dientes del engranaje como se desee. Si hay muy pocos dientes, la parte inferior de los dientes estar\u00e1 por debajo del punto l\u00edmite, como consecuencia, cuando los dientes se hacen por los cortadores de dientes, una parte sobrante de la ra\u00edz de los dientes se cortar\u00e1.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e2606c0\" data-id=\"e2606c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f6f3e2 elementor-widget elementor-widget-image\" data-id=\"7f6f3e2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"250\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/undercutting-of-gear-tooth.jpg\" class=\"attachment-large size-large wp-image-1479\" alt=\"socavaci\u00f3n del diente del engranaje\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/undercutting-of-gear-tooth.jpg 450w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/undercutting-of-gear-tooth-300x167.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca24231 elementor-widget elementor-widget-text-editor\" data-id=\"ca24231\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSi los dientes no se mecanizan con talladoras de dientes, y los perfiles de los dientes se mantienen intactos, los 2 engranajes se atascar\u00e1n en la transmisi\u00f3n.\n\nLa f\u00f3rmula para calcular el n\u00famero m\u00ednimo de dientes sin socavar es:\n\n<strong>z<sub>min<\/sub>=2ha*\/sin<sup>2<\/sup>\u03b1<\/strong>\n\nCuando ha*=1, y \u03b1=20\u00b0\uff0c tendremos la z<sub>min<\/sub>=2*1\/(sen20\u00b0\uff09<sup>2<\/sup>=17,09=17\uff08siempre se redondea hacia abajo\uff09. Por tanto, el n\u00famero m\u00ednimo de dientes para los engranajes est\u00e1ndar es 17.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c02df0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c02df0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dbba31\" data-id=\"4dbba31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a79660c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a79660c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4cc485e\" data-id=\"4cc485e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d33bc9 elementor-widget elementor-widget-heading\" data-id=\"0d33bc9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"7_Profile_shift_coefficient_x\"><\/span>7. Coeficiente de desplazamiento del perfil (x)<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a3de6b elementor-widget elementor-widget-menu-anchor\" data-id=\"1a3de6b\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"profile_shift\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a8d70a9\" data-id=\"a8d70a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b67862 elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"6b67862\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#topic\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al tema \u2191<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6bfcca elementor-widget elementor-widget-text-editor\" data-id=\"d6bfcca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Normalmente para el perfil de los dientes, el addendum de los dientes ha=1*m, y el dedendum hf=1.25*m, sin embargo el perfil de los dientes puede moverse un poco hacia arriba o hacia abajo:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b569973 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b569973\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2aac869\" data-id=\"2aac869\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2b941b elementor-widget elementor-widget-image\" data-id=\"d2b941b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"290\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-profile-shift-cofficient.jpg\" class=\"attachment-large size-large wp-image-1481\" alt=\"coeficiente de cambio de perfil de marcha\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-profile-shift-cofficient.jpg 550w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/gear-profile-shift-cofficient-300x158.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-206c8d7\" data-id=\"206c8d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d26fdae elementor-widget elementor-widget-image\" data-id=\"d26fdae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"500\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/machining-of-plastic-gear-teeth.jpg\" class=\"attachment-large size-large wp-image-1482\" alt=\"\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/machining-of-plastic-gear-teeth.jpg 410w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/01\/machining-of-plastic-gear-teeth-246x300.jpg 246w\" sizes=\"(max-width: 410px) 100vw, 410px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-810687b elementor-widget elementor-widget-text-editor\" data-id=\"810687b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"fusion-text\"><p class=\"translation-block\">Ahora tenemos el coeficiente de desplazamiento del perfil (x). Cuando el perfil se desplaza hacia arriba, el valor de x es positivo (x&gt;0), y si el perfil se desplaza hacia abajo, el valor de x es negativo (x&lt;0).<\/p><p class=\"translation-block\">Con el movimiento de perfil de los dientes, ahora tenemos:<\/p><ul><li>addendum ha=(1+x)*m<\/li><li>dedendum hf=(1,25-x)*m<\/li><\/ul><p class=\"translation-block\">La altura de los dientes h=ha+hf=2,25*m, sigue siendo la misma que la de los dientes est\u00e1ndar.<\/p><\/div><div class=\"fusion-text\"><p class=\"translation-block\">Las principales razones del cambio de perfil son:<\/p><p class=\"translation-block\">1) Con el perfil desplazado, podemos evitar la socavaci\u00f3n de los dientes con un menor n\u00famero de dientes. La f\u00f3rmula es la siguiente:<\/p><p class=\"translation-block\"><strong>x<sub>min<\/sub>=(17-z)\/17<\/strong><\/p><p class=\"translation-block\">Por ejemplo, si desea que el n\u00famero de dientes sea 14, entonces X=(17-14)\/17=0,176<\/p><p class=\"translation-block\">2)Ajuste fino de la distancia entre ejes<\/p><p class=\"translation-block\"><strong>a=[(m+x1)z1+(m+x2)z2]\/2<\/strong>, por lo que la distancia al centro no tiene por qu\u00e9 ser (z1+z2)*m<\/p><p class=\"translation-block\">3)Hacer el pi\u00f1\u00f3n m\u00e1s fuerte. Por lo general, el pi\u00f1\u00f3n falla antes de la marcha, mediante la adici\u00f3n de un cambio de perfil positivo, la parte inferior del pi\u00f1\u00f3n se hace m\u00e1s ancha (mientras que la punta se hace m\u00e1s estrecha) por lo que es m\u00e1s fuerte.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b828f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b828f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0226883\" data-id=\"0226883\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c9b4fa elementor-widget elementor-widget-menu-anchor\" data-id=\"6c9b4fa\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"summary\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c563f04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c563f04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6d9cc3a\" data-id=\"6d9cc3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5eb6e9 elementor-widget elementor-widget-heading\" data-id=\"d5eb6e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"In_summary\"><\/span>En resumen:\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-38c155b\" data-id=\"38c155b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3564fdd elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"3564fdd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#topic\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al tema \u2191<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3437d0 elementor-widget elementor-widget-text-editor\" data-id=\"b3437d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">\n<\/p><table id=\"tablepress-1\" class=\"tablepress tablepress-id-1\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">#<\/th><th class=\"column-2\">Art\u00edculo<\/th><th class=\"column-3\">S\u00edmbolo<\/th><th class=\"column-4\">F\u00f3rmula<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">n\u00famero de dientes<\/td><td class=\"column-3\">z<\/td><td class=\"column-4\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">m\u00f3dulo<\/td><td class=\"column-3\">m<\/td><td class=\"column-4\">m=pitch\/\u03c0<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">relaci\u00f3n de transmisi\u00f3n<\/td><td class=\"column-3\">i<\/td><td class=\"column-4\">i=d2\/d1=z2\/z1<br>\n1: engranaje motriz, y 2: engranaje conducido<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">coeficiente de adici\u00f3n<\/td><td class=\"column-3\">da*<\/td><td class=\"column-4\">da*=1+x<br>\nx=0 para marchas est\u00e1ndar<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">coeficiente dedendum<\/td><td class=\"column-3\">df*<\/td><td class=\"column-4\">df*=1,25-x<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">coeficiente de desplazamiento del perfil<\/td><td class=\"column-3\">x<\/td><td class=\"column-4\">Para los engranajes est\u00e1ndar,, x=0<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">\u00e1ngulo de presi\u00f3n<\/td><td class=\"column-3\">\u03b1<\/td><td class=\"column-4\">\u03b1=20\u00b0 para la mayor\u00eda de las marchas<br>\nOtros menos utilizados son 14,5\u00b0 y 25\u00b0.<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">di\u00e1metro de referencia<\/td><td class=\"column-3\">d<\/td><td class=\"column-4\">d=mz<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">di\u00e1metro de la punta<\/td><td class=\"column-3\">da<\/td><td class=\"column-4\">da=d+2Ha* x m, da=(z+2ha*) m<br>\nPara los engranajes normalizados, da=(z+2) x m<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">di\u00e1metro de la ra\u00edz<\/td><td class=\"column-3\">df<\/td><td class=\"column-4\">df=d-2Hf* x m, df=(z-2hf*) x m<br>\nPara los engranajes est\u00e1ndar, df=(z-2,5) x m<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">adenda<\/td><td class=\"column-3\">ha<\/td><td class=\"column-4\">ha=m x ha*<br>\nPara los engranajes est\u00e1ndar, ha=m<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">dedendum<\/td><td class=\"column-3\">hf<\/td><td class=\"column-4\">hf=m x hf*<br>\nPara marchas est\u00e1ndar, hf=1,25m<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">altura del diente<\/td><td class=\"column-3\">h<\/td><td class=\"column-4\">h=m x (ha*+hf*)<br>\nha*+Hf*=2,25 para la mayor\u00eda de las marchas<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">distancia entre centros<\/td><td class=\"column-3\">a<\/td><td class=\"column-4\">a=m x (z1+z2)\/2 para marchas est\u00e1ndar<br>\na=[(m+x1)z1+(m+x2)z2]\/2 para marchas desplazadas de perfil<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">N\u00famero m\u00ednimo de dientes sin socavar<\/td><td class=\"column-3\">Zmin<\/td><td class=\"column-4\">Zmin=2ha*\/sin\u03b1^2<br>\nZmin=17 cuando ha*=1, \u03b1=20\u00b0.<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">Desplazamiento m\u00ednimo del perfil sin socavaci\u00f3n<\/td><td class=\"column-3\">Xmin<\/td><td class=\"column-4\">Xm\u00edn=(17-z)\/17<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1 from cache -->\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65c8e6b elementor-widget elementor-widget-spacer\" data-id=\"65c8e6b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e590b75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e590b75\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6030336\" data-id=\"6030336\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1d4c84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1d4c84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-05a6338\" data-id=\"05a6338\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c3af75 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0c3af75\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-question-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b7302d7\" data-id=\"b7302d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6d890b elementor-widget elementor-widget-heading\" data-id=\"e6d890b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Frequently_Asked_Questions%E2%80%8B\"><\/span>Preguntas frecuentes<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9498ff8 elementor-widget elementor-widget-toggle\" data-id=\"9498ff8\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1l es el \u00e1ngulo de presi\u00f3n m\u00e1s adecuado para los engranajes?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1551\"><h4>Introducci\u00f3n a las fuerzas de engranaje<\/h4><p class=\"translation-block\">En el proceso de engrane entre dos engranajes, la fuerza ejercida por el engranaje motriz sobre el engranaje conducido puede descomponerse en una fuerza normal perpendicular a la superficie del engranaje conducido y una fuerza tangencial perpendicular a la fuerza normal. La fuerza tangencial no participa en el accionamiento del engranaje conducido y provoca el desgaste entre los dos engranajes. El \u00e1ngulo en el punto de engrane de las ruedas motriz y conducida es mayor al principio y al final del engrane y menor en el centro. Cuando el punto de engrane est\u00e1 en la l\u00ednea central de los dos engranajes, es igual a cero. Por lo tanto, un \u00e1ngulo menor puede mejorar la eficacia de la transmisi\u00f3n y reducir el desgaste.<\/p><h4>Relaci\u00f3n entre el \u00e1ngulo de presi\u00f3n y el \u00e1ngulo de mallado<\/h4><p class=\"translation-block\">El \u00e1ngulo de presi\u00f3n est\u00e1 directamente relacionado con el \u00e1ngulo de engrane. Por otra parte, un \u00e1ngulo de presi\u00f3n menor da lugar a ra\u00edces de engranaje m\u00e1s delgadas, lo que reduce la resistencia de los engranajes. Por tanto, es importante encontrar un equilibrio.<\/p><h4><strong>Normas industriales para \u00e1ngulos de presi\u00f3n de engranajes<\/strong><\/h4><ol><li>En la producci\u00f3n industrial actual, la mayor\u00eda de los engranajes est\u00e1ndar utilizan un \u00e1ngulo de presi\u00f3n de 20\u00b0.<\/li><li>Los engranajes dise\u00f1ados para cargas ligeras y altas velocidades suelen utilizar un \u00e1ngulo de presi\u00f3n de 14,5\u00b0, que presenta las ventajas de un menor ruido y una mayor eficacia de transmisi\u00f3n.<\/li><li>Los engranajes dise\u00f1ados para aplicaciones de baja velocidad y carga pesada utilizan un \u00e1ngulo de presi\u00f3n de 25\u00b0, que ofrece una mayor resistencia del diente pero a costa de una menor eficacia de la transmisi\u00f3n y un mayor ruido.<\/li><\/ol><h4>Engranajes de pl\u00e1stico<\/h4><p class=\"translation-block\">En el caso de los engranajes de pl\u00e1stico, puede elegirse cualquier \u00e1ngulo de presi\u00f3n, ya que para su fabricaci\u00f3n no se requieren herramientas de corte est\u00e1ndar. Sin embargo, para simplificar el dise\u00f1o, es habitual ce\u00f1irse a estos valores est\u00e1ndar.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1552\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1552\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1l es la diferencia entre el c\u00edrculo de circunferencia y el c\u00edrculo de paso?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1552\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1552\"><p class=\"translation-block\">El c\u00edrculo circunferencial es la base para el c\u00e1lculo de engranajes. Su di\u00e1metro se calcula como el m\u00f3dulo (m) multiplicado por el n\u00famero de dientes (Z). Esencialmente, es un c\u00edrculo te\u00f3rico que se utiliza principalmente para los c\u00e1lculos, y del que se derivan otros par\u00e1metros de los engranajes.<\/p><p class=\"translation-block\">En cambio, el di\u00e1metro de paso se define durante el engrane real de dos ruedas dentadas. Es el c\u00edrculo formado por la intersecci\u00f3n de la normal com\u00fan de los engranajes y la l\u00ednea que une sus centros, pasando por el punto de tangencia. Los c\u00edrculos de paso de dos ruedas dentadas engranadas son tangentes entre s\u00ed. Sin embargo, los c\u00edrculos de circunferencia pueden no ser siempre tangentes<\/p><p class=\"translation-block\">En los dise\u00f1os de engranajes est\u00e1ndar, el c\u00edrculo de circunferencia y el c\u00edrculo de paso suelen coincidir. Sin embargo, si la distancia entre ejes se ajusta para aumentar el juego o si los engranajes se han modificado, el c\u00edrculo perif\u00e9rico y el c\u00edrculo primitivo pueden diferir.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1553\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1553\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfSon iguales el grosor del diente y la anchura de la ranura en el c\u00edrculo circunferencial?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1553\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1553\"><p class=\"translation-block\">S\u00ed. En los dise\u00f1os est\u00e1ndar, el grosor del diente y la anchura de la ranura en el c\u00edrculo de la circunferencia son iguales.<\/p><p class=\"translation-block\">Sin embargo, en aplicaciones pr\u00e1cticas, para permitir cierto juego manteniendo la distancia entre ejes est\u00e1ndar, el espesor del diente se hace ligeramente m\u00e1s fino.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1554\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1554\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfC\u00f3mo puede garantizarse una holgura adecuada en el engrane de los engranajes?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1554\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1554\"><p class=\"translation-block\">Un m\u00e9todo consiste en hacer que el grosor del diente sea ligeramente inferior a la anchura de la ranura en el c\u00edrculo de la circunferencia.<\/p><p class=\"translation-block\">Otro m\u00e9todo consiste en instalar los engranajes a una distancia entre ejes ligeramente superior a la est\u00e1ndar.<\/p><p class=\"translation-block\">El tama\u00f1o necesario de la holgura depende de la precisi\u00f3n de fabricaci\u00f3n de los engranajes; una mayor precisi\u00f3n reduce la necesidad de holgura.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1555\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1555\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 es el paso del c\u00edrculo base de un engranaje?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1555\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1555\"><p class=\"translation-block\">El c\u00edrculo de base de un engranaje es el c\u00edrculo a partir del cual se genera su evolvente. Su paso es la longitud de arco entre puntos id\u00e9nticos de los perfiles de dos dientes adyacentes en el c\u00edrculo base, as\u00ed:<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\">Pb = Db\/Z.<\/p><p class=\"translation-block\">Aqu\u00ed, Db es el di\u00e1metro del c\u00edrculo base.<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\">O Pb = Df * cos(\u03b1) \/ Z = m\u03c0 * cos(\u03b1),<\/p><p class=\"translation-block\">donde Df es el di\u00e1metro del c\u00edrculo de circunferencia, m es el m\u00f3dulo del engranaje y \u03b1 es el \u00e1ngulo de presi\u00f3n del c\u00edrculo de circunferencia.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1556\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1556\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1les son las condiciones para que dos marchas engranen correctamente?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1556\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1556\"><p class=\"translation-block\">1. Para los engranajes rectos, es necesario que el engrane de un par de dientes est\u00e9 sincronizado con el engrane del par anterior. Esto exige que los pasos de sus c\u00edrculos base sean iguales, es decir:<\/p><p class=\"translation-block\">m1 * cos(\u03b11) = m2 * cos(\u03b12).<\/p><p class=\"translation-block\">De ello se deduce que los m\u00f3dulos (m) de un par de engranajes no tienen por qu\u00e9 ser necesariamente iguales.<\/p><p class=\"translation-block\">2. Al mismo tiempo, el grado de compromiso (relaci\u00f3n de contacto \u03b5) es superior a 1<\/p><p class=\"translation-block\">Para los engranajes fabricados con herramientas de corte est\u00e1ndar, debido a la normalizaci\u00f3n y serializaci\u00f3n de las herramientas, es pr\u00e1ctica com\u00fan utilizar el mismo m\u00f3dulo y \u00e1ngulo de presi\u00f3n del c\u00edrculo de circunferencia para ambos engranajes.<\/p><p class=\"translation-block\">3. Para los engranajes helicoidales, tambi\u00e9n es necesario que sus \u00e1ngulos de h\u00e9lice sean iguales, suponiendo que sus ejes de instalaci\u00f3n sean paralelos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1557\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1557\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1l es la relaci\u00f3n de contacto (\u03b5) de dos engranajes engranados?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1557\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1557\"><p class=\"translation-block\">La relaci\u00f3n de contacto (\u03b5) es la longitud del segmento normal com\u00fan entre dos ruedas dentadas que engranan, cortada por los c\u00edrculos de adici\u00f3n de las ruedas dentadas, dividida por el paso base (Pb) de la rueda dentada.<\/p><ul><li style=\"list-style-type: none;\"><ul><li>Cuando \u03b5 &lt;1, los engranajes no pueden funcionar correctamente porque hay momentos en los que ning\u00fan diente est\u00e1 en contacto.<\/li><li>Si 1 &lt; \u03b5 &lt; 2, hay momentos en los que s\u00f3lo un diente est\u00e1 en contacto. Por ejemplo, con \u03b5 = 1,63, se puede imaginar una media de 1,63 pares de dientes engranados. Durante 37% del proceso de transmisi\u00f3n, s\u00f3lo un diente est\u00e1 en contacto, mientras que durante 63%, dos dientes est\u00e1n en contacto, lo que provoca un mayor impacto durante la transmisi\u00f3n.<\/li><li>Si \u03b5 &gt; 2, en un momento dado hay m\u00e1s de dos pares de dientes en contacto, lo que se traduce en una transmisi\u00f3n m\u00e1s suave.<\/li><\/ul><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1558\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1558\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfC\u00f3mo se puede aumentar la relaci\u00f3n de contacto (\u03b5) de dos marchas?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1558\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1558\"><p class=\"translation-block\">El n\u00famero de dientes (Z) de los engranajes es un factor importante que afecta a la relaci\u00f3n de contacto.<\/p><p class=\"translation-block\">En el caso de los engranajes m\u00e1s peque\u00f1os, se suelen utilizar engranajes helicoidales para aumentar la relaci\u00f3n de contacto. Sin embargo, el coste de fabricaci\u00f3n de los engranajes helicoidales es significativamente mayor que el de los engranajes rectos.<\/p><p class=\"translation-block\">Otro m\u00e9todo consiste en utilizar un \u00e1ngulo de presi\u00f3n menor del c\u00edrculo de cabeceo, pero esto tiene un efecto menor.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1559\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1559\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 determina la vida \u00fatil de un engranaje?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1559\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1559\"><p class=\"translation-block\">La vida \u00fatil de un engranaje viene determinada principalmente por el desgaste y la rotura por fatiga. Estos problemas se derivan de diversos factores, como la baja precisi\u00f3n del engranaje, un juego inadecuado, una lubricaci\u00f3n deficiente, el sobrecalentamiento, etc. Aunque es dif\u00edcil calcular la vida \u00fatil con f\u00f3rmulas emp\u00edricas, la precisi\u00f3n del engranaje y el material utilizado son factores cr\u00edticos para su longevidad.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d226747 elementor-widget elementor-widget-spacer\" data-id=\"d226747\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2bb396 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2bb396\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c8aabe\" data-id=\"9c8aabe\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-607dea5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"607dea5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-497a076\" data-id=\"497a076\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1c4379 elementor-widget elementor-widget-image\" data-id=\"e1c4379\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"273\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2019\/04\/plastic-gear-with-spline-shaft.png\" class=\"attachment-large size-large wp-image-4622\" alt=\"engranaje de pl\u00e1stico con eje estriado\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6312b39\" data-id=\"6312b39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-308bd76 elementor-widget elementor-widget-heading\" data-id=\"308bd76\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"If_youre_looking_for_plastic_gear_solutions_we_might_be_able_to_assist_Let_us_know_how_we_can_help\"><\/span>Si busca soluciones para engranajes de pl\u00e1stico, quiz\u00e1 podamos ayudarle. H\u00e1ganos saber c\u00f3mo podemos ayudarle.<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5d3f7e1\" data-id=\"5d3f7e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57277c7 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"57277c7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar un presupuesto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Esta es una versi\u00f3n m\u00e1s sencilla de la terminolog\u00eda de engranajes y las f\u00f3rmulas de c\u00e1lculo de dientes. Esta publicaci\u00f3n tiene como objetivo explicar la terminolog\u00eda de engranajes y las f\u00f3rmulas de c\u00e1lculo de dientes de una manera m\u00e1s f\u00e1cil para principiantes, y tambi\u00e9n para aquellos que aprendieron sobre engranajes hace mucho tiempo pero quieren retomarlo r\u00e1pidamente. Los engranajes tienen muchos par\u00e1metros que tomar\u00e1n...&nbsp;<a href=\"https:\/\/boyanmfg.com\/es\/gear-terminology-teeth-calculation-formulas-easy-guide\/\" rel=\"bookmark\">Leer M\u00e1s \u00bb<span class=\"screen-reader-text\">Terminolog\u00eda de los engranajes y f\u00f3rmulas de c\u00e1lculo de los dientes gu\u00eda f\u00e1cil<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":1485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-1463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/posts\/1463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/comments?post=1463"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/posts\/1463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/media\/1485"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/media?parent=1463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/categories?post=1463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/tags?post=1463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}