{"id":9248,"date":"2024-10-20T23:03:19","date_gmt":"2024-10-20T23:03:19","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=9248"},"modified":"2024-11-19T03:22:13","modified_gmt":"2024-11-19T03:22:13","slug":"injection-mold-assembly-and-manual-fitting","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/","title":{"rendered":"Spritzgie\u00dfwerkzeug-Montage und manuelles Anpassen"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9248\" class=\"elementor elementor-9248\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db1d274 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db1d274\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbfd7fd\" data-id=\"cbfd7fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3b91ac elementor-widget elementor-widget-heading\" data-id=\"d3b91ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Inhalts\u00fcbersicht<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis umschalten\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten auf<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#The_Importance_of_Injection_Mold_Assembly_and_Manual_Fitting\" >Die Bedeutung der Montage von Spritzgie\u00dfwerkzeugen und des manuellen Einbaus<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#What_is_Manual_Fitting\" >Was ist manuelle Anpassung?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Key_Areas_to_Inspect_in_Manual_Fitting\" >Zu pr\u00fcfende Schl\u00fcsselbereiche bei der manuellen Montage<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Common_Inspection_Methods\" >\u00dcbliche Inspektionsmethoden<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Red_Dan_Inspection_Method\" >Red-Dan-Inspektionsmethode<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Adjustment_Methods\" >Anpassungsmethoden<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Inspection_of_Sliders_and_Lifters\" >Inspektion von Schiebern und Liftern<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Tactile_Inspection\" >Taktile Inspektion<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Mold_Fitting_Timeline\" >Zeitleiste f\u00fcr die Anpassung von Formen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/#Summary\" >Zusammenfassung<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"The_Importance_of_Injection_Mold_Assembly_and_Manual_Fitting\"><\/span>Die Bedeutung der Montage von Spritzgie\u00dfwerkzeugen und des manuellen Einbaus<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a196b8 elementor-widget elementor-widget-text-editor\" data-id=\"7a196b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Bei der Herstellung von Spritzgussteilen sind die <strong>Formenmontage<\/strong> und die <strong>manuelle Montage<\/strong> entscheidende Schritte, die viel Zeit und M\u00fche erfordern. Diese Prozesse erfordern akribische Liebe zum Detail, einen gro\u00dfen Erfahrungsschatz und handwerkliche Pr\u00e4zision.<\/p><p class=\"translation-block\"><strong>Ein sorgf\u00e4ltiges und \u00fcberlegtes Vorgehen<\/strong> ist f\u00fcr eine optimale Formqualit\u00e4t unerl\u00e4sslich. Nur durch dieses Ma\u00df an Pr\u00e4zision kann eine hochwertige Form gew\u00e4hrleistet werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b09f9c elementor-widget elementor-widget-heading\" data-id=\"5b09f9c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_is_Manual_Fitting\"><\/span>Was ist manuelle Anpassung?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4778f1e elementor-widget elementor-widget-text-editor\" data-id=\"4778f1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Unter manuellem Einpassen versteht man das manuelle Einstellen der Ma\u00dfhaltigkeit der einzelnen Formteile nach der Bearbeitung. Dadurch wird sichergestellt, dass alle <a href=\"http:\/\/boyanmfg.com\/injection-mold-cost-in-china\/#basic_structure\">Formkomponenten<\/a> <strong>perfekt zusammenpassen, korrekt ausgerichtet sind und die erforderlichen Abst\u00e4nde f\u00fcr bewegliche Komponenten<\/strong> wie Schieber, Heber und Auswerferstifte eingehalten werden. Ziel ist die Feinabstimmung dieser Komponenten f\u00fcr eine pr\u00e4zise Funktion und Ausrichtung w\u00e4hrend des Einspritzvorgangs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-224d773 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"224d773\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e6b37e\" data-id=\"7e6b37e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d4901c elementor-widget elementor-widget-heading\" data-id=\"8d4901c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Key_Areas_to_Inspect_in_Manual_Fitting\"><\/span>Zu pr\u00fcfende Schl\u00fcsselbereiche bei der manuellen Montage<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0886827 elementor-widget elementor-widget-text-editor\" data-id=\"0886827\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Bei der manuellen Montage m\u00fcssen mehrere kritische Bereiche \u00fcberpr\u00fcft werden:<\/p><p class=\"translation-block\"><strong>1. Trennfl\u00e4che<\/strong>: Die <a href=\"http:\/\/boyanmfg.com\/design-for-manufacturing-plastic-injection-molding\/#parting_design\">Trennfl\u00e4che<\/a> der Form muss flach und gut ausgerichtet sein. Schlechter Kontakt oder L\u00fccken zwischen diesen Fl\u00e4chen k\u00f6nnen beim Spritzgie\u00dfen zu Graten f\u00fchren. Das Erreichen einer perfekten Ausrichtung ist bei flachen Oberfl\u00e4chen relativ einfach, kann aber bei dreidimensionalen Trennebenen komplexer sein.<\/p><p class=\"translation-block\"><strong>2. durchgestanzte Fl\u00e4che<\/strong>: Die durchgestanzten Fl\u00e4chen, die \u00d6ffnungen im Formteil erzeugen, m\u00fcssen genau passen.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-001f6a6 elementor-widget elementor-widget-image\" data-id=\"001f6a6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/plastic-part-with-opening.jpg\" class=\"attachment-large size-large wp-image-9355\" alt=\"ein Kunststoffteil mit einer \u00d6ffnung, die eine durchgestanzte Oberfl\u00e4che in einer Spritzgussform erfordert\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/plastic-part-with-opening.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/plastic-part-with-opening-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">ein Kunststoffteil mit einer \u00d6ffnung <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8145e79 elementor-widget elementor-widget-text-editor\" data-id=\"8145e79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Der Formkern und die Kavit\u00e4t m\u00fcssen sich in der richtigen H\u00f6he ber\u00fchren, um einen gleichm\u00e4\u00dfigen Kontakt zu gew\u00e4hrleisten, wenn sich die Form schlie\u00dft. Eine falsche Ausrichtung kann hier zu ungleichm\u00e4\u00dfigem Druck und Gratbildung f\u00fchren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0200112 elementor-widget elementor-widget-image\" data-id=\"0200112\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9357\" alt=\"Die durchgestanzte Oberfl\u00e4che einer Spritzgussform in 3D-Ansicht\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Die durchgestanzte Oberfl\u00e4che in einer 3D-Ansicht<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84e44c8 elementor-widget elementor-widget-image\" data-id=\"84e44c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"451\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-2.jpg\" class=\"attachment-large size-large wp-image-9356\" alt=\"Die Stempelfl\u00e4che einer Spritzgussform im Querschnitt\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/punch-through-surface-injection-mold-2-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Die Stanzfl\u00e4che in der Querschnittsansicht.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5d9a16 elementor-widget elementor-widget-text-editor\" data-id=\"c5d9a16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>3. Schieber und Heber<\/strong>: Schieber und Heber m\u00fcssen den richtigen Abstand zu ihren F\u00fchrungsschienen haben, normalerweise zwischen 0,01 und 0,05 mm, je nach Gr\u00f6\u00dfe. Diese Komponenten m\u00fcssen au\u00dferdem b\u00fcndig mit dem Formkern abschlie\u00dfen, um Fehllinien oder Ma\u00dfprobleme am Formteil zu vermeiden.<\/p><p class=\"translation-block\"><strong>4. Scharfe Kanten und Grate<\/strong>: W\u00e4hrend das Anfasen w\u00e4hrend der CNC-Bearbeitung kostspielig sein kann, ist es g\u00e4ngige Praxis, Grate und scharfe Kanten manuell mit Schleifmaschinen zu entfernen, um einen reibungslosen Betrieb zu gew\u00e4hrleisten und Sch\u00e4den bei der Montage der Form zu vermeiden.<\/p><p class=\"translation-block\"><strong>5. Entl\u00fcftung der Form<\/strong>: Eine ordnungsgem\u00e4\u00dfe Entl\u00fcftung ist wichtig, damit die Luft w\u00e4hrend des Spritzgie\u00dfens entweichen kann. Die Entl\u00fcftungs\u00f6ffnungen m\u00fcssen auf ihre richtige Gr\u00f6\u00dfe \u00fcberpr\u00fcft werden. Zu gro\u00dfe Entl\u00fcftungs\u00f6ffnungen k\u00f6nnen zu Gratbildung f\u00fchren, w\u00e4hrend zu kleine Entl\u00fcftungs\u00f6ffnungen Luft einschlie\u00dfen und Defekte verursachen k\u00f6nnen.<\/p><p class=\"translation-block\">Indem sie sich bei der manuellen Montage auf diese Bereiche konzentrieren, k\u00f6nnen die Formenbauer den reibungslosen Betrieb der Spritzgussform sicherstellen und Fehler w\u00e4hrend der Produktion vermeiden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d50f168 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d50f168\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30bf079\" data-id=\"30bf079\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b30a48f elementor-widget elementor-widget-heading\" data-id=\"b30a48f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Common_Inspection_Methods\"><\/span>\u00dcbliche Inspektionsmethoden<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cd6b2f elementor-widget elementor-widget-text-editor\" data-id=\"9cd6b2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Die am h\u00e4ufigsten verwendete Methode zur \u00dcberpr\u00fcfung der Passung und Ausrichtung von bearbeiteten Formoberfl\u00e4chen ist die Verwendung von roter oder blauer Markierungsmasse (bezeichnet als <strong>\u201cRed Dan\u201d <\/strong>oder<strong> \u201cBlue Dan\u201d<\/strong>). Diese Technik wird h\u00e4ufig durch pr\u00e4zise Messwerkzeuge wie Messschieber und Mikrometer erg\u00e4nzt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a274af6 elementor-widget elementor-widget-text-editor\" data-id=\"a274af6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Hinweis:<\/strong><br><strong>Red Dan<\/strong>: Es hat eine h\u00e4rtere Textur und ist relativ rau, wodurch es sich besser f\u00fcr die gro\u00dffl\u00e4chige Formenanpassung oder die Ausrichtung von schweren mechanischen Teilen eignet. Es kann ausgepr\u00e4gtere Kontaktpunkte aufweisen.<br><strong>Blaues Dan<\/strong>: Es hat eine weichere Textur und ist ideal f\u00fcr die pr\u00e4zise Anpassung von Formen und zeigt deutlich leichtere Kontaktspuren. Es eignet sich f\u00fcr hochpr\u00e4zise Formausrichtungskontrollen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f82dd82 elementor-widget elementor-widget-text-editor\" data-id=\"f82dd82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Mit den st\u00e4ndigen Fortschritten in der Bearbeitungs- und Messtechnik ist der Einsatz von Koordinatenmessger\u00e4ten (KMG)<\/strong> immer beliebter geworden. KMGs k\u00f6nnen ein vollst\u00e4ndiges Profil des zu messenden Teils liefern und k\u00f6nnen oft die traditionelle Red-Dan-Methode f\u00fcr genauere und umfassendere Pr\u00fcfungen ersetzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eb4d7f elementor-widget elementor-widget-text-editor\" data-id=\"4eb4d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Red_Dan_Inspection_Method\"><\/span>Red-Dan-Inspektionsmethode<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">Bei der Red-Dan- (oder Blue-Dan-) Methode wird eine d\u00fcnne, gleichm\u00e4\u00dfige Schicht Anrei\u00dfmasse auf eine H\u00e4lfte der Formoberfl\u00e4che aufgetragen. Es ist wichtig, dass der Auftrag gleichm\u00e4\u00dfig und in gleichbleibender Dicke erfolgt.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4e5dd7 elementor-widget elementor-widget-image\" data-id=\"f4e5dd7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/red-Dan-mold.jpg\" class=\"attachment-large size-large wp-image-9283\" alt=\"Auftragen von Red Dan auf die Formoberfl\u00e4che\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/red-Dan-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/red-Dan-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6931f1d elementor-widget elementor-widget-text-editor\" data-id=\"6931f1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Die beiden H\u00e4lften der Form werden dann zusammengef\u00fchrt und fest angedr\u00fcckt, um einen vollst\u00e4ndigen Kontakt zu gew\u00e4hrleisten.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-755c3e6 elementor-widget elementor-widget-image\" data-id=\"755c3e6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/closed-mold-dan-transfer.jpg\" class=\"attachment-large size-large wp-image-9291\" alt=\"\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/closed-mold-dan-transfer.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/closed-mold-dan-transfer-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a2d200 elementor-widget elementor-widget-text-editor\" data-id=\"1a2d200\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nach dem Trennen der Formh\u00e4lften wird die \u00dcbertragung von Red Dan auf die gegen\u00fcberliegende Formoberfl\u00e4che gepr\u00fcft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8975041 elementor-widget elementor-widget-image\" data-id=\"8975041\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/dan-transfer-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9293\" alt=\"Pr\u00fcfung der Dan-\u00dcbertragung auf der anderen H\u00e4lfte der Form\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/dan-transfer-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/dan-transfer-injection-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af32b25 elementor-widget elementor-widget-text-editor\" data-id=\"af32b25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Gute Passform<\/strong>: Wenn die Oberfl\u00e4chen gut ausgerichtet sind, \u00fcbertr\u00e4gt sich das Rote Dan gleichm\u00e4\u00dfig auf die entsprechende Oberfl\u00e4che der anderen Formh\u00e4lfte, was eine gleichm\u00e4\u00dfige und korrekte Passung anzeigt.<\/li><li><strong>Zu enger Sitz<\/strong>: Eine tiefe Farbe weist auf einen minimalen Abstand zwischen den Oberfl\u00e4chen hin, was auf einen sehr festen Sitz schlie\u00dfen l\u00e4sst.<\/li><li><strong>Gro\u00dfe L\u00fccken<\/strong>: Eine hellere oder ungleichm\u00e4\u00dfige Farbe deutet auf gr\u00f6\u00dfere L\u00fccken zwischen den Fl\u00e4chen hin. Wenn kein Roter Dan \u00fcbertragen wird, deutet dies auf eine erhebliche Fehlausrichtung hin, und die fraglichen Bereiche m\u00fcssen in ihren Abmessungen oder ihrer Form weiter angepasst werden.<\/li><\/ul><p class=\"translation-block\">Sobald die Formh\u00e4lften zusammengef\u00fcgt sind, ist es wichtig, mit einem Kupfer- oder Aluminiumstab mit Kraft auf die Form zu h\u00e4mmern, um einen festen Kontakt der Formh\u00e4lften zu gew\u00e4hrleisten. Geschieht dies nicht, k\u00f6nnen gro\u00dfe Bereiche ohne Red-Dan-\u00dcbertragung entstehen, was zu einer unvollst\u00e4ndigen Pr\u00fcfung und ungenauen Ergebnissen f\u00fchrt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe2a75b elementor-widget elementor-widget-image\" data-id=\"fe2a75b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/hammering-mold-dye-transfer.jpg\" class=\"attachment-large size-large wp-image-9302\" alt=\"H\u00e4mmern der Form, um einen vollst\u00e4ndigen Farbstofftransfer zu gew\u00e4hrleisten\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/hammering-mold-dye-transfer.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/hammering-mold-dye-transfer-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Abklopfen der Form mit einem Aluminiumstab, um den Farbstoff zu \u00fcbertragen.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c67a4a elementor-widget elementor-widget-text-editor\" data-id=\"2c67a4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Zur Verbesserung der Effizienz wird der Einsatz einer <a href=\"https:\/\/www.youtube.com\/watch?v=1nROYXfgDFA\" target=\"_blank\" rel=\"noopener\">Formenanrei\u00dfpresse<\/a> dringend empfohlen. Diese Maschine kann einen gleichm\u00e4\u00dfigen Druck auf die Formoberfl\u00e4chen aus\u00fcben, wodurch eine bessere \u00dcbertragung der Markierungsmasse erreicht wird als durch manuelles H\u00e4mmern. Dar\u00fcber hinaus verringert sie die k\u00f6rperliche Belastung der Mitarbeiter und beschleunigt den Prozess. Bei gr\u00f6\u00dferen Formen ist der Einsatz einer Spannmaschine unerl\u00e4sslich, da ihr Gewicht die manuelle Handhabung unpraktisch und uneffektiv macht, um genaue Ergebnisse zu erzielen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d16113 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d16113\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2c48aa\" data-id=\"b2c48aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddddc64 elementor-widget elementor-widget-heading\" data-id=\"ddddc64\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Adjustment_Methods\"><\/span>Anpassungsmethoden<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49253c9 elementor-widget elementor-widget-text-editor\" data-id=\"49253c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Es gibt mehrere Methoden, um die Abmessungen von Spritzgussteilen so anzupassen, dass die erforderliche Pr\u00e4zision erreicht wird:<\/p><h4 style=\"padding-left: 40px;\"><strong>1. Schleifmaschine<\/strong><\/h4><p style=\"padding-left: 40px;\" class=\"translation-block\">Eine der am h\u00e4ufigsten verwendeten Methoden zur H\u00f6henanpassung von ebenen Fl\u00e4chen ist die Schleifmaschine. Diese Methode ist schnell, bequem und kosteng\u00fcnstig und daher ideal f\u00fcr kleinere Anpassungen an den ebenen Abschnitten von Formteilen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8a3a1 elementor-widget elementor-widget-image\" data-id=\"ee8a3a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/grind-Injection-mold-surface.jpg\" class=\"attachment-large size-large wp-image-9312\" alt=\"Schleifen der Oberfl\u00e4che des Formteils zur H\u00f6henanpassung\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/grind-Injection-mold-surface.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/grind-Injection-mold-surface-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96e02b3 elementor-widget elementor-widget-text-editor\" data-id=\"96e02b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"padding-left: 40px;\"><strong>2. Manuelle Feinabstimmung<\/strong><\/h4><p style=\"padding-left: 40px;\" class=\"translation-block\">Bei gekr\u00fcmmten Oberfl\u00e4chen beschr\u00e4nken sich die manuellen Anpassungen in der Regel auf kleine, \u00f6rtlich begrenzte Korrekturen. Werkzeuge wie Feilen, Schmirgelpapier und elektrische Schleifmaschinen (z. B. <strong>rotierende Werkzeuge<\/strong> oder <strong>Winkelschleifer<\/strong>) werden verwendet, um bestimmte Bereiche zu verfeinern. Diese Methode wird oft schrittweise durchgef\u00fchrt, wobei die bereits erw\u00e4hnte Red-Dan-Technik verwendet wird, um sich den gew\u00fcnschten Abmessungen anzun\u00e4hern. Da die manuelle Feinabstimmung jedoch zeitaufw\u00e4ndig ist, eignet sie sich am besten f\u00fcr kleinere Anpassungen und nicht f\u00fcr gro\u00df angelegte \u00c4nderungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43421bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43421bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c5bc0c2\" data-id=\"c5bc0c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c401a8f elementor-widget elementor-widget-image\" data-id=\"c401a8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-1.jpg\" class=\"attachment-large size-large wp-image-9335\" alt=\"Verwenden Sie ein Rotationswerkzeug, um \u00fcbersch\u00fcssiges Material zu entfernen und die Gr\u00f6\u00dfe in der manuellen Anpassung der Form anzupassen.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-1-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d33a89\" data-id=\"3d33a89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-867fbf4 elementor-widget elementor-widget-image\" data-id=\"867fbf4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-2.jpg\" class=\"attachment-large size-large wp-image-9334\" alt=\"Verwenden Sie ein Rotationswerkzeug, um \u00fcbersch\u00fcssiges Material zu entfernen und die Gr\u00f6\u00dfe in der manuellen Anpassung der Form anzupassen.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/rotary-tool-grinding-2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3696472 elementor-widget elementor-widget-text-editor\" data-id=\"3696472\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" class=\"translation-block\">Verwenden Sie ein Rotationswerkzeug, um \u00fcbersch\u00fcssiges Material zu entfernen und die Gr\u00f6\u00dfe anzupassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b558b82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b558b82\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9149f6c\" data-id=\"9149f6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bce8832 elementor-widget elementor-widget-image\" data-id=\"bce8832\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/angle-grinder-chamfer.jpg\" class=\"attachment-large size-large wp-image-9336\" alt=\"Verwenden Sie einen Winkelschleifer zum Anfasen von Handformst\u00fccken.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/angle-grinder-chamfer.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/angle-grinder-chamfer-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Verwenden Sie einen Winkelschleifer, um scharfe Kanten anzufasen<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-707ff0c\" data-id=\"707ff0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d31e9d elementor-widget elementor-widget-image\" data-id=\"4d31e9d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/file-removing-excessive-material.jpg\" class=\"attachment-large size-large wp-image-9337\" alt=\"\u00dcbersch\u00fcssiges Material mit einer Feile abschleifen und die Gr\u00f6\u00dfe anpassen, Form manuell anpassen\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/file-removing-excessive-material.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/file-removing-excessive-material-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Verwenden Sie eine Feile, um \u00fcbersch\u00fcssiges Material abzuschleifen und die Gr\u00f6\u00dfe anzupassen.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-193a786 elementor-widget elementor-widget-text-editor\" data-id=\"193a786\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"padding-left: 40px;\"><strong>3. CNC-Fr\u00e4sen und EDM-Nachbearbeitung<\/strong><\/h4><p style=\"padding-left: 40px;\" class=\"translation-block\">Wenn gr\u00f6\u00dfere Anpassungen erforderlich sind, insbesondere bei komplexen Konturen oder Oberfl\u00e4chen mit erheblichen Abweichungen, sind CNC-Fr\u00e4smaschinen oder Funkenerosionsmaschinen (EDM) erforderlich, um das Teil nachzubearbeiten. Manuelle Korrekturen sind f\u00fcr gr\u00f6\u00dfere \u00c4nderungen nicht pr\u00e4zise genug, insbesondere bei Formen mit hohen Anforderungen an die Ma\u00dfhaltigkeit. Dar\u00fcber hinaus wird von manuellem Feilen bei hochpr\u00e4zisen Formen abgeraten, da sichtbare Werkzeugspuren nicht akzeptabel sind und die Qualit\u00e4t und Funktionalit\u00e4t des Endprodukts beeintr\u00e4chtigen k\u00f6nnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b4f849 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b4f849\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8fb6b4a\" data-id=\"8fb6b4a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a2a4fa elementor-widget elementor-widget-image\" data-id=\"2a2a4fa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/cnc-milling-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9320\" alt=\"CNC-Fr\u00e4sen f\u00fcr die Herstellung von Spritzgussformen\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/cnc-milling-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/cnc-milling-injection-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">CNC-Fr\u00e4sen<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1346631\" data-id=\"1346631\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8f4a49 elementor-widget elementor-widget-image\" data-id=\"c8f4a49\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/EDM-machining-injection-mold.jpg\" class=\"attachment-large size-large wp-image-9321\" alt=\"EDM-Bearbeitung f\u00fcr die Herstellung von Spritzgussformen\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/EDM-machining-injection-mold.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/EDM-machining-injection-mold-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">EDM (Elektroerosionsbearbeitung)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d67549a elementor-widget elementor-widget-text-editor\" data-id=\"d67549a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Diese Methoden gew\u00e4hrleisten, dass Formteile effizient angepasst werden k\u00f6nnen und gleichzeitig die f\u00fcr eine optimale Formleistung erforderliche hohe Genauigkeit beibehalten wird. Jede Methode hat ihren eigenen Anwendungsfall, wobei sich manuelle Methoden f\u00fcr kleinere Ausbesserungen eignen und f\u00fcr gr\u00f6\u00dfere Korrekturen eine fortschrittlichere Bearbeitung erforderlich ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7fd801 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7fd801\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73b5203\" data-id=\"73b5203\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-100d3f7 elementor-widget elementor-widget-heading\" data-id=\"100d3f7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Inspection_of_Sliders_and_Lifters\"><\/span>Inspektion von Schiebern und Liftern<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-555cda8 elementor-widget elementor-widget-text-editor\" data-id=\"555cda8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Bei der manuellen Montage sind die \u00dcberpr\u00fcfung und Einstellung von Gleitern und Hebern eine wichtige Aufgabe. Die Sicherstellung ihrer Ma\u00df- und Formgenauigkeit sowie die Einhaltung des korrekten Spiels mit den F\u00fchrungsschienen ist von entscheidender Bedeutung.<\/p><p class=\"translation-block\"><strong>Unzureichende Passgenauigkeit kann die Genauigkeit der hergestellten Kunststoffteile beeintr\u00e4chtigen und den Verschlei\u00df dieser Komponenten w\u00e4hrend des Werkzeugbetriebs beschleunigen.<\/strong><\/p><h3><span class=\"ez-toc-section\" id=\"Tactile_Inspection\"><\/span>Taktile Inspektion<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"translation-block\">Eine g\u00e4ngige Methode zur Beurteilung der Passform und des Spiels von Schiebern und Hebern ist die taktile Pr\u00fcfung. Dabei werden die Gleiter (und Heber) manuell bewegt:<\/p><ul><li><strong>Seitliche Bewegung<\/strong>: Wenn Sie den Schieber von einer Seite zur anderen bewegen, darf kein merkliches Spiel oder Spiel vorhanden sein.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524eceb elementor-widget elementor-widget-image\" data-id=\"524eceb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Lateral-Movement-Slider.jpg\" class=\"attachment-large size-large wp-image-9342\" alt=\"\u00dcberpr\u00fcfung der seitlichen Bewegung des Schiebers in der Formeinheit\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Lateral-Movement-Slider.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Lateral-Movement-Slider-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e023def elementor-widget elementor-widget-text-editor\" data-id=\"e023def\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Vorw\u00e4rts- und R\u00fcckw\u00e4rtsbewegung<\/strong>: Der Schieber sollte sich mit dem richtigen Widerstand bewegen - weder zu fest noch zu locker.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d31d24a elementor-widget elementor-widget-image\" data-id=\"d31d24a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Forward-Movement-Slider.jpg\" class=\"attachment-large size-large wp-image-9341\" alt=\"\u00dcberpr\u00fcfung der Vorw\u00e4rts- und R\u00fcckw\u00e4rtsbewegung des Schiebers entlang der F\u00fchrungsschiene w\u00e4hrend der Montage der Spritzgussform.\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Forward-Movement-Slider.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/Forward-Movement-Slider-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8540fca elementor-widget elementor-widget-text-editor\" data-id=\"8540fca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Wenn die Passung zu eng ist oder das Bauteil \u00fcberhaupt nicht passt, kann Material entfernt werden, um die Abmessungen etwas zu verringern. Ist die Passung jedoch zu locker, besteht die einzige L\u00f6sung darin, den Schieber oder Heber neu anzufertigen, um die richtige Gr\u00f6\u00dfe und Toleranz zu erreichen. Daher muss bei der Anpassung sehr sorgf\u00e4ltig vorgegangen werden, um ein \u00fcberm\u00e4\u00dfiges Abtragen von Material zu vermeiden.<\/p><p class=\"translation-block\">Angesichts der Pr\u00e4zision, die f\u00fcr die Montage von Schiebern und Hebern erforderlich ist, erfordert dieser Prozess erfahrene Techniker mit starken F\u00e4higkeiten. Die Genauigkeit und Effizienz der manuellen Werkzeugmontage h\u00e4ngt stark von ihrem Fachwissen ab, um sicherzustellen, dass alle Komponenten ausgerichtet sind und wie vorgesehen funktionieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccab789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccab789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bdd5205\" data-id=\"bdd5205\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d80bc elementor-widget elementor-widget-heading\" data-id=\"17d80bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Mold_Fitting_Timeline\"><\/span>Zeitleiste f\u00fcr die Anpassung von Formen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b5c153 elementor-widget elementor-widget-text-editor\" data-id=\"6b5c153\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Das manuelle Einstellen der Formabmessungen ist arbeitsintensiv und zeitaufwendig, weshalb es einen erheblichen Teil des gesamten Formherstellungszyklus ausmacht.<\/p><ul><li><strong>Einfache Produkte<\/strong>: Bei Produkten, die nur flache Trennfl\u00e4chen erfordern, ist das Verfahren relativ schnell und dauert in der Regel etwa 1-2 Tage.<\/li><li><strong>Stanzen durch Oberfl\u00e4chen<\/strong>: Wenn die Form durchgestanzte Oberfl\u00e4chen aufweist, wird der Anpassungsprozess komplexer und dauert in der Regel 2-3 Tage.<\/li><li><strong>Schieber und Heber<\/strong>: Wenn eine Form zahlreiche Schieber und Heber hat, erh\u00f6ht sich der Zeitbedarf erheblich. Je nach Anzahl und Komplexit\u00e4t dieser Komponenten kann der Einpassungsprozess zwischen 3 und 10 Tagen dauern.<\/li><\/ul><p class=\"translation-block\">Zusammenfassend l\u00e4sst sich sagen, dass der Zeitplan f\u00fcr den Einbau der Form weitgehend von der Anzahl und der Komplexit\u00e4t der beteiligten Schieber und Heber abh\u00e4ngt. Auch die Gesamtgr\u00f6\u00dfe der Form und ihre strukturelle Komplexit\u00e4t spielen eine Rolle bei der Bestimmung der Dauer des Einbaus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0e1cfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0e1cfa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46f16c1\" data-id=\"46f16c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5044e11 elementor-widget elementor-widget-heading\" data-id=\"5044e11\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Summary\"><\/span>Zusammenfassung<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92793c8 elementor-widget elementor-widget-text-editor\" data-id=\"92793c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Zusammenfassend l\u00e4sst sich sagen, dass der Zusammenbau und die Montage von Formen wichtige Schritte im gesamten Prozess der Herstellung von Spritzgussformen sind. Sie haben einen erheblichen Einfluss auf die <strong>Dauer des Herstellungszyklus<\/strong> und sind f\u00fcr die Gew\u00e4hrleistung der <strong>Qualit\u00e4t der Formen<\/strong> entscheidend.<\/p><p class=\"translation-block\">Sollten Sie Fragen haben, k\u00f6nnen Sie uns gerne kontaktieren oder unten einen Kommentar hinterlassen. Wir werden unser Bestes tun, um Ihnen zu antworten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Bedeutung der Montage von Spritzgie\u00dfwerkzeugen und der manuellen Montage Bei der Herstellung von Spritzgie\u00dfwerkzeugen sind die Montage von Werkzeugen und die manuelle Montage entscheidende Schritte, die viel Zeit und M\u00fche erfordern. Diese Prozesse erfordern akribische Aufmerksamkeit f\u00fcr Details, einen gro\u00dfen Erfahrungsschatz und handwerkliche Pr\u00e4zision. Ein sorgf\u00e4ltiges und \u00fcberlegtes Vorgehen ist unerl\u00e4sslich, um eine optimale Formqualit\u00e4t zu erreichen....&nbsp;<a href=\"https:\/\/boyanmfg.com\/de\/injection-mold-assembly-and-manual-fitting\/\" rel=\"bookmark\">Weiterlesen \u00bb<span class=\"screen-reader-text\">Spritzgie\u00dfwerkzeug-Montage und manuelles Anpassen<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":9367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"default","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":90,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"[\"thumbnail\",\"title\",\"meta\",\"content\",\"tags\",\"comments\",\"post-navigation\",\"sharing-icons\"]","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,72],"tags":[],"class_list":["post-9248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-plastic-molding"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/9248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/comments?post=9248"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/9248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media\/9367"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media?parent=9248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/categories?post=9248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/tags?post=9248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}