{"id":7103,"date":"2023-12-20T15:40:13","date_gmt":"2023-12-20T15:40:13","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=7103"},"modified":"2025-02-05T15:13:12","modified_gmt":"2025-02-05T15:13:12","slug":"pa6-and-pa66-nylon-injection-molding","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/","title":{"rendered":"Nylon-Spritzgie\u00dfen beherrschen: Einblicke in PA6 und PA66"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"7103\" class=\"elementor elementor-7103\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf1f5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf1f5e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb4be5c\" data-id=\"eb4be5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57d1e08 elementor-widget elementor-widget-shortcode\" data-id=\"57d1e08\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle translation-block\" style=\"cursor:pointer\">Inhalts\u00fcbersicht<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis umschalten\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten auf<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"><\/path><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default\"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Understanding_the_Fundamentals_of_Nylon_Injection_Molding\">Die Grundlagen des Nylon-Spritzgie\u00dfens verstehen<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Versality_of_Nylon_Injection_Molded_Products\">Vielseitigkeit von spritzgegossenen Nylonprodukten<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#What_is_Nylon\">Was ist Nylon?<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Types_of_Nylon\">Arten von Nylon<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Advantages_and_Disadvantages_of_Nylon\">Vorteile und Nachteile von Nylon<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Nylon_6_and_Nylon_66_for_Injection_Molding\">Nylon 6 und Nylon 66 f\u00fcr das Spritzgie\u00dfen<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Types_of_Modified_Nylon\">Arten von modifiziertem Nylon<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Key_Considerations_for_Nylon_Injection_Molding\">Wichtige \u00dcberlegungen zum Nylon-Spritzgie\u00dfen<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Why_Many_Small_and_Medium_Enterprises_Engage_in_Nylon_Modification\">Warum sich viele kleine und mittlere Unternehmen mit der Modifizierung von Nylon besch\u00e4ftigen<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#On-Site_Visits_to_Small_and_Medium_Material_Manufacturers\">Vor-Ort-Besuche bei kleinen und mittleren Materialherstellern<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#Material_Performance_Testing_Experiments\">Experimente zur Pr\u00fcfung der Materialleistung<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/#We_are_experts_in_plastic_injection_molding_Contact_us_now_and_get_a_quick_quote\">Wir sind Experten f\u00fcr Kunststoff-Spritzgie\u00dfen. Kontaktieren Sie uns jetzt und erhalten Sie ein schnelles Angebot!<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bad65d4 elementor-widget elementor-widget-heading\" data-id=\"bad65d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Understanding_the_Fundamentals_of_Nylon_Injection_Molding\"><\/span>Die Grundlagen des Nylon-Spritzgie\u00dfens verstehen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f66aa5c elementor-widget elementor-widget-text-editor\" data-id=\"f66aa5c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Im Bereich der Kunststoffherstellung ist das Spritzgie\u00dfen von Nylon ein zentrales Verfahren, das f\u00fcr seine <strong>Vielseitigkeit<\/strong> und <strong>St\u00e4rke<\/strong> bekannt ist. Dieses Verfahren verwandelt Nylon in verschiedenste Produkte, von Automobilteilen bis hin zu Alltagsgegenst\u00e4nden, und stellt seine Haltbarkeit und Anpassungsf\u00e4higkeit unter Beweis.<\/p><p class=\"translation-block\">Dieser Artikel befasst sich mit den Feinheiten des Nylon-Spritzgie\u00dfens und konzentriert sich dabei auf die beliebtesten Formen, PA6 und PA66, sowie auf die wesentlichen Aspekte des Gie\u00dfverfahrens. Unsere Untersuchung bietet Einblicke in diesen wichtigen Herstellungsprozess und zeigt auf, wie Modifikationen die Eigenschaften von Nylon und seine Anwendungen in verschiedenen Branchen verbessern. Entdecken Sie mit uns die komplizierte Welt des Nylon-Spritzgie\u00dfens, eines Eckpfeilers der modernen Fertigung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2e8ae0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2e8ae0\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a2b4ab\" data-id=\"9a2b4ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dda2507 elementor-widget elementor-widget-heading\" data-id=\"dda2507\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Versality_of_Nylon_Injection_Molded_Products\"><\/span>Vielseitigkeit von spritzgegossenen Nylonprodukten<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-252792a elementor-widget elementor-widget-text-editor\" data-id=\"252792a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\"><em>Nylon wird so h\u00e4ufig verwendet, dass spritzgegossene Produkte aus Nylon fast \u00fcberall in unserem t\u00e4glichen Leben zu finden sind. Im Folgenden finden Sie einige Beispiele f\u00fcr Nylonprodukte, die einen schnellen \u00dcberblick \u00fcber ihre weit verbreiteten Anwendungen geben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5185eb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5185eb4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38031ef\" data-id=\"38031ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4743ae0 elementor-widget elementor-widget-image\" data-id=\"4743ae0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/injection-mold-power-tool-housing\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing.jpg\" class=\"attachment-large size-large wp-image-4437\" alt=\"Elektrowerkzeuggeh\u00e4use\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing.jpg 800w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing-600x450.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing-300x225.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/04\/power-tool-housing-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Nylongeh\u00e4use f\u00fcr Elektrowerkzeuge<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-55b5c8b\" data-id=\"55b5c8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e1c358 elementor-widget elementor-widget-image\" data-id=\"9e1c358\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/finding-custom-plastic-gear-manufacturer\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2019\/04\/2-level-plastic-gear.jpg\" class=\"attachment-large size-large wp-image-4245\" alt=\"2-stufiges Kunststoffgetriebe\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2019\/04\/2-level-plastic-gear.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2019\/04\/2-level-plastic-gear-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Kunststoffzahnr\u00e4der aus Nylon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d07c9e3\" data-id=\"d07c9e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d814f32 elementor-widget elementor-widget-image\" data-id=\"d814f32\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/shop\/plastic-lens-retainer-for-smartphone-cameras\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/plastic-retainer-for-phone-lens-r8r87wtxr1eoplvzqh85itt4l2ukcdzvgwx571p4fs.jpg\" title=\"Kunststoff-Halterung f\u00fcr Phone-Linse\" alt=\"Kunststoff-Halterung f\u00fcr Phone-Linse\" loading=\"lazy\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Objektivhalterung f\u00fcr Smartphones<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e6dab9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e6dab9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d487828\" data-id=\"d487828\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5460797 elementor-widget elementor-widget-image\" data-id=\"5460797\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg\" class=\"attachment-large size-large wp-image-7720\" alt=\"Nylon-Geh\u00e4useeinsatzformteil\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Insert Molding von Nylon-Geh\u00e4usen<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38c5257\" data-id=\"38c5257\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9d9214 elementor-widget elementor-widget-image\" data-id=\"c9d9214\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Hair-Dryer-Casing.jpg\" class=\"attachment-large size-large wp-image-7129\" alt=\"Geh\u00e4use f\u00fcr Haartrockner aus hochfestem Nylon\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Hair-Dryer-Casing.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Hair-Dryer-Casing-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Nylon-Geh\u00e4use f\u00fcr Haartrockner<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-80c8ace\" data-id=\"80c8ace\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e3ba78 elementor-widget elementor-widget-image\" data-id=\"8e3ba78\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/Automotive-Air-Filtration-Enclosure-r8r86x42jc1sgfbvj1sbw2tm0fqm7w22o04oyj6308.jpg\" title=\"Geh\u00e4use f\u00fcr Kfz-Luftfilterung\" alt=\"Geh\u00e4use f\u00fcr Kfz-Luftfilterung\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Geh\u00e4use f\u00fcr Kfz-Luftfilterung<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eac1e90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eac1e90\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-aac89bb\" data-id=\"aac89bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-157914a elementor-widget elementor-widget-image\" data-id=\"157914a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Auto-Cable-Fasteners-and-Clasps.jpg\" class=\"attachment-large size-large wp-image-7132\" alt=\"Nylon-Autokabelverschl\u00fcsse und Klammern\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Auto-Cable-Fasteners-and-Clasps.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Nylon-Auto-Cable-Fasteners-and-Clasps-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Nylon-Autokabelverschl\u00fcsse und Klammern<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ae1f7c2\" data-id=\"ae1f7c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb9740 elementor-widget elementor-widget-image\" data-id=\"bbb9740\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Vehicle-Radiator-Fan-Blades.jpg\" class=\"attachment-large size-large wp-image-7130\" alt=\"K\u00fchlerl\u00fcfterbl\u00e4tter f\u00fcr Fahrzeuge\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Vehicle-Radiator-Fan-Blades.jpg 500w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/Vehicle-Radiator-Fan-Blades-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">K\u00fchlerl\u00fcfterbl\u00e4tter f\u00fcr Fahrzeuge<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2418b66\" data-id=\"2418b66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9203401 elementor-widget elementor-widget-image\" data-id=\"9203401\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/custom-nylon-gear-top-view-r8r8c9szgddkkhjz9v2ul873sfcv1ub1qhv8c98dko.jpg\" title=\"benutzerdefinierte Nylon-Getriebe Draufsicht\" alt=\"benutzerdefinierte Nylon-Getriebe Draufsicht\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Dickwandiges Nylon-Getriebe<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbcfc33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbcfc33\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf91560\" data-id=\"bf91560\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b8e394 elementor-widget elementor-widget-spacer\" data-id=\"9b8e394\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e359c15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e359c15\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4197fe9\" data-id=\"4197fe9\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-436e19c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"436e19c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-33e93c6\" data-id=\"33e93c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43883c1 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"43883c1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Angebot anfordern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f40b05a\" data-id=\"f40b05a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4023e84 elementor-widget elementor-widget-text-editor\" data-id=\"4023e84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Brauchen Sie Know-how im Bereich Nylon-Spritzguss? Kontaktieren Sie uns f\u00fcr au\u00dfergew\u00f6hnlichen Service!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-207abb7\" data-id=\"207abb7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1475acc elementor-widget elementor-widget-image\" data-id=\"1475acc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-1.png\" class=\"attachment-large size-large wp-image-3998\" alt=\"Kunststoff-Eckverbinder 1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-1.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/02\/plastic-corner-connector-1-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e38009d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e38009d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8979946\" data-id=\"8979946\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffc7ab2 elementor-widget elementor-widget-heading\" data-id=\"ffc7ab2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_is_Nylon\"><\/span>Was ist Nylon?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-929605c elementor-widget elementor-widget-text-editor\" data-id=\"929605c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><a href=\"https:\/\/en.wikipedia.org\/wiki\/Nylon\" target=\"_blank\" rel=\"noopener\">Nylon ist ein synthetisches <strong>Polyamid<\/strong><\/a> (abgek\u00fcrzt als <strong>PA<\/strong>), eine Art von Polymer, das durch<strong> Amid<\/strong>-Bindungen (-NH-CO-) gebildet wird. Es geh\u00f6rt zur Familie der <strong>halbkristallinen thermoplastischen Polymere<\/strong>. Bekannt f\u00fcr seine<strong> Festigkeit, Z\u00e4higkeit,<\/strong> Hochtemperaturbest\u00e4ndigkeit, Verschlei\u00dffestigkeit und geringe Reibung, wird Nylon h\u00e4ufig in der Textilherstellung und bei Spritzgussverfahren verwendet. <a href=\"https:\/\/en.wikipedia.org\/wiki\/Nylon\" target=\"_blank\" rel=\"noopener\">Dieses Material wurde in den sp\u00e4ten 1930er Jahren von der amerikanischen Firma DuPont erfunden und benannt.<\/a> Nylon wurde zun\u00e4chst f\u00fcr Zahnb\u00fcrstenborsten verwendet und sp\u00e4ter auf die Herstellung von Str\u00fcmpfen, Fallschirmen und anderen Artikeln ausgeweitet.<\/p><p class=\"translation-block\">Der Name \u201cNylon\u201d ist sehr einpr\u00e4gsam, auch wenn es keine klare Erkl\u00e4rung f\u00fcr seine spezifische Bedeutung gibt. Nichtsdestotrotz ist er ein erfolgreiches Beispiel f\u00fcr kommerzielles Branding.<\/p><p class=\"translation-block\">Es ist wichtig zu wissen, dass Nylon zwar eine Art von Polyamid ist, aber <strong>nicht alle Polyamide als Nylon bezeichnet werden<\/strong>. Zum Beispiel sind nat\u00fcrliche Materialien wie Seide und Wolle Polyamide, die aus Aminos\u00e4uren bestehen, und bestimmte aromatische Polyamide fallen auch nicht unter die Kategorie Nylon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5afe1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5afe1e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c01de3\" data-id=\"3c01de3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5719f6a elementor-widget elementor-widget-heading\" data-id=\"5719f6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Types_of_Nylon\"><\/span>Arten von Nylon<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-332a459 elementor-widget elementor-widget-text-editor\" data-id=\"332a459\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Die Haupttypen von Nylon sind <strong>Nylon 6<\/strong> und <strong>Nylon 66<\/strong>, die den Markt beherrschen. Nylon 6 ist als Polycaprolactam bekannt, w\u00e4hrend es sich bei Nylon 66 um Polyhexamethylenadipamid handelt. Nylon 66 ist etwa 12% h\u00e4rter als Nylon 6. Es folgen Nylon 11, Nylon 12, Nylon 610 und Nylon 612.<\/p><p class=\"translation-block\">Dar\u00fcber hinaus gibt es Typen wie Nylon 1010, Nylon 46, Nylon 7, Nylon 9, Nylon 13 und neuere Sorten wie Nylon 6I, Nylon 9T und die Spezialit\u00e4t Nylon MXD6, die f\u00fcr ihre Barriereeigenschaften bekannt ist. Diese verschiedenen Nylonarten bieten eine Reihe von Eigenschaften, die den unterschiedlichen industriellen Anforderungen und Anwendungen gerecht werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86f48e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86f48e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b75688c\" data-id=\"b75688c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5edb48d elementor-widget elementor-widget-heading\" data-id=\"5edb48d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Advantages_and_Disadvantages_of_Nylon\"><\/span>Vorteile und Nachteile von Nylon<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4cc921 elementor-widget elementor-widget-text-editor\" data-id=\"e4cc921\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Nylon, ein weit verbreitetes synthetisches Material, hat die folgenden Vor- und Nachteile:<\/p><h4><strong>Vorteile:<\/strong><\/h4><ol><li><strong>Hohe mechanische Festigkeit<\/strong>: Nylon ist f\u00fcr seine hervorragende Festigkeit und Z\u00e4higkeit bekannt und eignet sich daher ideal f\u00fcr Anwendungen, die eine hohe mechanische Festigkeit erfordern. Seine Z\u00e4higkeit nimmt weiter zu, wenn es Wasser absorbiert.<\/li><li><strong>Hochtemperaturbest\u00e4ndigkeit<\/strong>: Standard-Nylon kann Temperaturen \u00fcber 100 \u2103 standhalten, und bestimmte modifizierte Typen k\u00f6nnen sogar bis zu 200 \u2103 aushalten.<\/li><li><strong>Glatte und abnutzungsresistente Oberfl\u00e4che<\/strong>: Die Oberfl\u00e4che von Nylon ist glatt und hat einen niedrigen Reibungskoeffizienten, der eine hohe Verschlei\u00dffestigkeit bietet. Es weist selbstschmierende Eigenschaften auf, wenn es als Teil von sich bewegenden Maschinen verwendet wird, was die Ger\u00e4uschentwicklung reduziert und den Bedarf an Schmiermitteln bei Anwendungen mit geringer Reibung eliminiert.<\/li><li><strong>Korrosionsbest\u00e4ndigkeit<\/strong>: Nylon ist gut best\u00e4ndig gegen Laugen und die meisten Salzl\u00f6sungen. Es widersteht auch schwachen S\u00e4uren, Motor\u00f6len, Benzin, aromatischen Kohlenwasserstoffverbindungen und allgemeinen L\u00f6sungsmitteln. Nylon ist inert gegen\u00fcber aromatischen Verbindungen und bietet eine ausgezeichnete Best\u00e4ndigkeit gegen\u00fcber Benzin, \u00d6len, Fetten, Alkohol und schwachen Laugen sowie beeindruckende Anti-Aging-Eigenschaften.<\/li><li><strong>Gute elektrische Isolierung<\/strong>: Nylon beh\u00e4lt auch in feuchten Umgebungen einen gewissen elektrischen Widerstand bei.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8520911 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8520911\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee545b5\" data-id=\"ee545b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-792460c elementor-widget elementor-widget-text-editor\" data-id=\"792460c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" class=\"translation-block\">Nylon ist aufgrund seiner Festigkeit ideal f\u00fcr das Spritzgie\u00dfen von Metalleins\u00e4tzen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b4a724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b4a724\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-42753ab\" data-id=\"42753ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5f46a0 elementor-widget elementor-widget-image\" data-id=\"b5f46a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg\" class=\"attachment-large size-large wp-image-7720\" alt=\"Nylon-Geh\u00e4useeinsatzformteil\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/nylon-enclosure-insert-molding-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67472e3\" data-id=\"67472e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3057627 elementor-widget elementor-widget-image\" data-id=\"3057627\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/inserted-nut-nylon-part.jpg\" class=\"attachment-large size-large wp-image-7724\" alt=\"eingelegte Mutter Nylonteil\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/inserted-nut-nylon-part.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/inserted-nut-nylon-part-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2824fdf elementor-widget elementor-widget-text-editor\" data-id=\"2824fdf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Die Festigkeit und Z\u00e4higkeit von Nylon machen es ideal f\u00fcr das Formen von Metalleins\u00e4tzen. Das Geh\u00e4use enth\u00e4lt 34 eingebettete Metallmuttern. Da das manuelle Einsetzen l\u00e4nger als 2 Minuten dauert, ist das Vorw\u00e4rmen der Eins\u00e4tze ineffizient. Dennoch ist die Wahrscheinlichkeit, dass der Kunststoff rei\u00dft, gering, selbst bei k\u00fchlen Eins\u00e4tzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-426a7a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"426a7a0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce068fc\" data-id=\"ce068fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a274c08 elementor-widget elementor-widget-text-editor\" data-id=\"a274c08\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Benachteiligungen:<\/strong><\/h4><ol><li><strong>Wasserabsorption und Schwellung<\/strong>: Nylon neigt dazu, Wasser zu absorbieren, mit einer Absorptionsrate von mehr als 3%, was zu einer schlechten <a href=\"http:\/\/boyanmfg.com\/injection-molding-tolerances\/\">Formbest\u00e4ndigkeit<\/a>.<\/li><li><strong>Schlechte UV-Best\u00e4ndigkeit<\/strong>: L\u00e4ngerer Aufenthalt im Freien kann dazu f\u00fchren, dass Nylon altert und sich zersetzt.<\/li><li><strong>Begrenzte Temperaturbest\u00e4ndigkeit<\/strong>: Nylon wird bei niedrigen Temperaturen spr\u00f6de und verliert an Festigkeit, w\u00e4hrend es bei hohen Temperaturen zur Alterung und Zersetzung neigt.<\/li><\/ol><p class=\"translation-block\">Bei der Wahl von Nylon als Material ist es daher wichtig, diese St\u00e4rken und Schw\u00e4chen zu ber\u00fccksichtigen, um seine Eignung und Haltbarkeit f\u00fcr bestimmte Anwendungen sicherzustellen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc9bf7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc9bf7e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecef1f6\" data-id=\"ecef1f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cbabe5 elementor-widget elementor-widget-heading\" data-id=\"2cbabe5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Nylon_6_and_Nylon_66_for_Injection_Molding\"><\/span>Nylon 6 und Nylon 66 f\u00fcr das Spritzgie\u00dfen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d7f6b elementor-widget elementor-widget-text-editor\" data-id=\"c4d7f6b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Da diese beiden Arten von Nylon beim Spritzgie\u00dfen am h\u00e4ufigsten verwendet werden, sollten wir sie vergleichen, um ihre Eigenschaften zu verstehen. Beide geh\u00f6ren zur Familie der Polyamide und weisen \u00c4hnlichkeiten in ihrer Molekularstruktur auf.<\/p><p class=\"translation-block\"><strong>\u00c4hnlichkeiten und Unterschiede:<\/strong><\/p><ol><li><p class=\"translation-block\"><strong>Halbkristalline Natur<\/strong>: Beide sind halbkristalline Kunststoffe, aber Nylon 66 hat einen h\u00f6heren Kristallinit\u00e4tsgrad als Nylon 6, was zu einigen Unterschieden in den physikalischen Eigenschaften f\u00fchrt.<\/p><\/li><li><p class=\"translation-block\"><strong>Dichte<\/strong>: Die Dichte von Nylon 6 und Nylon 66 betr\u00e4gt etwa 1,10 bis 1,15 g\/cm3. Durch die Zugabe von Glasfasern oder anderen F\u00fcllstoffen kann die Dichte jedoch erh\u00f6ht werden, wobei sie in der Regel unter 1,5 g\/cm3 liegt.<\/p><\/li><li><p class=\"translation-block\"><a href=\"http:\/\/boyanmfg.com\/melting-point-of-plastics-guide\/\"><strong>Schmelzpunkt<\/strong><\/a>: Der Schmelzpunkt von Nylon 66 liegt bei etwa 260 \u2103 und damit 20-40 Grad h\u00f6her als bei Nylon 6. Dies verleiht Nylon 66 eine h\u00f6here Hitzebest\u00e4ndigkeit, aber es ist weniger elastisch, z\u00e4h und erm\u00fcdungsbest\u00e4ndig als Nylon 6.<\/p><\/li><li><p class=\"translation-block\"><strong>Z\u00e4higkeit<\/strong>: Nylon 6 bietet eine bessere Z\u00e4higkeit.<\/p><\/li><li><p class=\"translation-block\"><strong>H\u00e4rte<\/strong>: Nylon 66 ist h\u00e4rter als Nylon 6.<\/p><\/li><li><p class=\"translation-block\"><strong>Viskosit\u00e4t und Formgebung<\/strong>: Nylon 6 hat eine geringere Viskosit\u00e4t, wodurch es sich leichter formen l\u00e4sst und einen besseren Oberfl\u00e4chenglanz aufweist. Es hat jedoch eine h\u00f6here Wasserabsorptionsrate, mit einer S\u00e4ttigungswasserabsorptionsrate von etwa 10%. Diese hohe Absorption kann die Leistungsf\u00e4higkeit des Materials erheblich beeintr\u00e4chtigen, was bei der Konstruktion ber\u00fccksichtigt werden muss.<\/p><\/li><li><p class=\"translation-block\"><strong>Temperaturbest\u00e4ndigkeit<\/strong>: Nylon 66 kann Temperaturen von etwa 180-190 Grad Celsius standhalten, was 50-60 Grad h\u00f6her ist als bei Nylon 6.<\/p><\/li><\/ol><p class=\"translation-block\">Durch das Verst\u00e4ndnis dieser Unterschiede und Gemeinsamkeiten k\u00f6nnen Hersteller und Designer fundiertere Entscheidungen dar\u00fcber treffen, welche Art von Nylon f\u00fcr ihre spezifischen Anwendungen am besten geeignet ist, insbesondere im Hinblick auf Spritzgussverfahren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96c7f40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96c7f40\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5911117\" data-id=\"5911117\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aab1139 elementor-widget elementor-widget-heading\" data-id=\"aab1139\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Types_of_Modified_Nylon\"><\/span>Arten von modifiziertem Nylon<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de28149 elementor-widget elementor-widget-text-editor\" data-id=\"de28149\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Um die Schw\u00e4chen des Nylons zu \u00fcberwinden, wurden auf dem Markt verschiedene modifizierte Formen des Nylons entwickelt. Zu den gebr\u00e4uchlichsten Modifizierungsmethoden geh\u00f6ren <strong>Mischen, F\u00fcllen<\/strong>und<strong> Copolymerisation<\/strong>. Beim Mischen wird Nylon mit anderen Kunststoffen oder Kautschuken gemischt, um deren St\u00e4rken zu erg\u00e4nzen; bei der Modifizierung durch F\u00fcllen werden typischerweise Materialien wie Glasfasern, Kalziumkarbonat oder Talkum hinzugef\u00fcgt, um die Festigkeit zu erh\u00f6hen und die Schrumpfung zu verringern; bei der Copolymerisation wird die Molek\u00fclkette modifiziert, indem andere funktionelle Gruppen oder Polymere auf PA6-Ketten aufgepfropft oder segmentiert werden, um die Gesamtleistung zu verbessern.<\/p><p class=\"translation-block\">Hier sind einige h\u00e4ufig verwendete modifizierte Nylons:<\/p><ol><li><p class=\"translation-block\"><strong>Verst\u00e4rktes Nylon<\/strong>: Bei den meisten verst\u00e4rkten Nylons werden Glasfasern zusammen mit F\u00fcllstoffen wie Kalziumkarbonat und Talkum verwendet. Diese Zusatzstoffe verbessern die Dimensionsstabilit\u00e4t und H\u00e4rte, k\u00f6nnen aber auch die Dichte erh\u00f6hen und die Z\u00e4higkeit und den Oberfl\u00e4chenglanz des Materials verringern.<\/p><\/li><li><p class=\"translation-block\"><strong>Aufgeh\u00e4rtetes Nylon<\/strong>: Der Hauptzweck des Aufh\u00e4rtens mit Gummi ist die Verbesserung der Leistung bei niedrigen Temperaturen. Normales Nylon wird spr\u00f6de und verliert bei Temperaturen zwischen -30 und -20 Grad Celsius seine Funktionalit\u00e4t. Zu den g\u00e4ngigen Vorspannmitteln geh\u00f6ren EPDM-Kautschuk, EPR-Kautschuk, Nitrilkautschuk, Styrol-Butadien-Kautschuk und Polybutadien-Kautschuk, wobei EPDM am h\u00e4ufigsten verwendet wird. Allerdings kann geh\u00e4rtetes Nylon die Flie\u00dff\u00e4higkeit des Materials verringern, was das Spritzgie\u00dfen erschwert. Es ist wichtig zu beachten, dass die gleichzeitige Verwendung von Vorspannmitteln und Flammschutzmitteln dazu f\u00fchren kann, dass die Flammschutzmittel unwirksam werden.<\/p><\/li><li><p class=\"translation-block\"><strong>Verschlei\u00dffestes Nylon<\/strong>: Verschlei\u00dffestes Nylon wird durch Zugabe von Additiven wie Kohlenstofffasern, Molybd\u00e4ndisulfid, Graphit, PTFE-Pulver oder Silikonpulver erreicht, um die Reibung zu verringern oder die Oberfl\u00e4chenh\u00e4rte zu erh\u00f6hen und damit den Verschlei\u00df zu verringern.<\/p><\/li><li><p class=\"translation-block\"><a href=\"http:\/\/boyanmfg.com\/explore-flame-retardant-plastics\/\"><strong>Flammhemmendes Nylon<\/strong><\/a>: Die auf dem Markt erh\u00e4ltlichen Flammschutzmittel lassen sich im Allgemeinen in drei Kategorien einteilen: halogenierte, nicht-halogenierte und auf rotem Phosphor basierende Mittel, wobei letztere weniger verbreitet sind. Nicht halogenierte Flammschutzmittel sind umweltfreundlicher, da sie bei der Verbrennung weniger Rauch und weniger Nebenprodukte erzeugen. Halogenierte Flammschutzmittel sind effizienter, erzeugen aber bei der Verbrennung schwarzen Rauch und sch\u00e4dliche Gase. Es ist wichtig zu wissen, dass flammhemmende Kunststoffe nicht nicht brennbar sind, sondern so konzipiert sind, dass sie erl\u00f6schen, sobald die Flammenquelle entfernt wird.<\/p><\/li><li><p class=\"translation-block\"><strong>Transparentes Nylon<\/strong>: Transparentes Nylon kann eine Lichtdurchl\u00e4ssigkeit von \u00fcber 90% erreichen, vergleichbar mit PMMA, und besitzt au\u00dferdem eine gute Zugfestigkeit und Schlagfestigkeit. Der Schl\u00fcssel zur Herstellung von transparentem Nylon liegt in der Ver\u00e4nderung der Anordnung der Polymerketten oder der Einf\u00fchrung bestimmter Comonomere, um die Kristallinit\u00e4t zu verringern, da die kristallinen und amorphen Bereiche f\u00fcr die Opazit\u00e4t des Materials verantwortlich sind.<\/p><\/li><\/ol><p class=\"translation-block\">Dar\u00fcber hinaus gibt es weitere Arten wie galvanisiertes Nylon, UV-best\u00e4ndiges Nylon usw., die hier nicht n\u00e4her erl\u00e4utert werden. Durch diese Modifizierungsverfahren haben sich die Anwendungsm\u00f6glichkeiten von Nylon erheblich erweitert, so dass ein breiteres Spektrum an industriellen und allt\u00e4glichen Anforderungen erf\u00fcllt werden kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c10f42 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0c10f42\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c1ed0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c1ed0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c135d0e\" data-id=\"c135d0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c93e6d elementor-widget elementor-widget-heading\" data-id=\"6c93e6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Key_Considerations_for_Nylon_Injection_Molding\"><\/span>Wichtige \u00dcberlegungen zum Nylon-Spritzgie\u00dfen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91cf286 elementor-widget elementor-widget-text-editor\" data-id=\"91cf286\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Beim Spritzgie\u00dfen von Nylon m\u00fcssen mehrere wichtige Methoden und Techniken beherrscht werden, um die Produktqualit\u00e4t sicherzustellen. Dazu geh\u00f6ren:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61a3261 elementor-widget elementor-widget-image\" data-id=\"61a3261\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/all-electric-molding-machine.jpg\" title=\"vollelektrische Formmaschine\" alt=\"vollelektrische Formmaschine\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4ddd6e elementor-widget elementor-widget-text-editor\" data-id=\"a4ddd6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Trocknen von Nylonmaterial<\/strong>: Nylon neigt zur Feuchtigkeitsaufnahme, daher ist es wichtig, es vor dem Spritzgie\u00dfen zu trocknen. Die empfohlene Trocknungstemperatur betr\u00e4gt 120 \u2103 f\u00fcr 4 Stunden. Dieser Schritt unterscheidet sich von dem einiger anderer Kunststoffe wie PP, bei denen eine Trocknung vor der Verarbeitung nicht erforderlich ist.<\/p><p class=\"translation-block\"><strong>Spritzgie\u00dftemperatur<\/strong>:<\/p><ul><li><p class=\"translation-block\"><strong>PA6<\/strong>: Der normale Spritzgie\u00dftemperaturbereich f\u00fcr PA6 betr\u00e4gt 220-260 \u2103. Es wird allgemein empfohlen, die Temperaturen der zweiten und dritten Stufe auf 240-250 \u2103 einzustellen, wobei die D\u00fcsentemperatur auf 210-220 \u2103 geregelt wird. Die Temperatur am Anschnitt sollte 10 Grad niedriger sein als die D\u00fcsentemperatur, da eine zu hohe Temperatur zu Schwierigkeiten beim Materialaustrag und Schneckenschlupf f\u00fchren kann.<\/p><\/li><li><p class=\"translation-block\"><strong>PA66<\/strong>: Der Schmelzpunkt von PA66 liegt bei 255-260 \u2103. Die D\u00fcsentemperatur sollte auf 265-275 \u2103 und die Temperaturen der zweiten und dritten Stufe auf 280-290 \u2103 eingestellt werden, wobei die Anschnitttemperatur bei 280 \u2103 liegt.<\/p><\/li><li><p class=\"translation-block\"><strong>Verst\u00e4rktes Nylon<\/strong>: Bei verst\u00e4rktem Nylon (sowohl bei Nylon 6 als auch bei Nylon 66) ist es ratsam, die Spritzgie\u00dftemperatur um 10-20 Grad zu erh\u00f6hen, da es relativ schlecht flie\u00dff\u00e4hig ist. Um das Aussehen des Produkts zu verbessern, k\u00f6nnen die Temperaturen der zweiten und dritten Stufe ebenfalls um 10-20 Grad erh\u00f6ht werden.<\/p><\/li><\/ul><p class=\"translation-block\"><strong>Einspritzgeschwindigkeit<\/strong>: Bei der Herstellung von Nylonprodukten, die Glasfasern enthalten, ist es notwendig, die Einspritzgeschwindigkeit zu erh\u00f6hen, um das Auftreten von schwimmenden Fasern auf der Produktoberfl\u00e4che zu verhindern.<\/p><p class=\"translation-block\"><strong>Formtemperatur<\/strong>: F\u00fcr Nylon 6 und Nylon 66 betr\u00e4gt die empfohlene Formtemperatur 80-120 \u2103. Die Formtemperatur beeinflusst die Oberfl\u00e4chenqualit\u00e4t und <strong>Kristallinit\u00e4t<\/strong> des Produkts. Produkte mit d\u00fcnneren W\u00e4nden erfordern eine h\u00f6here Formtemperatur, w\u00e4hrend Produkte mit dickeren W\u00e4nden mit einer niedrigeren Formtemperatur, z. B. 40-80 Grad, verarbeitet werden k\u00f6nnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9db9ca5 elementor-widget elementor-widget-text-editor\" data-id=\"9db9ca5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Weitere Erl\u00e4uterungen zur Formtemperatur<\/strong><\/h4><p class=\"translation-block\">Die Formtemperatur spielt eine entscheidende Rolle bei der Bestimmung der Oberfl\u00e4chenqualit\u00e4t und der Kristallinit\u00e4t der Produkte. Eine h\u00f6here Formtemperatur f\u00fchrt zu einer besseren Oberfl\u00e4chenqualit\u00e4t und erh\u00f6ht auch die Kristallinit\u00e4t des Produkts. Dies geschieht, weil eine h\u00f6here Temperatur den Abk\u00fchlungsprozess verlangsamt und dem Kunststoff mehr Zeit zum Kristallisieren gibt.<\/p><p class=\"translation-block\">Eine erh\u00f6hte Kristallinit\u00e4t macht Nylonprodukte dichter, verschlei\u00dffester, h\u00e4rter und erh\u00f6ht ihren Elastizit\u00e4tsmodul. Au\u00dferdem wird die Wasseraufnahme verringert, so dass sich diese Produkte besser f\u00fcr Anwendungen eignen, bei denen es auf Festigkeit und Steifigkeit ankommt.<\/p><p class=\"translation-block\">Wenn Ihre Nylonprodukte hingegen flexibler und dehnbarer sein sollen, sollten Sie eine geringere Kristallinit\u00e4t anstreben. Dies kann durch eine Senkung der Formtemperatur erreicht werden. Niedrigere Temperaturen beschleunigen den Abk\u00fchlungsprozess, wodurch der Kristallisationsprozess im Nylonmaterial unterbrochen wird und folglich seine Kristallinit\u00e4t sinkt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62ac0c6 elementor-widget elementor-widget-text-editor\" data-id=\"62ac0c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"994105e7-9248-40f9-98a9-2f4ec3386ea1\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><h4><strong>Anpacken <a href=\"http:\/\/boyanmfg.com\/common-injection-molding-defects\/\">Schwimmende Faser<\/a> auf Nylonoberfl\u00e4che<\/strong><\/h4><p class=\"translation-block\">Beim Spritzgie\u00dfen von glasfaserverst\u00e4rktem Nylon tritt h\u00e4ufig das Problem der \u201cschwimmenden Fasern\u201d auf, d. h. raue, fleckige Bereiche auf der Oberfl\u00e4che, die durch die Ansammlung und das Auftauchen von Glasfasern entstehen.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ccb657 elementor-widget elementor-widget-image\" data-id=\"0ccb657\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/common-injection-molding-defects\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"487\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic.jpg\" class=\"attachment-large size-large wp-image-7376\" alt=\"schwimmende Faser auf der Oberfl\u00e4che eines Kunststoffteils aus Nylon\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic.jpg 650w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic-600x450.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/floating-fiber-nylon-plastic-300x225.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56dfdf4 elementor-widget elementor-widget-text-editor\" data-id=\"56dfdf4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Um das Aufschwimmen von Fasern zu verhindern, werden in erster Linie die <strong>Flie\u00dff\u00e4higkeit des Nylonmaterials verbessert, die Werkzeugtemperatur erh\u00f6ht und die <strong>Einspritzgeschwindigkeit<\/strong> sowie der <strong>Druck erh\u00f6ht.<\/strong> Eine andere Methode besteht darin, einen Kompatibilisator zwischen die Glasfasern und das Nylonmaterial zu geben, obwohl dies in der Regel kostspieliger ist, da es zus\u00e4tzliche Unterst\u00fctzung von den Materiallieferanten erfordert und die Leistung des Nylons in anderen Aspekten verringern k\u00f6nnte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce418f8 elementor-widget elementor-widget-text-editor\" data-id=\"ce418f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Verwendung von reinem Nylon zur Vermeidung von flottierenden Fasern<\/strong><\/h4><p class=\"translation-block\">Manchmal ist es auch nach Ergreifen aller oben genannten Ma\u00dfnahmen nicht m\u00f6glich, kleine schwimmende Fasern auf der Oberfl\u00e4che des Produkts zu verhindern, wie auf den folgenden Bildern zu sehen ist:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eea6420 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eea6420\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0fb07e4\" data-id=\"0fb07e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79b7ee7 elementor-widget elementor-widget-image\" data-id=\"79b7ee7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-1.jpg\" class=\"attachment-large size-large wp-image-9430\" alt=\"leicht schwimmende Faser auf Nylon-Spritzgussteil, Ansicht von weiter weg\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-1-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b336002\" data-id=\"b336002\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39addfd elementor-widget elementor-widget-image\" data-id=\"39addfd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-2.jpg\" class=\"attachment-large size-large wp-image-9429\" alt=\"leicht schwimmende Faser auf Nylon-Spritzgussteil, n\u00e4here Betrachtung\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/12\/slight-floating-fiber-nylon-2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-82955ca elementor-widget elementor-widget-text-editor\" data-id=\"82955ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Diese schwimmenden Fasern sind im Allgemeinen in vielen F\u00e4llen akzeptabel, aber f\u00fcr h\u00f6herwertige Produkte sind sie nicht akzeptabel. In diesem Fall m\u00fcssen Sie sich m\u00f6glicherweise f\u00fcr reines Nylon entscheiden. Ohne das Vorhandensein von Glasfasern sind die flottierenden Fasern nat\u00fcrlich kein Problem mehr.<\/p><p class=\"translation-block\">Reines Nylon bringt jedoch andere Herausforderungen mit sich. Es haftet st\u00e4rker an der Form, was zu lokalen Aufhellungen und Verformungen f\u00fchren kann, wenn das Produkt aus der Form ausgeworfen wird. Au\u00dferdem ist die Schrumpfungsrate h\u00f6her als bei glasfaserverst\u00e4rktem Nylon, was zu einer Verkleinerung des Produkts f\u00fchren kann. Dies sind zus\u00e4tzliche Probleme, die angegangen werden m\u00fcssen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72be79f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"72be79f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d87516a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d87516a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-843f83a\" data-id=\"843f83a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6471936 elementor-widget elementor-widget-heading\" data-id=\"6471936\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Why_Many_Small_and_Medium_Enterprises_Engage_in_Nylon_Modification\"><\/span>Warum sich viele kleine und mittlere Unternehmen mit der Modifizierung von Nylon besch\u00e4ftigen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5d765a elementor-widget elementor-widget-text-editor\" data-id=\"e5d765a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Zahlreiche kleine und mittlere Unternehmen entscheiden sich aus mehreren Gr\u00fcnden f\u00fcr die Modifizierung von Nylon, insbesondere PA6 und PA66:<\/p><p class=\"translation-block\"><strong>Weiter Anwendungsbereich<\/strong>: Die ausgezeichnete Festigkeit, Verschlei\u00dffestigkeit, chemische Korrosionsbest\u00e4ndigkeit und Hochtemperaturtoleranz von Nylon machen es in verschiedenen Bereichen wie Automobil, Elektronik, Maschinen und Alltagsgegenst\u00e4nden einsetzbar. Diese Vielfalt bietet kleinen und mittleren Unternehmen einen breiten Markt.<\/p><p class=\"translation-block\"><strong>Hohes Modifizierungspotenzial<\/strong>: Nylon kann durch Zugabe verschiedener Materialien (wie Glas- oder Kohlenstofffasern), F\u00fcllstoffe (z. B. mineralische F\u00fcllstoffe) und anderer Additive (wie Flammschutzmittel und UV-Stabilisatoren) verbessert werden, um spezifischen Anforderungen gerecht zu werden.<\/p><p class=\"translation-block\"><strong>Einfache Verarbeitung<\/strong>: Nylon ist leicht zu formen, und die Kosten f\u00fcr die Produktions- und Pr\u00fcfausr\u00fcstung sind nicht hoch, was die Eintrittsbarriere senkt. Die Hauptkosten entstehen durch den Bedarf an gro\u00dfen Produktions- und Lagerfl\u00e4chen.<\/p><p class=\"translation-block\"><strong>Kosteneffizient<\/strong>: Nylon bietet ein gutes Gleichgewicht zwischen Kosten und Leistung. Kleine und mittlere Unternehmen k\u00f6nnen Rohstoffe zu niedrigeren Kosten einkaufen und die Wettbewerbsf\u00e4higkeit ihrer Produkte durch Modifikationen verbessern.<\/p><p class=\"translation-block\"><strong>Stabile Marktnachfrage<\/strong>: Die Nachfrage nach Nylon ist relativ stabil und bietet kleinen und mittleren Unternehmen ein berechenbares Gesch\u00e4ftsumfeld, was besonders f\u00fcr Unternehmen mit begrenzten Ressourcen wichtig ist.<\/p><p class=\"translation-block\"><strong>Ausgereifte Technologie<\/strong>: Die Technologie zur Modifizierung von Nylon ist relativ ausgereift, und die entsprechenden Verarbeitungsmethoden und Formeln sind leicht zug\u00e4nglich, was die technischen Schwierigkeiten verringert und es kleinen und mittleren Unternehmen erleichtert, sie zu beherrschen.<\/p><p class=\"translation-block\">Daher ist die Modifizierung von Nylon die ideale Wahl f\u00fcr kleine und mittlere Kunststofffabriken, da sie technisch machbar, wirtschaftlich sinnvoll und an die stabile Marktnachfrage anpassbar ist. Dies hilft ihnen, in der hart umk\u00e4mpften Branche Fu\u00df zu fassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8468aca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8468aca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f30e30d\" data-id=\"f30e30d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ad2a29 elementor-widget elementor-widget-heading\" data-id=\"3ad2a29\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"On-Site_Visits_to_Small_and_Medium_Material_Manufacturers\"><\/span>Vor-Ort-Besuche bei kleinen und mittleren Materialherstellern<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c49054 elementor-widget elementor-widget-text-editor\" data-id=\"6c49054\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Bei der Auswahl und Bewertung von kleinen und mittleren Materialherstellern ist ein Besuch vor Ort in den Werken ein entscheidender Schritt. Wenn Sie pers\u00f6nlich vor Ort sind, k\u00f6nnen Sie sich ein direktes Bild davon machen, ob der Produktionsprozess und die Lagerverwaltung den Qualit\u00e4tskontrollstandards entsprechen. Bei einem solchen Besuch k\u00f6nnen Sie auch die Qualit\u00e4t der verwendeten Rohstoffe \u00fcberpr\u00fcfen und feststellen, ob das Unternehmen \u00fcber angemessene Pr\u00fcfger\u00e4te zur Gew\u00e4hrleistung der Produktqualit\u00e4t verf\u00fcgt.<\/p><p class=\"translation-block\">Auch die pers\u00f6nliche Kommunikation mit den Herstellern ist wichtig. In Gespr\u00e4chen k\u00f6nnen Sie feststellen, ob der Hersteller \u00fcber das n\u00f6tige Fachwissen und Verst\u00e4ndnis verf\u00fcgt, um die Produktqualit\u00e4t und die anschlie\u00dfende Serviceunterst\u00fctzung zu gew\u00e4hrleisten. Dar\u00fcber hinaus k\u00f6nnen Sie durch die Interaktion mit den Teammitgliedern Einblicke in deren Arbeitseinstellung und Servicebewusstsein gewinnen, die f\u00fcr die Wahl des richtigen Lieferanten wichtig sind.<\/p><p class=\"translation-block\">Zur besseren Veranschaulichung dieses Prozesses finden Sie hier ein Video, das die Produktionsst\u00e4tte von modifiziertem Nylon zeigt. Anhand dieses Videos k\u00f6nnen Sie sich ein Bild von der Produktionsumgebung und den betrieblichen Abl\u00e4ufen machen, was f\u00fcr die Bewertung der Produktionskapazit\u00e4ten und der Produktqualit\u00e4t \u00e4u\u00dferst hilfreich ist.<\/p><p class=\"translation-block\">Zusammenfassend l\u00e4sst sich sagen, dass Besuche vor Ort Ihnen nicht nur Informationen aus erster Hand \u00fcber die Hersteller liefern, sondern Ihnen auch helfen, fundierte und praktische Entscheidungen zu treffen. Solche Bewertungen k\u00f6nnen Ihr Vertrauen in die Qualit\u00e4tskontrolle und die Produktionskapazit\u00e4ten des Anbieters st\u00e4rken und sicherstellen, dass der gew\u00e4hlte Partner Ihre gesch\u00e4ftlichen Anforderungen erf\u00fcllen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1d48fb elementor-widget elementor-widget-video\" data-id=\"e1d48fb\" data-element_type=\"widget\" data-settings='{\"youtube_url\":\"https:\\\/\\\/youtu.be\\\/kJjP1VA620c\",\"video_type\":\"youtube\",\"controls\":\"yes\"}' data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c312a22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c312a22\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2509e3\" data-id=\"c2509e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6912c94 elementor-widget elementor-widget-heading\" data-id=\"6912c94\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Material_Performance_Testing_Experiments\"><\/span>Experimente zur Pr\u00fcfung der Materialleistung<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf48ef elementor-widget elementor-widget-text-editor\" data-id=\"4bf48ef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Materialherstellungsbetriebe sind in der Regel mit verschiedenen Versuchsger\u00e4ten ausgestattet, um die Leistung von Materialien zu testen. Diese Tests umfassen haupts\u00e4chlich:<\/p><ol><li><p class=\"translation-block\"><strong>Zugfestigkeitspr\u00fcfung (einschlie\u00dflich Bruchdehnung)<\/strong>: Dieser Test misst die F\u00e4higkeit des Materials, Zugkr\u00e4ften standzuhalten. Die Ergebnisse werden normalerweise in Megapascal (MPa) angegeben. Er umfasst auch die Bruchdehnung, d. h. das Ausma\u00df, in dem sich das Material dehnen kann, bevor es bricht, und wird in der Regel als Prozentsatz (%) angegeben.<\/p><\/li><li><p class=\"translation-block\"><strong>Biegefestigkeitspr\u00fcfung<\/strong>: Mit dieser Pr\u00fcfung wird die Leistung des Materials beim Biegen bewertet. Dabei wird eine Kraft aufgebracht, um das Material zu biegen, und die erforderliche Kraft und der Grad der Biegung gemessen, normalerweise ausgedr\u00fcckt in Megapascal (MPa).<\/p><\/li><li><p class=\"translation-block\"><strong>Schlagfestigkeitspr\u00fcfung<\/strong>: Mit dieser Pr\u00fcfung wird die Widerstandsf\u00e4higkeit des Materials gegen pl\u00f6tzliche St\u00f6\u00dfe bewertet. Die Ergebnisse werden in Kilojoule pro Quadratmeter (KJ\/m\u00b2) ausgedr\u00fcckt und geben Aufschluss \u00fcber die Z\u00e4higkeit oder Schlagfestigkeit des Materials.<\/p><\/li><li><p class=\"translation-block\"><strong>Pr\u00fcfung der Materialdichte<\/strong>: Mit dieser Pr\u00fcfung wird die Dichte des Materials bestimmt, d. h. die Masse pro Volumeneinheit. Die Ergebnisse werden in Gramm pro Kubikzentimeter (g\/cm\u00b3) angegeben. Bei der Pr\u00fcfung wird das Material in Luft und Wasser gewogen, um seine Dichte zu bestimmen.<\/p><\/li><li><p class=\"translation-block\"><strong>Schmelzflusspr\u00fcfung<\/strong>: Die Schmelzmassendurchflussrate (MFR) oder der Schmelzindex (MI) misst, wie viele Gramm geschmolzenes Harz unter bestimmten Temperatur- und Druckbedingungen innerhalb einer bestimmten Zeit (in der Regel 10 Minuten) durch ein Standardkapillarrohr flie\u00dfen, ausgedr\u00fcckt in Gramm pro 10 Minuten (g\/10min).<\/p><\/li><\/ol><p class=\"translation-block\">Hier finden Sie ein Video, das die Durchf\u00fchrung dieser Tests veranschaulicht. In dem Video k\u00f6nnen Sie den eigentlichen Pr\u00fcfprozess und die Ausr\u00fcstung sehen, was Ihnen hilft, die spezifischen Abl\u00e4ufe und die Bedeutung der einzelnen Pr\u00fcfungen besser zu verstehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44481f8 elementor-widget elementor-widget-video\" data-id=\"44481f8\" data-element_type=\"widget\" data-settings='{\"youtube_url\":\"https:\\\/\\\/youtu.be\\\/_pyAI0IbShA\",\"video_type\":\"youtube\",\"controls\":\"yes\"}' data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a3a196 elementor-widget elementor-widget-text-editor\" data-id=\"9a3a196\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Diese Tests sind entscheidend, um sicherzustellen, dass die Materialien die Leistungsanforderungen f\u00fcr bestimmte Anwendungen erf\u00fcllen. Anhand dieser detaillierten Versuchsdaten k\u00f6nnen die Hersteller die Materialien genau bewerten und verbessern und so qualitativ hochwertigere Produkte herstellen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c86a7f9 elementor-widget elementor-widget-spacer\" data-id=\"c86a7f9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c8bc7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c8bc7c\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc20e01\" data-id=\"bc20e01\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55b2a5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55b2a5e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-95011af\" data-id=\"95011af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6119e4 elementor-widget elementor-widget-image\" data-id=\"e6119e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png\" class=\"attachment-large size-large wp-image-6453\" alt=\"TPU-umspritzte Dreiecksbox\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2023\/11\/TPU-overmolded-triangle-box-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d97de55\" data-id=\"d97de55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a176a73 elementor-widget elementor-widget-heading\" data-id=\"a176a73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Wir sind Experten f\u00fcr Kunststoff-Spritzgie\u00dfen. Kontaktieren Sie uns jetzt und erhalten Sie ein schnelles Angebot!<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-72ab601\" data-id=\"72ab601\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24c9e9e elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"24c9e9e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Angebot anfordern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Grundlagen des Nylon-Spritzgie\u00dfens verstehen Im Bereich der Kunststoffherstellung ist das Nylon-Spritzgie\u00dfen eine zentrale Technik, die f\u00fcr ihre Vielseitigkeit und Festigkeit bekannt ist. Diese Methode verwandelt Nylon in vielf\u00e4ltige Produkte, von Automobilteilen bis hin zu Alltagsgegenst\u00e4nden, und zeigt dabei seine Haltbarkeit und Anpassungsf\u00e4higkeit. Dieser Artikel geht auf die Feinheiten des Nylon-Spritzgie\u00dfens ein,\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/de\/pa6-and-pa66-nylon-injection-molding\/\" rel=\"bookmark\">Weiterlesen \u00bb<span class=\"screen-reader-text\">Nylon-Spritzgie\u00dfen beherrschen: Einblicke in PA6 und PA66<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":7142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":92,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,56],"tags":[],"class_list":["post-7103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-sourcing-skills"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/7103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/comments?post=7103"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/7103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media\/7142"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media?parent=7103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/categories?post=7103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/tags?post=7103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}