{"id":3064,"date":"2021-11-21T10:54:24","date_gmt":"2021-11-21T10:54:24","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=3064"},"modified":"2024-05-27T17:16:28","modified_gmt":"2024-05-27T17:16:28","slug":"sheet-metal-bending-tolerances","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/","title":{"rendered":"Ein vorl\u00e4ufiger Leitfaden f\u00fcr die Biegetoleranzen von Blechen"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3064\" class=\"elementor elementor-3064\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3369cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3369cd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e3a6e9\" data-id=\"3e3a6e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfc28b4 elementor-widget elementor-widget-heading\" data-id=\"bfc28b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Inhalts\u00fcbersicht<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis umschalten\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten auf<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Understanding_and_Applying_Tolerances_for_Sheet_Metal_Bending_Processes\" >Verstehen und Anwenden von Toleranzen f\u00fcr Blechbiegevorg\u00e4nge<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Where_the_variations_come_from\" >Woher die Abweichungen kommen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Material_thickness_variations\" >Schwankungen der Materialst\u00e4rke<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Two_types_of_variations_for_sheet_metal_bending\" >Zwei Arten von Varianten f\u00fcr das Blechbiegen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#1_Angular\" >1. Eckig<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#2_Linear\" >2. Linear<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Normal_tolerances_for_sheet_metal_bending\" >Normale Toleranzen f\u00fcr das Biegen von Blechen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Laser-cut_dimensions_%C2%B1010_to_%C2%B1020mm_more_accurate\" >Lasergeschnittene Ma\u00dfe: \u00b10,10 bis \u00b10,20 mm (genauer)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Bent_dimensions_%C2%B1025_to_%C2%B12mm_less_accurate\" >Gebogene Abmessungen: \u00b10,25 bis \u00b12 mm (weniger genau)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Prioritize_the_tolerances\" >Priorisieren Sie die Toleranzen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Bending_sequence_1\" >Biegefolge 1<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Bending_sequence_2\" >Biegefolge 2<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/#Conclusion\" >Schlussfolgerung<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Understanding_and_Applying_Tolerances_for_Sheet_Metal_Bending_Processes\"><\/span>Verstehen und Anwenden von Toleranzen f\u00fcr Blechbiegevorg\u00e4nge<span class=\"ez-toc-section-end\"><\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c4398b elementor-widget elementor-widget-text-editor\" data-id=\"4c4398b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Korrekte Toleranzen f\u00fcr Blechbiegearbeiten sind wichtig, damit Ihre Entw\u00fcrfe f\u00fcr die Fertigung bereit sind. In diesem Beitrag wird kurz erl\u00e4utert, woher die Abweichungen kommen und wie die einhaltbaren Toleranzen f\u00fcr die \u00fcblichen Arbeitsabl\u00e4ufe in der Werkstatt aussehen k\u00f6nnten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db5523a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db5523a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ceed402\" data-id=\"ceed402\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad1700d elementor-widget elementor-widget-heading\" data-id=\"ad1700d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Where_the_variations_come_from\"><\/span>Woher die Abweichungen kommen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d279a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d279a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-224841e\" data-id=\"224841e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5b29d1 elementor-widget elementor-widget-text-editor\" data-id=\"c5b29d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Das Biegen (Umformen) ist ein <strong>nicht materialabbauender Prozess<\/strong>.\u00a0<\/p><p class=\"translation-block\">Bei spanabhebenden Verfahren (wie der CNC-Bearbeitung) wird die bearbeitete Geometrie haupts\u00e4chlich durch die Pr\u00e4zision der Bewegungen der Schneidwerkzeuge bestimmt. Andere Faktoren tragen viel weniger zur endg\u00fcltigen Pr\u00e4zision der Abmessungen bei.<\/p><p class=\"translation-block\">Beim Biegen von Blechen k\u00f6nnen die Werkzeuge und Matrizen zwar sehr genau hergestellt werden, aber die <strong>Materialdehnung, die R\u00fcckfederung<\/strong> und die Faserrichtung usw. spielen alle eine Rolle. All diese Faktoren m\u00fcssen f\u00fcr eine korrekte Toleranz der Blechteile ber\u00fccksichtigt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9e935dc\" data-id=\"9e935dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a963d59 elementor-widget elementor-widget-image\" data-id=\"a963d59\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"350\" height=\"224\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/fundamental-components-press-brake.gif\" class=\"attachment-large size-large wp-image-3088\" alt=\"Hauptbestandteile einer Abkantpresse\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Der Biegevorgang auf einer Abkantpresse<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9082d5 elementor-widget elementor-widget-text-editor\" data-id=\"a9082d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In der Realit\u00e4t variieren die <strong>Dicke<\/strong> und <strong>Anlassh\u00e4rte<\/strong> von Blech zu Blech oder sogar in verschiedenen Bereichen desselben Blechs.\u00a0<\/p><p class=\"translation-block\">In der Zwischenzeit werden beim Blechbiegen die Schnittkante oder die geformte Kante als Bezugspunkte f\u00fcr die Positionierung des Werkst\u00fccks verwendet; diese Bezugspunkte sind weniger genau als die CNC-gefr\u00e4sten Bezugspunkte.<\/p><p class=\"translation-block\">Daher ist es sehr wichtig, die entsprechenden Toleranzen zu kennen. So k\u00f6nnen Sie Ihre Blechteile effizient und kosteng\u00fcnstig herstellen. \u00dcbertriebene Toleranzen f\u00fchren zu einem drastischen Anstieg der Kontroll- und Sortierarbeiten und damit zu h\u00f6heren Preisen und einer geringeren Produktionsgeschwindigkeit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f03108f elementor-widget elementor-widget-image\" data-id=\"f03108f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"659\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/punch-die-press-brake.jpg\" class=\"attachment-large size-large wp-image-3089\" alt=\"Stempel f\u00fcr Abkantpresse\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/punch-die-press-brake.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/punch-die-press-brake-273x300.jpg 273w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Stempel, Matrize und Hinteranschlag f\u00fcr eine Abkantpresse<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7ee784 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7ee784\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e04b686\" data-id=\"e04b686\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06ffaac elementor-widget elementor-widget-menu-anchor\" data-id=\"06ffaac\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"thickness_variations\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fae3217 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fae3217\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18cfa40\" data-id=\"18cfa40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d75cf0 elementor-widget elementor-widget-heading\" data-id=\"2d75cf0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Material_thickness_variations\"><\/span>Schwankungen der Materialst\u00e4rke<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59faeee elementor-widget elementor-widget-text-editor\" data-id=\"59faeee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In der Praxis kann die Blechdicke in ihren zul\u00e4ssigen Variationen ein wenig variieren. Zum Beispiel:<\/p><ul><li>2mm kaltgewalzter Stahl: 1.90-1.97mm<\/li><li>5 mm warmgewalzter Stahl: 4,60-4,80 mm f\u00fcr Markenstahl; 4,40-4,75 mm f\u00fcr Nicht-Markenstahl (schlechtere Qualit\u00e4t und billiger)<\/li><\/ul><p class=\"translation-block\">Die Dickenschwankungen haben einen gro\u00dfen Einfluss auf die Pr\u00e4zision der fertigen Teile.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37e829a\" data-id=\"37e829a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4ff5ba elementor-widget elementor-widget-image\" data-id=\"e4ff5ba\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"472\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/09\/sheet-metal-material-background-2-1024x472.jpg\" class=\"attachment-large size-large wp-image-2630\" alt=\"Hintergrundbild Blechmaterial\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/09\/sheet-metal-material-background-2-1024x472.jpg 1024w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/09\/sheet-metal-material-background-2-600x277.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/09\/sheet-metal-material-background-2-300x138.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/09\/sheet-metal-material-background-2-768x354.jpg 768w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/09\/sheet-metal-material-background-2.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29506af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29506af\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57484a4\" data-id=\"57484a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe33530 elementor-widget elementor-widget-heading\" data-id=\"fe33530\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Two_types_of_variations_for_sheet_metal_bending\"><\/span>Zwei Arten von Varianten f\u00fcr das Blechbiegen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c52600 elementor-widget elementor-widget-menu-anchor\" data-id=\"1c52600\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"angular_variation\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-051b4d5 elementor-widget elementor-widget-heading\" data-id=\"051b4d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"1_Angular\"><\/span>1. Eckig<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c410d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c410d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30356c0\" data-id=\"30356c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f9e752 elementor-widget elementor-widget-text-editor\" data-id=\"6f9e752\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\">Wenn der Stempel (die obere Matrize) losgelassen wird, federt das Teil ein wenig zur\u00fcck. Das Ausma\u00df der R\u00fcckfederung ist nicht immer gleich, sondern h\u00e4ngt von der H\u00e4rte und Dicke des Materials ab.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d02951 elementor-widget elementor-widget-text-editor\" data-id=\"6d02951\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\">Wenn der Biegeradius und die Materialh\u00e4rte richtig gew\u00e4hlt werden, kann der Biegewinkel normalerweise auf +\/-0,5\u00b0 bis +\/-1\u00b0 eingestellt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3360b2b\" data-id=\"3360b2b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a313897 elementor-widget elementor-widget-image\" data-id=\"a313897\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"356\" height=\"210\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/springback-press-brake-bending.gif\" class=\"attachment-large size-large wp-image-3093\" alt=\"R\u00fcckfederung Abkantpresse Biegen\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">R\u00fcckfederung der Biegung<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac9f9da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac9f9da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83d23cb\" data-id=\"83d23cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd31dc2 elementor-widget elementor-widget-heading\" data-id=\"dd31dc2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Wie sie sich auf die linearen Dimensionen auswirkt<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adceb71 elementor-widget elementor-widget-text-editor\" data-id=\"adceb71\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Wenn wir die linearen Abmessungen messen, sollten wir die nahe Seite der Biegungen messen, da die Messungen auf der entfernten Seite weniger genau und konsistent sind (siehe die Bilder unten).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4270dca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4270dca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-28bd73a\" data-id=\"28bd73a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b88a16 elementor-widget elementor-widget-image\" data-id=\"1b88a16\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"205\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/actual-dimension-of-U-bends.jpg\" class=\"attachment-large size-large wp-image-3098\" alt=\"tats\u00e4chliche Abmessung der U-B\u00f6gen\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/actual-dimension-of-U-bends.jpg 340w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/actual-dimension-of-U-bends-300x181.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Ideal<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0db7dec\" data-id=\"0db7dec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e25107d elementor-widget elementor-widget-image\" data-id=\"e25107d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"205\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/ideal-dimension-of-U-bends.jpg\" class=\"attachment-large size-large wp-image-3097\" alt=\"ideale Abmessung von U-B\u00f6gen\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/ideal-dimension-of-U-bends.jpg 340w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/ideal-dimension-of-U-bends-300x181.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">In Wirklichkeit<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d57b3a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d57b3a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-243eedd\" data-id=\"243eedd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cee931a elementor-widget elementor-widget-menu-anchor\" data-id=\"cee931a\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"linear_variation\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-452ef16 elementor-widget elementor-widget-heading\" data-id=\"452ef16\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"2_Linear\"><\/span>2. Linear<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee6cfd1 elementor-widget elementor-widget-text-editor\" data-id=\"ee6cfd1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Beim Biegen wird der gebogene Bereich d\u00fcnner gedehnt und verl\u00e4ngert (gestreckt). Auch hier ist das Ausma\u00df der Dehnung aufgrund der Ungleichm\u00e4\u00dfigkeit der Materialdicke und des Kabelbaums nicht einheitlich, was zu einer Inkonsistenz der Abmessungen f\u00fchrt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb658fc elementor-widget elementor-widget-text-editor\" data-id=\"bb658fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"padding-left: 40px;\"><strong>Kontrollierte vs. unkontrollierte Dimensionen<\/strong><\/h4><p style=\"padding-left: 40px;\" class=\"translation-block\">Die linearen Abmessungen k\u00f6nnen in kontrollierte und unkontrollierte Abmessungen unterteilt werden.<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\">Die kontrollierten Abmessungen werden direkt von der Biegung abgeleitet, indem das flache Blech gegen den Hinteranschlag gelegt wird, wodurch sie besser kontrolliert werden k\u00f6nnen.<\/p><p style=\"padding-left: 40px;\" class=\"translation-block\">Die unkontrollierten Ma\u00dfe werden indirekt aus 2 oder mehr Biegungen gewonnen, sie sollten mit gr\u00f6\u00dferen Toleranzen versehen werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bd5097 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bd5097\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e97173d\" data-id=\"e97173d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0fb7b4 elementor-widget elementor-widget-heading\" data-id=\"d0fb7b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ein Beispiel<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-465cd6f elementor-widget elementor-widget-text-editor\" data-id=\"465cd6f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Angenommen, wir wollen ein Teil wie dieses herstellen, das 2 Schritte durchl\u00e4uft<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f3c2426 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3c2426\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cc769d5\" data-id=\"cc769d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a508786 elementor-widget elementor-widget-image\" data-id=\"a508786\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"280\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/U-bend-part-example.gif\" class=\"attachment-large size-large wp-image-3099\" alt=\"Beispiel f\u00fcr ein U-Biegeteil\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-76a2b89\" data-id=\"76a2b89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9febce9 elementor-widget elementor-widget-image\" data-id=\"9febce9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"224\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/U-bend-first-step.gif\" class=\"attachment-large size-large wp-image-3100\" alt=\"U-Bogen erster Schritt\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Erster Schritt<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7a4740d\" data-id=\"7a4740d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bdab9d elementor-widget elementor-widget-image\" data-id=\"2bdab9d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"224\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/U-bend-second-step.gif\" class=\"attachment-large size-large wp-image-3101\" alt=\"U-Biegung zweite Stufe\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Zweiter Schritt<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d55398e elementor-widget elementor-widget-text-editor\" data-id=\"d55398e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Die kontrollierten Ma\u00dfe k\u00f6nnen mit einer engeren Toleranz gehalten werden als die nicht kontrollierten Ma\u00dfe, wie unten dargestellt:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-537ea8f elementor-widget elementor-widget-image\" data-id=\"537ea8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"159\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Controlled-and-uncontrolled-dimensions.gif\" class=\"attachment-large size-large wp-image-3102\" alt=\"Kontrollierte und unkontrollierte Abmessungen f\u00fcr das Biegen von Blechen\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ee7540 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ee7540\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d56c6a3\" data-id=\"d56c6a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1ef493 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c1ef493\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a416c2e elementor-widget elementor-widget-menu-anchor\" data-id=\"a416c2e\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"normal_tolerances\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b42c2f elementor-widget elementor-widget-heading\" data-id=\"3b42c2f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Normal_tolerances_for_sheet_metal_bending\"><\/span>Normale Toleranzen f\u00fcr das Biegen von Blechen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-647eb44 elementor-widget elementor-widget-text-editor\" data-id=\"647eb44\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In der Praxis sind die einhaltbaren Toleranzen von vielen Faktoren abh\u00e4ngig, z. B. von der Materialdicke, der Gesamtspanne der Abmessungen, kalt- oder warmgewalztem Stahl usw. Schneller und einfacher geht es, wenn Sie sich einige Beispiele ansehen, um einige Ideen zu bekommen, und dann mit Ihrem DFM-Ingenieur zusammenarbeiten, um die richtigen Toleranzen f\u00fcr jeden spezifischen Auftrag zu finden.<\/p><p class=\"translation-block\"><strong>Bedingung f\u00fcr die folgenden Beispiele<\/strong>: Die Materialst\u00e4rke ist <strong>weniger als 2 mm<\/strong>, die Teile werden durch <strong>Laserschneiden<\/strong> und <strong>Abkantpresse<\/strong> <strong>Biegen<\/strong> hergestellt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd90f5f elementor-widget elementor-widget-text-editor\" data-id=\"fd90f5f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Diese Beispiele geben die \u201cKomfortzonen\u201d der Toleranzen an, aber sie gelten nur f\u00fcr die Gro\u00dfserienproduktion, wenn die Werkzeuge, das Material und die Prozesse optimiert wurden. Bei kleinen Produktionsserien m\u00fcssen die Toleranzen m\u00f6glicherweise noch gelockert werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7da0ddf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7da0ddf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8657b62\" data-id=\"8657b62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbb64ab elementor-widget elementor-widget-menu-anchor\" data-id=\"dbb64ab\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"laser_cut\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f705bc4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f705bc4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5cc8ab elementor-widget elementor-widget-heading\" data-id=\"a5cc8ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Laser-cut_dimensions_%C2%B1010_to_%C2%B1020mm_more_accurate\"><\/span>Lasergeschnittene Ma\u00dfe: \u00b10,10 bis \u00b10,20 mm (genauer)<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d42da0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d42da0b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-042358e\" data-id=\"042358e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cd71dd elementor-widget elementor-widget-text-editor\" data-id=\"1cd71dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Zu den lasergeschnittenen Abmessungen geh\u00f6ren der Lochdurchmesser, der Abstand von Loch zu Loch, der Abstand von Loch zu Kante, die L\u00e4nge und die Breite des Rohlings usw. Bei gro\u00dfen Spannweiten (z. B. 2 m) kann sich die Toleranz auf \u00b11 mm erh\u00f6hen.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a703fce\" data-id=\"a703fce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a5a1a0 elementor-widget elementor-widget-image\" data-id=\"4a5a1a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/normal-tolerance-laser-cutting.jpg\" class=\"attachment-large size-large wp-image-3130\" alt=\"normale Toleranz beim Laserschneiden\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/normal-tolerance-laser-cutting.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/normal-tolerance-laser-cutting-300x144.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-383009e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"383009e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa35239\" data-id=\"aa35239\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72926f1 elementor-widget elementor-widget-menu-anchor\" data-id=\"72926f1\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"bent_dimensins\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-972b521 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"972b521\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dbd5c6 elementor-widget elementor-widget-heading\" data-id=\"4dbd5c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Bent_dimensions_%C2%B1025_to_%C2%B12mm_less_accurate\"><\/span>Gebogene Abmessungen: \u00b10,25 bis \u00b12 mm (weniger genau)<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b685b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b685b6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-144b6bf\" data-id=\"144b6bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3e9d09 elementor-widget elementor-widget-text-editor\" data-id=\"b3e9d09\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Die gebogenen Abmessungen umfassen <strong>Loch zu Biegung, Biegung zu Kante und Biegung zu Biegung.<\/strong>\u00a0<\/p><p class=\"translation-block\">Die Toleranzen variieren je nach der Biegefolge. Die ersten Biegungen sind genauer, da sie die Schnittkante als Bezugspunkt verwenden, die n\u00e4chsten Biegungen, die die gebogene Kante als Bezugspunkt verwenden, sind weniger genau. Das letzte unkontrollierte Ma\u00df ist am ungenauesten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eef84da\" data-id=\"eef84da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81903fc elementor-widget elementor-widget-image\" data-id=\"81903fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/bend-tolerance-sample-1.jpg\" class=\"attachment-large size-large wp-image-3137\" alt=\"Toleranz f\u00fcr das Biegen an der Abkantpresse Beispiel 1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/bend-tolerance-sample-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/bend-tolerance-sample-1-300x202.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa4e58f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa4e58f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0710e68\" data-id=\"0710e68\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2740964 elementor-widget elementor-widget-text-editor\" data-id=\"2740964\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Verwendung der Schnittkante als Bezugsebene<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-645ec1a elementor-widget elementor-widget-image\" data-id=\"645ec1a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"224\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/press-brake-back-gauge-2.gif\" class=\"attachment-large size-large wp-image-3306\" alt=\"Abkantpresse Hinteranschlag 2\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Genauer<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-293c0d0\" data-id=\"293c0d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60f19a0 elementor-widget elementor-widget-text-editor\" data-id=\"60f19a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Verwendung der gebogenen Kante als Bezugsebene<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf54c42 elementor-widget elementor-widget-image\" data-id=\"cf54c42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"224\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/press-brake-back-gauge-1.gif\" class=\"attachment-large size-large wp-image-3307\" alt=\"Abkantpresse Hinteranschlag 1\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Weniger genau<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-64045c0 elementor-widget elementor-widget-text-editor\" data-id=\"64045c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><em>Tipp: Sie werden feststellen, dass es schwierig ist, die <strong>L\u00f6cher (oder andere Merkmale) zum Biegen<\/strong> oder die <strong>Loch-zu-Loch-Abst\u00e4nde (nach dem Biegen)<\/strong> in einer engen Toleranz zu halten. Wenn enge Toleranzen f\u00fcr diese unvermeidlich sind, sollten diese L\u00f6cher (oder andere \u00e4hnliche Merkmale) nach dem Biegen CNC-gefr\u00e4st werden.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67ad64a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67ad64a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec02ba3\" data-id=\"ec02ba3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eaea6ca elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"eaea6ca\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25d0969 elementor-widget elementor-widget-menu-anchor\" data-id=\"25d0969\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"prioritize\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91b7c8c elementor-widget elementor-widget-heading\" data-id=\"91b7c8c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Prioritize_the_tolerances\"><\/span>Priorisieren Sie die Toleranzen<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70fd254 elementor-widget elementor-widget-text-editor\" data-id=\"70fd254\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Wenn wir unterschiedliche Biegefolgen nehmen, k\u00f6nnen wir f\u00fcr jedes Ma\u00df unterschiedliche Toleranzen erhalten. Deshalb ist es wichtig, dass Sie die Schl\u00fcsselma\u00dfe angeben oder Ihrem Hersteller erkl\u00e4ren, wie die Teile bei der Montage funktionieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe514f5 elementor-widget elementor-widget-heading\" data-id=\"fe514f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Bending_sequence_1\"><\/span>Biegefolge 1<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99d7a9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99d7a9d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-86505b6\" data-id=\"86505b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bbe230 elementor-widget elementor-widget-image\" data-id=\"0bbe230\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/tolerance-bending-sequence-1.jpg\" class=\"attachment-large size-large wp-image-3151\" alt=\"Toleranz bei Biegefolge 1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/tolerance-bending-sequence-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/tolerance-bending-sequence-1-300x202.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-84d6d33\" data-id=\"84d6d33\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a29b11 elementor-widget elementor-widget-image\" data-id=\"4a29b11\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"234\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-1.jpg\" class=\"attachment-large size-large wp-image-3145\" alt=\"Biegefolge 1-1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-1.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-1-300x201.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abfada1 elementor-widget elementor-widget-image\" data-id=\"abfada1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"234\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-3.jpg\" class=\"attachment-large size-large wp-image-3147\" alt=\"Biegefolge 1-3\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-3.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-3-300x201.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 3<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c091dd0\" data-id=\"c091dd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34d6bcd elementor-widget elementor-widget-image\" data-id=\"34d6bcd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"234\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-2.jpg\" class=\"attachment-large size-large wp-image-3146\" alt=\"Biegefolge 1-2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-2.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-2-300x201.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7fb55d elementor-widget elementor-widget-image\" data-id=\"c7fb55d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"234\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-4.jpg\" class=\"attachment-large size-large wp-image-3144\" alt=\"Biegefolge 1-4\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-4.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-1-4-300x201.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 4<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-be45fdb elementor-widget elementor-widget-text-editor\" data-id=\"be45fdb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Bei dieser Biegefolge betr\u00e4gt die untere Breite 80\u00b11 mm und die H\u00f6he 22 \u00b10,50 mm.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15fa37b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15fa37b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-196df05\" data-id=\"196df05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80a3835 elementor-widget elementor-widget-heading\" data-id=\"80a3835\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Bending_sequence_2\"><\/span>Biegefolge 2<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-39dc3d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39dc3d1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cd7bd8e\" data-id=\"cd7bd8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d376e84 elementor-widget elementor-widget-image\" data-id=\"d376e84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/tolerance-bending-sequence-2.jpg\" class=\"attachment-large size-large wp-image-3152\" alt=\"Toleranz bei Biegefolge 2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/tolerance-bending-sequence-2.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/tolerance-bending-sequence-2-300x202.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0f0dca2\" data-id=\"0f0dca2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ae2638 elementor-widget elementor-widget-image\" data-id=\"1ae2638\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"233\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-1.jpg\" class=\"attachment-large size-large wp-image-3154\" alt=\"Biegefolge 2-1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-1.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-1-300x200.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dcf22d elementor-widget elementor-widget-image\" data-id=\"7dcf22d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"233\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-3.jpg\" class=\"attachment-large size-large wp-image-3156\" alt=\"Biegefolge 2-3\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-3.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-3-300x200.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 3<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9f3d8df\" data-id=\"9f3d8df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fc54ed elementor-widget elementor-widget-image\" data-id=\"8fc54ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"233\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-2.jpg\" class=\"attachment-large size-large wp-image-3155\" alt=\"Biegefolge 2-2\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-2.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-2-300x200.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cee105 elementor-widget elementor-widget-image\" data-id=\"3cee105\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"233\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-4.jpg\" class=\"attachment-large size-large wp-image-3153\" alt=\"Biegefolge 2-4\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-4.jpg 350w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2021\/11\/Bending-sequence-2-4-300x200.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schritt 4<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e12b48a elementor-widget elementor-widget-text-editor\" data-id=\"e12b48a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Dies ist eine unnormale Biegefolge, f\u00fcr die spezielle Werkzeuge erforderlich sind, um zu vermeiden, dass das Werkst\u00fcck mit der Maschine kollidiert.<\/p><p class=\"translation-block\">Mit dieser Biegefolge kann die untere Breite auf 80\u00b10,5 mm gehalten werden, die H\u00f6he jedoch nur auf 22 \u00b11 mm.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd138e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd138e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f60fe3d\" data-id=\"f60fe3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b66da63 elementor-widget elementor-widget-menu-anchor\" data-id=\"b66da63\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"conclusion\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b603ea8 elementor-widget elementor-widget-heading\" data-id=\"b603ea8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Schlussfolgerung<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-833e13e elementor-widget elementor-widget-text-editor\" data-id=\"833e13e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Dieser Beitrag soll Ihnen helfen zu verstehen, wie die einhaltbare Toleranz f\u00fcr Ihre Blechteile aussehen kann. Doch selbst f\u00fcr einen erfahrenen Konstrukteur kann es schwierig und zeitaufw\u00e4ndig sein, die Toleranzen f\u00fcr jedes einzelne Ma\u00df festzulegen. Ein einfacherer Ansatz besteht darin, dem Hersteller oder DFM-Ingenieur zu erkl\u00e4ren, wie das Teil in die Baugruppe passt und funktioniert und wie es mit den Gegenst\u00fccken zusammenwirkt. Der Hersteller oder DFM-Ingenieur verf\u00fcgt \u00fcber die n\u00f6tige Erfahrung oder kann auf der Grundlage Ihrer Informationen Pr\u00fcfvorrichtungen anfertigen und die am besten geeigneten Toleranzen f\u00fcr die wichtigsten Abmessungen ermitteln.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-186d521 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"186d521\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9380052\" data-id=\"9380052\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f360b8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9f360b8\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-530a060 elementor-widget elementor-widget-text-editor\" data-id=\"530a060\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><em>Boyan Manufacturing Solutions hat reiche Erfahrung in der Blechverarbeitung. Wenn Sie Fragen haben, hinterlassen Sie uns bitte eine Nachricht oder <a href=\"http:\/\/boyanmfg.com\/enquiry-sheet-metal-fabrication\/\">schicken Sie uns Ihre Zeichnungen<\/a> zur Beratung.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d1de59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d1de59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ca06bd\" data-id=\"2ca06bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Verstehen und Anwenden von Toleranzen f\u00fcr Blechbiegeprozesse Eine korrekte Toleranzierung f\u00fcr Blechbiegearbeiten ist wichtig, um Ihre Konstruktionen fertigungsbereit zu machen. Dieser Beitrag erkl\u00e4rt kurz, woher die Abweichungen kommen und welche haltbaren Toleranzen f\u00fcr \u00fcbliche Werkstattoperationen m\u00f6glich sein k\u00f6nnten. Woher die Abweichungen kommen Das Biegen (Umformen)\u2026&nbsp;<a href=\"https:\/\/boyanmfg.com\/de\/sheet-metal-bending-tolerances\/\" rel=\"bookmark\">Weiterlesen \u00bb<span class=\"screen-reader-text\">Ein vorl\u00e4ufiger Leitfaden f\u00fcr die Biegetoleranzen von Blechen<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":3173,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":90,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"[\"title\",\"meta\",\"thumbnail\",\"content\",\"tags\",\"comments\",\"post-navigation\"]","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,73],"tags":[],"class_list":["post-3064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-knowledge","category-sheet-metal-fabrication"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/3064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/comments?post=3064"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/3064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media\/3173"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media?parent=3064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/categories?post=3064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/tags?post=3064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}