{"id":1762,"date":"2020-02-05T12:43:49","date_gmt":"2020-02-05T12:43:49","guid":{"rendered":"http:\/\/boyanmfg.com\/?p=1762"},"modified":"2024-05-27T17:16:29","modified_gmt":"2024-05-27T17:16:29","slug":"anodized-aluminum-extrusions","status":"publish","type":"post","link":"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/","title":{"rendered":"Hochwertige eloxierte Aluminium-Strangpressprofile"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1762\" class=\"elementor elementor-1762\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38ec6a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38ec6a4\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-969a84e\" data-id=\"969a84e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6302d59 elementor-widget elementor-widget-text-editor\" data-id=\"6302d59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Es ist nicht einfach, einen Hersteller von hochwertigen eloxierten Aluminium-Strangpressprofilen zu finden. Als Beschaffungsunternehmen haben wir mehrere verschiedene Hersteller ausprobiert, bis wir einen gefunden haben, mit dem wir uns wohlf\u00fchlen. In diesem Beitrag geben wir gerne unser Wissen und unsere Erfahrung in diesem Bereich weiter. Wenn Sie m\u00f6chten, dass wir Ihnen beim Kauf von eloxierten Aluminium-Strangpressprofilen oder daraus hergestellten Fertigteilen behilflich sind, oder wenn Sie den Hersteller direkt kontaktieren m\u00f6chten, <a href=\"http:\/\/boyanmfg.com\/contact-us\/\">bitte kontaktieren Sie uns<\/a>.<\/p><p class=\"translation-block\"><strong>Inhaltsverzeichnis:<\/strong><\/p><ol><li><a href=\"#advantages\">Welchen Vorteil hat die Verwendung von eloxiertem Aluminium gegen\u00fcber rohen Strangpressprofilen?;<\/a><\/li><li><a href=\"#quality_requirements\">Eine kurze Einf\u00fchrung in die \u00fcblichen Qualit\u00e4tsanforderungen<\/a>;<\/li><li><a href=\"#common_defects\">Was sind die h\u00e4ufigsten Eloxalfehler bei Aluminium-Strangpressprofilen?<\/a>;<\/li><li><a href=\"#qualified_manufacturer\">Was macht einen guten Hersteller von eloxierten Aluminium-Strangpressprofilen aus?<\/a>.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2544521 elementor-widget__width-inherit elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"2544521\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"2\",\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"speed\":500,\"image_spacing_custom\":{\"unit\":\"px\",\"size\":20,\"sizes\":[]},\"image_spacing_custom_tablet\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"image_spacing_custom_mobile\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]}}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bildkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-extrusions-anodizing-loading-area.jpg\" alt=\"Aluminium-Strangpressprofile Eloxieren Ladefl\u00e4che\"><figcaption class=\"elementor-image-carousel-caption\">Ladefl\u00e4che<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-extrusions-anodizing-rinsing-tank.jpg\" alt=\"Sp\u00fclbeh\u00e4lter f\u00fcr die Eloxierung von Aluminium-Strangpressprofilen\"><figcaption class=\"elementor-image-carousel-caption\">Sp\u00fcltanks f\u00fcr die Aluminiumanodisierung<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-anodizing-waist-water-treatment.jpg\" alt=\"Taillenwasseraufbereitung f\u00fcr die Eloxierung von Aluminium\"><figcaption class=\"elementor-image-carousel-caption\">Wasseraufbereitung f\u00fcr die Taille<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-extrusions-production-line.jpg\" alt=\"Produktionslinie f\u00fcr Aluminium-Strangpressprofile\"><figcaption class=\"elementor-image-carousel-caption\">Produktionslinie f\u00fcr Aluminiumstrangpressen<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-extrusios-stocks.jpg\" alt=\"Lagerbest\u00e4nde von Aluminium-Strangpressprofilen\"><figcaption class=\"elementor-image-carousel-caption\">Aluminium-Strangpressbest\u00e4nde<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-extrusion-warehouse.jpg\" alt=\"Lager f\u00fcr Aluminium-Strangpressprofile\"><figcaption class=\"elementor-image-carousel-caption\">Lagerhaus<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9bb864 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9bb864\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd24729\" data-id=\"cd24729\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67359c0 elementor-widget elementor-widget-heading\" data-id=\"67359c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Inhalts\u00fcbersicht<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis umschalten\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten auf<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#What_are_anodized_aluminum_extrusions\" >Was sind anodisierte Aluminium-Strangpressprofile?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#The_advantages_of_using_anodized_aluminum_extrusions\" >Die Vorteile der Verwendung von eloxierten Aluminium-Strangpressprofilen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#1_Anodize_the_aluminum_extrusion_before_machining\" >1. Eloxieren Sie das Aluminium-Strangpressprofil vor der Bearbeitung.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#2_Anodize_the_parts_after_they_have_been_machined_from_raw_extrusions\" >2. Eloxieren Sie die Teile, nachdem sie aus rohen Strangpressprofilen bearbeitet worden sind.<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#Usual_quality_requirements_for_anodized_aluminum\" >\u00dcbliche Qualit\u00e4tsanforderungen f\u00fcr anodisiertes Aluminium<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#High_quality_requirements_for_aluminum_extrusions_is_quite_challenging\" >Hohe Qualit\u00e4tsanforderungen f\u00fcr Aluminium-Strangpressprofile sind eine gro\u00dfe Herausforderung<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#Common_anodizing_defects_for_aluminum_extrusions\" >H\u00e4ufige Eloxalfehler bei Aluminium-Strangpressprofilen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#What_makes_a_qualified_aluminum_extrusion_manufacturer\" >Was macht einen qualifizierten Hersteller von Aluminium-Strangpressprofilen aus?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/#What_we_can_supply\" >Was wir liefern k\u00f6nnen<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_are_anodized_aluminum_extrusions\"><\/span>Was sind anodisierte Aluminium-Strangpressprofile?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b03ee63 elementor-widget elementor-widget-text-editor\" data-id=\"b03ee63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Sie werden in der Regel auf 6 Meter L\u00e4nge zugeschnitten und eloxiert. Die Eloxierung kann in verschiedenen Farben erfolgen, aber klare Eloxierung ist die h\u00e4ufigste, schwarze Eloxierung kommt die n\u00e4chste. Es gibt andere Farboptionen, aber sie m\u00fcssen eine h\u00f6here MOQ, sagen wir, wie 15 bis 20 Tonnen erf\u00fcllen.<\/p><p class=\"translation-block\">Die Eloxalschicht f\u00fcr das klare Eloxieren ist normalerweise 0,005 bis 0,008 mm dick. Eine dickere Eloxalschicht kann einen besseren Schutz bieten, aber das Aussehen wird stumpfer und gelblicher, was es weniger ansprechend macht.<\/p><p class=\"translation-block\">Bei der schwarzen Eloxierung betr\u00e4gt die Schichtdicke normalerweise 0,009 bis 0,012 mm.<\/p><p class=\"translation-block\">Die Oberfl\u00e4che wird in der Regel sandgestrahlt, um leichte Formabdr\u00fccke und andere kleinere Unvollkommenheiten zu verdecken. Dies hat auch ein angenehmes Aussehen und ist f\u00fcr viele Produkte eine erforderliche Oberfl\u00e4chenbehandlung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc8f401 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc8f401\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4deca9a\" data-id=\"4deca9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7de85a6 elementor-widget elementor-widget-menu-anchor\" data-id=\"7de85a6\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"advantages\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1934b95 elementor-widget elementor-widget-heading\" data-id=\"1934b95\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"The_advantages_of_using_anodized_aluminum_extrusions\"><\/span>Die Vorteile der Verwendung von eloxierten Aluminium-Strangpressprofilen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d63a309 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d63a309\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f61139\" data-id=\"3f61139\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc6937b elementor-widget elementor-widget-image\" data-id=\"fc6937b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"151\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/6-meter-long-anodized-aluminum-extrusion.jpg\" class=\"attachment-large size-large wp-image-1854\" alt=\"6 Meter langes, eloxiertes Aluminium-Strangpressprofil\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/6-meter-long-anodized-aluminum-extrusion.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/6-meter-long-anodized-aluminum-extrusion-300x76.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">6 Meter lange Aluminium-Strangpressprofile<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1efe07e\" data-id=\"1efe07e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c2f0f8 elementor-widget elementor-widget-image\" data-id=\"4c2f0f8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"327\" height=\"150\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/part-machined-from-aluminum-extrusion.jpg\" class=\"attachment-large size-large wp-image-1855\" alt=\"Ein aus eloxiertem stranggepresstem Aluminium gefertigtes Teil\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/part-machined-from-aluminum-extrusion.jpg 327w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/part-machined-from-aluminum-extrusion-300x138.jpg 300w\" sizes=\"(max-width: 327px) 100vw, 327px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Fertiges Teil<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-81cbb1a elementor-widget elementor-widget-text-editor\" data-id=\"81cbb1a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Ein gro\u00dfer Vorteil sind die geringeren Kosten. Stellen Sie sich vor, Sie wollen einige eloxierte Aluminiumteile aus den Strangpressprofilen herstellen. Es gibt 2 M\u00f6glichkeiten: Eloxieren <strong>vor<\/strong> oder <strong>nach<\/strong> der Herstellung der Teile:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0397659 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0397659\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dd6078\" data-id=\"7dd6078\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60b26e3 elementor-widget elementor-widget-heading\" data-id=\"60b26e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"1_Anodize_the_aluminum_extrusion_before_machining\"><\/span>1. Eloxieren Sie das Aluminium-Strangpressprofil vor der Bearbeitung.<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8233fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8233fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9a530c\" data-id=\"e9a530c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7462b9 elementor-widget elementor-widget-text-editor\" data-id=\"d7462b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Pros:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f73a03\" data-id=\"1f73a03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2829ea3 elementor-widget elementor-widget-text-editor\" data-id=\"2829ea3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Geringere Kosten. Es ist billiger, die gesamten Teile zu eloxieren, als viele Einzelteile zu eloxieren.<\/li><li>Sie vermeiden die R\u00fcckweisung des Teils aufgrund von Eloxalfehlern, was Ihnen viel Zeit und Geld spart.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80b7930 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80b7930\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fc31e8c\" data-id=\"fc31e8c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a43116 elementor-widget elementor-widget-text-editor\" data-id=\"4a43116\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Nachteile:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e447913\" data-id=\"e447913\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f3010f elementor-widget elementor-widget-text-editor\" data-id=\"1f3010f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Der geschnittene Abschnitt wird ohne anodische Feile (blankes Metall) freigelegt. In vielen F\u00e4llen ist dies jedoch akzeptabel.<\/li><li>Sie k\u00f6nnen die Oberfl\u00e4chenfehler (Kratzer, Dellen), die bei den zweiten Prozessen (Bearbeitung, Be- und Entladen usw.) entstehen, nicht beheben.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5087593\" data-id=\"5087593\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28a3c4e elementor-widget elementor-widget-image\" data-id=\"28a3c4e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/end-surface-of-aluminum-profile-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-1800\" alt=\"Endfl\u00e4che des Aluminiumprofils\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/end-surface-of-aluminum-profile-150x150.jpg 150w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/end-surface-of-aluminum-profile-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Der Schnitt (Endfl\u00e4che) wird ohne Eloxalschicht freigelegt.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8133aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8133aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e860234\" data-id=\"e860234\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eca6ef elementor-widget elementor-widget-heading\" data-id=\"3eca6ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"2_Anodize_the_parts_after_they_have_been_machined_from_raw_extrusions\"><\/span>2. Eloxieren Sie die Teile, nachdem sie aus rohen Strangpressprofilen bearbeitet worden sind.<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-778d6f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"778d6f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4ab8560\" data-id=\"4ab8560\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f8fa4c elementor-widget elementor-widget-text-editor\" data-id=\"5f8fa4c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Pros:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ab8aaf7\" data-id=\"ab8aaf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcca545 elementor-widget elementor-widget-text-editor\" data-id=\"dcca545\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Das gesamte Teil ist mit der Schutzschicht eloxiert, mit Ausnahme der Zahnstangenspuren (es handelt sich meist um kleine Flecken).<\/li><li>Einige kleinere Oberfl\u00e4chenfehler k\u00f6nnen vor dem Eloxieren behoben werden, aber nur f\u00fcr diese sehr kleinen Fehler.\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6055162 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6055162\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4830405\" data-id=\"4830405\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15b6647 elementor-widget elementor-widget-text-editor\" data-id=\"15b6647\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Nachteile:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b1d6ac\" data-id=\"3b1d6ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f4474a elementor-widget elementor-widget-text-editor\" data-id=\"7f4474a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Die Teile mit Eloxalfehlern werden alle zur\u00fcckgewiesen. Viele von ihnen sind nicht behebbar.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2903e36 elementor-widget elementor-widget-text-editor\" data-id=\"2903e36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Schlussfolgerung:<\/strong> Wie Sie sehen k\u00f6nnen, kann die Verwendung von eloxierten Aluminium-Strangpressprofilen zur Herstellung von Teilen (Option 1, siehe oben) Kosten einsparen und Qualit\u00e4tsm\u00e4ngel reduzieren, so dass diese Option gegen\u00fcber der anderen (Eloxieren der einzelnen Teile) zu empfehlen ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1166ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1166ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-060cb62\" data-id=\"060cb62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7c9191 elementor-widget elementor-widget-menu-anchor\" data-id=\"d7c9191\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"quality_requirements\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e57aed elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4e57aed\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a48051 elementor-widget elementor-widget-heading\" data-id=\"2a48051\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Usual_quality_requirements_for_anodized_aluminum\"><\/span>\u00dcbliche Qualit\u00e4tsanforderungen f\u00fcr anodisiertes Aluminium<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-795b9aa elementor-widget elementor-widget-text-editor\" data-id=\"795b9aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Eloxieren ist ein komplexes elektrochemisches Verfahren, das aus drei Schritten besteht: Vorbehandlung, Eloxieren und Versiegeln. Jeder Schritt hat mehrere Parameter (wie Temperatur, Konzentration und Zeit), die genau kontrolliert werden m\u00fcssen. Mehr oder weniger werden die Eloxalfehler mit den fertigen Teilen kommen, viele der Eloxalfehler sind nicht zu beheben, was bedeutet, dass die ganzen Teile mit Eloxalfehlern zur\u00fcckgewiesen werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2afd741 elementor-widget elementor-widget-text-editor\" data-id=\"2afd741\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Im Allgemeinen k\u00f6nnen die Qualit\u00e4tsanforderungen f\u00fcr das Eloxieren von Aluminium in 2 Gruppen eingeteilt werden:<\/p><ul><li>Die anodische Oxidschicht muss die erwartete Qualit\u00e4t aufweisen (z. B. Dicke, Gleichm\u00e4\u00dfigkeit), damit sie den gew\u00fcnschten Schutz, die gew\u00fcnschte H\u00e4rte usw. bietet.<\/li><li>Dass das Aussehen der Teile gleichm\u00e4\u00dfig und ansprechend ist, der Glanz und die Farbe wie gew\u00fcnscht sind und sie keine mechanischen Besch\u00e4digungen (wie Kratzer, Dellen) aufweisen.<\/li><\/ul><p class=\"translation-block\">Es ist etwas kompliziert, die Qualit\u00e4tsanforderungen f\u00fcr das Eloxieren von Aluminium in allen Einzelheiten zu erkl\u00e4ren, aber im Folgenden werden die h\u00e4ufigsten Eloxierfehler bei Strangpressprofilen beschrieben.<\/p><p class=\"translation-block\">Viele Eloxalfehler lassen sich durch Sichtpr\u00fcfung feststellen. Je gr\u00f6\u00dfer die Teile sind, desto wahrscheinlicher ist es, dass sie an der einen oder anderen Stelle M\u00e4ngel aufweisen, einfach weil sie gr\u00f6\u00dfer sind. Dies stellt h\u00f6here Anforderungen an die langen Aluminium-Strangpressprofile, weil sie so lang sind (und damit gr\u00f6\u00dfer in der Fl\u00e4che und schwerer im Gewicht).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce823b elementor-widget elementor-widget-heading\" data-id=\"5ce823b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"High_quality_requirements_for_aluminum_extrusions_is_quite_challenging\"><\/span>Hohe Qualit\u00e4tsanforderungen f\u00fcr Aluminium-Strangpressprofile sind eine gro\u00dfe Herausforderung<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6d2d36 elementor-widget elementor-widget-text-editor\" data-id=\"b6d2d36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In vielen F\u00e4llen sind die optischen Anforderungen an Aluminium-Strangpressprofile niedriger als an andere kleinere Teile.<\/p><p class=\"translation-block\">Wie bei Aluminiumleitern oder M\u00f6beln f\u00fcr den Au\u00dfenbereich werden einige kleine M\u00e4ngel als akzeptabel angesehen.<\/p><p class=\"translation-block\">Wenn Sie jedoch h\u00f6here Qualit\u00e4tsanforderungen haben, k\u00f6nnen wir auch 6 Meter lange eloxierte Aluminium-Strangpressprofile mit fast keinen Fehlern liefern, nur diese Art von Fehlern wie Pin-Point sollte akzeptiert werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a6f80 elementor-widget elementor-widget-text-editor\" data-id=\"57a6f80\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">In jedem 1 Meter langen Profil sind 3 Flecken von weniger als 0,3 mm<sup>2 <\/sup> zul\u00e4ssig.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73a81bd elementor-widget elementor-widget-heading\" data-id=\"73a81bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Flecken von weniger als 0,3 mm2<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b929a41 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"b929a41\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"gallery-1\" class=\"gallery galleryid-1762 gallery-columns-2 gallery-size-full\"><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon portrait\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b929a41\" data-elementor-lightbox-title=\"tiny spot aluminum anodizing\" data-elementor-lightbox-description=\"tiny spot on the surface of aluminum anodizing\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTc5MywidXJsIjoiaHR0cHM6XC9cL2JveWFubWZnLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMDJcL3Rpbnktc3BvdC1hbHVtaW51bS1hbm9kaXppbmcuanBnIiwic2xpZGVzaG93IjoiYjkyOWE0MSJ9\" href=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/tiny-spot-aluminum-anodizing.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"563\" height=\"750\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/tiny-spot-aluminum-anodizing.jpg\" class=\"attachment-full size-full\" alt=\"Winziger Fleck auf der Oberfl\u00e4che von eloxiertem Aluminium\" aria-describedby=\"gallery-1-1793\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/tiny-spot-aluminum-anodizing.jpg 563w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/tiny-spot-aluminum-anodizing-225x300.jpg 225w\" sizes=\"(max-width: 563px) 100vw, 563px\"><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class=\"wp-caption-text gallery-caption\" id=\"gallery-1-1793\">\n\t\t\t\tEin kleiner Fleck von etwa 0,2 mm2 Gr\u00f6\u00dfe\n\t\t\t\t<\/figcaption><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon portrait\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b929a41\" data-elementor-lightbox-title=\"small spot anodized aluminum\" data-elementor-lightbox-description=\"anodizing defects of small spot on anodized aluminum\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTc5NCwidXJsIjoiaHR0cHM6XC9cL2JveWFubWZnLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMDJcL3NtYWxsLXNwb3QtYW5vZGl6ZWQtYWx1bWludW0uanBnIiwic2xpZGVzaG93IjoiYjkyOWE0MSJ9\" href=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/small-spot-anodized-aluminum.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"562\" height=\"750\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/small-spot-anodized-aluminum.jpg\" class=\"attachment-full size-full\" alt=\"Eloxalfehler kleine Stelle auf eloxiertem Aluminium\" aria-describedby=\"gallery-1-1794\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/small-spot-anodized-aluminum.jpg 562w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/small-spot-anodized-aluminum-225x300.jpg 225w\" sizes=\"(max-width: 562px) 100vw, 562px\"><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class=\"wp-caption-text gallery-caption\" id=\"gallery-1-1794\">\n\t\t\t\t2. Beispiel\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9e8bf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9e8bf5\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db8422b\" data-id=\"db8422b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5485a22 elementor-widget elementor-widget-menu-anchor\" data-id=\"5485a22\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"common_defects\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-312e7e2 elementor-widget elementor-widget-heading\" data-id=\"312e7e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Common_anodizing_defects_for_aluminum_extrusions\"><\/span>H\u00e4ufige Eloxalfehler bei Aluminium-Strangpressprofilen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f70618 elementor-widget elementor-widget-text-editor\" data-id=\"2f70618\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Oberfl\u00e4chenkratzer und Dellen (mechanische Sch\u00e4den)<\/strong>. Je gr\u00f6\u00dfer die Oberfl\u00e4che und je schwerer die Teile sind, desto wahrscheinlicher ist es, dass die Teile diese Art von Fehlern aufweisen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3844382 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3844382\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"1\",\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"effect\":\"slide\",\"speed\":500}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bildkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-anodizing-defects-dents-2.jpg\" alt=\"Eloxalfehler an einer Stelle mit mechanischer Besch\u00e4digung\"><figcaption class=\"elementor-image-carousel-caption\">Kleiner dunkler Fleck auf der Oberfl\u00e4che<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/anodizing-defects-dents.jpg\" alt=\"Eloxalfehler oder Dellen auf der Oberfl\u00e4che\"><figcaption class=\"elementor-image-carousel-caption\">Dellen auf der Oberfl\u00e4che<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/anodizing-defects-scratch-3.jpg\" alt=\"Eloxalfehler eines Kratzers\"><figcaption class=\"elementor-image-carousel-caption\">Ein leichter Kratzer (aber ein bisschen gro\u00df)<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-anodizing-defects-scratch-2.jpg\" alt=\"Defekte am eloxierten Aluminiumstrangpressprofil eines Kratzers\"><figcaption class=\"elementor-image-carousel-caption\">Scratch Beispiel 2<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/aluminum-anodizing-defects-scratch.jpg\" alt=\"Fehler auf eloxiertem Aluminium-Strangpressprofil eines Kratzers 3\"><figcaption class=\"elementor-image-carousel-caption\">Scratch-Beispiel 3<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aef30fb elementor-widget elementor-widget-text-editor\" data-id=\"aef30fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Spangle-\u00e4hnliche Oberfl\u00e4che<\/strong>, Dies ist vermutlich auf die Verunreinigung des Materials zur\u00fcckzuf\u00fchren. Nicht alle anodisierten Oberfl\u00e4chen sind so, vielleicht wie 20-30%. Allerdings wird diese Menge an Defekten die Ablehnung der gesamten Partie des Materials verursachen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c15b570 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"c15b570\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"1\",\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"effect\":\"slide\",\"speed\":500}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bildkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/anodizing-defects-spangle-like-finish.jpg\" alt=\"Eloxaloberfl\u00e4che mit kantiger Oberfl\u00e4che\"><figcaption class=\"elementor-image-carousel-caption\">Gro\u00dffl\u00e4chige Eloxalspangen<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/anodizing-spangle-closer-view.jpg\" alt=\"Eine n\u00e4here Betrachtung der Eloxalfehler Spangles\"><figcaption class=\"elementor-image-carousel-caption\">Eine n\u00e4here Betrachtung der Eloxalspangen<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/less-anodizing-spangles.jpg\" alt=\"weniger Eloxalflecken\"><figcaption class=\"elementor-image-carousel-caption\">Weniger Pailletten auf der Oberfl\u00e4che<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/small-area-of-anodizing-spangles.jpg\" alt=\"kleine Fl\u00e4che mit Eloxalflecken\"><figcaption class=\"elementor-image-carousel-caption\">Kleiner Bereich von Eloxalflecken<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c75237d elementor-widget elementor-widget-text-editor\" data-id=\"c75237d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Schimmelspuren<\/strong> (oder Werkzeugspuren). Die Form muss regelm\u00e4\u00dfig in einem bestimmten Produktionsintervall gewartet werden, da sich sonst Werkzeugspuren bilden.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0543336 elementor-widget elementor-widget-text-editor\" data-id=\"0543336\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Formspuren sind bei rohen Aluminium-Strangpressprofilen durchaus \u00fcblich. Solange die Spuren nicht zu tief sind und nach dem Sandstrahlen und Eloxieren entfernt werden k\u00f6nnen, sind sie akzeptabel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1087bc elementor-widget elementor-widget-heading\" data-id=\"d1087bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Abdr\u00fccke vor dem Eloxieren (rohe Oberfl\u00e4che)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2aea3f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"a2aea3f\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"1\",\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"effect\":\"slide\",\"speed\":500}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bildkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/Mold-marks-on-raw-aluminum-extrusion.jpg\" alt=\"Formabdr\u00fccke auf dem rohen Aluminiumstrangpressprofil\"><figcaption class=\"elementor-image-carousel-caption\">Diese Art von Schimmelspuren sind akzeptabel<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/mold-marks-aluminum-extrusions-too-deep.jpg\" alt=\"Dieser Abdruck ist zu tief und sollte zur\u00fcckgewiesen werden.\"><figcaption class=\"elementor-image-carousel-caption\">Dieser Abdruck ist zu tief und sollte zur\u00fcckgewiesen werden.<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a3cc18 elementor-widget elementor-widget-text-editor\" data-id=\"2a3cc18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Diese Abdr\u00fccke sind zu tief, sie sind auch nach dem Sandstrahlen und Eloxieren noch sichtbar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f083c46 elementor-widget elementor-widget-heading\" data-id=\"f083c46\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Abdr\u00fccke nach dem Eloxieren<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eb4d05 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4eb4d05\" data-element_type=\"widget\" data-settings='{\"slides_to_show\":\"1\",\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"effect\":\"slide\",\"speed\":500}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bildkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/Mold-marks-anodized-aluminum-extrusions.jpg\" alt=\"Abdr\u00fccke auf eloxierten Aluminium-Strangpressprofilen\"><figcaption class=\"elementor-image-carousel-caption\">Abdr\u00fccke auf eloxierten Aluminium-Strangpressprofilen<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/mold-marks-anodized-aluminum-closer-view.jpg\" alt=\"Nahaufnahme von Formmarken auf anodisierten Aluminium-Strangpressprofilen\"><figcaption class=\"elementor-image-carousel-caption\">Schauen wir genauer hin<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/Tool-marks-anodized-aluminum-extrusion-2.jpg\" alt=\"Werkzeugspuren auf eloxiertem Aluminiumstrangpressprofil Bild 2\"><figcaption class=\"elementor-image-carousel-caption\">2. Beispiel<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2020\/02\/Mold-marks-anodized-aluminum-extrusions-3.jpg\" alt=\"Abdr\u00fccke auf eloxierten Aluminium-Strangpressprofilen Bild 3\"><figcaption class=\"elementor-image-carousel-caption\">3. Beispiel. Es gibt mehr Formspuren auf dieser einen.<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c45de3 elementor-widget elementor-widget-text-editor\" data-id=\"9c45de3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Schlechte Abdichtung<\/strong>. Mit dem Auge kann man die schlechte Versiegelung vielleicht nicht erkennen, aber wenn man sie anfasst, hat sie eine unangenehm klebrige Oberfl\u00e4che. Manchmal verwenden wir einen Filzstift, um die Versiegelung der klar eloxierten Teile zu \u00fcberpr\u00fcfen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-560599c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"560599c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e02c117\" data-id=\"e02c117\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64f8eee elementor-widget elementor-widget-menu-anchor\" data-id=\"64f8eee\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"qualified_manufacturer\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b4ea40 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2b4ea40\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85ced97 elementor-widget elementor-widget-heading\" data-id=\"85ced97\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_makes_a_qualified_aluminum_extrusion_manufacturer\"><\/span>Was macht einen qualifizierten Hersteller von Aluminium-Strangpressprofilen aus?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9375a48 elementor-widget elementor-widget-text-editor\" data-id=\"9375a48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><strong>Ein engagiertes Managementteam<\/strong><\/p><p class=\"translation-block\">Sie werden sich f\u00fcr Ihre Qualit\u00e4tsanforderungen einsetzen und die fehlerhaften Teile ersetzen, auch wenn Ihr Auftragsvolumen gering ist (etwa 1 bis 2 Tonnen).\u00a0<\/p><p class=\"translation-block\"><strong>Ein konzentriertes Arbeitsteam<\/strong><\/p><p class=\"translation-block\">Wie Sie sich vorstellen k\u00f6nnen, erfordert jeder Prozess, einschlie\u00dflich des Eloxierens, des Be- und Entladens, der Inspektion, des Abl\u00e4ngens und des Verpackens, ein hohes Ma\u00df an Aufmerksamkeit. Wir brauchen konzentriertes Personal, um diese Prozesse durchzuf\u00fchren.<\/p><p class=\"translation-block\"><strong>Ein ger\u00e4umiger Arbeitsplatz<\/strong><\/p><p class=\"translation-block\">F\u00fcr die Inspektion und das Verpacken wird ein ausreichender Arbeitsbereich ben\u00f6tigt, daher ist es wichtig, eine ger\u00e4umige Werkstatt zu haben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17e9b97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17e9b97\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3feb84\" data-id=\"e3feb84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1888a73 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1888a73\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58a3ada elementor-widget elementor-widget-heading\" data-id=\"58a3ada\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"What_we_can_supply\"><\/span>Was wir liefern k\u00f6nnen<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d05566 elementor-widget elementor-widget-text-editor\" data-id=\"0d05566\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Wir k\u00f6nnen die Aluminium-Strangpressprofile in klar eloxiert und schwarz eloxiert liefern. Andere Farben sind auch verf\u00fcgbar, aber die MOQ wird 15 bis 20 Tonnen sein.<\/li><li>Die Strangpressprofile sind in der Regel 6 Meter lang, k\u00f6nnen aber auch auf individuelle Ma\u00dfe zugeschnitten werden. Sie brauchen nur f\u00fcr die fertigen St\u00fccke zu bezahlen, nicht f\u00fcr die Reste der \u00dcberl\u00e4nge.<\/li><li>Die Strangpressprofile werden sorgf\u00e4ltig gepr\u00fcft und anschlie\u00dfend in Kunststofffolien, Papier oder Karton verpackt.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist nicht einfach, einen hochwertigen Hersteller f\u00fcr eloxierte Aluminium-Strangpressprofile zu finden. Als Beschaffungsunternehmen haben wir mehrere verschiedene Hersteller ausprobiert, bis wir einen gefunden haben, mit dem wir uns wohlf\u00fchlen. In diesem Beitrag teilen wir gerne unser Wissen und unsere Erfahrungen in diesem Bereich. Wenn Sie m\u00f6chten, dass wir Ihnen helfen...&nbsp;<a href=\"https:\/\/boyanmfg.com\/de\/anodized-aluminum-extrusions\/\" rel=\"bookmark\">Weiterlesen \u00bb<span class=\"screen-reader-text\">Hochwertige eloxierte Aluminium-Strangpressprofile<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":1804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"full-width","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[57,55],"tags":[],"class_list":["post-1762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-working-with-boyan","category-manufacturing-knowledge"],"acf":[],"_links":{"self":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/1762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/comments?post=1762"}],"version-history":[{"count":0,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/posts\/1762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media\/1804"}],"wp:attachment":[{"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/media?parent=1762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/categories?post=1762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boyanmfg.com\/de\/wp-json\/wp\/v2\/tags?post=1762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}