{"id":9118,"date":"2024-09-02T08:22:22","date_gmt":"2024-09-02T08:22:22","guid":{"rendered":"http:\/\/boyanmfg.com\/?page_id=9118"},"modified":"2025-01-03T02:24:25","modified_gmt":"2025-01-03T02:24:25","slug":"injection-molding-service-for-australia","status":"publish","type":"page","link":"http:\/\/boyanmfg.com\/es\/injection-molding-service-for-australia\/","title":{"rendered":"Servicio de moldeo por inyecci\u00f3n para Australia"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9118\" class=\"elementor elementor-9118\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41d6b80 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41d6b80\" data-element_type=\"section\" data-settings='{\"stretch_section\":\"section-stretched\",\"background_background\":\"slideshow\",\"background_slideshow_gallery\":[{\"id\":9011,\"url\":\"http:\\\/\\\/boyanmfg.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/plastic-molding-background-1.jpg\"},{\"id\":9013,\"url\":\"http:\\\/\\\/boyanmfg.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/EDM-machining-background-1.jpg\"}],\"background_slideshow_transition_duration\":1500,\"background_slideshow_ken_burns\":\"yes\",\"background_slideshow_loop\":\"yes\",\"background_slideshow_slide_duration\":5000,\"background_slideshow_slide_transition\":\"fade\",\"background_slideshow_ken_burns_zoom_direction\":\"in\"}'>\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0bff8d2\" data-id=\"0bff8d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd8f952 elementor-widget elementor-widget-text-editor\" data-id=\"dd8f952\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<div id=\"wp-block-themeisle-blocks-advanced-columns-a0b4c57a\" class=\"wp-block-themeisle-blocks-advanced-columns has-0-columns has-desktop-undefined-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-unset\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\"><\/div><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f9725c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9725c5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65d9768\" data-id=\"65d9768\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dea2ec8 elementor-widget elementor-widget-heading\" data-id=\"dea2ec8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Boyan Manufacturing Solutions Limited<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e4811cb\" data-id=\"e4811cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8df6d96 elementor-icon-list--layout-inline elementor-align-right elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8df6d96\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info1@boyanmfg.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+8618005896811\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-square-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wa.me\/8615325962228\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"skype:johnshi180?chat\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-skype\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e706d71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e706d71\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c4a47f5\" data-id=\"c4a47f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c94fc7 elementor-widget elementor-widget-spacer\" data-id=\"1c94fc7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebfebe6 elementor-widget elementor-widget-heading\" data-id=\"ebfebe6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Servicios de moldeo por inyecci\u00f3n a medida de alta calidad para Australia, Made in China<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a5f1f5 elementor-widget elementor-widget-text-editor\" data-id=\"5a5f1f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\" class=\"translation-block\">Tenemos una amplia experiencia en colaboraciones de \u00e9xito con m\u00faltiples clientes australianos, especialmente en <strong>producci\u00f3n de componentes de pl\u00e1stico moldeados por inyecci\u00f3n a medida<\/strong> y <strong>herramientas<\/strong>.<\/p>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">Nuestro s\u00f3lido historial de estrecha colaboraci\u00f3n nos permite ofrecer soluciones a medida y ofrecer constantemente resultados de alta calidad, garantizando la satisfacci\u00f3n en cada proyecto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-014a936 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"014a936\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">solicitar presupuesto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b95213c\" data-id=\"b95213c\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f45c211 elementor-widget elementor-widget-heading\" data-id=\"f45c211\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">revisi\u00f3n y optimizaci\u00f3n del dise\u00f1o<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c92bce7 elementor-widget elementor-widget-heading\" data-id=\"c92bce7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">fabricaci\u00f3n de moldes<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd28033 elementor-widget elementor-widget-heading\" data-id=\"bd28033\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">producci\u00f3n de moldeo por inyecci\u00f3n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00db8b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00db8b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ea6a1e\" data-id=\"9ea6a1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b90fd19 elementor-widget elementor-widget-spacer\" data-id=\"b90fd19\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59f514c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59f514c\" data-element_type=\"section\" data-settings='{\"stretch_section\":\"section-stretched\",\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3d237c\" data-id=\"b3d237c\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab2afde elementor-widget elementor-widget-spacer\" data-id=\"ab2afde\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bd4d5c elementor-widget elementor-widget-heading\" data-id=\"5bd4d5c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">del dise\u00f1o a la realidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f50b8c elementor-widget elementor-widget-text-editor\" data-id=\"2f50b8c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div>\n<div class=\"pt-0\">\n<div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\">\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">Incluso si no es un experto en moldeo por inyecci\u00f3n, aplicaremos nuestra experiencia y conocimientos para salvar las distancias, perfeccionando su dise\u00f1o para garantizar que se adapta perfectamente al proceso de moldeo por inyecci\u00f3n.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebe32c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebe32c3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43d3fbb\" data-id=\"43d3fbb\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b40dea elementor-widget elementor-widget-text-editor\" data-id=\"7b40dea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Revisi\u00f3n exhaustiva del dise\u00f1o<\/h3>\n<p class=\"translation-block\">Revisamos a fondo los dise\u00f1os de los productos para asegurarnos de que est\u00e1n optimizados para el moldeo por inyecci\u00f3n. Proporcionamos recomendaciones de mejora y realizamos los ajustes necesarios, que luego se env\u00edan al cliente para su aprobaci\u00f3n, lo que supone un valioso ahorro de tiempo.<\/p>\n<h3>An\u00e1lisis detallado del contenido<\/h3>\n<p class=\"translation-block\">Nuestra revisi\u00f3n aborda aspectos clave como los \u00e1ngulos de desmoldeo, el grosor de las paredes, los requisitos est\u00e9ticos, las tolerancias dimensionales y la selecci\u00f3n de los materiales adecuados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8df6be3\" data-id=\"8df6be3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a33304 elementor-widget elementor-widget-text-editor\" data-id=\"1a33304\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div>\n<div class=\"pt-0\">\n<div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\">\n<h3 class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">Dise\u00f1o colaborativo de moldes<\/h3>\n<p class=\"translation-block\">A continuaci\u00f3n, pasamos a la fase de dise\u00f1o del molde, trabajando en estrecha colaboraci\u00f3n con el cliente para ultimar detalles cr\u00edticos como el tipo de compuerta, su ubicaci\u00f3n y las l\u00edneas de separaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words text-start [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"196b496a-bde6-4b4a-a1d7-d3de63217783\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h3>Entrega del producto final<\/h3>\n<p class=\"translation-block\">Una vez aprobado el dise\u00f1o, puede dejarnos el resto a nosotros. Garantizaremos la entrega de productos de alta calidad al cliente.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01f305e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01f305e\" data-element_type=\"section\" data-settings='{\"stretch_section\":\"section-stretched\",\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14aa12b\" data-id=\"14aa12b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1bca342 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bca342\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-614b89e\" data-id=\"614b89e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fc15e9 elementor-widget elementor-widget-image\" data-id=\"0fc15e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/plastic-enclosure-assembly-r8r87xrt5q8en80czwhy7eey7sxk7ubbou5stq4yao.jpg\" title=\"montaje de la caja de pl\u00e1stico\" alt=\"alineaci\u00f3n de componentes para el montaje de cajas de pl\u00e1stico\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec9e18f\" data-id=\"ec9e18f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5cda78 elementor-widget elementor-widget-heading\" data-id=\"f5cda78\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Atenci\u00f3n a los detalles clave<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fab9482 elementor-widget elementor-widget-text-editor\" data-id=\"fab9482\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Abordamos cada proyecto con un profundo conocimiento del producto, reconociendo que la atenci\u00f3n a los detalles clave es esencial para lograr resultados de alta calidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43fabf5 elementor-widget elementor-widget-text-editor\" data-id=\"43fabf5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Aspecto y sensaci\u00f3n de calidad<\/strong><\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">En nuestro proceso es crucial prestar atenci\u00f3n al aspecto del producto y a la sensaci\u00f3n de calidad.<\/p>\n<h3><strong>Precisi\u00f3n en las dimensiones<\/strong><\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">Asegurar la precisi\u00f3n dimensional es vital para garantizar el buen funcionamiento y la alineaci\u00f3n entre las piezas tras el montaje.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a73aed7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a73aed7\" data-element_type=\"section\" data-settings='{\"stretch_section\":\"section-stretched\",\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff45344\" data-id=\"ff45344\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a07d01f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a07d01f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9612e11\" data-id=\"9612e11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d17a77f elementor-widget elementor-widget-heading\" data-id=\"d17a77f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alta precisi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-265d534 elementor-widget elementor-widget-text-editor\" data-id=\"265d534\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Situada en una regi\u00f3n conocida por su desarrollada industria de procesamiento de moldes, nuestra f\u00e1brica se beneficia de una gran cantidad de recursos para la fabricaci\u00f3n de moldes y el moldeo por inyecci\u00f3n de calidad superior.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd2eb9 elementor-widget elementor-widget-text-editor\" data-id=\"3fd2eb9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Maquinaria de precisi\u00f3n<\/strong><\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">Nuestro equipo de mecanizado de precisi\u00f3n garantiza la exactitud necesaria, que es crucial para mantener la calidad de nuestros moldes.<\/p>\n<h3><strong>Moldes de alta precisi\u00f3n<\/strong><\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">Para moldes con requisitos estrictos, podemos lograr una precisi\u00f3n de hasta +\/-0,01 mm, lo que permite montar y utilizar los moldes con unos ajustes manuales m\u00ednimos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-64ba8a7\" data-id=\"64ba8a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7adca37 elementor-widget elementor-widget-image\" data-id=\"7adca37\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/09\/precision-mold-surface.jpg\" class=\"attachment-full size-full wp-image-9226\" alt=\"sin superficie de lijado para moldes de inyecci\u00f3n de precisi\u00f3n\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/09\/precision-mold-surface.jpg 700w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/09\/precision-mold-surface-300x169.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/09\/precision-mold-surface-600x338.jpg 600w\" sizes=\"(max-width: 700px) 100vw, 700px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8bbdab8 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bbdab8\" data-element_type=\"section\" data-settings='{\"stretch_section\":\"section-stretched\",\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40df008\" data-id=\"40df008\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c9f40b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c9f40b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af29161\" data-id=\"af29161\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d4888e elementor-widget elementor-widget-heading\" data-id=\"2d4888e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soluciones asequibles de moldeo por inyecci\u00f3n de pl\u00e1stico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-344296f elementor-widget elementor-widget-text-editor\" data-id=\"344296f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Precio del molde de inyecci\u00f3n<\/b><\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">Elegimos el equipo de mecanizado m\u00e1s adecuado teniendo en cuenta los <strong>requisitos visuales, la precisi\u00f3n, <\/strong>y la <strong>complejidad estructural<\/strong> del producto, garantizando la calidad al tiempo que se minimizan los gastos de moldeado.<\/p>\n<h3><strong>Costes de producci\u00f3n del moldeo por inyecci\u00f3n<\/strong><\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">Al seleccionar el dise\u00f1o de molde adecuado en funci\u00f3n de las <strong>cantidades de producci\u00f3n previstas<\/strong>, nos esforzamos por reducir al m\u00e1ximo los costes del moldeo por inyecci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d83a33f\" data-id=\"d83a33f\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22bdfd0 e-transform e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"22bdfd0\" data-element_type=\"widget\" data-settings='{\"_animation\":\"zoomIn\",\"_transform_scale_effect\":{\"unit\":\"px\",\"size\":0.8,\"sizes\":[]},\"_transform_scale_effect_hover\":{\"unit\":\"px\",\"size\":1,\"sizes\":[]},\"_transform_scale_effect_tablet\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"_transform_scale_effect_mobile\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"_transform_scale_effect_hover_tablet\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"_transform_scale_effect_hover_mobile\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]}}' data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/injection-mold-cost-in-china\/#mold_calculator\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/09\/calculator-image.png\" class=\"attachment-large size-large wp-image-9179\" alt=\"imagen de la calculadora\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/09\/calculator-image.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/09\/calculator-image-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3354ca2 elementor-align-center elementor-mobile-align-justify e-transform elementor-widget elementor-widget-button\" data-id=\"3354ca2\" data-element_type=\"widget\" data-settings='{\"_transform_scale_effect_hover\":{\"unit\":\"px\",\"size\":1.1,\"sizes\":[]},\"_transform_scale_effect_hover_tablet\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"_transform_scale_effect_hover_mobile\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]}}' data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/injection-mold-cost-in-china\/#mold_calculator\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Calculador en l\u00ednea<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccebfcf elementor-widget elementor-widget-text-editor\" data-id=\"ccebfcf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Puede estimar el precio del molde de forma r\u00e1pida e independiente con nuestra calculadora<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81ee73c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81ee73c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be8fbae\" data-id=\"be8fbae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edfcafd elementor-widget elementor-widget-spacer\" data-id=\"edfcafd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4faba5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4faba5a\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b4a2b4\" data-id=\"1b4a2b4\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-28e304f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28e304f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-671438a\" data-id=\"671438a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d83dec elementor-widget elementor-widget-image\" data-id=\"2d83dec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"364\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/custom-plastic-enclosure-1.png\" class=\"attachment-large size-large wp-image-9053\" alt=\"caja de pl\u00e1stico a medida 1\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/custom-plastic-enclosure-1.png 400w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/custom-plastic-enclosure-1-300x273.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-49a2b80\" data-id=\"49a2b80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2024d8 elementor-widget elementor-widget-heading\" data-id=\"a2024d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Para obtener un presupuesto manual m\u00e1s exacto y realista, p\u00f3ngase en contacto con nosotros.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6420f71\" data-id=\"6420f71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ef3cf9 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"0ef3cf9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar un presupuesto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc144ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc144ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e4b25c1\" data-id=\"e4b25c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b67cc10 elementor-widget elementor-widget-spacer\" data-id=\"b67cc10\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8d6a4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8d6a4a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5e4c48\" data-id=\"e5e4c48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef50fe3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef50fe3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b00fad7 elementor-widget elementor-widget-menu-anchor\" data-id=\"b00fad7\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"logistics\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0d24b52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d24b52\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86e141c\" data-id=\"86e141c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e01a8f2 elementor-tabs-alignment-stretch elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"e01a8f2\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\">\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2341\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2341\" aria-expanded=\"false\">Entrega urgente<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2342\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2342\" aria-expanded=\"false\">Transporte mar\u00edtimo y a\u00e9reo tradicional<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2341\" aria-expanded=\"false\">Entrega urgente<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2341\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2341\" tabindex=\"0\" hidden=\"false\"><p class=\"translation-block\">La entrega expr\u00e9s ofrece la comodidad de la entrega directa en la puerta de su casa sin necesidad de pasar por aduanas, ya que el mensajero se encarga de ello por usted. Adem\u00e1s, existe un modelo combinado de transporte mar\u00edtimo y entrega urgente, que ofrece una opci\u00f3n m\u00e1s rentable en comparaci\u00f3n con el transporte mar\u00edtimo tradicional.<\/p>\n<table style=\"border-collapse: collapse; margin: 20px auto; background-color: #d9e8f5; border: 1px solid #cccccc; font-family: Arial, sans-serif;\">\n<thead>\n<tr style=\"background-color: #c7d9ed; text-align: left; line-height: 1.8;\">\n<th style=\"padding: 8px 12px; border: 1px solid #cccccc;\">M\u00e9todo de env\u00edo<\/th>\n<th style=\"padding: 8px 12px; border: 1px solid #cccccc;\">Plazo de entrega<\/th>\n<th style=\"padding: 8px 12px; border: 1px solid #cccccc;\">Coste (US$\/kg)<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"line-height: 1.4;\">\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">Premium Express<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">4-5 d\u00edas<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">12-13<\/td>\n<\/tr>\n<tr style=\"line-height: 1.4;\">\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">Tarifa Plana Express<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">5-10 d\u00edas<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">8.5-9.5<\/td>\n<\/tr>\n<tr style=\"line-height: 1.4;\">\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">Carga mar\u00edtima + Express<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">35-40 d\u00edas<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">2.5-3.5<\/td>\n<\/tr>\n<tr style=\"line-height: 1.4;\">\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">Carga a\u00e9rea + Express<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">12-18 d\u00edas<\/td>\n<td style=\"padding: 6px 12px; border: 1px solid #cccccc;\">7-8.5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"translation-block\"><strong>Nota:<\/strong> Las tarifas anteriores se aplican a env\u00edos con un peso superior a 21 kg. Para mercanc\u00edas de gran volumen pero poco peso, las tarifas se basan en el volumen, calculado como volumen (cent\u00edmetros c\u00fabicos) \/ 5000.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2342\" aria-expanded=\"false\">Transporte mar\u00edtimo y a\u00e9reo tradicional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2342\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2342\" tabindex=\"0\" hidden=\"hidden\"><p class=\"translation-block\">Para grandes vol\u00famenes de env\u00edos, el transporte mar\u00edtimo tradicional es la opci\u00f3n m\u00e1s econ\u00f3mica.<\/p>\n<p class=\"translation-block\">Los costes del transporte a\u00e9reo tradicional son similares a los de la entrega urgente, lo que hace que se utilice menos.<\/p>\n<p class=\"translation-block\">Tanto el transporte mar\u00edtimo como el a\u00e9reo requieren un despacho de aduanas, que suele realizarse contratando a un agente de aduanas. No obstante, podemos organizar la entrega puerta a puerta.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8f4bdcd\" data-id=\"8f4bdcd\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23f653e elementor-widget elementor-widget-heading\" data-id=\"23f653e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Amplias opciones log\u00edsticas\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7134115 elementor-widget elementor-widget-text-editor\" data-id=\"7134115\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Hay varias opciones para enviar mercanc\u00edas de China a Australia, que se clasifican en entrega urgente (servicio de mensajer\u00eda) y flete mar\u00edtimo o a\u00e9reo tradicional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dadd3a elementor-widget elementor-widget-image\" data-id=\"3dadd3a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/packaging-and-shipping-1.jpg\" class=\"attachment-large size-large wp-image-8977\" alt=\"Carga de cajas de cart\u00f3n en un pal\u00e9 listo para su env\u00edo\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/packaging-and-shipping-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/packaging-and-shipping-1-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97197aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97197aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ae37ff\" data-id=\"5ae37ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9255419 elementor-widget elementor-widget-spacer\" data-id=\"9255419\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5663f46 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"5663f46\" data-element_type=\"widget\" data-settings='{\"navigation\":\"both\",\"autoplay\":\"yes\",\"pause_on_hover\":\"yes\",\"pause_on_interaction\":\"yes\",\"autoplay_speed\":5000,\"infinite\":\"yes\",\"speed\":500,\"image_spacing_custom\":{\"unit\":\"px\",\"size\":20,\"sizes\":[]},\"image_spacing_custom_tablet\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"image_spacing_custom_mobile\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]}}' data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/injection-mold-plastic-enclosure-11-r8r88m7kvkdff2v4ma72w5ekmhdh47smkej95inhrs.jpg\" alt=\"molde de inyecci\u00f3n caja de pl\u00e1stico 11\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/injection-mold-helical-gear-202304-r8r8bsvw1cqeri8k0nrkccgt3ho97afvo64hp9xgoo.jpg\" alt=\"molde de inyecci\u00f3n para el engranaje helicoidal\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/mold-for-plastic-worm-gear-3-r8r8bgnzki9okkqb00hexxjtdhchf83dahn6gofkxk.jpg\" alt=\"molde de inyecci\u00f3n para tornillo sin fin de pl\u00e1stico 3\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/injection-mold-plastic-helical-gear-close-view-r8r8bcwmt64ja4vrlyuwnyhyzxv0kfofxz18jkl5mg.jpg\" alt=\"molde de inyecci\u00f3n de pl\u00e1stico engranaje helicoidal vista de cerca\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/close-view-of-mold-for-plastic-pin-connector-r8r8bcwmt64ja4vrlyuwnyhyzxv0kfofxz18jkl5mg.jpg\" alt=\"vista cercana del molde para conector de pl\u00e1stico\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/injection-mold-lifters-12-r8r899pjmf9lhbwzt2cr4hh3h45ngndwzmue5fong8.jpg\" alt=\"molde de inyecci\u00f3n de pl\u00e1stico con 2 elevadores\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/Injection-mold-substrate-r8r88ssg7emfoclkjv1gvlqss6h1m3iqxb3nigdqk8.jpg\" alt=\"Molde de inyecci\u00f3n para el sustrato\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/example-for-domestic-used-mold-r8r86bhs65871e7a1afwsqa0ckp6auo8x14ix624zc.jpg\" alt=\"ejemplo de molde dom\u00e9stico usado para un cilindro de pl\u00e1stico\"><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a207e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a207e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4aa0125\" data-id=\"4aa0125\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e31034 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4e31034\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d5388 elementor-widget elementor-widget-menu-anchor\" data-id=\"16d5388\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"communication\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d852f elementor-widget elementor-widget-heading\" data-id=\"42d852f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comunicaci\u00f3n c\u00f3moda y eficaz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7cd6faf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cd6faf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-93c170c\" data-id=\"93c170c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4164484 elementor-widget elementor-widget-text-editor\" data-id=\"4164484\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Detalles clave<\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">La inspecci\u00f3n de productos no s\u00f3lo depende de los conocimientos y la experiencia, sino tambi\u00e9n de una buena fotograf\u00eda. Esto nos permite enviarle im\u00e1genes detalladas y precisas, garantiz\u00e1ndole una comprensi\u00f3n m\u00e1s completa del producto que la que podr\u00eda proporcionarle una inspecci\u00f3n en persona.<\/p>\n<h3>Enfoque colaborativo<\/h3>\n<p style=\"padding-left: 40px;\" class=\"translation-block\">Nos tomamos el tiempo necesario para comprender plenamente sus necesidades e ideas, y resolvemos los problemas con prontitud para satisfacer sus requisitos de calidad. Nuestro objetivo es garantizar su plena satisfacci\u00f3n con nuestros productos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9f78e1e\" data-id=\"9f78e1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b56a0c elementor-widget elementor-widget-image\" data-id=\"7b56a0c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/phone-video-call-meeting-1.jpg\" class=\"attachment-large size-large wp-image-9058\" alt=\"reuni\u00f3n telef\u00f3nica por videollamada para hablar de la producci\u00f3n de piezas de pl\u00e1stico\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/phone-video-call-meeting-1.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/06\/phone-video-call-meeting-1-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9671b0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d9671b0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08e211e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08e211e\" data-element_type=\"section\" data-settings='{\"stretch_section\":\"section-stretched\",\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45536e9\" data-id=\"45536e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f11749 elementor-widget elementor-widget-text-editor\" data-id=\"1f11749\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>P\u00f3ngase en contacto con nosotros<\/h2>\n<p class=\"translation-block\">En Boyan Manufacturing Solutions, le ayudamos en todas las fases del desarrollo del producto, desde el dise\u00f1o y la creaci\u00f3n r\u00e1pida de prototipos, la fabricaci\u00f3n de moldes, la producci\u00f3n de piezas de pl\u00e1stico hasta diversas fases de postprocesamiento, como la impresi\u00f3n, la pintura y el mecanizado secundario.<\/p>\n<p class=\"translation-block\">Nuestro compromiso con la calidad, la comunicaci\u00f3n eficaz y la satisfacci\u00f3n del cliente garantiza que convertir su idea en realidad sea un proceso fluido. P\u00f3ngase en contacto con nosotros<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf68de6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf68de6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e257e7b\" data-id=\"e257e7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e10205f elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"e10205f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar un presupuesto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86556a4\" data-id=\"86556a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8f00de elementor-widget elementor-widget-image\" data-id=\"a8f00de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/elementor\/thumbs\/plastic-gear-with-spline-shaft-r8r87xrp9e49uvruc8o69ms77e7pixlyxvvirlttfk.png\" title=\"engranaje de pl\u00e1stico con eje estriado\" alt=\"engranaje de pl\u00e1stico con eje estriado\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69b5b93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69b5b93\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b255f63\" data-id=\"b255f63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e8ca9a elementor-widget elementor-widget-spacer\" data-id=\"4e8ca9a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7ae271 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7ae271\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa0a6fd\" data-id=\"aa0a6fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-196930a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"196930a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27cb732\" data-id=\"27cb732\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-daec2fc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"daec2fc\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-question-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c085707\" data-id=\"c085707\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3be9f04 elementor-widget elementor-widget-heading\" data-id=\"3be9f04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Preguntas frecuentes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-42ee137 elementor-widget elementor-widget-toggle\" data-id=\"42ee137\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfEn qu\u00e9 ciudades de Australia se encuentran sus clientes?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7011\"><p class=\"translation-block\">Actualmente, nuestros clientes se encuentran en Brisbane, Jandakot, Balcatta, Perth y Camp Hill. Si desea algunas referencias de clientes, podemos facilitarle sus datos de contacto.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7012\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-7012\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 ventajas tiene el comercio entre Australia y China en comparaci\u00f3n con otros pa\u00edses?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7012\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-7012\"><p class=\"translation-block\">Respuesta: En primer lugar, el transporte es c\u00f3modo y rentable. En segundo lugar, los husos horarios son similares: la hora de Pek\u00edn en China es la misma que la de Perth en Australia.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7013\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-7013\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1l es el plazo de entrega de los proyectos de moldeo por inyecci\u00f3n?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7013\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-7013\"><p class=\"translation-block\">El plazo de entrega de los proyectos de moldeo por inyecci\u00f3n var\u00eda en funci\u00f3n de la complejidad, la precisi\u00f3n y el tama\u00f1o del molde. Normalmente, el ciclo de producci\u00f3n de un molde de inyecci\u00f3n oscila entre 25 y 40 d\u00edas. Las muestras iniciales producidas con el molde se denominan muestras T0.<\/p>\n<p class=\"translation-block\">Tras la inspecci\u00f3n de las muestras T0, puede ser necesario realizar modificaciones en el molde. Esto puede incluir ajustes de dise\u00f1o o correcciones para cumplir las dimensiones especificadas. Tras las modificaciones, se fabrica el siguiente conjunto de muestras, conocidas como muestras T1. Este ciclo puede durar entre 15 y 25 d\u00edas m\u00e1s, a los que hay que a\u00f1adir el tiempo necesario para el env\u00edo y la inspecci\u00f3n de las muestras, lo que hace un total de unos 30 d\u00edas.<\/p>\n<p class=\"translation-block\">En resumen, el proceso completo, desde el inicio hasta la finalizaci\u00f3n de un molde, suele durar entre 2 y 3 meses. A veces, es necesaria una segunda ronda de modificaciones, aunque es menos habitual.<\/p>\n<p class=\"translation-block\">La comunicaci\u00f3n eficaz durante la inspecci\u00f3n de muestras y el proceso de resoluci\u00f3n de problemas es crucial. Sin ella, el plazo total puede alargarse a\u00fan m\u00e1s.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7014\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-7014\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1l es su cantidad m\u00ednima de pedido?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7014\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-7014\"><p class=\"translation-block\">No imponemos restricciones al MOQ. Para algunos productos, la cantidad puede ser tan baja como 100 piezas. Esperamos que esto se traduzca en m\u00e1s pedidos en el futuro, pero no pasa nada si no es as\u00ed.<\/p>\n<p class=\"translation-block\">Sin embargo, tenga en cuenta que los pedidos m\u00e1s peque\u00f1os pueden tener plazos de entrega m\u00e1s largos. Esto se debe a que estos pedidos se suelen procesar durante los intervalos de otros programas de producci\u00f3n, especialmente cuando se requieren condiciones de producci\u00f3n espec\u00edficas o un procesamiento posterior adicional.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7015\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-7015\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfOfrecen operaciones secundarias o servicios de acabado?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7015\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-7015\"><p class=\"translation-block\">Por supuesto. Ofrecemos una amplia gama de operaciones secundarias y servicios de acabado, incluidos tratamientos superficiales como pintura, chapado, serigraf\u00eda, tampograf\u00eda y grabado por l\u00e1ser. Adem\u00e1s, ofrecemos servicios de soldadura, mecanizado y montaje, entre otros, para satisfacer las diversas necesidades de nuestros clientes y garantizar que sus proyectos se completan con los m\u00e1s altos est\u00e1ndares.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7016\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-7016\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Si financiamos el molde y el producto se fabrica en sus instalaciones, \u00bfes de nuestra propiedad?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7016\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-7016\"><p class=\"translation-block\">Por supuesto, si lo solicita, le enviaremos el molde sin demora, aunque estas situaciones son poco frecuentes. Por lo general, una vez que los clientes empiezan a fabricar sus moldes y los guardan en nuestras instalaciones para la producci\u00f3n, no es habitual que recuperen los moldes a mitad del proceso.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7017\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-7017\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1les son sus condiciones generales de pago?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7017\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-7017\"><p class=\"translation-block\">Para los costes del molde, generalmente exigimos un anticipo de 50%, y el resto de 50% se abona tras la confirmaci\u00f3n de la muestra.<\/p>\n<p class=\"translation-block\">Para la producci\u00f3n del producto, normalmente requerimos un anticipo de 30%, y el resto de 70% se paga antes del env\u00edo. Sin embargo, inspeccionaremos cuidadosamente la calidad del producto y enviaremos los resultados de la inspecci\u00f3n antes del env\u00edo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f64cb91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f64cb91\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2df12f3\" data-id=\"2df12f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-255b99f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"255b99f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298f584 elementor-widget elementor-widget-heading\" data-id=\"298f584\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/boyanmfg.com\/category\/plastic-molding\/\">Entradas de blog<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd7f53e elementor-widget elementor-widget-obfx-posts-grid\" data-id=\"fd7f53e\" data-element_type=\"widget\" data-widget_type=\"obfx-posts-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"obfx-grid\"><div class=\"obfx-grid-container obfx-grid-desktop-4\"><div class=\"obfx-grid-wrapper\"><article class=\"obfx-grid-col\"><div class=\"obfx-grid-col-image\"><a href=\"http:\/\/boyanmfg.com\/es\/thin-wall-injection-molding\/\" title=\"Retos y soluciones en el dise\u00f1o de moldeo por inyecci\u00f3n de pared delgada\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/04\/thin-wall-injection-molding-plastic-parts.jpg\" class=\"img-responsive wp-post-image\" alt=\"piezas de pl\u00e1stico de pared delgada moldeadas por inyecci\u00f3n\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/04\/thin-wall-injection-molding-plastic-parts.jpg 1100w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/04\/thin-wall-injection-molding-plastic-parts-300x123.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/04\/thin-wall-injection-molding-plastic-parts-1024x419.jpg 1024w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/04\/thin-wall-injection-molding-plastic-parts-768x314.jpg 768w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2025\/04\/thin-wall-injection-molding-plastic-parts-600x245.jpg 600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\"><\/a><\/div><div class=\"obfx-grid-col-content\">\t\t\t<h2 class=\"entry-title obfx-grid-title\">\n\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/es\/thin-wall-injection-molding\/\" title=\"Retos y soluciones en el dise\u00f1o de moldeo por inyecci\u00f3n de pared delgada\">\n\t\t\t\t\tRetos y soluciones en el dise\u00f1o de moldeo por inyecci\u00f3n de pared delgada\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<div class=\"entry-content obfx-grid-content\">\n\t\t\t\t\u00bfQu\u00e9 es el moldeo por inyecci\u00f3n de pared delgada? Las piezas moldeadas por inyecci\u00f3n son t\u00edpicamente productos pl\u00e1sticos con espesores de pared delgados y uniformes. Mientras que paredes excesivamente gruesas pueden causar ciertos problemas, las paredes que\u2026\t\t\t<\/div>\n\t\t\t<\/div><\/article><\/div><div class=\"obfx-grid-wrapper\"><article class=\"obfx-grid-col\"><div class=\"obfx-grid-col-image\"><a href=\"http:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/\" title=\"Montaje de moldes de inyecci\u00f3n y ajuste manual\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"450\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/manual-fitting-mold-assembly.jpg\" class=\"img-responsive wp-post-image\" alt=\"montaje manual de moldes de ajuste\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/manual-fitting-mold-assembly.jpg 1100w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/manual-fitting-mold-assembly-300x123.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/manual-fitting-mold-assembly-1024x419.jpg 1024w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/manual-fitting-mold-assembly-768x314.jpg 768w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/10\/manual-fitting-mold-assembly-600x245.jpg 600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\"><\/a><\/div><div class=\"obfx-grid-col-content\">\t\t\t<h2 class=\"entry-title obfx-grid-title\">\n\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/es\/injection-mold-assembly-and-manual-fitting\/\" title=\"Montaje de moldes de inyecci\u00f3n y ajuste manual\">\n\t\t\t\t\tMontaje de moldes de inyecci\u00f3n y ajuste manual\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<div class=\"entry-content obfx-grid-content\">\n\t\t\t\tLa importancia del ensamblaje de moldes de inyecci\u00f3n y el ajuste manual En el proceso de fabricaci\u00f3n de moldeo por inyecci\u00f3n, el ensamblaje del molde y el ajuste manual son etapas cruciales que requieren un tiempo y esfuerzo considerables. Estos\u2026\t\t\t<\/div>\n\t\t\t<\/div><\/article><\/div><div class=\"obfx-grid-wrapper\"><article class=\"obfx-grid-col\"><div class=\"obfx-grid-col-image\"><a href=\"http:\/\/boyanmfg.com\/es\/plastic-product-design\/\" title=\"Agilice su creaci\u00f3n con el servicio de dise\u00f1o de productos de pl\u00e1stico de Boyan\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"368\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-product-design-guide.jpg\" class=\"img-responsive wp-post-image\" alt=\"gu\u00eda de dise\u00f1o de productos de pl\u00e1stico\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-product-design-guide.jpg 900w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-product-design-guide-600x245.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-product-design-guide-300x123.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-product-design-guide-768x314.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\"><\/a><\/div><div class=\"obfx-grid-col-content\">\t\t\t<h2 class=\"entry-title obfx-grid-title\">\n\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/es\/plastic-product-design\/\" title=\"Agilice su creaci\u00f3n con el servicio de dise\u00f1o de productos de pl\u00e1stico de Boyan\">\n\t\t\t\t\tAgilice su creaci\u00f3n con el servicio de dise\u00f1o de productos de pl\u00e1stico de Boyan\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<div class=\"entry-content obfx-grid-content\">\n\t\t\t\tIntroducci\u00f3n a la experiencia de Boyan en el dise\u00f1o de productos pl\u00e1sticos Boyan cuenta con una amplia experiencia y un alto nivel de especializaci\u00f3n en el dise\u00f1o de productos pl\u00e1sticos moldeados por inyecci\u00f3n. Estamos aqu\u00ed\u2026\t\t\t<\/div>\n\t\t\t<\/div><\/article><\/div><div class=\"obfx-grid-wrapper\"><article class=\"obfx-grid-col\"><div class=\"obfx-grid-col-image\"><a href=\"http:\/\/boyanmfg.com\/es\/injection-molded-plastic-parts-painting\/\" title=\"Esenciales para la Pintura de Piezas de Pl\u00e1stico Moldeadas por Inyecci\u00f3n: De la preparaci\u00f3n a la perfecci\u00f3n\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"368\" src=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-parts-painting-guide.jpg\" class=\"img-responsive wp-post-image\" alt=\"gu\u00eda de pintura de piezas de pl\u00e1stico\" srcset=\"https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-parts-painting-guide.jpg 900w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-parts-painting-guide-600x245.jpg 600w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-parts-painting-guide-300x123.jpg 300w, https:\/\/boyanmfg.com\/wp-content\/uploads\/2024\/04\/plastic-parts-painting-guide-768x314.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\"><\/a><\/div><div class=\"obfx-grid-col-content\">\t\t\t<h2 class=\"entry-title obfx-grid-title\">\n\t\t\t\t\t\t\t<a href=\"http:\/\/boyanmfg.com\/es\/injection-molded-plastic-parts-painting\/\" title=\"Esenciales para la Pintura de Piezas de Pl\u00e1stico Moldeadas por Inyecci\u00f3n: De la preparaci\u00f3n a la perfecci\u00f3n\">\n\t\t\t\t\tEsenciales para la Pintura de Piezas de Pl\u00e1stico Moldeadas por Inyecci\u00f3n: De la preparaci\u00f3n a la perfecci\u00f3n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<div class=\"entry-content obfx-grid-content\">\n\t\t\t\t\u00a1Bienvenido a los servicios de pintura de Boyan para piezas moldeadas por inyecci\u00f3n! En Boyan, nos enorgullecemos de ofrecer una gama completa de servicios de pintura adaptados a varios tipos de materiales pl\u00e1sticos y\u2026\t\t\t<\/div>\n\t\t\t<\/div><\/article><\/div><\/div><!-- .obfx-grid-container --><\/div><!-- .obfx-grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6244add elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6244add\" data-element_type=\"section\" data-settings='{\"background_background\":\"classic\",\"shape_divider_top\":\"triangle-asymmetrical\"}'>\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M738,99l262-93V0H0v5.6L738,99z\"><\/path>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b13a4b\" data-id=\"8b13a4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c7798c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c7798c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b8e9517\" data-id=\"b8e9517\" data-element_type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0990b44 elementor-widget elementor-widget-heading\" data-id=\"0990b44\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfBusca un proveedor de moldeo por inyecci\u00f3n fiable para su pr\u00f3ximo proyecto?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e74f16f elementor-widget elementor-widget-spacer\" data-id=\"e74f16f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d67b527 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"d67b527\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"http:\/\/boyanmfg.com\/enquiry-plastic-injection-molding\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar un presupuesto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Boyan Manufacturing Solutions Limited Servicios de Moldeo por Inyecci\u00f3n Personalizado de Alta Calidad para Australia, Fabricado en China Contamos con amplia experiencia en colaboraciones exitosas con m\u00faltiples clientes australianos, particularmente en la producci\u00f3n de componentes pl\u00e1sticos y herramientas de moldeo por inyecci\u00f3n personalizados. Nuestro s\u00f3lido historial de cooperaci\u00f3n estrecha nos permite ofrecer soluciones a medida y entregar consistentemente resultados de alta calidad, garantizando la satisfacci\u00f3n\u2026&nbsp;<a href=\"http:\/\/boyanmfg.com\/es\/injection-molded-plastic-parts-painting\/\" rel=\"bookmark\">Leer M\u00e1s \u00bb<span class=\"screen-reader-text\">Esenciales para la Pintura de Piezas de Pl\u00e1stico Moldeadas por Inyecci\u00f3n: De la preparaci\u00f3n a la perfecci\u00f3n<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"full-width","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"on","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-9118","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"http:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/pages\/9118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/comments?post=9118"}],"version-history":[{"count":0,"href":"http:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/pages\/9118\/revisions"}],"wp:attachment":[{"href":"http:\/\/boyanmfg.com\/es\/wp-json\/wp\/v2\/media?parent=9118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}